{"id":17423,"date":"2018-03-21T08:25:23","date_gmt":"2018-03-21T08:25:23","guid":{"rendered":""},"modified":"2018-03-21T08:25:23","modified_gmt":"2018-03-21T08:25:23","slug":"17423-mi-vecina-hace-cornudo-al-marido","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/17423-mi-vecina-hace-cornudo-al-marido\/","title":{"rendered":"Mi vecina hace cornudo al marido"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"17423\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">4<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\"><em>En los &uacute;ltimos d&iacute;as han sido varios los relatos que he subido. La verdad es que la aceptaci&oacute;n ha sido buena ya que varias personas me han escrito&hellip; y eso ayuda bastante a seguir escribiendo. Agradezco que invirt&aacute;is vuestros minutos en leer lo que escribo y que, encima, os guste.<\/em><\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">En esta ocasi&oacute;n antes del relato en s&iacute; debo contaros algo para que lo entend&aacute;is bien. Los relatos que he subido hasta ahora, aunque contienen detalles reales, son m&aacute;s fruto de mi imaginaci&oacute;n. Sin embargo el que a continuaci&oacute;n escribo es totalmente real. Todo lo que cuento ha sucedido en realidad. Puede parecer, seguro, menos &ldquo;fuerte&rdquo; que otros que he escrito antes, pero el hecho de que sea totalmente real y me ocurriera a m&iacute; me lo hace muy morboso. Espero que a vosotros y vosotras tambi&eacute;n, claro.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Por ello, adem&aacute;s, me ten&eacute;is que permitir que en unas l&iacute;neas os cuente algunos detalles para que entend&aacute;is bien el relato.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Vivo en una localidad de Sevilla. Concretamente dentro de esa localidad, en un barrio bastante nuevo. Con nuevo quiero decir que es de construcci&oacute;n reciente pero que adem&aacute;s, en su mayor&iacute;a, la gente que en &eacute;l habitamos somos gente joven. Eso explica que entre semana sea dif&iacute;cil encontrar a gente en mi barrio. Y en el fin de semana ni os cuento.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Entre semana la gente trabaja y las casas est&aacute;n cerradas a cal y canto la mayor&iacute;a del tiempo. En el fin de semana la gente que no es de aqu&iacute; se marcha a visitar a la familia, los que tienen un piso en la playa tambi&eacute;n se van&hellip; En los fines de semana mi barrio parece un barrio fantasma. Algo bueno, eso s&iacute;, para aparcar el coche.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Pues precisamente era un viernes de hace unos meses cuando ocurri&oacute; todo. Yo hab&iacute;a salido del curro el viernes al mediod&iacute;a y me encaminaba desde Sevilla a mi casa en el coche. Ser&iacute;a un viernes tarde y noche tranquilo. Mi mujer trabaja en unos grandes almacenes. Estaba de inventario as&iacute; que saldr&iacute;a antes y encima el s&aacute;bado deb&iacute;a volver a primera hora. As&iacute; que se quedaba en la casa de sus padres, que viv&iacute;an en la propia Sevilla. Era algo tonto desplazarse tanto para tan poco tiempo.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Mis planes&hellip; ver la tele, beber cerveza y poco m&aacute;s.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Adem&aacute;s era un d&iacute;a de esos grises, con llovizna.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Pues nada. De camino a casa parada en el Carrefour y cerveza al carro.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Un cuarto de hora aparcaba en mi barrio y me iba a mi casa con la bolsa de la compra y las cosas del curro.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Al pasar por la casa de mi vecino se abri&oacute; la puerta. Sali&oacute; mi vecino cargando un par de maletas.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&#8211; Qu&eacute;? Una escapada? -le dije deteni&eacute;ndome.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">-Eh? Hola! Una escapada?? Ojal&aacute;!! Trabajo, amigo, trabajo. Mi empresa ser&aacute; muy buena pero tiene las cosas de poner una reuni&oacute;n ma&ntilde;ana s&aacute;bado y encima en Bilbao. Imag&iacute;nate.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">-Ostia, gran putada.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">-Pues ya ves, macho. Maleta y manta -dijo mientras met&iacute;a las maletas en el coche.- Y me voy pitando que ya lo que me falta es perder el avi&oacute;n. Nos vemos la semana que viene.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Y diciendo esto, d&aacute;ndome un toque en el hombro, se fue.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Yo entr&eacute; en casa, met&iacute; la cerveza al fr&iacute;o y empec&eacute; a perder el tiempo de la tarde.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Aprovechar&eacute; un momento ahora para contaros algo sobre mis vecinos.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Vivimos en una serie de casitas pareadas. Este vecino en concreto no llevaba mucho tiempo entonces viviendo all&iacute;. Unos tres meses creo recordar. Trabaja en una empresa bastante importante. Y yo le envidio por los coches que tiene&hellip; Su mujer no me da envidia pero s&iacute; bastante morbo. Ambos ser&aacute;n de mi edad. Unos 35 a&ntilde;os y tienen un par de ni&ntilde;as. La mujer es lo que se dice por aqu&iacute; una &ldquo;jaquetona&rdquo;. Es una mujer no gorda pero grande. Es alta y de formas contundentes. Morena, ojos oscuros, casi algo agitanada, podr&iacute;amos decir. Dos tetas bien puestas, un culo resping&oacute;n y una cara bonita. La verdad es que siempre me pregunto c&oacute;mo ha tenido dos ni&ntilde;as y tener ese cuerpo. Va casi siempre, o yo la veo casi siempre, en ropa deportiva. Su ropa t&iacute;pica son las t&iacute;picas mallas de deporte, zapatillas deportivas y tal. Algunas veces la he visto en vaqueros ce&ntilde;idos, pero pocas.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Y os contar&eacute; una cosa m&aacute;s. Al fin y al cabo puedo sincerarme por aqu&iacute;. Hace algo de tiempo me di cuenta que tiende la ropa en un tendedero port&aacute;til en la terraza. Nuestras casas tienen unas peque&ntilde;as terrazas en la parte delantera y desde una se puede ver sin problemas la de los lados. Pues bien un d&iacute;a que sal&iacute; para ver como de nublado andaba el d&iacute;a vi en ese tendedero colgada toda una colecci&oacute;n de ropa interior que hizo que un poco m&aacute;s y una ambulancia tuviera que ir a por m&iacute;. Un par de tangas de hilo negros, unas braguitas naranjas brillantes, unas blancas y un par de ellas de encaje rojo. No os enga&ntilde;ar&eacute;. Desde ese momento cada vez que la veo me pregunto qu&eacute; cojones llevar&aacute; debajo de las mallas. No s&eacute; si es bueno o malo reconocerlo, pero es verdad que cada vez que la veo me la como con las miradas. Habr&aacute; t&iacute;as mejores. Pero para m&iacute; &eacute;sta es un ejemplo, si me lo permit&iacute;s, de esas mujeres que se catalogan como Milf.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">En fin que me pierdo. Vuelvo a ese d&iacute;a. Mand&eacute; a la mierda la corbata y la camisa, me coloqu&eacute; el pijama y me propuse echar una tarde sin muchos jaleos.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Un par de horas despu&eacute;s estaba hasta los cojones de la programaci&oacute;n de la tele.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Sobre las 20 me coloqu&eacute; las zapatillas, algo de ropa de deporte y sal&iacute; a correr un rato a la calle. La tarde se hab&iacute;a llenado de niebla. Y la lluvia se hab&iacute;a convertido en eso que se llama calabobos. Yo no soy un gran deportista as&iacute; que con unos 20 minutos de carrera tuve m&aacute;s que suficiente. Un trozo de camino de vuelta a casa lo tuve que hacer caminando.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Al llegar a una isleta de contenedores de basura donde echamos los vecinos la basura vi tir&aacute;ndola a mi vecina. La verdad es que yo cre&iacute;a que no estar&iacute;a por all&iacute; despu&eacute;s de que el marido se fuera, pero all&iacute; estaba. La salude y nos fuimos caminando juntos para la casa.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Yo hablaba con ella y de camino le daba un repaso visual. Gracias a esa caminata con ella me enter&eacute; que las ni&ntilde;as estaban en Sevilla con los abuelos y que su marido ya iba en el avi&oacute;n. Llegamos a su puerta y mientras habl&aacute;bamos de temas triviales yo me imaginaba haci&eacute;ndole de todo, disfrutando de su cuerpazo. Pero vamos, al par de minutos se hab&iacute;a ido ella a su casa y yo entraba en la m&iacute;a.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Me fui a la ducha y me coloqu&eacute; de nuevo el pijama. Luego una cerveza y algo de tele. Hablar con mi mujer por tel&eacute;fono. Otra cerveza, Iniciar una pel&iacute;cula. Y no terminarla. Iniciar otra. A eso de las 11 me vecina se puso a ducharse. Lo escuch&eacute; perfectamente porque las casas donde vivimos son muy curiosas: las ventanas est&aacute;n tela de aisladas con el climalit. No entra ni frio ni calor ni nada de ruego. Pero las paredes&hellip; bueno no est&aacute;n muy aisladas por lo que se ve.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Escucha por tanto el agua de la ducha correr. Y me imaginaba el agua desliz&aacute;ndose por su cuerpo&hellip; ufffff. Decid&iacute; ponerme a ver la tele.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Unos minutos despu&eacute;s escuch&eacute; a mi vecina caminar en tacones, cerrar la puerta e irse.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Ir&iacute;a a alg&uacute;n lugar. Yo en concreto donde fui un rato despu&eacute;s fue a la cama. Me puse en ella a leer un rato y luego me qued&eacute; dormido, pensando que mi vecina estar&iacute;a a pocos metros de mi sola tambi&eacute;n en la cama aquella noche. Su habitaci&oacute;n est&aacute; justo al otro lado de mi pared.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Ser&iacute;a cerca de las dos cuando me despert&eacute;. Se hab&iacute;a levantado mucho viento y se escuchaba un sonido met&aacute;lico fuerte. Me levant&eacute; cag&aacute;ndome en todo para ir a la terraza. Ser&iacute;a cualquier cosa movi&eacute;ndose por el viento. Pero nada de nada.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">All&iacute; no hab&iacute;a nada y no se escuchaba adem&aacute;s.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Volv&iacute; al dormitorio. Ya no se escuchaba. Espera&hellip; si. Se escuchaba. Qu&eacute; cojones era ese sonido met&aacute;lico? De pronto se volvi&oacute; m&aacute;s r&iacute;tmico. Empec&eacute; a imaginar lo que pod&iacute;a ser con una mezcla entre sorpresa, deseo y morbo.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Un leve gemido me dijo que estaba en lo cierto. Alguien se estaba tirando a mi vecina en su cama.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Mi coraz&oacute;n se aceler&oacute; y mi polla, no os lo ocultar&eacute;, empez&oacute; a hincharse.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Y no s&eacute; si fue porque al saber lo que era mi o&iacute;do se hizo al sonido, si fue porque me acerqu&eacute; m&aacute;s a la pared, o si ellos con la acci&oacute;n elevaron la voz. Pero empec&eacute; a escuchar trozo de frases que hicieron que mi deseo de cruzar la pared fuera descomunal. Literalmente, os pongo algunas de las cosas que escuch&eacute; de la boca de mi vecina porque se me quedaron grabadas casi a fuego:<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Si, si, as&iacute;, as&iacute;.&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Joder, que bueno eres&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;c&oacute;metelo, c&oacute;metelo&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Ponte arriba tu ahora&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Y escuche una voz de t&iacute;o, que desde luego no era la de mi vecino, decir que:<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Vaya culo tienes zorra&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">No pares de chupar&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Yo la verdad es que me masturbaba escuchando eso, salpicado de gemidos. A continuaci&oacute;n escuch&eacute; retazos de una cosa que me puso m&aacute;s cachondo si eso era posible. Era mi vecina diciendo que<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Por ah&iacute; no, por ah&iacute; no&hellip; vale, vale, pero despacito&hellip; yo te aviso&hellip; sigue, va bien&hellip; que rico, joder&hellip; dame fuerte, dame fuerte&hellip;&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Y el sonido met&aacute;lico del inicio se hizo m&aacute;s fuerte. Para terminar un gemido del t&iacute;o y lo que yo dir&iacute;a que era una cachetada al culo. Luego el silencio.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Fui al ba&ntilde;o de mi casa y termin&eacute; de masturbarme pensando en mi vecina follando.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Cuando volv&iacute; a la cama segu&iacute;a sin escucharse nada m&aacute;s, as&iacute; que volv&iacute; a acostarme. Al rato de estar all&iacute; escuch&eacute; el grifo de mis vecinos del ba&ntilde;o, y la ducha. Aguant&eacute; el sue&ntilde;o deseando que volvieran a follar de nuevo y escucharlo todo. Pero lo que se escuch&oacute; media hora despu&eacute;s fue la puerta de mi vecina abrirse y cerrarse. Me qued&eacute; a la escucha pero nada de nada. Un poco despu&eacute;s me qued&eacute; dormido.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Desde ese d&iacute;a, cada vez que veo a mi vecina me la imagino como vosotros os pod&eacute;is hacer una idea. Con esas tetas botando, con ese cuerpo movi&eacute;ndose en la cama con otro&hellip; Le meto yo ficha alguna vez aunque por ahora con poco &eacute;xito, supongo que no soy su tipo o que eso de follarse al vecino&hellip; Pero cada vez que recuerdo aquella noche&hellip; uffff.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>4 En los &uacute;ltimos d&iacute;as han sido varios los relatos que he subido. La verdad es que la aceptaci&oacute;n ha sido buena ya que varias personas me han escrito&hellip; y eso ayuda bastante a seguir escribiendo. Agradezco que invirt&aacute;is vuestros minutos en leer lo que escribo y que, encima, os guste. En esta ocasi&oacute;n antes [&hellip;]<\/p>\n","protected":false},"author":11742,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-17423","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-infidelidad"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/17423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/11742"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=17423"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/17423\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=17423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=17423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=17423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}