{"id":17468,"date":"2018-03-25T07:34:23","date_gmt":"2018-03-25T07:34:23","guid":{"rendered":""},"modified":"2018-03-25T07:34:23","modified_gmt":"2018-03-25T07:34:23","slug":"17468-cita-a-ciegas-segunda-parte","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/17468-cita-a-ciegas-segunda-parte\/","title":{"rendered":"Cita a ciegas (Segunda parte)"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"17468\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\"><\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p style=\"text-align:justify\"><span style=\"font-size:48px\">Y<\/span><span style=\"font-size:16px\">a deben haber sido alrededor de las tres de la ma&ntilde;ana, m&aacute;s menos, bebimos algo para aplacar la sed y yo no s&eacute; si se hab&iacute;a tomado un viagra o no, pero su pene nunca se baj&oacute; y yo, completamente agradecida por su excelente labor anterior, me acerqu&eacute;, lo bes&eacute; apasionadamente y comenc&eacute; a intentar darle su recompensa.<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Baj&eacute; con mis labios y mi lengua, lentamente por su cuello, por su pecho, mordisqueando sus tetillas mientras &eacute;l se encontraba relajadamente en la cama, con los brazos detr&aacute;s de su cabeza, mir&aacute;ndome con cara de caliente y como diciendo: Sigue m&aacute;s abajo&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Le devolv&iacute; la mirada, m&aacute;s caliente a&uacute;n y comenc&eacute; a besar sus caderas y a pasar mi lengua jugosa por entre sus muslos, haciendo c&iacute;rculos, chupando y mordisqueando y ve&iacute;a c&oacute;mo sus ojos estaban expectantes porque yo tomara pronto el objetivo principal. Pero quer&iacute;a &quot;vengarme&quot; un poco y hacerlo sufrir, not&eacute; c&oacute;mo su respiraci&oacute;n se agitaba y mov&iacute;a sus caderas y me dijo:<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">&#8211; &iexcl;Ay, Javi, no seas maldita!<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">La verdad es que la que no aguant&oacute; m&aacute;s fui yo y tom&eacute; su pene entre mis manos y lo acerqu&eacute; a mi boca, primero lo ol&iacute;&#8230; Mmmm qu&eacute; rico ol&iacute;a, un olor que qued&oacute; grabado en mi memoria olfativa y que a&uacute;n activa mis sentidos cuando lo recuerdo&#8230; De la punta de su pene brotaban ya unas gotitas de semen, yo levant&eacute; bien mi culito y agach&eacute; la cabeza y chup&eacute; esas gotitas de miel&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">&Eacute;l comenz&oacute; a quejarse, a respirar profundo y yo con mi leng&uuml;ita empec&eacute; a hacer c&iacute;rculos en la cabecita y &eacute;l solo intentaba meterlo en mi boca, la cual abr&iacute; y comenc&eacute; a meter su pene lentamente, primero hasta la mitad y luego met&iacute; lo que m&aacute;s pude y as&iacute;, con un sube y baja constante y con el roce leve de mis dientes y mis labios, sent&iacute; como aceler&aacute;bamos m&aacute;s el ritmo y yo me sent&iacute;a m&aacute;s caliente que antes as&iacute; que mientras con una mano agarraba su pene, sin dejar de chup&aacute;rselo, baj&eacute; mi otra mano y la llev&eacute; hasta mi vagina que otra vez estaba muy mojada y me met&iacute; un dedo lo m&aacute;s adentro que pude. Y as&iacute; estaba, con mi culito parado, chup&aacute;ndoselo bien rico y meti&eacute;ndome uno o dos dedos en mi conchita&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">-Mmmmm &iexcl;Sigue, Javiera, lo chupas tan rico! &iexcl;Sigue, chiquitita!<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Entonces hice algo que siempre quise hacer y no me atrev&iacute;a. Me met&iacute; su pene hasta la garganta y aguant&eacute; lo que m&aacute;s pude sin respirar, hasta que mi aliento se agotaba, ahhhhhh, casi me ahogaba, y vi como mi improvisado amante comenzaba a temblar, tom&eacute; aire y volv&iacute; a repetir esto varias veces, me lo met&iacute;a tan adentro de la boca que casi pod&iacute;a tocar sus huevos con mi cara de calentona&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Y comenc&eacute; a subir y a bajar con mi boca por su pene una y otra vez&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">&#8211; Ooooh &iexcl;Me vengo, Javiera, no pares que me vengoooo!<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Y en eso lanz&oacute; un gran chorro de semen que me dio de lleno en la cara, entonces lo tom&eacute; y me lo pas&eacute; por las tetas y me chup&eacute; los dedos hasta que ya no quedaba nada&#8230; y &eacute;l con cara de agradecido, as&iacute; que ya est&aacute;bamos a mano&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Pero yo hab&iacute;a quedado con ganas de m&aacute;s y &eacute;l tambi&eacute;n as&iacute; que nos comenzamos a besarnos como dos locos, nuestras lenguas pasaban por los labios, el cuello y el pecho del otro, respectivamente, como queriendo saborearnos enteros. Se fue otra vez a mis tetas y me las comi&oacute; tan rico como antes, ahora las apretaba y me tiraba los pezones hasta hacerme gemir&#8230; me quejaba tanto, llegaba a jadear&#8230; Se tir&oacute; sobre m&iacute; y me abri&oacute; las piernas, toc&oacute; y vagina y su mano se empap&oacute;, entonces, de una, me meti&oacute; tres dedos lo m&aacute;s que pudo dentro m&iacute;o. Yo casi llor&eacute; del dolor&#8230; Aaaay! Pero no tuvo piedad&#8230; No s&eacute; c&oacute;mo cab&iacute;an tres dedos dentro pero los mov&iacute;a tan rico que comenc&eacute; a pedirle m&aacute;s y m&aacute;s y le supliqu&eacute;:<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">-&iexcl;Andrees, m&eacute;temelo ya, m&eacute;temelo!<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">&Eacute;l se rio y me dijo:<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">&#8211; Eso era lo que quer&iacute;a escuchar, quer&iacute;a o&iacute;rte pedirme que te lo meta&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Y as&iacute; sin m&aacute;s se abalanz&oacute; sobre m&iacute; y de un solo empuj&oacute;n me meti&oacute; todo su pene, me lo meti&oacute; hasta el fondo&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">&#8211; Aaaaah, oooohhhh, &iexcl;Mierda, qu&eacute; rico! -gritaba yo&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Y comenz&oacute; un mete y saca con mucha fuerza, pod&iacute;a sentir como sus coquitos rebotaban en mi culo&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">&#8211; &iexcl;Sigueee, quiero maaas! &#8211; Le dec&iacute;a.<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">&#8211; &iquest;Apuesto a que ya no est&aacute;s tan asustada, no? &iquest;Quieres m&aacute;s, Javi?, &iquest;Quieres m&aacute;s?<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">-Siiii, quiero&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Y as&iacute; m&aacute;s y m&aacute;s duro me daba y yo casi pierdo el conocimiento, no s&eacute; a d&oacute;nde se fue mi cerebro, yo s&oacute;lo suplicaba por m&aacute;s y m&aacute;s cuando de pronto siento un escalofr&iacute;o recorrer mi espina dorsal desde la nuca hasta mis pies&#8230; Arque&eacute; mi espalda, apret&eacute; su espalda y lo aferr&eacute; contra m&iacute; y me corr&iacute;&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">mmmmm&#8230; me corr&iacute; como dos veces seguidas y &eacute;l se vino tambi&eacute;n, se vino dentro m&iacute;o hasta descargar hasta la &uacute;ltima gota de semen que ten&iacute;a&#8230; &iexcl;Qu&eacute; placer recordarlo!<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">De a poco fuimos volviendo a la tierra aunque ambos con todos los sentidos embrutecidos de placer&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Esa noche lo hicimos como tres veces m&aacute;s y cada vez era igual o mejor que la anterior. Nos dieron las 12 p.m. y ah&iacute; entend&iacute; por qu&eacute; hab&iacute;a dicho que necesitaba toda la noche&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Nos fuimos del lugar, nos despedimos con un beso y tomamos rumbos diferentes.<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Yo llegu&eacute; a mi casa sinti&eacute;ndome la mujer m&aacute;s feliz del mundo pero la m&aacute;s puta de todas tambi&eacute;n&#8230;<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">S&eacute; que mis relatos est&aacute;n siendo breves, pero estoy partiendo en esto. Espero ir mejorando poco a poco, por eso recibo sus comentarios ac&aacute; o si gustan, me escriben a mi correo. javieramor27@gmail.com<\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\">Besos para todos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Ya deben haber sido alrededor de las tres de la ma&ntilde;ana, m&aacute;s menos, bebimos algo para aplacar la sed y yo no s&eacute; si se hab&iacute;a tomado un viagra o no, pero su pene nunca se baj&oacute; y yo, completamente agradecida por su excelente labor anterior, me acerqu&eacute;, lo bes&eacute; apasionadamente y comenc&eacute; a intentar [&hellip;]<\/p>\n","protected":false},"author":1661,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-17468","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-hetero"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/17468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/1661"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=17468"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/17468\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=17468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=17468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=17468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}