{"id":17765,"date":"2018-04-27T06:24:58","date_gmt":"2018-04-27T06:24:58","guid":{"rendered":""},"modified":"2018-04-27T06:24:58","modified_gmt":"2018-04-27T06:24:58","slug":"17765-jovencitas-estudiantes-y-marchosas","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/17765-jovencitas-estudiantes-y-marchosas\/","title":{"rendered":"J\u00f3venes estudiantes y marchosas"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"17765\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\"><\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 7<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p style=\"text-align:justify\"><span style=\"font-size:48px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">I<\/span><\/span><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">ba yo en b&uacute;squeda de sexo porque el sol ya est&aacute; aqu&iacute; y que quer&eacute;is que os diga&#8230; el calor, la poca ropa que empezamos a llevar, la primavera&hellip;y o que s&eacute;&hellip;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Como no ten&iacute;a planes y uno ya tiene una edad como para intentar ligar en condiciones, me propuse ir a un club donde a veces hay parejas que buscan un hombre para pasar un rato con ellos. Un club swinger de mi ciudad, pero al llegar all&iacute;, era el d&iacute;a de descanso y estaba cerrado. Mi gozo en un pozo!!!<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Volv&iacute; a montar en mi coche y desilusionado volv&iacute;a a mi rutina habitual cuando&hellip;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&hellip;Un par de chicas de unos 20-22 a&ntilde;os pasaron por el paso de peatones y mientras yo las miraba embobado, ellas re&iacute;an y charlaban de lo suyo. Faldas cortas y camisetas con unos escotes dignos de esa edad y con esas risas, unos movimientos que hac&iacute;an temblar sus camisetas y&hellip; mi polla, jajaja.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Sin querer, os lo prometo, toqu&eacute; el claxon de mi coche y del ruido ellas y yo mismo nos asustamos y levantando la mano les ped&iacute; perd&oacute;n&hellip; que bochorno!!!<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Al levantar la mano ellas se acercaron (cre&iacute;an que las llamaba) y vinieron hacia mi pregunt&aacute;ndome si quer&iacute;a algo.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Pens&eacute; que era el d&iacute;a apropiado y todo se pon&iacute;a de cara porque llevaban en la mano unos numeritos de esos sorteos que hacen para viajes de estudios, ya sab&eacute;is. Les ped&iacute; de nuevo disculpas y&hellip;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Perdonadme&hellip; os miraba al pasar y sin querer&#8230;&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Que susto nos ha dado, jajaja&hellip; Pero&#8230; &iquest;qu&eacute; quer&iacute;a?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Por favor, no me hables de usted&hellip; No quer&iacute;a nada&hellip; bueno&hellip; si, oye, &iquest;vend&eacute;is n&uacute;meros? &iquest;Para qu&eacute; son?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Nos vamos a Italia al acabar la carrera el a&ntilde;o que viene y estamos sorteando un patinete el&eacute;ctrico&hellip; &iquest;le interesa? &iquest;Nos compra alguno? Jajajaja&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Puede que s&iacute;&rdquo;, les dije&hellip; &ldquo;Podr&iacute;a incluso compraros todo el bloque de n&uacute;meros&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;&iquest;&iquest;&iquest;C&oacute;mo???&rdquo; Dijo sorprendida la m&aacute;s alta de ellas. &ldquo;&iquest;De verdad har&iacute;as esto?&#8230; vale mucha pasta!!!&rdquo; dijo en un tono poco elegante, m&aacute;s bien un poco barriobajero.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Laura y Ana no eran dos estudiantes de esas pijitas con dinero, no, para nada&hellip; Eran m&aacute;s bien chicas con pinta de alcohol, chulillas&hellip; guerreras, vamos. Cuando vi por donde iban, arriesgu&eacute; y les propuse que les compraba todo ese bloc de n&uacute;meros si me propon&iacute;an a cambio algo que me convenciera. Me vend&iacute; como un tipo con pasta (el coche que llevaba me ayud&oacute;, un Mercedes de mi Empresa jeje) y que ten&iacute;a ganas de pasarlo bien esa tarde.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Se apartaron de la ventanilla del coche y empezaron a hablar, a medio discutir entre ellas y a elevar la voz con lo que yo o&iacute;a que la m&aacute;s alta, Ana, le dec&iacute;a a Laura que con un par de chorradas pod&iacute;a vender los n&uacute;meros y tener la tarde libre&hellip; &ldquo;Total que puede pedirnos, que se la toquemos jajaja???&rdquo; &ldquo;Est&aacute;s loca Ana&hellip; y si es un mal t&iacute;o y nos hace una putada?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Mirad chicas (interrump&iacute;)&hellip; Soy un buen tipo no teng&aacute;is miedo y solo quiero pasar un buen rato con dos jovencitas como vosotras&hellip; Vosotras pon&eacute;is los l&iacute;mites y seg&uacute;n que me dej&eacute;is hacer, os compro m&aacute;s o menos n&uacute;meros&hellip; Vamos ser&aacute; divertido, subid al coche&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Un par de minutos m&aacute;s discutiendo y finalmente subieron en los asientos traseros. Antes de cerrar la puerta, Laura, la m&aacute;s desconfiada, pregunt&oacute; que donde ir&iacute;amos con el coche, a lo que yo respond&iacute; que si lo prefer&iacute;an, aparcaba el coche y nos &iacute;bamos a alg&uacute;n bar de la zona.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Lo prefiero&rdquo; dijo Laura, a lo que yo les dije &ldquo;Esperadme aqu&iacute; que vuelvo en dos minutos&rdquo; y me fui a un parquing cercano a dejar el coche.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Volv&iacute; al sitio y les propuse ir a un bar que hab&iacute;a en esa misma calle. Entramos, nos sentamos y pedimos bebidas.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Laura pregunt&oacute; &ldquo;&iquest;Qu&eacute; nos dar&aacute;s por los n&uacute;meros y que quieres a cambio?<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;No vayas tan r&aacute;pido, jajaja&rdquo; le dije. &iquest;Cu&aacute;nto valen todos los que llev&aacute;is?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Llevamos 40 n&uacute;mero y a 5 &euro; son 200&euro;&rdquo; dijo Ana. &ldquo;&iquest;te los quedaras todos?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;La verdad es que no quer&iacute;a gastarme tanto hoy jajaja, pero, un trato es un trato&#8230; Os puedo dar 200&euro; y me dais la mitad de los n&uacute;meros, con lo que si acab&aacute;is vendi&eacute;ndolos todos, sacareis en total&hellip; a ver&hellip; 300&euro;, &iquest;verdad?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;&iquest;Podemos hablar a solas Ana y yo?<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Por supuesto&rdquo; les dije&hellip; &ldquo;Voy a los lavabos y a la vuelta me dec&iacute;s que hacemos&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Me levant&eacute; y las dej&eacute; hablando mientras iba al ba&ntilde;o. A la vuelta estaban las dos riendo con lo que pens&eacute; que era una buena se&ntilde;al.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;&iquest;Y qu&eacute;?&#8230; &iquest;hab&eacute;is llegado a un acuerdo las dos?<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Nos tienes que decir que tenemos que hacer&rdquo; dijo Ana&hellip; Estamos preparadas&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Bien, haremos un juego. Os ir&eacute; pidiendo cosas y cada vez que las cumpl&aacute;is, os pagar&eacute; 10&euro; y me dar&eacute;is 1 numerito, &iquest;ok?&#8230; Os pedir&eacute; 10 cositas a cada una y as&iacute; llegaremos a esos 200&euro; y yo tendr&eacute; los 20 n&uacute;meros. Si me animo y depende de donde llegu&eacute;is igual seguimos. Para que no haya dudas, ser&aacute;n cosas atrevidas, excitantes y algunos juegos relacionados con sexo&hellip; &iquest;Acept&aacute;is?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Si pero con unos l&iacute;mites&rdquo; dijo Laura &ldquo;Imagino que querr&aacute;s pedirnos cosas atrevidas pero no voy a hacer nada contigo, ok?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Eso (recalco Ana), no nos puedes pedir que hagamos nada de sexo con nadie&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Nooo tranquilas&#8230; Empecemos y vemos como avanzamos, ser&aacute; divertido ya ver&eacute;is&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Ten&iacute;a que empezar por cosas suaves para que no se asustaran, sobre todo Laura, la m&aacute;s desconfiada.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Ana&hellip; empezar&aacute;s t&uacute;. Ve al ba&ntilde;o pero moviendo tu culete bien sexy para que te vean esos chicos que hay all&iacute; sentados&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Ana y Laura se rieron juntas con una mezcla de diversi&oacute;n y de nerviosismo. Ana se levant&oacute; y fue al ba&ntilde;o moviendo sus caderas hasta que uno de esos chicos le silb&oacute;, jajaja.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Al volver dijo &ldquo;que verg&uuml;enza&rdquo;&hellip; Le di los 10&euro; y le dije a Laura que me dijera de qu&eacute; color llevaba su ropa interior &ldquo;Las dos piezas blancas&#8230;&rdquo; Le di sus 10&euro; y dijo, &ldquo;&iquest;Ya est&aacute;? &iquest;Solo eso?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;S&iacute;, toma 10 &euro; para ti y otro numerito para mi&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Eso no vale!!!&rdquo; se quej&oacute; Ana y de seguido nos re&iacute;mos los tres &ldquo;jajajaja&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">As&iacute; pasamos unas cuantas pruebas tontas hasta que llevaba gastados 60&euro; pero ellas se estaban animando.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Vamos a otro bar que nos tienen ya muy vistos y esos chicos al final pensar&aacute;n que quer&eacute;is algo con ellos jajaja&rdquo;.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Por mi si ese rubio quiere algo que me lo diga&rdquo; dijo Ana.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Pues antes de irnos vas a hacer la &uacute;ltima prueba con &eacute;l&rdquo;, le dije a Ana. &ldquo;Ve al ba&ntilde;o, qu&iacute;tate las braguitas y se las regalas&hellip; Envu&eacute;lvelas con papel higi&eacute;nico, mucho papel y dile que no lo abra hasta que hayamos salido del bar. Nos iremos corriendo hasta el bar que hay en la otra calle para que no nos vean&#8230; &iquest;ok?&#8230; Si lo haces te compro dos numeritos, jajaja&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Ana con una carcajada se levant&oacute;, fue al ba&ntilde;o y al poco rato sali&oacute;, nosotros est&aacute;bamos pagando y al vernos como encar&aacute;bamos la puerta, fue y le di&oacute; al chico ese papel con sus bragas y le susurr&oacute; algo al o&iacute;do. Salimos corriendo entre risas.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Que fuerte t&iacute;a&hellip; le acabo de dar mis bragas a un t&iacute;o bueno que no conozco de nada y ahora voy sin nada, jajaja&#8230; si me lo encuentro otro d&iacute;a que le digo, jajaja&hellip; que fuerte jajaja&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Entramos en otro bar y les dije que quiz&aacute;s era mejor seguir en un sitio m&aacute;s discreto. &ldquo;&iquest;Te f&iacute;as de mi si vamos a mi coche ahora Laura?&#8230; all&iacute; podemos hacer mejor las &uacute;ltimas pruebas&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Y aceptaron. Fuimos al parquing y entraron en la parte trasera del coche y yo en el asiento de copiloto. Lo hab&iacute;amos pasado bien y estaban muy relajadas y con ganas de pasarlo mejor a&uacute;n. Las pocas escenas rematadas por la &uacute;ltima, nos hab&iacute;an subido la excitaci&oacute;n a todos y yo quer&iacute;a m&aacute;s<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Mirad&#8230; Llevo gastados 80&euro; y la verdad es que no me he llevado nada. Me gustar&iacute;a ser m&aacute;s p&iacute;caro y poder pediros cosas m&aacute;s atrevidas. Cuando quer&aacute;is lo dejamos y ponemos fin&hellip; Ahora&#8230; 10&euro; a cada una si os quit&aacute;is sujetador y tu Laura sujetador y las braguitas&rdquo;.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Se miraron, sonrieron y se quitaron lo pedido. Las ve&iacute;a muy animadas as&iacute; que me atrev&iacute; a la siguiente prueba<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Ahora quiero ver lo que escond&iacute;an estas prendas&hellip; Ten&eacute;is que ense&ntilde;arme pechos, culete y co&ntilde;ito&rdquo;.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Como te pasas t&iacute;o&rdquo; se quej&oacute; Laura.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Mira yo estoy que no puedo m&aacute;s Laura&hellip; que me pida lo que quiera que quiero vender todo el paquete de n&uacute;meros, jajaja&rdquo; y dicho esto se quit&oacute; la falda y levant&oacute; su camiseta para mostrarme sus pechos y bufff que pechos ten&iacute;a, grandes, preciosos. Se baj&oacute; la camiseta y se gir&oacute; para mostrarme su culo al que le di un leve cachete splash. &ldquo;Eh, eh&#8230; eso te va a salir m&aacute;s caro, eh? Jajajaja&rdquo;.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Ahora te toca a ti, Laura&rdquo;.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Laura se quit&oacute; tambi&eacute;n su falda, se levant&oacute; su camiseta y de la misma manera me ense&ntilde;&oacute; sus pechos, m&aacute;s peque&ntilde;os pero m&aacute;s erguidos que los de Ana. Iba totalmente depilada y al girarse vi un culo de modelo, jajaja&hellip; bufff. &ldquo;&iquest;no me das cachete a m&iacute;, t&iacute;o? jajaja&rdquo;.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Despu&eacute;s de decirme esto y propiciado por la posici&oacute;n que ten&iacute;a, se gir&oacute; hacia Ana d&aacute;ndole un morreo que no esperaba. Ya no hab&iacute;a marcha atr&aacute;s. Hab&iacute;a llegado donde quer&iacute;a. Empezaron a besarse con gemidos leves y a tocarse entre ellas por todos los lados. Era un espect&aacute;culo!!!<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Se animaba la cosa y mientras se besaban le di dos cachetazos m&aacute;s fuertes y sonoros mientras que a la vez y cuando terminaba con el segundo, metiendo mi mano en su mojado co&ntilde;o le dije &ldquo;como estoy toc&aacute;ndote y viendo lo mojada que estas te compro uno nuevo pero quiero estar 10 segundos as&iacute;&hellip; Est&aacute;s excitada Laurita y me gusta que lo est&eacute;s. Que rico co&ntilde;o tienes Laura&hellip; delicioso!!!&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Laura empez&oacute; con leves gimoteos y sigui&oacute; con sus besos y toques con Ana.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Las dej&eacute; hacer un rato y me puse en el sitio de pilotaje del coche. Les dije que nos &iacute;bamos a un lugar m&aacute;s seguro pero que siguieran durante el camino&hellip; que les daba 20&euro; m&aacute;s si segu&iacute;an.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Sin decir nada arranqu&eacute; el coche y salimos mientras por el retrovisor ve&iacute;a como se devoraban. Ana empez&oacute; a tocar el co&ntilde;o a Laura hasta que se corri&oacute; como una loca mientras yo iba conduciendo y mirando. Fuimos a una monta&ntilde;a cerca de la ciudad y aparqu&eacute; en un sitio lejano y solitario. Hab&iacute;an parado y estaban las dos relajad&iacute;simas (creo que Ana tambi&eacute;n se corri&oacute;).<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Que pasada&rdquo; dijo Laura &ldquo;Nunca hab&iacute;a estado tan perra como hoy&hellip; bufff&hellip; lo del bar me ha puesto a mil y lo del parquing&hellip; bufff, &iquest;Verdad Ana?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Si, si&hellip; una pasada tia&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Estaban a punto de caramelo y muy excitadas las dos!!!<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;S&eacute; que ten&eacute;is ganas de m&aacute;s, estoy seguro y que necesit&aacute;is algo para poneros dentro de vuestros mojaditos co&ntilde;etes&hellip; &iquest;o no? Voy a venir aqu&iacute; con vosotras, me sentar&eacute; en medio y la que quiera puede subirse y clavarse mi polla como desee. Con eso os compro lo prometido&hellip; &iquest;Qui&eacute;n empezar&aacute;?&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Baj&eacute; del coche, abr&iacute; la puerta rasera y entr&eacute;. Me puse entre las dos y me baj&eacute; los pantalones qued&aacute;ndose mi polla hinchada, erecta y mirando al techo.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Ana se subi&oacute; primero y me dijo &ldquo;no te corras dentro que no tomo nada&rdquo; y encar&oacute; la punta en su mojad&iacute;simo co&ntilde;o y mientras se sentaba y hac&iacute;a que entrara lentamente empec&eacute; a sobarle sus duros pechos y a pellizcarle los dur&iacute;simos pezones por encima de su camiseta. Empez&oacute; a follarme como una loca mientras dec&iacute;a con palabras entrecortadas&hellip; &ldquo;Ufff, ohhh no te puedes correeerrr prometemelo vamos, Diosss Laura que pollaca tiene este tioo voy a corrermeee ahhhhggg me corrooo&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Se corri&oacute; y se tumb&oacute; encima de m&iacute; y le dije que saliera o me corr&iacute;a.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Laura se subi&oacute; al instante y le dije: &ldquo;No podr&eacute; resistir Laura&hellip; estoy a punto de correrme cielo&rdquo; y respondi&oacute; &ldquo;Esa mojigata de Ana no toma nada pero yo si&hellip; puedes correrte sin miedo t&iacute;o&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Y se puso encima, apunt&oacute; con mi polla su entrada y se la meti&oacute; de un solo golpe empezando a moverse como si le fuera la vida en ello&hellip; &ldquo;Uauuuu que ganas de polla ten&iacute;a&hellip; este cerdo ha conseguido follarnos a las dos con la tonter&iacute;a de los numeritooosss y uuiiii que polla tienes tio&hellip; uuuauuu buffff Dios m&iacute;o que folladaaaa ahhhh no tardo ni medio segundo en correrrmeeee ehhh ahhgggg diooosss miooo&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">&ldquo;Me corro Laura&hellip; toma mi leche para ti&hellip; que bien follas zorraa ahhhggg&rdquo;<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Y nos corrimos los dos y al pasar un rato nos quedamos medio dormidos los tres. Volvimos al mundo y saldamos la deuda, me quede con los numerito y las volv&iacute; al sem&aacute;foro donde nos hab&iacute;amos conocido tres horas antes.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Me desped&iacute; de ellas pero me qued&eacute; las braguitas de Laura como recuerdo.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">No me toc&oacute; ese patinete, aunque me lo pas&eacute; genial con Ana y Laura.<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Espero os haya gustado mi relato<\/span><\/span><\/p>\n<p style=\"text-align:justify\"><span style=\"font-size:16px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Escribid a peterpan69es@yahoo.es.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 7<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Iba yo en b&uacute;squeda de sexo porque el sol ya est&aacute; aqu&iacute; y que quer&eacute;is que os diga&#8230; el calor, la poca ropa que empezamos a llevar, la primavera&hellip;y o que s&eacute;&hellip; Como no ten&iacute;a planes y uno ya tiene una edad como para intentar ligar en condiciones, me propuse ir a un club donde [&hellip;]<\/p>\n","protected":false},"author":6972,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-17765","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-hetero"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/17765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/6972"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=17765"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/17765\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=17765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=17765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=17765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}