{"id":18038,"date":"2018-06-05T07:34:00","date_gmt":"2018-06-05T07:34:00","guid":{"rendered":""},"modified":"2018-06-05T07:34:00","modified_gmt":"2018-06-05T07:34:00","slug":"18038-cita-con-escritora-de-cuentorelatos-2-y-fin","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/18038-cita-con-escritora-de-cuentorelatos-2-y-fin\/","title":{"rendered":"Cita con una escritora de relatos (Parte 2- Final)"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"18038\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\"><\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Hola de nuevo.<\/p>\n<p>En este relato os cuento la continuaci&oacute;n de la historia que viv&iacute; con una escritora de relatos para que ve&aacute;is que los milagros existen!!!<\/p>\n<p>En el anterior relato contaba como contact&eacute; y conoc&iacute; a Nuria adem&aacute;s de nuestra primera toma de contacto y aventura en ese Starbucks.<\/p>\n<p>Tambi&eacute;n comentaba que ella y yo hab&iacute;amos acordado quedar de nuevo para planear una nueva aventura, as&iacute; que&hellip; nos citamos de nuevo en el mismo lugar que la primera vez y delante de nuestro rico caf&eacute; empezamos a hablar.<\/p>\n<p>Le propuse abrir una cuenta en una p&aacute;gina de contactos y que pod&iacute;amos buscar juntos alguna aventura con lo que fuera saliendo.<\/p>\n<p>Ella me dijo que aceptaba y que pod&iacute;amos ir a su casa que estaba sola esos d&iacute;as, que ten&iacute;a ordenador con c&aacute;mara y que pod&iacute;amos empezar ese mismo d&iacute;a.<\/p>\n<p>Estuvimos recordando nuestra primera aventura y me confes&oacute; que esa vez no tendr&iacute;a que ir al wc para quitarse su tanga porque iba sin nada<\/p>\n<p>&ldquo;Jajaja&#8230; te va la marcha, &iquest;eh?&#8230; jajaja&rdquo; le dije sonriendo<\/p>\n<p>&ldquo;Esperaba una nueva propuesta indecente, jajaja&rdquo; me dijo ella<\/p>\n<p>&ldquo;&iquest;Y qui&eacute;n ha dicho que no pasar&aacute; nada de aqu&iacute; a tu casa?&rdquo; la amenace con una sonrisa ruidosa.<\/p>\n<p>Nos fuimos del Starbucks. Para ir a su casa, deb&iacute;amos coger el autob&uacute;s. El trayecto era de unos 20 minutos y r&aacute;pidamente se me ocurri&oacute; que hacer en ese bus, al ver que estaba bastante lleno. Nos sentamos en unos asientos traseros y empezamos a hablar de lo que har&iacute;amos y a caldearnos los dos&hellip; yo estaba con mi polla a punto de reventar de pensar que entre otras cosas que se nos hab&iacute;an ocurrido, pod&iacute;amos follar mientras nos ve&iacute;an por Skype, por ejemplo. Cuando llev&aacute;bamos 2 paradas hab&iacute;a una se&ntilde;ora mayor que hab&iacute;a subido al bus y que no pod&iacute;a sentarse al estar todos los asientos ocupados.<\/p>\n<p>&ldquo;Dile que se siente esa pobre mujer, Nuria&rdquo; &ldquo;OK&rdquo; dijo mientras hac&iacute;a la intenci&oacute;n de levantarse para ello&hellip; &rdquo;no te levantes, si&eacute;ntate encima m&iacute;o y que ella se siente en el asiento ni&ntilde;a&rdquo; le dije, &ldquo;&hellip;al sentarte encima de m&iacute;, aparta tu falda y si&eacute;ntate encima de mi polla cielo, as&iacute; no te caer&aacute;s jajajaja&rdquo;<\/p>\n<p>Dicho y hecho&#8230; &ldquo;Se&ntilde;ora, si&eacute;ntese aqu&iacute; por favor&rdquo; dijo Nuria apart&aacute;ndose del asiento y sent&aacute;ndose encima de mis piernas, habiendo apartado y preparado bien su falda, despacio mientras yo con mi mano hab&iacute;a desabrochado mi pantal&oacute;n y apuntaba con la punta de mi polla a la entrada de su co&ntilde;o.<\/p>\n<p>&ldquo;Muchas gracias parejita&rdquo; dijo la se&ntilde;ora mientras Nuria se sent&oacute; de un solo baj&oacute;n clav&aacute;ndosela toda entera.<\/p>\n<p>&ldquo;Uuhhhff&rdquo; exclam&oacute; Nuria al notarla hasta sus entra&ntilde;as &ldquo;que sacudidas da este autob&uacute;s se&ntilde;ora, buuffff por Dios&rdquo;<\/p>\n<p>Le ped&iacute; que no se moviera mucho que no hac&iacute;a falta hacer un espect&aacute;culo, pero Nuria, sin mirarme ni hacerme mucho caso, se mov&iacute;a lo que pod&iacute;a sin dejar entrever nada de lo que pasaba. Estuvimos as&iacute; hasta que faltaban un par de paradas y le pedimos a la se&ntilde;ora que nos dejara salir. Nos acomodamos como pudimos, sobre todo yo que deb&iacute;a guardar mi hombr&iacute;a en mi pantal&oacute;n y bajamos del bus.<\/p>\n<p>&ldquo;Jajajaja&hellip; que pasada Santi. Casi me corro ah&iacute; arriba&hellip; me encant&oacute; tu idea, eres la bomba, jajaja&rdquo; &ldquo;T&uacute; tambi&eacute;n eres una pasada de t&iacute;a, cielo<\/p>\n<p>Y llegamos a su casa, nos acomodamos y abri&oacute; su PC y entramos en una p&aacute;gina de contactos muy conocida para buscar chicos con los que interactuar o intentarlo.<\/p>\n<p>Le propuse buscar gente con Skipe y si le apetec&iacute;a sentarse de nuevo en mi polla pero frente al ordenador y que vieran como me follaba de espaldas a m&iacute; y mir&aacute;ndolos a ellos&#8230; &ldquo;&iquest;y si me reconocen? &iquest;y si hay alguien que me conoce o me&hellip;?&rdquo; &ldquo;&iquest;no tienes una m&aacute;scara? &iquest;Algo con lo que tapar tu cara para que no se vea qui&eacute;n eres?&rdquo; &ldquo;Si&hellip; es verdad, tengo una m&aacute;scara veneciana que me tapar&iacute;a toda la cara&hellip;eres grande Santi!!!&rdquo;<\/p>\n<p>Fue a buscar su m&aacute;scara y efectivamente tapaba todo su rostro&#8230; &ldquo;Salvados&rdquo; le dije.<\/p>\n<p>Nos conectamos a una web y empezamos a buscar chicos que nos parecieran adecuados&#8230; Nuestra oferta era para hacer cosas delante de ellos.<\/p>\n<p>Finalmente encontramos un hombre mayor, de unos 60 a&ntilde;os que a N&uacute;ria le pareci&oacute; bien ya que ten&iacute;a imagen de seriedad y morbo a la vez y nos mostraba la imagen suya para poder ver como se masturbaba mientras nos miraba, as&iacute; que empezamos.<\/p>\n<p>N&uacute;ria hizo un striptease delante de la c&aacute;mara con su m&aacute;scara puesta y al estar desnuda le pregunt&oacute; a Mario (as&iacute; se llamaba ese hombre) si le gustaba lo que ve&iacute;a&hellip;<\/p>\n<p>&ldquo;Eres muy linda chica&hellip; tienes un cuerpo de mujer muy bonito y solo de verte ya me pongo a mil chica&hellip; &iquest;Por qu&eacute; no te tocas las tetas mientras miras como me toco?&#8230; Mmmm est&aacute;s de muerte ni&ntilde;a&rdquo; le dec&iacute;a Mario<\/p>\n<p>Yo estaba sentado, desnudo tambi&eacute;n y acariciando mi hombr&iacute;a que ya estaba muy dura. N&uacute;ria se agacho para hacerme una mamada y empez&oacute; a chupar mis huevos, mi polla mientras se tocaba el co&ntilde;o con una de sus manos y se pon&iacute;a de espaldas a la c&aacute;mara, dando una imagen de su culo que Mario agradeci&oacute;&hellip; Mientras esto pasaba, Mario segu&iacute;a animando desde la distancia&hellip; &ldquo;Mmmm por Dios que culo chica&hellip; lo que dar&iacute;a por poder toc&aacute;rtelo&hellip; mmmm&hellip; chica est&aacute;s para comerte enterita&hellip; debe chuparla bien &iquest;verdad Santi?&rdquo; me preguntaba &ldquo;Ni te lo imaginas Mario&hellip; estoy ya apunto de correrme&hellip; &iquest;Qu&eacute; quieres que haga con ella?&rdquo;<\/p>\n<p>&ldquo;F&oacute;llatela para m&iacute; que quiero ver como se corre esa chica mala&rdquo;, me dijo de nuevo.<\/p>\n<p>Levant&eacute; a Nuria, la puse de frente a la c&aacute;mara. Yo estaba sentado en una silla, frente al ordenador, ella miraba hacia esa c&aacute;mara. La hice sentar encima de m&iacute; y se sent&oacute; clav&aacute;ndose mi polla dentro de su mojad&iacute;simo co&ntilde;o empezando a cabalgarme.<\/p>\n<p>&ldquo;T&oacute;cate las tetas para mi cielo, mira como me tienes de mirarte ni&ntilde;a, ohhhh&rdquo; le dec&iacute;a Mario a Nuria.<\/p>\n<p>Nuria aument&oacute; su ritmo y sus gemidos indic&aacute;ndome que estaba a puntito de correrse<\/p>\n<p>&ldquo;Ahhh que buenooo&hellip; como me gusta esa polla&hellip; &iquest;te gustar&iacute;a que fuera la tuya Mariooo uuuhhhh buffff como me gusta sentir tu polla dentroooo Santii ohhh aaaggghhh me corro chicoosss oooohhh ahhhh&rdquo;.<\/p>\n<p>No nos dimos cuenta pero Mario ya se hab&iacute;a corrido tambi&eacute;n ante tal espect&aacute;culo<\/p>\n<p>&ldquo;Menuda corrida chicos&rdquo; nos dijo &ldquo;Cu&aacute;ndo quer&aacute;is repetir quedamos ya que ha sido fenomenal&hellip; gracias de nuevo, voy a limpiarme&#8230; Hasta otra!!!&rdquo; Y desconect&oacute;, plufff.<\/p>\n<p>&ldquo;Ha sido bestial Santi&rdquo; me dijo Nuria<\/p>\n<p>&ldquo;&iquest;Has notado que no me corr&iacute; verdad?&rdquo; Le pregunte&hellip; &ldquo;Ahora me toca a m&iacute;, no me puedes dejar as&iacute;, jajaja&rdquo;.<\/p>\n<p>Nos levantamos de la silla, la llev&eacute; a una mesa que ten&iacute;a cerca, la puse apoyada en la mesa, de espaldas a m&iacute; y le pregunt&eacute; si me hab&iacute;a ganado su culo &ldquo;quiero correrme en tu espectacular culo, &iquest;me dejas?&rdquo;. &ldquo;Te lo has merecido pero despacito que con la polla que tienes me vas a partir, jajaja&rdquo;<\/p>\n<p>La inclin&eacute; y empec&eacute; follando de nuevo su co&ntilde;o. Empec&eacute; con un bombeo r&aacute;pido mientras se o&iacute;an sus gemidos mezclados con el choque de mi barriga con sus nalgotas, cada vez m&aacute;s r&aacute;pido. Con mi pulgar, le iba dilatando la entrada de su culete&hellip; Mientras eso pasaba, le di un par de azotes que resonaron en la sala&ldquo;&hellip; Plash, plash&#8230; esto es para ti ni&ntilde;a mala&hellip; &iquest;te gusta c&oacute;mo te doy cielo?&rdquo;<\/p>\n<p>&ldquo;Ahhh ohhh vas a hacer que me corra de nuevo Santi&#8230; dame un par de azotes m&aacute;s y me corroooo&hellip; Plashh!!! Plashh!!!&hellip; Ohhhh Dios que bien follaaass ahhggg buffff me corrooo&rdquo;.<\/p>\n<p>Mientras se corr&iacute;a de nuevo, saqu&eacute; mi polla, la puse en la entrada de su culo dilatado ya por mis juegos y se la ensart&eacute; toda de un golpe&hellip;<\/p>\n<p>&ldquo;Ahhhggg Diosss sigo corriendommeeehe Santiiihhh ahhhggggg&rdquo;<\/p>\n<p>&ldquo;Tomaaahhh Nuria. Toma mi leche para ti&#8230; que culazo tienes mi amooorrr oooohhhh&rdquo;<\/p>\n<p>Nos quedamos exhaustos despu&eacute;s de esos orgasmos. Saqu&eacute; mi polla de su ano y nos tumbamos en el sof&aacute; a descansar.<\/p>\n<p>&ldquo;Ha sido espectacular Santi&rdquo;<\/p>\n<p>Y as&iacute; termin&oacute; la sesi&oacute;n&#8230; Hubo m&aacute;s encuentros aunque no dur&oacute; demasiado ya que Nuria dej&oacute; a su novio y encontr&oacute; una nueva pareja que la saciaba sexualmente. Eso s&iacute;, me confes&oacute; que conmigo se hab&iacute;a sentido una autentica viciosa y que no olvidar&iacute;a nunca nuestras aventuras.<\/p>\n<p>Con eso me conform&eacute;.<\/p>\n<p>Espero os haya gustado mi relato<\/p>\n<p>Escribid a peterpan69es@yahoo.es<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Hola de nuevo. En este relato os cuento la continuaci&oacute;n de la historia que viv&iacute; con una escritora de relatos para que ve&aacute;is que los milagros existen!!! En el anterior relato contaba como contact&eacute; y conoc&iacute; a Nuria adem&aacute;s de nuestra primera toma de contacto y aventura en ese Starbucks. Tambi&eacute;n comentaba que ella y [&hellip;]<\/p>\n","protected":false},"author":6972,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-18038","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-hetero"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/18038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/6972"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=18038"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/18038\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=18038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=18038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=18038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}