{"id":18510,"date":"2018-08-07T22:00:00","date_gmt":"2018-08-07T22:00:00","guid":{"rendered":""},"modified":"2018-08-07T22:00:00","modified_gmt":"2018-08-07T22:00:00","slug":"4135-jose-la-tia-de-mi-esposa","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/4135-jose-la-tia-de-mi-esposa\/","title":{"rendered":"Una mujer apasionada con sexualidad reprimida"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"18510\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">2<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Cuando conoc&iacute; a la familia de mi esposa, hace tres a&ntilde;os cuando ten&iacute;a 25, me presento a su t&iacute;a Mar&iacute;a Jos&eacute;, una mujer de 33 a&ntilde;os que 5 a&ntilde;os atr&aacute;s se hab&iacute;a casado con un tipo que seg&uacute;n me contaron era todo un pat&aacute;n que la golpeaba y aparte de darle una vida econ&oacute;micamente miserable mi esposa me platic&oacute; que no ten&iacute;an intimidad, y dos a&ntilde;os despu&eacute;s se separ&oacute; para al fin divorciarse, algo que la traum&oacute; e incluso el contacto con cualquier hombre la aterraba, este hecho afecto a toda la familia pues Mar&iacute;a Jos&eacute; siempre se hab&iacute;a distinguido por su car&aacute;cter alegre, bailadora, dicharachera y abierta, pero todo eso desapareci&oacute; al casarse.<\/p>\n<p>Ese d&iacute;a que la conoc&iacute; me conto mi esposa, entonces mi novia, que apenas estaba saliendo de su trauma, pues adem&aacute;s de haber tomado un psicoan&aacute;lisis se hab&iacute;a entregado en cuerpo y alma a su profesi&oacute;n de maestra en una escuela p&uacute;blica mientras platicaba con la familia me pude percatar que a&uacute;n ten&iacute;a la mirada triste y aunque participaba de las bromas se percib&iacute;a oscuridad en su car&aacute;cter.<\/p>\n<p>Mar&iacute;a Jos&eacute; es una mujer de mediana estatura, busto peque&ntilde;o, cintura muy estrecha, caderona aunque con poca pompa y unas piernas muy torneaditas gracias a los aerobics, debo aclarar que ella no es una mujer guapa, vest&iacute;a con ropa holgada o deportiva.<\/p>\n<p>Cierto d&iacute;a casi un a&ntilde;o despu&eacute;s de casarnos y dos de conocerla ella adquiri&oacute; un equipo de c&oacute;mputo pero como de computadoras sab&iacute;a lo que yo de f&iacute;sica nuclear me pidi&oacute; mi ayuda para instalar la m&aacute;quina y darle un curso de computaci&oacute;n, pues soy programador, as&iacute; que acud&iacute; a su departamento donde ella viv&iacute;a con una amiga, iba solo pues mi esposa estaba de viaje con mis papas que la invitaron a su viaje por Europa, as&iacute; que llegando conectamos la m&aacute;quina y empezamos el curso, mientras le ense&ntilde;aba a usarla me di cuenta que cada vez que tomaba su mano para ayudarla, se pon&iacute;a muy nerviosa, hasta que le pregunte qu&eacute; era lo que le estaba sucediendo. Me coment&oacute; todo lo que ya sab&iacute;a de su matrimonio, y me dijo que ten&iacute;a mucho tiempo que no estaba tan cerca de hombre alguno.<\/p>\n<p>Yo trate de animarla con palabras de aliento y de pronto comenz&oacute; a llorar, y confes&oacute; que ten&iacute;a poco m&aacute;s de 6 a&ntilde;os que no ten&iacute;a contacto sexual con nadie y que adem&aacute;s no sab&iacute;a lo que era un orgasmo, algo que me sorprendi&oacute; pues me conto adem&aacute;s que se hab&iacute;a casado virgen y solo tuvo relaciones con su ex en muy contadas ocasiones. Para animarla un poco le lanc&eacute; varios piropos resaltando la belleza de sus piernas, sus caderas, su busto, adem&aacute;s la invit&eacute; a que vistiera m&aacute;s juvenil, pues parec&iacute;a una sesentona quedada pues rara vez se maquillaba, ella me dijo que por qu&eacute; le dec&iacute;a todo esto, le comente que no me gustaba esa tristeza en su rostro, entonces me dijo que de todos modos no ten&iacute;a otra ropa, a lo que la invit&eacute; a que fu&eacute;ramos a un centro comercial a comprar algo y ella acept&oacute;.<\/p>\n<p>Al llegar, le ped&iacute; que me permitiera ser yo quien escogiera la ropa, poco despu&eacute;s salimos de esa tienda con pantalones ajustados, minifaldas, tops, bustiers, y zapatos, cuando pasamos enfrente de una tienda de lencer&iacute;a, y la jale para que pas&aacute;ramos, al principio no quer&iacute;a pues le daba pena, la persuad&iacute; y al final quiso, cuando la vendedora nos abord&oacute; lo primero que pregunto fue su talla, a lo que muerta de pena contesto &ldquo;34C&rdquo;. Lo que me sorprendi&oacute; pues su busto no se ve&iacute;a tan grande, y compramos una serie de coordinados muy sexis todos con tanga. Cuando nos dan la cuenta vimos que estaba muy abultada y me dijo que ya no le alcanzaba para pagar ni siquiera un coordinado, yo le dije que se los invitaba con la condici&oacute;n de que me modelara toda la ropa que compro incluida la lencer&iacute;a y como era de esperarse me dijo que la lencer&iacute;a no, lo dem&aacute;s s&iacute;. Pagu&eacute; y camino a su casa me dio las gracias, pero que le iba a costar trabajo ponerse ropa tan peque&ntilde;a. No hicimos m&aacute;s comentarios y llegamos a su casa, ah&iacute; me pregunto qu&eacute; cuanto le iba a cobrar por el curso de c&oacute;mputo que le estaba dando, le volv&iacute; a decir que en pago me modelar&iacute;a la lencer&iacute;a que compramos, esta vez ella se molest&oacute; y me pidi&oacute; que me retirara.<\/p>\n<p>Al d&iacute;a siguiente me llamo a mi oficina y se disculp&oacute; por lo ocurrido y me dijo que me esperaba despu&eacute;s de trabajar, como yo sal&iacute;a a las 3:00 PM a las 4:00 ya estaba en su casa. Me abri&oacute; y llevaba puesto uno de los atuendos que adquirimos, y realmente se ve&iacute;a buen&iacute;sima pues resaltaba su gran busto que escond&iacute;a tras blusas holgadas. Le hice notar mi asombro y se ruboriz&oacute; toda, me dijo &ldquo;si&eacute;ntate en la sala y esp&eacute;rame&rdquo;, y empez&oacute; a modelar la ropa comprada. En eso sale su amiga con su novio y se despiden pues pasar&iacute;an el fin de semana juntos y solos. Al irse Mar&iacute;a Jos&eacute; me coment&oacute; que bueno que se hab&iacute;an ido pues toda la noche estuvieron haciendo ruido y no la dejaron dormir, le dije:<\/p>\n<p>&mdash;Envidia o coraje?<\/p>\n<p>&mdash;Pues un poco de los dos &mdash;comento.<\/p>\n<p>&mdash;Por qu&eacute; quieres verme modelar la ropa interior &mdash;me dijo.<\/p>\n<p>&mdash;Por qu&eacute; crees &mdash;le dije.<\/p>\n<p>&mdash;no creo que sea por la ropa, o si? &mdash;pregunto.<\/p>\n<p>&mdash;por todo Mar&iacute;a Jos&eacute;.<\/p>\n<p>Lo que respondi&oacute; quit&aacute;ndose la ropa que llevaba puesta y se qued&oacute; luciendo la ropa interior que tra&iacute;a y dijo:<\/p>\n<p>&mdash;te gusta?<\/p>\n<p>&mdash;me encanta &mdash;conteste<\/p>\n<p>&mdash;sabes al escuchar a mi amiga con su novio me masturbe un buen rato y no se baj&oacute; la calentura.<\/p>\n<p>&mdash;Eso tiene arreglo &mdash;le dije.<\/p>\n<p>Al acercarme a ella me dice:<\/p>\n<p>&mdash;Y mi sobrina?<\/p>\n<p>&mdash;en Europa con mis papas.<\/p>\n<p>&mdash;no, que va a pasar con ella.<\/p>\n<p>&mdash;Nada, si t&uacute; no dices yo menos.<\/p>\n<p>No me respondi&oacute; se abalanzo contra m&iacute; y nos fundimos en un beso apasionado, r&aacute;pidamente me desvisti&oacute; y al ver mi palo exclamo:<\/p>\n<p>&mdash;a caray no pens&eacute; que la tuvieras tan grande.<\/p>\n<p>&mdash;No, lo que pasa es que tienes las manos peque&ntilde;as &mdash;le contest&eacute;.<\/p>\n<p>Nos re&iacute;mos un poco y continuamos ya desnudos los dos, me comenz&oacute; a masturbar con la mano muy desesperadamente, se la meti&oacute; en la boca y me la empez&oacute; a mamar, pero muy torpemente pues no sab&iacute;a hacerlo, as&iacute; que le dije como y poco a poco lo hizo mejor, despu&eacute;s comenc&eacute; a mamarle su cosita hasta que consigui&oacute; su primer orgasmo gritando y llorando del placer que sent&iacute;a, inmediatamente se trepo en m&iacute; y se la meti&oacute; hasta dentro y a golpe de mete y saca y grito y grito se vino dos veces m&aacute;s, en ese momento se la saque y la puse en cuatro puntos y comenc&eacute; chupar su ano, lo &uacute;nico que comento fue que con cuidado, despu&eacute;s de mucho chuparlo y lubricarlo bien se la deje ir hasta el fondo recibi&eacute;ndola ella con m&aacute;s gritos aun ya hasta que me vine en su culo, desfallecido ca&iacute; en el sof&aacute; y me dijo:<\/p>\n<p>&mdash;Wow, as&iacute; que esto es coger verdad?<\/p>\n<p>&mdash;Y solo es el principio &mdash;le dije.<\/p>\n<p>As&iacute; que nos dirigimos a la alcoba y estuvimos cogiendo un muy buen rato hasta que nos dormimos, de esta forma siguieron los cursos de cyber y sex.<\/p>\n<p>Al amanecer despert&eacute; y me llamo la atenci&oacute;n que no estaba en la cama, por lo que me levante, me vest&iacute; y fui a la cocina donde ella se encontraba preparando el desayuno. La observ&eacute; durante unos minutos sin ser visto, y me di cuenta que su semblante hab&iacute;a cambiado, ahora se ve&iacute;a feliz, motivada, con un excelente humor, su mismo rostro hab&iacute;a cambiado, pues ya no era esa faz sin expresi&oacute;n y sin vida. Momentos despu&eacute;s noto mi presencia y me dijo con una expresi&oacute;n de ternura y gratitud:<\/p>\n<p>&mdash;Gracias.<\/p>\n<p>&mdash;&iquest;porque? &mdash;Le pregunte.<\/p>\n<p>&mdash;por hacerme sentir mujer nuevamente, deseada y amada, porque nunca antes hab&iacute;a experimentado estos placeres extremos, porque volv&iacute; a creer en m&iacute; y s&eacute; que hoy mi vida ha cambiado gracias a ti. Concluy&oacute;.<\/p>\n<p>No supe que decir, solo me concret&eacute; a darle un beso largo y profundo en los labios.<\/p>\n<p>Despu&eacute;s de desayunar nos ba&ntilde;amos y decidimos que pasar&iacute;amos juntos ese fin de semana aprovechando el reci&eacute;n iniciado viaje de mi esposa por Europa, as&iacute; que despu&eacute;s de arreglarnos decidimos asear su departamento. Ya en la tarde despu&eacute;s de la comida acordamos ir al cine.<\/p>\n<p>Al llegar a dicho lugar entramos a ver una proyecci&oacute;n que se distingu&iacute;a por su contenido er&oacute;tico, al avanzar la cinta no encendimos y comenzamos a besarnos y ya con un alto grado de excitaci&oacute;n comenc&eacute; a chupar sus pezones, sin importarnos que la sala estaba al 50% de su capacidad de gente, ella hacia un esfuerzo sobrehumano para no hacer ruido, levante su falda, quite su ropa interior (bragas) y empec&eacute; a chupar su cl&iacute;toris, sus labios, hasta que llego al orgasmo, ya estando s&uacute;per caliente correspondi&oacute; al favor y me la mam&oacute; durante un rato hasta que nos interrumpi&oacute; el personal de seguridad y nos oblig&oacute; a desalojar la sala.<\/p>\n<p>Sin pena y ya altamente excitados salimos, y en un descuido de este individuo nos escapamos y terminamos en el estacionamiento dentro mi auto haciendo el amor, nos subimos en el asiento trasero, ella sin bragas (pues las dejo en la sala del cine) se mont&oacute; en m&iacute; y estuvo cabalgando hasta que se vino otra vez, poco despu&eacute;s nos dirigimos a su casa y ah&iacute; terminamos lo iniciado en el cine.<\/p>\n<p>Poco despu&eacute;s nos quedamos descansando un rato en el sill&oacute;n donde ocurri&oacute; todo y de pronto tocaron la puerta, era la hija de una de sus hermanas, al entrar le extra&ntilde;&oacute; mucho verme y pregunt&oacute;:<\/p>\n<p>&mdash;Tu qu&eacute; haces aqu&iacute;?<\/p>\n<p>&mdash;le estoy dando un curso de computo a tu t&iacute;a<\/p>\n<p>&mdash;pero la computadora est&aacute; apagada<\/p>\n<p>&mdash;es que ya terminamos y estaba por irme.<\/p>\n<p>En eso se dirige a la computadora y despu&eacute;s de tocar el monitor dijo:<\/p>\n<p>&mdash;el monitor esta frio lo cual quiere decir que no se ha prendido, d&iacute;ganme que pasa y porque se percibe ese olor.<\/p>\n<p>&mdash;La verdad no entender&iacute;as hija &mdash;comento Mar&iacute;a Jos&eacute;.<\/p>\n<p>&mdash;que es lo no entender&iacute;a, que aprovechan que mi prima est&aacute; de viaje para hacer sus cosas?<\/p>\n<p>&mdash;hija yo&#8230;<\/p>\n<p>&mdash;nada t&iacute;a yo entiendo c&oacute;mo te has sentido, y entiendo que tengas muchas ganas de hacerlo, pero con el esposo de mi prima?<\/p>\n<p>&mdash;Creo que tienes raz&oacute;n hija, esto no debi&oacute; pasar &mdash;y comenz&oacute; a llorar.<\/p>\n<p>&mdash;no llores t&iacute;a, que no voy a decir palabra, pero eso va a tener un precio.<\/p>\n<p>&mdash;cual? &mdash;comentamos los dos<\/p>\n<p>&mdash;que me inviten a su fiesta el d&iacute;a de hoy.<\/p>\n<p>Y as&iacute; de esta forma se incorpor&oacute; a nuestra aventura Romina, la prima de mi esposa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>2 Cuando conoc&iacute; a la familia de mi esposa, hace tres a&ntilde;os cuando ten&iacute;a 25, me presento a su t&iacute;a Mar&iacute;a Jos&eacute;, una mujer de 33 a&ntilde;os que 5 a&ntilde;os atr&aacute;s se hab&iacute;a casado con un tipo que seg&uacute;n me contaron era todo un pat&aacute;n que la golpeaba y aparte de darle una vida econ&oacute;micamente [&hellip;]<\/p>\n","protected":false},"author":1744,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-18510","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/18510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/1744"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=18510"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/18510\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=18510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=18510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=18510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}