{"id":24820,"date":"2020-07-21T22:00:00","date_gmt":"2020-07-21T22:00:00","guid":{"rendered":""},"modified":"2020-07-21T22:00:00","modified_gmt":"2020-07-21T22:00:00","slug":"mi-infidelidad-con-fernando-parte-2","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/mi-infidelidad-con-fernando-parte-2\/","title":{"rendered":"Mi infidelidad con Fernando (Parte 2)"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"24820\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">2<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>No me dio tiempo ni de pensar en m&aacute;s, Fernando estaba duro y listo para m&aacute;s acci&oacute;n y el remordimiento que sent&iacute;a poco a poco fue despareciendo en lo que su boca me besaba mi cuello y sus manos agarraban con fuerza mis nalgas.<\/p>\n<p>K: &iquest;Quieres m&aacute;s?<\/p>\n<p>FC: Claro, &iexcl;no s&eacute; cu&aacute;ndo te vuelva a tener y mejor provecho!<\/p>\n<p>K: &iexcl;Guau! &iexcl;Que macho!<\/p>\n<p>FC: Si y ser&eacute; el tuyo, &iexcl;ven vamos para ac&aacute;!<\/p>\n<p>Me abraz&oacute; por atr&aacute;s y mientras su verga estaba en medio de mis nalgas, me llevo hasta el sof&aacute; o silla de forma rara que sirve para coger rico.<\/p>\n<p>Ah&iacute; subi&oacute; una de mis rodillas y coloque mis manos en el respaldo quedando paradita de nalgas, el lentamente me las acaricio y fue abri&eacute;ndolas para m&eacute;teme sus dedos y comenzar a masturbarme rico, mientras mis nalgas masajeaban su pene duro como el fierro.<\/p>\n<p>Mi cl&iacute;toris estaba inflado, el met&iacute;a tres dedos, mientras me besaba el cuello y me lamia la oreja, me sent&iacute;a una perra sucia, una traidora, la, pero mujer del mundo, pero al mismo tiempo, sent&iacute;a riqu&iacute;simo como me pon&iacute;a, que le ped&iacute; me &iexcl;cogiera ya!<\/p>\n<p>K: &iexcl;M&eacute;temela ya!<\/p>\n<p>FC: &iexcl;Golosa! P&iacute;demela por favor!<\/p>\n<p>K: m&eacute;temela por favor, la necesito, &iexcl;estoy escurriendo por tenerla dentro!<\/p>\n<p>FC: Eso es, que buena ni&ntilde;a, &iexcl;aqu&iacute; est&aacute; tu premio!<\/p>\n<p>Me tom&oacute; del hombro y me ensarto riqu&iacute;simo, no s&eacute; porque o tal vez fue mi imaginaci&oacute;n, pero ahora los sent&iacute;a ms duro y grande, &eacute;l se mov&iacute;a riqu&iacute;simo, me jalaba el cabello y me daba de nalgadas, yo solo gem&iacute;a al recibir su tunda y me mov&iacute;a un poco ya que continuaba con un pie arriba y el otro abajo.<\/p>\n<p>K: &iexcl;Ah!! &iexcl;Si as&iacute;, uhm, ah!!<\/p>\n<p>FC: &iexcl;Que rico, toma, toma mi verga!<\/p>\n<p>K: &iexcl;Que rica verga papi, ah!<\/p>\n<p>FC; Me encanta cuando hablas as&iacute;, &iexcl;uhm!<\/p>\n<p>Sub&iacute; mis dos piernas en ese sill&oacute;n y me inclin&eacute; m&aacute;s adelante, arando as mis nalgas, eso le daba m&aacute;s placer a mi nuevo amante, y me la met&iacute;a m&aacute;s rico.<\/p>\n<p>Yo ayudaba tambi&eacute;n meneando mis caderas y haci&eacute;ndome para adelante y para atr&aacute;s, que rico momento pas&aacute;bamos.<\/p>\n<p>K: &iexcl;Que rico, ah, uhm!<\/p>\n<p>FC: Me excita como gimes bebe, &iexcl;ah!<\/p>\n<p>K: M&eacute;temela, uhm, que rico, c&oacute;geme, &iexcl;c&oacute;geme!<\/p>\n<p>FC: &iexcl;S&iacute;, eso es, p&iacute;demela, p&iacute;demela amor!<\/p>\n<p>Me empin&eacute; lo m&aacute;s que pude, mi cara chocaba con el respaldo de ese sof&aacute; mientras Fernando me embest&iacute;a riqu&iacute;simo, me daba de nalgadas, luego se quedaba quieto y yo solita mov&iacute;a mi cadera, mov&iacute;a mi pelvis y mis nalgas, quer&iacute;a hacerlo feliz, &iexcl;quer&iacute;a que gozara!<\/p>\n<p>Me tomo dela mano y me arrodillo, yo gustosa baj&eacute; a su dura verga que ya ten&iacute;a mis fluidos y comenc&eacute; a mam&aacute;rsela nuevamente, esta vez sin pena y m&aacute;s apasionada por su verga.<\/p>\n<p>Se la lamia desde los test&iacute;culos hasta su punta, luego la succionaba y succionaba todos los fluidos que ten&iacute;an, la mord&iacute;a suave, me quedaba solo chupando la cabecita y el solo gem&iacute;a y disfrutaba de mis chupadas.<\/p>\n<p>FC: &iexcl;Ah! que rico, uhm, &iexcl;que excelente mamada!<\/p>\n<p>K: &iexcl;Mmm! &iexcl;Que rica sabe uhm!<\/p>\n<p>FC: &iexcl;Eres fuego puso nena, ah!!<\/p>\n<p>K: Ya vez, &iexcl;aprovecha tu suerte!<\/p>\n<p>Me tomo de la nuca y empez&oacute; a follarme la boca, me ahogaba con velocidad, pero yo disfrutaba sentir como tocaba mi garganta, le apretaba sus duras nalgas de hombre, &eacute;l me tomaba de las orejas y con desesperaci&oacute;n continuaba cogi&eacute;ndome la boca.<\/p>\n<p>Me puso de pie luego de ahogarme un buen rato con su duro pene y nos besamos de lengua el pudor ya no exist&iacute;a, ahora &eacute;l se sent&oacute; en el sill&oacute;n raro y yo empec&eacute; a darme de sentones.<\/p>\n<p>FC: Que rico nena, ah, &iexcl;eso ensarte sola ah!<\/p>\n<p>K: &iexcl;Ah!, &iexcl;uhm, que rico!<\/p>\n<p>FC: &iexcl;Maravilloso, mu&eacute;vete nena mu&eacute;vete!<\/p>\n<p>K: &iquest;As&iacute; nene, as&iacute;?<\/p>\n<p>Estaba sacando mis mejores movimientos, mi marido no toleraba mucho eso, se ven&iacute;a luego, luego, pero Fernando me estaba dando batalla y me estaba cogiendo rico, tolerando todo lo que hac&iacute;amos, la verdad quer&iacute;a ser su funda por siempre.<\/p>\n<p>Me di vuelta y sub&iacute; en &eacute;l, mientras nos bes&aacute;bamos como locos, lo cabalgaba riqu&iacute;simo, que rico sent&iacute;a su dureza, me mord&iacute;a las tetas el cuello, yo lo mord&iacute;a hasta casi sangrarlo, pero el resist&iacute;a y me permit&iacute;a eso y m&aacute;s, le ara&ntilde;aba su espalda, le jalaba los cabellos mientras el mov&iacute;a rico su pelvis pata dejarme sentir toda su dureza.<\/p>\n<p>FC: &iexcl;Me voy a venir bebe!<\/p>\n<p>K: &iexcl;Si! vente, &iexcl;termina dentro otra vez!<\/p>\n<p>FC: Si, &iexcl;lo quieres dentro!<\/p>\n<p>K: Si, vamos, s&aacute;cala, ll&eacute;name de ti, &iexcl;ah!<\/p>\n<p>De pronto su semen caliente me inundo, el orgasmo fue riqu&iacute;simo, nos bes&aacute;bamos, gem&iacute;amos, respir&aacute;bamos acelerados disfrutando el placer que hab&iacute;amos obtenido.<\/p>\n<p>K: &iexcl;Que rico, ah!! &iexcl;Dios, ah!!<\/p>\n<p>FC: Nena, uhm, &iexcl;esto es magn&iacute;fico!<\/p>\n<p>Reposamos el orgasmo pegados bes&aacute;ndonos, luego vi la hora y not&eacute; que ya eran casi las 3 de la tarde y ten&iacute;a que irme, as&iacute; que me fui al ba&ntilde;o a enjuagarme.<\/p>\n<p>No pasaron ni cinco minutos, cuando estaba bien metida limpi&aacute;ndome, nuevamente Fernando apareci&oacute; tom&aacute;ndome por atr&aacute;s y con su verga dura para coger m&aacute;s.<\/p>\n<p>K: &iquest;Es en serio?<\/p>\n<p>FC: Lo siento mi amor, &iexcl;pero &eacute;l est&aacute; pose&iacute;do por ti!<\/p>\n<p>K: &iexcl;Ah! &iexcl;Pero, ah!! &iexcl;Ya me tengo que ir!<\/p>\n<p>FC: &iexcl;Ahorita te llevo r&aacute;pido, uhm!<\/p>\n<p>Met&iacute;a y sacaba su verga mientras yo estaba reclinada apoyada en la pared.<\/p>\n<p>Me tomaba las nalgas y me la met&iacute;a fuerte y rico, mi cabeza casi chocaba con la pared, as&iacute; que me di vuelta y apoy&aacute;ndome de unos fierros que sirven para colgar toallas, me apoy&eacute; en ellos y el me cargo meti&eacute;ndomela riqu&iacute;simo.<\/p>\n<p>K: &iexcl;Me encanta, ah!!<\/p>\n<p>FC: &iexcl;Te coger&iacute;a todo el d&iacute;a nena!<\/p>\n<p>K: &iexcl;Si, ah! &iexcl;Uhm!, &iexcl;Mmm!, &iexcl;m&aacute;s, dame m&aacute;s!<\/p>\n<p>FC: &iexcl;No que ya te ibas, jaj&aacute;!<\/p>\n<p>Me dio la vuelta y yo me agach&eacute; empin&aacute;ndome delicioso para &eacute;l, mis manos tocaban el suelo, el tom&aacute;ndome de la cintura me la met&iacute;a fuerte y r&aacute;pido, yo gem&iacute;a, el agua nos mojaba a ambos, que puta me hab&iacute;a vuelto ese d&iacute;a, jam&aacute;s cog&iacute; con mi marido como lo estaba haciendo con Fernando.<\/p>\n<p>FC: Que nalgotas, me encantan, &iexcl;quiero que seamos amantes!<\/p>\n<p>K: &iexcl;Ah! &iexcl;Si mi amor, coger&eacute; contigo cuando gustes!<\/p>\n<p>FC: &iquest;Neta?, uhm, oye, &iexcl;te comes mi leche!<\/p>\n<p>K: Si, papi, ya te vas a venir, &iexcl;uhm!<\/p>\n<p>FC: &iexcl;No! &iexcl;Pero te la dar&eacute; en tu boca!<\/p>\n<p>Fernando continuaba movi&eacute;ndose con fuerza, jal&aacute;ndome el cabello y apretando mis muslos, yo me mov&iacute;a hacia delante y atr&aacute;s, mov&iacute;a en c&iacute;rculos mi cintura, que rico sab&iacute;a que pronto llegar&iacute;a nuevamente.<\/p>\n<p>K: &iexcl;Ah!!, me corro amor, ah!!<\/p>\n<p>FC: Si nena, vente, vamos, &iexcl;ah!<\/p>\n<p>Empec&eacute; a venirme en liquido como hace tiempo no lo hac&iacute;a, mis gemidos y gritos hac&iacute;an eco en el ba&ntilde;o, Fernando segu&iacute;a duro y meti&eacute;ndomela con fuerza.<\/p>\n<p>En eso Fernando respiro acelerado y sent&iacute; como se inflaba pens&eacute; que no lograr&iacute;a sacarla, pero la saco y me arrodillo y puso su verga en mi cara y empez&oacute; a venirse.<\/p>\n<p>FC: &iexcl;Ah!! &iexcl;Comete mi leche nea, ah!<\/p>\n<p>K: &iexcl;Uhm, agh, uhm!!<\/p>\n<p>Su leche me llenaba la cara y la boca, su sabor no era desagradable, le chupaba la verga mientras ella segu&iacute;a expulsando semen, yo disfrutaba de estar roseada de su blanca leche,<\/p>\n<p>FC: &iexcl;Si, uhm, no sab&iacute;a que fueras tan caliente!<\/p>\n<p>K: Hay muchas cosas que no sabes, &iexcl;uhm!<\/p>\n<p>Una vez que termino de sacar su rica leche, me levante y lo bese, embarr&aacute;ndolo de su fluido, pero &eacute;l solo se rio y disfrutamos de un rico beso debajo del agua.<\/p>\n<p>Una vez que terminamos, me vest&iacute; r&aacute;pidamente y el tambi&eacute;n, salimos como si nos estuvieran correteando, eran casi las 4 de la tarde y mis hijos ya estaban en casa y no sab&iacute;an de m&iacute;.<\/p>\n<p>Fernando me dejo cerca de mi casa, ya que no quer&iacute;a que me vieran llegar con &eacute;l, creo que estuvimos como 3 horas cogiendo o cuatro, no lo s&eacute; bien, pero el chiste es que la verdad me encanto, de hecho, ese d&iacute;a se acabaron las discusiones con mi marido, tal vez por remordimiento o no s&eacute;, pero lo que si pas&oacute; es que algo nuevo en mi estaba naciendo.<\/p>\n<p>Les confieso que a partir de ese d&iacute;a me volv&iacute; amante de Fernando y cada que pod&iacute;a me ve&iacute;a a escondidas con &eacute;l para pasar un rico momento sexual con &eacute;l.<\/p>\n<p>Pero &eacute;l no fue el &uacute;nico hombre con quien me met&iacute;, si me dan confianza y me atrevo, m&aacute;s adelante les contare algunas otras infidelidades, ya que el estar con Fernando me desato una bestia sexual que ten&iacute;a dentro y hasta el d&iacute;a de hoy no puedo controlar.<\/p>\n<p>Kali<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>2 No me dio tiempo ni de pensar en m&aacute;s, Fernando estaba duro y listo para m&aacute;s acci&oacute;n y el remordimiento que sent&iacute;a poco a poco fue despareciendo en lo que su boca me besaba mi cuello y sus manos agarraban con fuerza mis nalgas. K: &iquest;Quieres m&aacute;s? FC: Claro, &iexcl;no s&eacute; cu&aacute;ndo te vuelva [&hellip;]<\/p>\n","protected":false},"author":13484,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-24820","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-infidelidad"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/24820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/13484"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=24820"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/24820\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=24820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=24820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=24820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}