{"id":24892,"date":"2020-07-27T01:49:57","date_gmt":"2020-07-27T01:49:57","guid":{"rendered":""},"modified":"2020-07-27T01:49:57","modified_gmt":"2020-07-27T01:49:57","slug":"el-dia-que-le-fui-infiel-y-de-manera-consentida","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/el-dia-que-le-fui-infiel-y-de-manera-consentida\/","title":{"rendered":"El d\u00eda que le fui infiel y de manera consentida"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"24892\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">10<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 10<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Mi nombre es Xavier. Ya hace tiempo con mi futura esposa Vivi y yo estamos variando en el sexo. Llevamos 4 a&ntilde;os de noviazgo. Ella es muy preciosa, flaca pero no tanto, piel blanca, cabello casta&ntilde;o (a veces se ti&ntilde;e negro e igual se ve buena), buenas tetas no muy grandes ni muy chicas, una cola perfecta, piernas torneadas y suaves, labios gruesos, unos muy bonitos pies que combinado con sus tacos altos se ve mejor que una modelo.<\/p>\n<p>Desde que nos conocimos ella siempre le gusto impresionarme con su manera de vestir, incluso llegando a vestirse de diferentes personajes&hellip; enfermera, colegiala o lo m&aacute;s zorra posible y a veces saliendo a la calle as&iacute; para que todos la deseen. Obvio que siempre acompa&ntilde;ada conmigo.<\/p>\n<p>Nos gusta mucho hacerlo en diferentes circunstancias y lugares. Hasta alguna vez; ella me chupaba la pija cerca de un barrio muy acomodado dentro del jeep y apareci&oacute; un auto con dos se&ntilde;oritas buscando una direcci&oacute;n, se dieron cuenta que pasaba y se fueron muy r&aacute;pido jajajaja. Luego ella volvi&oacute; a lo suyo y termine dentro de su boca como es costumbre trag&aacute;ndose todita la leche sin derramar &iexcl;&iexcl;ella sabe hacer la mejores chupadas de pija del mundo!! Por supuesto que a ella tambi&eacute;n le encanta el semen dentro de su boca, conchita y cola.<\/p>\n<p>Bueno basta de introducci&oacute;n, contare una de las experiencias que nos pas&oacute; alguna vez:<\/p>\n<p>Un d&iacute;a era fiesta de aniversario de la ciudad y decidimos ir justo al centro. Nosotros todav&iacute;a no vivimos juntos y cuando pase en taxi su casa quede impresionado&hellip;era toda una hembra hermosa y lista para hacerle todo:<\/p>\n<p>Ella como siempre se visti&oacute; espectacular, un vestido negro entero apretado muy corto, pr&aacute;cticamente dos cent&iacute;metros m&aacute;s y se le ve la cola, tacos altos que mostraban sus pies, sin sost&eacute;n y el cabello suelto.<\/p>\n<p>Mientras &iacute;bamos en el taxi le dec&iacute;a al o&iacute;do lo buena que esta y acariciaba sus suaves piernas&hellip; a tal punto que sobaba su conchita sobre su tanga, pero ella me sacaba la mano por verg&uuml;enza al taxista. En fin, llegamos al centro y nos bajamos a una cuadra del boliche que en realidad era la misma calle pero cerrada por los festejos. Mientras camin&aacute;bamos ese trecho no dejaban de acosarla silb&aacute;ndole o diciendo cosas como: mi amor ven&iacute; conmigo, hola cu&ntilde;ado, que linda, etc. Yo tratando de apurarnos y ver quienes eran los que hablaban porque me estaba cabreando. Bueno llegamos al lugar y nos pillamos con nuestros amigos. Era una pareja y una amiga llamada Susan, que deb&iacute;a estar con su novio pero no pudo venir por razones de trabajo o cosas as&iacute;. Ella estaba vestida con una falda a medio muslo y escote que mostraba sus grandes tetas, ella es un poco mas gruesa pero igual muy linda y cogible.<\/p>\n<p>Los cinco nos pusimos a tomar en una mesa VIP que ten&iacute;amos reservada. Mi mujer, Susan y yo siempre nos gust&oacute; la cerveza as&iacute; que empezamos con una botella cada uno.<\/p>\n<p>Era temprano como las 8 pm, ya est&aacute;bamos por nuestra 3 o 4 botella y la m&uacute;sica a full reggaet&oacute;n. Empezamos a bailar y en el poco espacio que ten&iacute;amos pr&aacute;cticamente yo bailaba con Vivi y Susan al mismo tiempo. Como el espacio era reducido por mesa y sillas, los tres est&aacute;bamos muy juntos y a ratos rozaba mi brazo o cuerpo con las tetas de Susan o mi paquete con mi pija dura a su cola, ella no dec&iacute;a nada ni tampoco Vivi porque era parte del baile y el poco espacio. Cada vez mas la situaci&oacute;n empez&oacute; a repetirse y yo estaba con la verga muy dura porque tambi&eacute;n a ratos abrazaba a Vivi y me estrujaba en su cola una que otra vez, mientras hac&iacute;a eso me agarraba la pija dura disimuladamente y se re&iacute;a como zorra.<\/p>\n<p>Todo segu&iacute;a as&iacute; hasta que yo fui muy descarado de bailar &ldquo;hasta abajo&rdquo; con Susan y al subir me la apegue y sin querer agarre un poco sus tetas para no caer. Esto puso molesta a Vivi y con cara de encabronada. La hicimos re&iacute;r y le explico Susan que fue un accidente, etc. Ya hasta eso les dieron ganas de ir al ba&ntilde;o que por suerte no hab&iacute;a mucha gente por ser temprano, las acompa&ntilde;e y primero entro Susan. Mientras esper&aacute;bamos abrace a Vivi, le di un gran beso, bajando a su cuello, mientras agarraba su cintura y me la apegaba. Ella gimi&oacute; un poco y me separo gentilmente dici&eacute;ndome que calme. Le dije que en un rato m&aacute;s nos ten&iacute;amos que ir porque quer&iacute;a cogerla lo antes posible y mi verga ya no aguantaba m&aacute;s.<\/p>\n<p>Como Vivi es muy perra, me dijo: &iquest;porque esperar tanto (con carita de perra picara)? La mire con cara de asombro porque no entend&iacute;a, ese mismo rato sali&oacute; Susan del ba&ntilde;o y de un empuj&oacute;n Vivi me meti&oacute; al ba&ntilde;o. Le dijo a Susan que cuide la puerta&hellip; ni bien entre se dio la vuelta apoyo sus manos en lavadero, puso cola en pompa facilitada por sus tacos altos, yo no tarde en bajarme el pantal&oacute;n y b&oacute;xer, subir su minivestido, hice a un lado su tanguita&hellip; me acomode la pija en su conchita que ya estaba h&uacute;meda y se la fui metiendo de a poco hasta el fondo, estuve bombe&aacute;ndola supongo que un minuto al ritmo de la m&uacute;sica mientras Vivi gem&iacute;a como lo puta que es&hellip; hasta que Susan empez&oacute; a tocar la puerta diciendo que ven&iacute;a gente&hellip; se asust&oacute; Vivi y me dijo que salga pero yo no quer&iacute;a irme hasta acabar, pr&aacute;cticamente se dio la vuelta y me empujo para que me calme y salga del ba&ntilde;o&hellip; no tuve otra opci&oacute;n que salirme. Ya afuera esperando que salga Vivi, mi amiga Susan empez&oacute; a preguntar:<\/p>\n<p>Susan: &iquest;y que hac&iacute;an ah&iacute; adentro? (mientras se re&iacute;a)<\/p>\n<p>Yo: Nada, pasa que se le atoro el cierre y la estaba ayudando jajaja<\/p>\n<p>Susan: Seraaa&hellip; yo escuche otra cosa jajaja. No coman delante de los pobres jajaja<\/p>\n<p>Yo: noo tranquila Susan seguro mas tarde llegando a casa tu novio te va dar lo que te gusta<\/p>\n<p>Susan: te cuento que no vino por que nos peleamos, estar&eacute; solita en casa hasta que nos volvamos a hablar.<\/p>\n<p>Yo: Pucha que pena ni modo&hellip; ya va pasar Uds. siempre son as&iacute;.<\/p>\n<p>Susan: Si puede ser, pero hoy quiero divertirme y hacer lo que quiera&hellip; si aparece uno que me guste no me importa y me lo llevo jajaja<\/p>\n<p>Yo: jajaja tampoco as&iacute;&hellip; los tres estamos pas&aacute;ndola bien, si quer&eacute;s nos quedamos mas tiempo para que no est&eacute;s solita porque no vamos a dejar que una se&ntilde;orita tan linda y con ese escote ande sola&hellip;<\/p>\n<p>Susa: ay que tierno&hellip; sabes qu&eacute;; si quieren luego vamos a mi casa a seguir tomando m&aacute;s tranquilos porque la zona VIP es muy chica y no es lo que esper&aacute;bamos.<\/p>\n<p>Yo: ah puede ser ya te aviso, le dir&eacute; a Vivi&hellip; (yo pensando que no era buena idea ya que quer&iacute;a coger con Vivi toda la noche)<\/p>\n<p>En eso sali&oacute; Vivi del ba&ntilde;o y nos fuimos a la mesa VIP. Le comente de ir a casa de Susan y como estaba media ebria se anim&oacute; bastante&hellip; cosa que me pareci&oacute; raro. Yo estaba ebrio, Vivi bailaba muy descarada y gritaba los coros de las canciones junto con Susan.<\/p>\n<p>A los 30 minutos nos despedimos de la otra pareja y nos fuimos los tres a casa de Susan. En el taxi yo estaba al medio y a ratos me besaba con Vivi&hellip; en una de esas sent&iacute; la mano de Susan en mi muslo muy cerca de mi verga y me tomo por sorpresa. Vivi me pregunto &iquest;qu&eacute; paso? Y le dije que nada todo tranquilo.<\/p>\n<p>Llegamos a casa de Susan, puse m&uacute;sica en la tv y abr&iacute; m&aacute;s cervezas, mientras miraba a las dos bellezas de Vivi y Susan. Las dos empezaron a bailar, hablar boludeces y gritar los coros de las canciones que sonaban. Me di cuenta que las dos ya estaban muy ebrias y obviamente yo ya me sent&iacute;a igual. Ese rato Susan nos hizo secar nuestro vaso y nos dijo que pod&iacute;amos quedarnos a dormir en su casa, porque mi casa quedaba al otro lado de la ciudad. Entonces Vivi dijo que si, pero con la condici&oacute;n de que podremos coger en su sof&aacute; mas grande, ya que solo hab&iacute;a una habitaci&oacute;n. Susan se rio y dijo que no hab&iacute;a problema.<\/p>\n<p>Luego me pidieron que sacara fotos para subir al Facebook e Instagram&hellip; siempre fui buen fot&oacute;grafo y buscaba el mejor &aacute;ngulo, tambi&eacute;n acercaba mis manos y las acomodaba para que salgan mejor. Ah&iacute; aproveche de tocarle la cola a Susan para que se vea mejor su cintura y tambi&eacute;n hice lo mismo con Vivi. Todo muy natural, segu&iacute; con las fotos y luego una &uacute;ltima&hellip; yo con las dos abrazadas y mis manos en sus cinturas, ah&iacute; aproveche de darle una palmada a cada una al mismo tiempo y se rieron. Eso me puso a mil porque Vivi no se enoj&oacute; y Susan volteo a mirarme con cara de zorra.<\/p>\n<p>Nos pusimos a bailar los tres y le hicimos &ldquo;s&aacute;ndwich&rdquo; a Susan, yo estaba en frente de ella&hellip;Vivi como estaba atr&aacute;s agarro y apret&oacute; sus tetas, mientras yo apretaba de su cintura a Susan, sin querer Vivi le bajo el escote y vi en primer plano sus grandes tetas de Susan&hellip; se rieron las dos perras y Vivi me dijo amput&aacute;ndome: Vos no viste nada!! Jajaja<\/p>\n<p>Luego Susan fue al ba&ntilde;o y me quede en la sala con Vivi&hellip;no la pens&eacute; dos veces, empec&eacute; a besarla y baje su vestido para chuparle las tetas porque no quer&iacute;a quedarme con ganas. Mientras se las chupaba y ella jadeaba empez&oacute; a preguntarme:<\/p>\n<p>Vivi: &iquest;te gustan las tetas de Susan&hellip; no? &iquest;Te gustar&iacute;a tocarlas y ahogarte en sus tetas como haces con las m&iacute;as? &iquest;Subir su faldita y met&eacute;rsela hasta el fondo como lo haces conmigo?<\/p>\n<p>Yo: Son bonitas pero me gustan m&aacute;s las tuyas (mientras intercalaba chupar y lamer sus ricas tetas)<\/p>\n<p>Vivi: pero decime&hellip; quer&eacute;s o no?<\/p>\n<p>Yo: si si las lamer&iacute;as y chupar&iacute;a con ganas!!! Eso quer&iacute;as escuchar!! Y tambi&eacute;n se la meter&iacute;a hasta el fondo una y otra vez hasta llenarla de leche!!<\/p>\n<p>Vivi: &hellip; entonces si ella quiere yo se las chupare mientras vos miras. Pero vos no haces nada porque si no terminamos!!<\/p>\n<p>Yo: no hay problema pero vas agarrar y chupar esas tetas como yo te diga!<\/p>\n<p>Vivi: si&hellip; hare lo que digas. Solo si ella quiere.<\/p>\n<p>Yo: ya amor&hellip; no hay problema. Ahora ch&uacute;pamela<\/p>\n<p>Vivi empez&oacute; a chup&aacute;rmela y yo estaba en la gloria&hellip; no se cuanto tiempo paso y apareci&oacute; Susan con un camis&oacute;n que cubr&iacute;a todo el cuerpo hasta la mitad de su cola. Se sent&oacute; al lado m&iacute;o como si nada pasara y miraba como Vivi me chupaba la pija fren&eacute;ticamente mientras acariciaba mis huevos. Susan se inclin&oacute; para chup&aacute;rmela pero Vivi la levanto y empez&oacute; a besar&hellip; eso me gust&oacute; mucho pero esperaba que tambi&eacute;n Susan me la chupe.<\/p>\n<p>Mientras las dos se besaban en frente de mi, Vivi empez&oacute; a manosear las tetas de Susan sobre el camis&oacute;n, se notaba la excitaci&oacute;n de las dos y como Susan le agarraba a la cola Vivi.<\/p>\n<p>Luego Vivi quito el camis&oacute;n de Susan y quedo casi desnuda con su tanguita color azul&hellip; Susan hizo lo mismo con el vestido de Vivi quedando con su tanga negra. Yo estaba muy arrecho y quer&iacute;a cogerlas.<\/p>\n<p>Vivi: mmmm que rico besas Susan y me gusta como me tocas la cola<\/p>\n<p>Susan: Lo mismo digo pero tu novio nos tiene que coger<\/p>\n<p>Vivi: no porque me sentir&iacute;a mal y el seria infiel<\/p>\n<p>Susan: no pasa nada amiga, solo ser&aacute; por hoy (mientras gem&iacute;a)<\/p>\n<p>Yo: Amor tranquila, puedo coger con a las dos sin problema&hellip;<\/p>\n<p>Vivi: Solo yo estar&eacute; con Susan!! Vos solo lim&iacute;tate a mirar (con voz seria).<\/p>\n<p>Yo: ya amor lo que digas no se me enoje&hellip;<\/p>\n<p>Ese momento mientras se segu&iacute;an besando, aproveche de sacarle la tanguita a Vivi, me pidi&oacute; que me recueste en el sof&aacute; y se mont&oacute; encima m&iacute;o&hellip; de a poco fue acomodando mi verga en su conchita bastante mojada por sus l&iacute;quidos y de a poco empez&oacute; a cabalgarme muy f&aacute;cilmente porque su conchita estaba muuuy mojada&hellip; ella disfrutaba de estar arriba y se olvid&oacute; de Susan.<\/p>\n<p>Al poco tiempo Susan empez&oacute; a besarme mientras Vivi estaba encima recibiendo pija, eso molesto a Vivi y medio que paro su movimiento, para reclamar porque me besaba Susan.<\/p>\n<p>Por suerte Susan dejo de besarme y empez&oacute; a besar a Vivi mientras segu&iacute;a cabalg&aacute;ndome. Tocaba sus tetas y empez&oacute; a besarle el cuello&hellip; eso puso a Vivi mas loca y cuando me di cuenta Susan puso son concha encima m&iacute;o!<\/p>\n<p>Pr&aacute;cticamente se sent&oacute; en mi cara para que le chupe la concha mientras ella besaba a mi mujer&hellip; eso me volvi&oacute; loco y lamia esa deliciosa concha mientras Vivi me montaba. Segu&iacute;a lamiendo su concha y ella se mov&iacute;a como una puta. Vivi segu&iacute;a mont&aacute;ndome con mas ganas y sus gemidos eran callados por los besos de Susan hasta que&#8230; Vivi no aguanto mas y empez&oacute; a terminar gimiendo cada vez mas y mas fuerte (se nota porque se moja bastante y sus l&iacute;quidos chorrean).<\/p>\n<p>Susa: oye amiga tu novio sabe lamer concha&hellip; que suerte ten&eacute;s (mientras gem&iacute;a sentada encima de boca)<\/p>\n<p>Estuvimos as&iacute; un buen rato hasta que Vivi se dio cuenta de que yo estaba por terminar, paro el movimiento y se desmonto. Empez&oacute; a chuparme la pija mientras junto con Susan al mismo tiempo&hellip;hasta que ya a ratos no sab&iacute;a cual me la estaba chupando y empec&eacute; a llegar al orgasmo&hellip;<\/p>\n<p>Yo: chicas estoy por terminaaar&hellip; ooh sigaaan asii<\/p>\n<p>Susan, vivi: dale termina, vamos a tragar toda la leche.<\/p>\n<p>Yo: estoy terminando&hellip; uuuff ah&iacute; va putas estoy terminando tomen ah&iacute; vaaa aaagg tomen lechee aaaggghh<\/p>\n<p>Empec&eacute; a eyacular por montones y las dos recib&iacute;an el chorro de semen como pod&iacute;an con sus bocas&hellip; se regaron en toda la cara, boca y tragaban lo que pod&iacute;an porque me descargue demasiado. Mi verga segu&iacute;a botando semen, ellas se turnaban para seguir chupando y succionarme hasta la &uacute;ltima gota de semen.<\/p>\n<p>Despu&eacute;s de eso se re&iacute;an y fueron las dos al ba&ntilde;o. Yo no pod&iacute;a creer lo que paso y me limpie lo poco de semen que faltaba con el camis&oacute;n de Susan para que le quede de recuerdo.<\/p>\n<p>Cuando volvieron las dos, sirvieron mas cerveza y bebimos un poco mas. Est&aacute;bamos desnudos y segu&iacute;amos bailando&hellip; en un rato de esos Susan se me apego mucho y la empec&eacute; a besar. Vivi nos separ&oacute; y nos empezamos a besar los tres turn&aacute;ndonos&#8230; mientras ellas se besaban sosteniendo sus cervezas me acomode en por atr&aacute;s de Susan con la verga dura y se la puse entre sus labios mayores, sin penetrar. Susan se excito mucho y con su mano acomodo mi verga directo en su rajita para que se la meta, no me opuse y cuando acorde ya la ten&iacute;a adentro de ella.<\/p>\n<p>Vivi se dio cuenta y nos separ&oacute; diciendo que no se val&iacute;a&hellip; entonces agarre a Vivi y la puse en el sof&aacute; en posici&oacute;n de misionero para empezar a penetrarla, se la met&iacute; de una! segu&iacute;a bombeando a Vivi y Susan se abri&oacute; esperando que tambi&eacute;n se la meta, me separe de Vivi y empec&eacute; a coger a Susan, fue f&aacute;cil mi entrada a su concha porque ya estaba lubricado con los jugos vaginales de Vivi. Empec&eacute; a bombear a Susan con todo y la muy puta gem&iacute;a pidi&eacute;ndome mas y mas!! Me agache y chupe sus hermosas tetas que se mov&iacute;an por cada embestida que le daba&hellip; muuuy bellas tetas y deliciosas!! Lamia esas tetas con todas mis ganas ahog&aacute;ndome&hellip;.<\/p>\n<p>Mientras hac&iacute;a todo eso, note a Vivi muy celosa y frustrada, as&iacute; que le dije Susan que se ponga en cuatro para que bese la concha de Vivi mientras le daba en esa pose&hellip; hicieron caso las dos y as&iacute; fue&hellip;<\/p>\n<p>Le daba a Susan en cuatro mientras ella lamia la concha de mi mujer, al mismo tiempo de mis embestidas&hellip;<\/p>\n<p>Estuvimos as&iacute; un buen tiempo y pude escuchar a mi mujer orgasmear por la lamida de concha de Susan&hellip; esa fue mi inspiraci&oacute;n para terminar adentro de Susan en esa pose. No pude m&aacute;s y le avise a Susan que iba acabar adentro&hellip; ella dijo:<\/p>\n<p>Susan: no hay problema hermoso terminame adentro&hellip; quiero tu semen por favor terminaaa yaaa<\/p>\n<p>Vivi: llenaaalaa amor!! Quiero que termines adentro de ellaaa terminaaa en su conchaaa dalee aagggh aahhhg<\/p>\n<p>Yo: oooh estoy terminandooo voy a llenaar de semeen tu conchaaa uuuggg ah&iacute; va uuuhg tomaaa tomaaaaaa aaahgggg&hellip;<\/p>\n<p>Termine adentro de la concha de Susan en cuatro. Era harto semen porque se chorreaba la concha de Susan.<\/p>\n<p>Nos separamos y Vivi fue al ba&ntilde;o. Susan me dijo que se sent&iacute;a mal por nuestra relaci&oacute;n y no quer&iacute;a interponerse. Nos sentamos juntos, me pidi&oacute; su ropa y para no manchar el sof&aacute; con semen se puso el camis&oacute;n. Aproveche de tocar sus tetas y explicar que yo solo amo a Vivi y esto fue un experimento.<\/p>\n<p>Susan muy amable lo acepto, me dio un beso muy tierno mientras me acariciaba la verga y limpiaba con su boca los rastros de semen. Pude notar que por su muslo chorreaba mi corrida y al parecer eso le gustaba.<\/p>\n<p>Hasta eso sali&oacute; Vivi y le dije que yo la amo y esto fue un experimento. Vivi entendi&oacute;, empez&oacute; a chuparme la pija, comento del sabor a la concha de Susan y empezamos a coger en el sof&aacute;&hellip; estuvimos as&iacute; hasta que yo empec&eacute; a montarla de misionero un buen rato hasta que:<\/p>\n<p>Yo: oooh mi amor estoy terminando adentrooo ah&iacute; vooyyy tomaaa<\/p>\n<p>Vivi: siiii terminame adentrooo aagghh daleee terminameee&hellip;<\/p>\n<p>Yo: ah&iacute; vaaa tomaaaa tomaaaa putaa<\/p>\n<p>Despu&eacute;s de llenar de semen a mi mujer nos abrazamos y nos echamos a dormir en el sof&aacute;.<\/p>\n<p>Luego de eso me despert&eacute; porque sent&iacute; algo raro y era Susan&hellip;estaba chup&aacute;ndome la pija mientras dorm&iacute;a con mi novia!!!<\/p>\n<p>No pude negarme y me llevo de la mano a su cuarto muy sigilosamente. All&iacute; empezamos a hacer el 69 y pod&iacute;a sentir el sabor de mi leche de hace unas horas. Estuvimos as&iacute; hasta que se subi&oacute; encima y empezamos a coger, de a poco empec&eacute; a terminar adentro de ella otra vez&hellip; oh ah&iacute; va estoy terminandooo aaagg<\/p>\n<p>Susan: sii daleee yo tambi&eacute;n estoy terminando uuufff daleee terminame daleee quiero tu lecheee<\/p>\n<p>Basto que termine adentro de ella otra vez para decidir que deb&iacute;amos tomarnos las cosas con calma.<\/p>\n<p>Susan: espero que Vivi no se moleste<\/p>\n<p>Yo: &hellip; por supuesto que si! Jjajjaja<\/p>\n<p>Sin darme cuenta Vivi estaba en la puerta con los brazos cruzados mirando c&oacute;mo me la cog&iacute; a Susan y dijo:<\/p>\n<p>Vivi: luego a mi me toca elegir que hacer y con quienes&hellip; as&iacute; que las consecuencias ser&aacute;n lo que mereces!!!<\/p>\n<p>Yo: que? Nada que ver!!! Yo solo te amo a vos Vivi!!<\/p>\n<p>Vivi:&hellip; ya veremos qu&eacute; pasa. Ahora solo quiero que te vayas y quedarme a solas con Susan.<\/p>\n<p>Yo: est&aacute; bien amor&hellip; te amo&hellip; no te enojes. Me ir&eacute; a casa&hellip;<\/p>\n<p>Esperen la segunda parte.<\/p>\n<p>Espero que hayan gustado de mi relato. Saludos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 10<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>10 Mi nombre es Xavier. Ya hace tiempo con mi futura esposa Vivi y yo estamos variando en el sexo. Llevamos 4 a&ntilde;os de noviazgo. Ella es muy preciosa, flaca pero no tanto, piel blanca, cabello casta&ntilde;o (a veces se ti&ntilde;e negro e igual se ve buena), buenas tetas no muy grandes ni muy chicas, [&hellip;]<\/p>\n","protected":false},"author":15728,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-24892","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-infidelidad"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/24892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/15728"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=24892"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/24892\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=24892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=24892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=24892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}