{"id":25582,"date":"2020-09-03T22:00:00","date_gmt":"2020-09-03T22:00:00","guid":{"rendered":""},"modified":"2020-09-03T22:00:00","modified_gmt":"2020-09-03T22:00:00","slug":"en-la-despedida-de-soltera","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/en-la-despedida-de-soltera\/","title":{"rendered":"En la despedida de soltera"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"25582\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">2<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>&ldquo;Como est&aacute;s, sabes mi novia cumplir&aacute; a&ntilde;os y tendr&aacute; una peque&ntilde;a fiesta privada con sus amigas, pero quisiera regalarle algo diferente, yo soy 15 a&ntilde;os mayor que ella, ella tiene 24 y adem&aacute;s de eso yo soy swinger, la verdad me gustar&iacute;a darle de regalo una verga que probar y de ti me han hablado muy bien, espero me puedas ayudar&rdquo;<\/p>\n<p>La verdad ese correo me llamo mucho la atenci&oacute;n, una chica de 24 a&ntilde;os era diferente a lo que yo acostumbraba, cuando contacte al novio d enorme Edgar el me mando unas cuantas fotos de su novia Karen, una morena alta de ojos miel, tetas paradas y un trasero delicioso, obviamente acepte inmediatamente.<\/p>\n<p>&Eacute;l me dijo que tendr&iacute;a que llegar como bailar&iacute;n y hacerle un show, que una amiga de ah&iacute; grabar&iacute;a todo, acepte sin ning&uacute;n problema, era algo diferente y obvio mi f&iacute;sico me ayudar&iacute;a a hacer el trabajo.<\/p>\n<p>Maneje mi auto solo con una bata y una tanga, llegue a la direcci&oacute;n y entre hasta el departamento, toque el timbre y al menos unas 15 chicas gritaron al verme entrar.<\/p>\n<p>Me quit&eacute; la bata y empec&eacute; a bailar, ellas gritaban como locas, hab&iacute;a de todo, se&ntilde;oras mayores, unas cuantas j&oacute;venes que ni 20 a&ntilde;os ten&iacute;an y una que otra sabrosa entre ella la cumplea&ntilde;era Karen que sonriente me aplaud&iacute;a y me ped&iacute;a me quitara la tanga.<\/p>\n<p>Unas amigas le acomodaron una silla en medio de la sal me acerque moviendo mi cintura y ella me miro y empez&oacute; a tocarme las nalgas, el pegaba mi pene a su cara ella lo lamia por encima de mi tanga, fue entonces que le gritaron que me la quitara, ella con cara de caliente y su boca empez&oacute; a quitarme la tanga hasta que mi verga erecta sali&oacute;, sus gritos se alzaron m&aacute;s, &iexcl;Karen ya m&aacute;s aventada comenz&oacute; a acariciarme la verga y besarme mis entre piernas!<\/p>\n<p>-C&oacute;metela!!!<\/p>\n<p>Fueron los gritos de sus amigas que retumbaban mientras la cumplea&ntilde;era me empezaba besar los test&iacute;culos, ten&iacute;a la lengua larga y me la mamaba como si fuese una paleta, los gritos de todas aumentaban m&aacute;s.<\/p>\n<p>Saqu&eacute; de mi gabardina una crema de chantill&iacute; y comenc&eacute; a llenar la puntita de mi verga con ella, uno a uno, pas&eacute; a los lugares para que me lo chuparan, empec&eacute; con las m&aacute;s veteranas, ellas se atascaban metiendo mi verga hasta su garganta, pegadas como sanguijuelas que fue dif&iacute;cil que me soltaran, luego fui con las m&aacute;s j&oacute;venes, una me lam&iacute;a con miedo, pero al otra ocupaba sus tetas para masajearme y comerse la puntita.<\/p>\n<p>Pase a las m&aacute;s sabrosa, dos mulatas caderonas y tetonas, sonriendo se hincaron y ambas comenzaron a mam&aacute;rmela de lujo, todas gritaban como locas, fue entonces que empezaron a besarse, eso me puso m&aacute;s cliente, note que una grababa todo, me quedaba claro que esa era la infiltrada de Edgar, mientras disfrutaba la doble mamada, la festejada se despojaba de su blusa quedando en brasear.<\/p>\n<p>Me quit&eacute; a esas mulatas de encima y fui directo a besarme con ella, nos bes&aacute;bamos ante los gritos de todas, sent&iacute;a como me manoseaban, pero mi cabeza estaba ocupada en aquella hermosa mujer.<\/p>\n<p>K: &iexcl;Que rico este papacito!<\/p>\n<p>CA: &iexcl;Soy tu regalo nena!<\/p>\n<p>K: &iexcl;Y que m&aacute;s vas a hacer?<\/p>\n<p>CA: Pues b&aacute;jate y adivina a donde podemos llegar.<\/p>\n<p>Karen se arrodillo y comenz&oacute; a darme una mamada descomunal, mientras algunas se acercaban a besarme y tocarme yo disfrutaba de la rica mamada de esa chica.<\/p>\n<p>-Hazlo venir!! s&aacute;cale la leche!!<\/p>\n<p>K: &iexcl;Como ves a mis amigas!<\/p>\n<p>CA: &iquest;Estas listas para la segunda mitad?<\/p>\n<p>K: &iexcl;Claro!! &iquest;Pero aqu&iacute;?<\/p>\n<p>CA: &iexcl;O donde t&uacute; quieras!<\/p>\n<p>Karen se levant&oacute; y sonriendo me tomo de la mano y me llevo a su habitaci&oacute;n ante los gritos de todas!<\/p>\n<p>Se escuchaba un verdadero desmadre afuera, m&uacute;sica todo volumen y gritos de &aacute;nimo para Karen.<\/p>\n<p>Sin rodeo se despoj&oacute; de toda la ropa y se acoto en la cama, con su dedo me pidi&oacute; fiera a ella, sin dudarlo y con un gran salto de tigre me avente a esa morena penetr&aacute;ndola al instante.<\/p>\n<p>K: &iexcl;Ah!!! &iexcl;Uhm que rico!<\/p>\n<p>CA: &iexcl;Que caliente eres!<\/p>\n<p>K: &iquest;Qui&eacute;n te trajo?<\/p>\n<p>CA: Soy tu regalo, &iexcl;pudo ser cualquiera!<\/p>\n<p>Le apretaba las nalgas y me empujaba con fuerza a ella, nos besamos, le chupaba los pezones, la nena apretaba riqu&iacute;simo.<\/p>\n<p>Le levante las piernas y le com&iacute;a los pies, me empujaba dej&aacute;ndole ir toda mi verga, &iexcl;ella gem&iacute;a y me ped&iacute;a m&aacute;s!<\/p>\n<p>K: &iexcl;As&iacute; que rica verga!<\/p>\n<p>CA: &iquest;Oye? &iexcl;Uhm! Tienes novio?<\/p>\n<p>K: &iexcl;Ah!! S&iacute;, tengo novio, &iexcl;pero no coge como t&uacute;!<\/p>\n<p>Acost&eacute; a Karen de ladito y empec&eacute; a darle suave, le acariciaba sus muslos, sus pechos, apretaba su pez&oacute;n y jugaba su cl&iacute;toris, fue entonces que al voltear vi que en el closet estaba la chica grabando, eso me puso m&aacute;s loco, &iexcl;le jale le cabello a Karen quien gem&iacute;a m&aacute;s y m&aacute;s!<\/p>\n<p>K: &iexcl;Ay!! &iexcl;Qu&eacute; rico, uhm, as&iacute; no pares!<\/p>\n<p>CA: Que nalgas tienes, estas buen&iacute;sima, &iexcl;m&aacute;s bien parece que t&uacute; eres el regalo!<\/p>\n<p>Afuera segu&iacute;a la verbena, la chica del closet segu&iacute;a grabando y Karen segu&iacute;a gimiendo.<\/p>\n<p>K: Mi novio quiere verme con otros, uhm, &iexcl;l&aacute;stima que no est&aacute; aqu&iacute;, estar&iacute;a feliz de verte encima m&iacute;o!<\/p>\n<p>CA: Nena, tu novio me contrato, &iexcl;quer&iacute;a que te cogieran rico de cumplea&ntilde;os!<\/p>\n<p>Karen me miro seria y me pido me acostar, yo la obedec&iacute; y entonces ella subi&oacute; ensart&aacute;ndose toda y comenzado a moverse maravillosamente.<\/p>\n<p>Mov&iacute;a su cadera en c&iacute;rculos, se levantaba y se dejaba caer, yo tambi&eacute;n me mov&iacute;a, acariciaba sus muslos, nalgas y tetas, le jalaba el cabello, ella m&aacute;s se mov&iacute;a que rica cabalgada me daba.<\/p>\n<p>K: &iquest;Te gusta? &iexcl;Uhm!<\/p>\n<p>CA: &iexcl;Me encanta que rico te mueves!<\/p>\n<p>K: &iquest;As&iacute;? &iquest;Uhm y ahora?<\/p>\n<p>CA: Por dios, &iexcl;eres lo m&aacute;ximo!<\/p>\n<p>Karen se daba de sentones tan fuerte que hasta me lastimaba la verga, yo le apretaba las tetas y le mord&iacute;a los pezones, ella se dio vuelta para cabalgarme al rev&eacute;s, mientras yo le ara&ntilde;aba la espalda y pon&iacute;a mis manos en su cochino.<\/p>\n<p>CA: As&iacute;, no pares, &iexcl;uhm!<\/p>\n<p>K: &iexcl;Ah!!! Que rico, uhm, &iexcl;que verga!<\/p>\n<p>CA: &iexcl;Te mueves fenomenal!<\/p>\n<p>K: &iexcl;Tu verga me motiva!<\/p>\n<p>La cama rechinaba fuerte, la chica continuaba grabando, afuera todas gritaban, cantaban y se o&iacute;a de todo, mientras Karen me cog&iacute;a tan rico que pase de ser el cogedor al cogido.<\/p>\n<p>La puse a cuatro patas, el di un tremendo par de nalgadas, ella solita se abri&oacute; y me la pidi&oacute;.<\/p>\n<p>Yo obedec&iacute; y comenc&eacute; a met&eacute;rsela suave, mientras ella criaba sus nalgas y sus muslos, era una mujer muy carnosa, muy rica, se me hac&iacute;a incre&iacute;ble que su novio quisiera compartirla.<\/p>\n<p>K: As&iacute; que rico, uhm, &iexcl;que verga!<\/p>\n<p>CA: &iexcl;T&oacute;mala toda, uhm, t&oacute;mala!<\/p>\n<p>K: Nunca me hab&iacute;a entrado una as&iacute; de grande, &iexcl;uhm!<\/p>\n<p>CA: Aprovecha tu suerte, mu&eacute;velas, &iexcl;mueve tus nalgas nena!<\/p>\n<p>Qu&eacute; manera de moverse, las mov&iacute;a r&aacute;pido, de arriba a abajo, &iexcl;eso hac&iacute;a que me apretara m&aacute;s mi verga que sent&iacute;a como ella comenzaba a escurr&iacute; y entre jadeos y gemidos tuvo su primer orgasmo!<\/p>\n<p>K: No pares, ay que rico se siente, &iexcl;no pares!<\/p>\n<p>Como buen macho hice que se le alargara lo m&aacute;s que pude, ella gritaba y se retorc&iacute;a, eso me daba un gran placer, la tome de sus tetas y m&aacute;s r&aacute;pido se la clavaba, mi verga le entraba por completo, &iexcl;poco a poco la empalaba hasta que sus nalgas ya chocaban con mi pelvis!<\/p>\n<p>K: &iexcl;Me matas!!<\/p>\n<p>CA: &iexcl;Me muero, uhm, que rico, ah!!<\/p>\n<p>K: &iexcl;Que verga!!! Rica, d&aacute;mela, &iexcl;dame tu leche!<\/p>\n<p>CA: &iquest;Y si te pre&ntilde;o?<\/p>\n<p>K: No importa, uhm, c&oacute;geme, &iexcl;ah!!<\/p>\n<p>Me aceler&eacute; como toro y comenc&eacute; a venirme dentro de su rica concha, &iexcl;entre gemidos y mordidas tuvimos un orgasmo fenomenal!<\/p>\n<p>Quedamos pegados como perro y luego ella cayo en la cama boca abajo agitada y aun con mi verga dentro que se mov&iacute;a y terminaba de escupir leche.<\/p>\n<p>K: Que rico, &iexcl;ha sido la mejor cogida en mi vida!<\/p>\n<p>CA: &iexcl;Te aseguro que de las m&iacute;as tambi&eacute;n!<\/p>\n<p>K: Espero que todo haya quedado bien grabado, jaj&aacute;, &iexcl;ya sal de ah&iacute;!<\/p>\n<p>La chica sali&oacute; del closet toda sudada, al parecer se hab&iacute;a masturbado, cuando pens&eacute; que todo termino ah&iacute;, ahora los dos hicimos un trio con ella, Karen se dio el lujo de chupar vagina y verga al mismo tiempo, que rico cog&iacute;a, era una diosa sexual.<\/p>\n<p>Luego al salir del cuarto algunas se me lanzaron y tuve que darles unas cuantas metidas de verga y un poco de semen, eran insaciables, pero aun as&iacute; les di batalla, todas terminaron contentas y llenas de semen, incluso las m&aacute;s j&oacute;venes.<\/p>\n<p>Unos d&iacute;as despu&eacute;s recib&iacute; un correo de Edgar.<\/p>\n<p>&ldquo;Muchas gracias, que rico la pasaste te envidio, pero quiero agradecerte por liberar a mi chica, ahora es m&aacute;s puta en la cama y luego de ver c&oacute;mo te la cogiste me dan ganas de compartirla m&aacute;s, gracias y te inclu&iacute; una buena propina&rdquo;<\/p>\n<p>CORNEADOR AN&Oacute;NIMO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>2 &ldquo;Como est&aacute;s, sabes mi novia cumplir&aacute; a&ntilde;os y tendr&aacute; una peque&ntilde;a fiesta privada con sus amigas, pero quisiera regalarle algo diferente, yo soy 15 a&ntilde;os mayor que ella, ella tiene 24 y adem&aacute;s de eso yo soy swinger, la verdad me gustar&iacute;a darle de regalo una verga que probar y de ti me han [&hellip;]<\/p>\n","protected":false},"author":13484,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-25582","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-infidelidad"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/25582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/13484"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=25582"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/25582\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=25582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=25582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=25582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}