{"id":35064,"date":"2022-06-02T22:00:00","date_gmt":"2022-06-02T22:00:00","guid":{"rendered":""},"modified":"2022-06-02T22:00:00","modified_gmt":"2022-06-02T22:00:00","slug":"mi-mujer-es-actriz-porno","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/mi-mujer-es-actriz-porno\/","title":{"rendered":"\u00bfMi mujer es actriz porno?"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"35064\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">6<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 10<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Qued&eacute; con mi amigo Tony en un bar-cafeter&iacute;a, despu&eacute;s del trabajo. Por lo visto, ten&iacute;a algo muy importante que decirme. No quiso contarme nada m&aacute;s, quer&iacute;a tenerme delante, seg&uacute;n me dijo. Al capullo le gustaba hacerse el interesante, pero no era un fanfarr&oacute;n, as&iacute; que le hice caso.<\/p>\n<p>Despu&eacute;s de tomarnos un par de vinitos y hablar de chorradas, le dije:<\/p>\n<p>\u2015Bueno, &iquest;entramos en materia, o qu&eacute;? &iquest;Me vas a contar eso que es tan importante?<\/p>\n<p>&Eacute;l dej&oacute; escapar una sonrisilla maligna, pero en seguida se reprimi&oacute;.<\/p>\n<p>\u2015Berto \u2015me dijo\u2015, no es broma, &iquest;eh? Esto no te va a gustar.<\/p>\n<p>\u2015Venga, t&iacute;o, d&eacute;jate de rollos y su&eacute;ltalo ya.<\/p>\n<p>\u2015Ok. Tu mujer te la pega con otro.<\/p>\n<p>Me qued&eacute; parado mir&aacute;ndolo.<\/p>\n<p>\u2015&iquest;Qu&eacute; dices?<\/p>\n<p>\u2015Lo que oyes.<\/p>\n<p>\u2015Tony, me cago en la hostia, no bromees con estas cosas. &iquest;Es el d&iacute;a de los inocentes, o qu&eacute;?<\/p>\n<p>\u2015Berto, tu mujer se est&aacute; tirando a otro. No te vacilar&iacute;a con algo as&iacute;.<\/p>\n<p>\u2015Pues, amigo, vas a tener que darme un argumento s&oacute;lido. &iquest;En qu&eacute; te basas para decir eso? Mapy no me ha dado nunca el menor motivo para dudar de ella.<\/p>\n<p>\u2015Las cosas no son a veces lo que parecen. Y que conste que tu mujer me cae muy bien, &iquest;eh?<\/p>\n<p>\u2015Pues, te lo repito, vas a tener que darme algo s&oacute;lido para que me crea eso. &iquest;En qu&eacute; te basas?<\/p>\n<p>\u2015La he visto \u2015me dice.<\/p>\n<p>\u2015&iquest;La has visto con el tipo? &iquest;D&oacute;nde?<\/p>\n<p>\u2015En la cama.<\/p>\n<p>Me qued&eacute; otra vez parado mir&aacute;ndolo.<\/p>\n<p>\u2015&iquest;Y eso c&oacute;mo es posible? &iquest;Te metiste en el armario?<\/p>\n<p>\u2015T&uacute; sabes d&oacute;nde vivo, &iquest;verdad?<\/p>\n<p>Pues s&iacute;, viv&iacute;a en un edificio de 14 plantas, y justo delante del suyo hab&iacute;a otro id&eacute;ntico. Yo estaba empezando a acojonarme.<\/p>\n<p>\u2015S&iacute;, &iquest;y qu&eacute;?<\/p>\n<p>\u2015Y tambi&eacute;n sabes que tengo una afici&oacute;n particular.<\/p>\n<p>En cuanto dijo eso, me vino a la mente su telescopio y su c&aacute;mara con teleobjetivo. Al t&iacute;o le gustaba espiar a los vecinos de enfrente. A veces pillaba a alguno que otro en las situaciones m&aacute;s indiscretas. Uno de los vecinos era una especie de exhibicionista. Le gustaba llevarse a las t&iacute;as a la cama y dejar el ventanal de su alcoba con las cortinas descorridas. Yo mismo hab&iacute;a visto algunos de sus v&iacute;deos en los que grab&oacute; al tipo follando.<\/p>\n<p>\u2015&iquest;La has pillado?<\/p>\n<p>Tony sac&oacute; su m&oacute;vil, busc&oacute; en una carpeta y le dio al play. Se ve&iacute;a a mi mujer con el exhibicionista follando a todo trapo en la alcoba. El humo empez&oacute; a salirme por las orejas.<\/p>\n<p>\u2015Pero me cago en&#8230; &iexcl;Qu&eacute; hija de puta! \u2015dije.<\/p>\n<p>Se la ve&iacute;a perfectamente comi&eacute;ndole la polla al tipo, haciendo el 69, a cuatro patas mientras &eacute;l se la met&iacute;a por el co&ntilde;o y por el culo. C&oacute;mo gozaba la maldita.<\/p>\n<p>Tony se ech&oacute; hacia atr&aacute;s en la silla y me dej&oacute; a m&iacute; viendo el v&iacute;deo. Supongo que le parec&iacute;a feo estar viendo esas im&aacute;genes delante de m&iacute;, pero me imaginaba que se hab&iacute;a hecho mil pajas viendo c&oacute;mo follaba mi mujer.<\/p>\n<p>\u2015La muy zorra&#8230; \u2015segu&iacute;a diciendo yo. No pod&iacute;a apartar los ojos de la pantalla, all&iacute; en la cafeter&iacute;a.<\/p>\n<p>Me lo tragu&eacute; enterito. La muy cabrona hac&iacute;a cosas que jam&aacute;s hab&iacute;a hecho conmigo. El t&iacute;o la agarraba del pelo y le restregaba la polla por toda la cara. Ella se tocaba el co&ntilde;o mientras &eacute;l le daba pollazos, se ve&iacute;a que le gustaba. &iquest;Y cu&aacute;ndo se la hab&iacute;a metido yo por el culo? &iexcl;Jam&aacute;s! Eso eran &laquo;cochinadas&raquo;. Era lo que me dec&iacute;a a m&iacute;. Joder, qu&eacute; pedazo de puta&#8230;<\/p>\n<p>Cuando acab&oacute; el v&iacute;deo, me qued&eacute; como alelado, con la mirada perdida. Estaba en shock. Me parec&iacute;a incre&iacute;ble.<\/p>\n<p>\u2015Lo siento, t&iacute;o \u2015dijo Tony\u2015, pero creo que ten&iacute;a que dec&iacute;rtelo.<\/p>\n<p>\u2015&iquest;Desde cu&aacute;ndo lo sabes?<\/p>\n<p>Tony se call&oacute; un momento. Me tem&iacute;a lo peor.<\/p>\n<p>\u2015Un mes, m&aacute;s o menos.<\/p>\n<p>\u2015Ya&#8230; Vamos, que te has puesto las botas, &iquest;no?<\/p>\n<p>Sonri&oacute; con un lado de la boca.<\/p>\n<p>\u2015Berto, no te l&iacute;es. Te lo estoy diciendo. Pod&iacute;a haberme callado.<\/p>\n<p>\u2015Tienes raz&oacute;n.<\/p>\n<p>Me qued&eacute; pensando. Entonces, le dije de pronto.<\/p>\n<p>\u2015&iquest;Tienes m&aacute;s v&iacute;deos?<\/p>\n<p>Se lo pens&oacute; antes de contestar. Era obvio.<\/p>\n<p>\u2015Unos pocos.<\/p>\n<p>\u2015&iquest;Podr&iacute;as editarlos y hacer uno&#8230; para m&iacute;?<\/p>\n<p>\u2015No te entiendo.<\/p>\n<p>\u2015Que si podr&iacute;as editarlos, joder, recortar aqu&iacute; y all&iacute;, sacar planos cortos en los que no se vieran las caras. Y al final vas ampliando el zoom hasta que aparezcan enteritos, como dios los trajo al mundo, con sus caras de disfrute.<\/p>\n<p>\u2015Pues claro que podr&iacute;a.<\/p>\n<p>\u2015Vale, entonces haz uno bueno. Los sacas como te acabo de decir y luego, justo delante, pegas el v&iacute;deo original completo, pero sin editarlo, que se les vea todo el tiempo enteritos, &iquest;ok?<\/p>\n<p>\u2015Claro, t&iacute;o, lo que t&uacute; quieras.<\/p>\n<p>\u2015Ok, hazlo y me avisas cuando lo tengas. Te pago y todo.<\/p>\n<p>\u2015Venga, no seas gilipollas. Te aviso cuando lo tenga. &iquest;Te vale con diez minutos de grabaci&oacute;n?<\/p>\n<p>\u2015M&aacute;s que suficientes. Pero saca las partes clave, sabes lo que te digo, &iquest;no?<\/p>\n<p>\u2015Entendido. Eres la hostia \u2015me dijo descojonado.<\/p>\n<p>Me fui a mi casa echando chispas. Tuve que serenarme en el garaje y respirar hondo, porque no quer&iacute;a que Mapy me lo notara. Estaba con su indumentaria cl&aacute;sica para estar en casa: pantaloncito de pijama de algod&oacute;n, calcetinitos, y camiseta holgada. Estaba comi&eacute;ndose una tarrina de helado de H&auml;agen-Dazs. Ojal&aacute; se atragantara. Le di un beso al llegar y me fui a la nevera a coger algo de comer.<\/p>\n<p>\u2015&iquest;Qu&eacute; tal? \u2015me pregunt&oacute;.<\/p>\n<p>\u2015Bien. Estuve con Tony. Me cont&oacute; una historia de lo m&aacute;s rocambolesca.<\/p>\n<p>\u2015De Tony me espero lo que sea. &iquest;Qu&eacute; historia?<\/p>\n<p>\u2015Pues algo de cuernos y tal. En fin, locuras suyas.<\/p>\n<p>Ella no contest&oacute; enseguida.<\/p>\n<p>\u2015Ya&#8230;<\/p>\n<p>Despu&eacute;s me di una ducha. Ten&iacute;a que distraerme como fuera para no saltar. No pod&iacute;a borrar de mi mente aquellas im&aacute;genes. Y luego verla a ella all&iacute; viendo la tele tan tranquila y modosita, con su pijamita de ositos&#8230;<\/p>\n<p>Tras unos d&iacute;as, me las fui ingeniando para hacerle ver que quer&iacute;a hacer cosas &laquo;nuevas&raquo; con ella, darle un poco de salsa a nuestras relaciones.<\/p>\n<p>\u2015Es que siempre hacemos lo mismo \u2015le dije\u2015. No est&aacute; mal variar, &iquest;no? Todo el mundo lo hace.<\/p>\n<p>\u2015&iquest;Ya est&aacute;s otra vez con esas cosas?<\/p>\n<p>La muy cabrona segu&iacute;a haci&eacute;ndose la se&ntilde;orita recatada. Ten&iacute;a huevos la cosa.<\/p>\n<p>\u2015&laquo;Esas cosas&raquo; se llama sexo, Mapy. No pican, &iquest;eh?<\/p>\n<p>\u2015Mira que eres pesado. &iquest;Y qu&eacute; has pensado?<\/p>\n<p>\u2015No s&eacute;, ver una peli porno juntos, por ejemplo. Nunca lo hemos hecho.<\/p>\n<p>Ella hizo un gesto de fastidio.<\/p>\n<p>Al final la fui convenciendo hasta que acept&oacute; a rega&ntilde;adientes. Qu&eacute; suplicio, la pobre, tener que ver esas &laquo;cochinadas&raquo; conmigo. Me daban ganas de carg&aacute;rmela.<\/p>\n<p>Por fin, el v&iacute;deo estaba preparado y fui a recogerlo. Era viernes, as&iacute; que esa misma noche llevar&iacute;a a cabo mi plan. Cuando llegu&eacute; a casa tras el curro, me di una buena ducha, com&iacute; algo ligero y dej&eacute; que pasaran algunas horas hasta que se hicieron las diez.<\/p>\n<p>\u2015&iquest;Te parece si probamos ahora? \u2015le dije a Mapy.<\/p>\n<p>\u2015&iquest;El qu&eacute;, lo del v&iacute;deo? \u2015me pregunt&oacute; como con desgana.<\/p>\n<p>\u2015S&iacute;. Venga, ponte algo apropiado, bragas y camisa sin sujetador.<\/p>\n<p>Se me qued&oacute; mirando con cara de &laquo;eres un cerdo salido&raquo;, pero al final lo hizo. Yo acab&eacute; en un santiam&eacute;n: me puse un b&oacute;xer bien el&aacute;stico y sanseacab&oacute;. Ella regres&oacute; con unas bragas de encaje azul turquesa y una camiseta suelta. Al caminar, los pezones le bailaban bajo la tela. Pas&oacute; por delante de m&iacute; y se ech&oacute; en el sof&aacute;. Las braguitas se le met&iacute;an entre las nalgas, y vaya pedazo de nalgas.<\/p>\n<p>La verdad es que mi mujer estaba la mar de buena, con aquella melena casta&ntilde;a ondulada y espesa y aquel cuerpo de guitarra que ten&iacute;a. Entonces me asaltaron las im&aacute;genes que me ense&ntilde;&oacute; Tony en la cafeter&iacute;a y me com&iacute;an los demonios. Aunque&#8230; puede sonar de lo m&aacute;s raro e incomprensible, pero, &iexcl;tambi&eacute;n me pon&iacute;a cachondo!<\/p>\n<p>Met&iacute; el pendrive en el reproductor, nos acomodamos en el sof&aacute;, muy cerca el uno del otro, y le di al play.<\/p>\n<p>Tony lo hizo de miedo. Sacaba planos tan cortitos que no se les ve&iacute;a nunca la cara, solo los cuerpos, los torsos, las piernas y, por supuesto, las partes &iacute;ntimas. El t&iacute;o logr&oacute; sacarlos bes&aacute;ndose sin que se les reconociera. Se ve&iacute;an sus lenguas y poco m&aacute;s. En menos de un santiam&eacute;n me estaba poniendo cachondo. Saber que aquella era la lengua de la putita que ten&iacute;a a mi lado me pon&iacute;a loco.<\/p>\n<p>Se me puso la polla dura de inmediato, as&iacute; que decid&iacute; empezar a tocarme sobre la tela. Mapy me mir&oacute; hacerlo y neg&oacute; con la cabeza.<\/p>\n<p>\u2015&iquest;Qu&eacute; te pasa? \u2015le dije\u2015. &iquest;Te molesta?<\/p>\n<p>\u2015Haz lo que quieras \u2015me dijo con desd&eacute;n.<\/p>\n<p>Aquellas lenguas segu&iacute;an movi&eacute;ndose. Hay que ver c&oacute;mo la mov&iacute;a mi mujer. Conmigo no lo hac&iacute;a, desde luego. Me estaba poniendo bastante enfermo. No aguant&eacute; m&aacute;s y me la saqu&eacute;. Mapy se estaba poniendo nerviosa, se lo notaba. Le mir&eacute; de reojo y ten&iacute;a los mofletes rojos, y los pezones estaban m&aacute;s picudos de la cuenta bajo la camisa. La muy puta&#8230; &iquest;qu&eacute; estar&iacute;a pensando? &iquest;En c&oacute;mo se la clavaba aquel tipo por el culo?<\/p>\n<p>Estir&eacute; un brazo y le toqu&eacute; el co&ntilde;o a Mapy sobre las bragas.<\/p>\n<p>\u2015T&uacute; tambi&eacute;n deber&iacute;as tocarte un poco \u2015le dije.<\/p>\n<p>\u2015&iquest;Qu&eacute; haces? &iexcl;Quita! \u2015me grit&oacute; haci&eacute;ndose la santa.<\/p>\n<p>Y &iquest;a que no saben qu&eacute;? Ten&iacute;a el co&ntilde;o ardiendo. La muy zorra estaba cachonda. Por supuesto, no se lo dije, pero eso me puso cachondo como un mono. Joder, me estaban entrando unas ganas de foll&aacute;rmela que no veas. Le cog&iacute; su propia mano y se la puse en su co&ntilde;o.<\/p>\n<p>\u2015T&oacute;cate, quiero verte.<\/p>\n<p>\u2015Ay, t&iacute;o \u2015dijo la pu&ntilde;etera.<\/p>\n<p>La t&iacute;a lo hac&iacute;a a rega&ntilde;adientes, pero s&eacute; que lo estaba deseando. Los tipos de la pantalla, o sea, ella y el exhibicionista, se estaban lamiendo el cuerpo. Se ve&iacute;a la boca del t&iacute;o bajando por el cuerpo de mi mujer y mam&aacute;ndole los pezones, que los ten&iacute;a tiesos como agujas. Luego pas&oacute; a otro plano en el que era la boca de Mapy la que bajaba, hasta que se tragaba su polla. Joder, &iexcl;c&oacute;mo se la mamaba la cabrona! Yo ten&iacute;a que controlar la paja que me estaba haciendo, porque sent&iacute;a que me corr&iacute;a.<\/p>\n<p>Cuando en el v&iacute;deo se vio al t&iacute;o comi&eacute;ndole el co&ntilde;o a mi mujer, y a ella abri&eacute;ndose de piernas ofreci&eacute;ndoselo todo, yo agarr&eacute; la mano de Mapy y me la puse en la polla.<\/p>\n<p>\u2015Paj&eacute;ame \u2015le dije.<\/p>\n<p>Ella volvi&oacute; a hacer un gesto de disgusto, pero accedi&oacute;. Yo le agarraba la mu&ntilde;eca y se la mov&iacute;a arriba y abajo.<\/p>\n<p>\u2015As&iacute;, que seguro que sabes hacerlo \u2015le dije a la muy zorra.<\/p>\n<p>Mientras tanto, yo le hurgaba el co&ntilde;o y le met&iacute;a los dedos. Lo ten&iacute;a empapado, Dios santo. Le met&iacute; bien los dedos y le hurgu&eacute; dentro, sacudi&eacute;ndolos. Not&eacute; en seguida c&oacute;mo la t&iacute;a se controlaba para no moverse, pero estaba m&aacute;s que claro que su co&ntilde;o quer&iacute;a polla. Me estaba encantando aquella situaci&oacute;n, hacerla sufrir.<\/p>\n<p>Poco despu&eacute;s, en el v&iacute;deo se ve&iacute;a c&oacute;mo el t&iacute;o le daba con la polla en la cara, planos muy cortos. Mi mujer abr&iacute;a la boca todo lo que pod&iacute;a sacando la lengua y recib&iacute;a los pollazos. Me pon&iacute;a como loco verla. Estir&eacute; un brazo y la tom&eacute; por la nuca.<\/p>\n<p>\u2015Ven \u2015le dije\u2015, chupa.<\/p>\n<p>\u2015&iquest;Qu&eacute;? \u2015me dice toda alterada.<\/p>\n<p>\u2015Que chupes \u2015y segu&iacute; tirando de ella.<\/p>\n<p>\u2015Ay, d&eacute;jame. \u2015La t&iacute;a se hac&iacute;a la estrecha, pero lo hac&iacute;a con una vocecilla lastimera que me pon&iacute;a todav&iacute;a m&aacute;s cachondo, pero yo sab&iacute;a que quer&iacute;a hacerlo.<\/p>\n<p>En cuanto tuvo la polla en la boca, comenz&oacute; a mamar con deleite. Y encima vi que giraba de vez en cuando la cara y miraba el v&iacute;deo. Chupaba y miraba, la muy zorrita. Yo le met&iacute;a los dedos en el co&ntilde;o mientras tanto. Creo que no se lo hab&iacute;a visto tan h&uacute;medo nunca. &laquo;&iquest;Ser&aacute; cabrona?&raquo;, pens&eacute;.<\/p>\n<p>\u2015As&iacute;, c&oacute;metela \u2015le dije. Me habr&iacute;a encantado decirle &laquo;as&iacute;, c&oacute;metela, pedazo de puta&raquo;, pero ten&iacute;a que controlarme. Lo cierto es que me la com&iacute;a de cine.<\/p>\n<p>El v&iacute;deo avanz&oacute; y se ve&iacute;a un plano en el que el t&iacute;o se la met&iacute;a a cuatro patas, primero por el co&ntilde;o y luego por el culo. El t&iacute;o se sujetaba la polla con la mano, se la sacaba enterita y se la volv&iacute;a a meter. El agujero del culo se ve&iacute;a completamente abierto. La agarraba por la carne de las caderas y le taladraba el culo a mi mujer, que, por cierto, me segu&iacute;a comiendo la polla como nunca, inspirada por el bonito v&iacute;deo.<\/p>\n<p>Entonces, de pronto, el crac de Tony fue ampliando el zoom y fue apareciendo poco a poco la putita de mi mujer a cuatro patas, con el t&iacute;o tras ella d&aacute;ndole bien duro por el culo. Le cog&iacute;a fuerte por la melena y se la clavaba una y otra vez. Ella disfrutaba de lo lindo, su cara era la m&aacute;xima expresi&oacute;n del placer. Y justo entonces, mi mujercita gir&oacute; la cara hacia el v&iacute;deo con mi polla en la boca. Casi se atraganta.<\/p>\n<p>\u2015&iexcl;Anda, pero mira qui&eacute;n es la zorrita del v&iacute;deo! \u2015dije yo\u2015. &iexcl;Pero si es la puta de mi mujer!<\/p>\n<p>Ella se zaf&oacute; de m&iacute; como pudo, hist&eacute;rica perdida, y se qued&oacute; mirando el v&iacute;deo, con la mano tap&aacute;ndose la boca.<\/p>\n<p>\u2015Vaya, vaya, as&iacute; que te gusta que te follen bien el culo, &iquest;eh? \u2015le dije mir&aacute;ndola fijamente.<\/p>\n<p>Ella segu&iacute;a sin habla, ten&iacute;a los ojos como platos, se tapaba la boca con las dos manos. Creo que le sal&iacute;a humo de la cara. En el v&iacute;deo se ve&iacute;a ahora c&oacute;mo ella se abr&iacute;a de piernas boca arriba y el t&iacute;o se la follaba de lo lindo. Su cara de placer no se la hab&iacute;a visto en mi vida. Le gustaba tanto que enroscaba las piernas alrededor de la cintura del t&iacute;o para que no se escapara.<\/p>\n<p>\u2015&iquest;Qu&eacute; te pasa? &iquest;Viste un fantasma?<\/p>\n<p>\u2015Pero&#8230; &iquest;d&oacute;nde conseguiste&#8230;? \u2015trat&oacute; de decir.<\/p>\n<p>\u2015No te preocupes, cari&ntilde;o. Me encanta saber que has estado buscando polla por ah&iacute;. Anda, ven, hazme lo que sabes hacer \u2015le dije, y volv&iacute; a agarrarla con fuerza por la nuca y la acerqu&eacute; a mi polla.<\/p>\n<p>Ella dio un quejidito de gusto, como resisti&eacute;ndose, y not&eacute; que se pon&iacute;a cachonda perdida.<\/p>\n<p>\u2015Eso es, chupa, s&eacute; que te gusta comer pollas.<\/p>\n<p>La t&iacute;a empez&oacute; a com&eacute;rmela y enseguida se llev&oacute; la mano al co&ntilde;o para masturbarse. En la tele, hab&iacute;a comenzado la secuencia completa, sin editar. Desde el principio, se ve&iacute;a a la putita de mi mujer con el exhibicionista.<\/p>\n<p>\u2015Mira, ah&iacute; est&aacute;s otra vez \u2015dije. Su lengua volv&iacute;a a moverse en la pantalla como una culebra hambrienta.<\/p>\n<p>Empez&oacute; a chuparme como loca. Entonces yo me agarr&eacute; la polla con fuerza, la sujet&eacute; por la melena y empec&eacute; darle con ella en la cara.<\/p>\n<p>\u2015Toma, pedazo de puta. Te gusta, &iquest;verdad? \u2015le dec&iacute;a azot&aacute;ndola.<\/p>\n<p>\u2015Ay, s&iacute;, p&eacute;game \u2015me dijo la muy cabrona, abriendo bien la boca y sacando la lengua.<\/p>\n<p>&iexcl;Me estaba poniendo fren&eacute;tico! Entonces se la restregu&eacute; por la cara, se la dej&eacute; brillante de saliva y de mis flujos. Me incorpor&eacute; bruscamente y la empuj&eacute; hacia atr&aacute;s en el sof&aacute;. Le saqu&eacute; las bragas a lo bestia y antes de tirarlas al suelo las inspeccion&eacute;. No estaban mojadas, estaban encharcadas. Me las llev&eacute; a la nariz. Qu&eacute; rico ol&iacute;a la puta de mi mujer, qu&eacute; ganas de foll&aacute;rmela.<\/p>\n<p>\u2015&iquest;Te gusta que te coman el co&ntilde;ito, cari&ntilde;o? \u2015le pregunt&eacute;.<\/p>\n<p>Ella no me contest&oacute;, pero abri&oacute; las piernas y me lo ofreci&oacute;, como pidi&eacute;ndomelo. As&iacute; que enterr&eacute; mi cara en su co&ntilde;o y comenc&eacute; a mam&aacute;rselo como nunca. En la pantalla del televisor, ella estaba comi&eacute;ndole la polla al t&iacute;o otra vez y recib&iacute;a pollazos por doquier. Mientras, yo me encargaba de su co&ntilde;o con toda mi habilidad, meti&eacute;ndole los dedos, chup&aacute;ndole los labios, el cl&iacute;toris&#8230; &iexcl;C&oacute;mo gem&iacute;a, la cabrona!<\/p>\n<p>Me deslic&eacute; hacia arriba y empec&eacute; a comerle las tetas. Los pezones estaban tan duros que cuando tropezaban con mi boca los sent&iacute;a como dos garbanzos. &iexcl;C&oacute;mo se los mam&eacute;, joder!<\/p>\n<p>Entonces me quit&eacute; el b&oacute;xer, me puse encima de ella, me agarr&eacute; el nabo y se lo met&iacute; en la raja. Cuando la ten&iacute;a dentro, le cog&iacute; la cara y se la gir&eacute; hacia el televisor.<\/p>\n<p>\u2015M&iacute;rate, putita, &iquest;te gusta c&oacute;mo te lo come el cabr&oacute;n ese? \u2015El tipo ten&iacute;a la cabeza metida entre sus piernas\u2015. Hay que ver c&oacute;mo abr&iacute;as las piernas, &iquest;eh, zorra?<\/p>\n<p>Entonces comenc&eacute; a foll&aacute;rmela con todas las ganas, sujet&aacute;ndola por el pelo. La t&iacute;a gozaba de lo lindo. Me volv&iacute;a loco ver c&oacute;mo giraba la cara para mirarse en la pantalla. Yo me echaba sobre ella y le com&iacute;a la boca mientras la taladraba. Ella enrosc&oacute; sus piernas a mi alrededor para que le llegara bien dentro. Yo le hablaba al o&iacute;do.<\/p>\n<p>\u2015Aqu&iacute; ya estuvo alguien antes que yo \u2015le dec&iacute;a\u2015. El co&ntilde;o de mi mujercita ya est&aacute; usado, &iquest;verdad que s&iacute;? Estuvo buscando polla por ah&iacute; \u2015y entonces la follaba con furia.<\/p>\n<p>Mis propias palabras me encend&iacute;an a m&iacute; y ella gem&iacute;a cada vez que yo le dec&iacute;a aquellas cerdadas. Despu&eacute;s la cog&iacute; con brusquedad y la puse a cuatro patas. Empec&eacute; a hurgarle el agujero del culo. Me empap&eacute; los dedos en saliva y se lo dej&eacute; bien untadito. Luego me agarr&eacute; la polla y empec&eacute; a empujar.<\/p>\n<p>\u2015&iexcl;Ay, no! \u2015dijo mi mujercita.<\/p>\n<p>\u2015&iquest;No quieres? Claro, a ti no te gustan las cochinadas, &iquest;verdad, zorra? \u2015le dije sujet&aacute;ndola del pelo y habl&aacute;ndole el o&iacute;do\u2015. Eres muy se&ntilde;orita para eso, &iquest;no? Anda, toma, so puta \u2015le dije, y se la clav&eacute; toda.<\/p>\n<p>Ella solt&oacute; un quejido de placer. Empec&eacute; a moverme adentro y afuera con ganas. La cabrona giraba la cara hacia el televisor para verse follando en el v&iacute;deo. Me pon&iacute;a loco. Yo la ten&iacute;a sujeta con una mano por el pelo y con la otra le agarraba bien la carne de la nalga. Dios, jam&aacute;s le hab&iacute;a hecho esto, qu&eacute; burrada.<\/p>\n<p>Tras unos minutos, yo ya no pod&iacute;a m&aacute;s, estaba a punto de reventar. Me corr&iacute; dentro de su culo como nunca me hab&iacute;a corrido. Me apoy&eacute; en sus caderas para coger resuello. Estaba sudando como un cerdo, y ella igual. Nunca la hab&iacute;a visto as&iacute;.<\/p>\n<p>Me despegu&eacute; de ella y me ech&eacute; para atr&aacute;s sobre el sof&aacute;, frito total, respirando con la boca abierta. Ella se sent&oacute; sobre sus talones, cansada como yo. Vi que empez&oacute; a gotearle mi semen por el agujero del culo. La t&iacute;a no se lo cre&iacute;a. Se tapaba la boca con la mano. Luego se gir&oacute; para mirarme. Su cara era de sorpresa total, y pon&iacute;a una sonrisa p&iacute;cara que me daba un morbo de la leche. Yo estaba flipando como ella.<\/p>\n<p>No sab&iacute;amos ni qu&eacute; decirnos. Nos mir&aacute;bamos atontados perdidos. Jam&aacute;s hab&iacute;amos follado as&iacute;. Entonces, con el sudor todav&iacute;a cay&eacute;ndome por la frente, cog&iacute; el puto m&oacute;vil que estaba sobre la mesa, abr&iacute; el WhatsApp y le escrib&iacute; a Tony.<\/p>\n<p>[23:12] Berto:<\/p>\n<p>Tony, eres un puto crack. Gracias. Tengo que contarte una cosa muy importante.<\/p>\n<p>Y cerr&eacute; el m&oacute;vil. Enseguida llegaron notificaciones de mensajes entrantes. Yo sab&iacute;a que era &eacute;l, pero ahora me iba a hacer yo el interesante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 10<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>6 Qued&eacute; con mi amigo Tony en un bar-cafeter&iacute;a, despu&eacute;s del trabajo. Por lo visto, ten&iacute;a algo muy importante que decirme. No quiso contarme nada m&aacute;s, quer&iacute;a tenerme delante, seg&uacute;n me dijo. Al capullo le gustaba hacerse el interesante, pero no era un fanfarr&oacute;n, as&iacute; que le hice caso. Despu&eacute;s de tomarnos un par de [&hellip;]<\/p>\n","protected":false},"author":15675,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-35064","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-infidelidad"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/35064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/15675"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=35064"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/35064\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=35064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=35064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=35064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}