{"id":41082,"date":"2023-02-22T23:00:00","date_gmt":"2023-02-22T23:00:00","guid":{"rendered":""},"modified":"2023-02-22T23:00:00","modified_gmt":"2023-02-22T23:00:00","slug":"la-rebelion-de-mi-madre-xiv-final","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/la-rebelion-de-mi-madre-xiv-final\/","title":{"rendered":"La rebeli\u00f3n de mi madre (XIV): Final"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"41082\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">3<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 9<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Anteriormente: Mi madre obtiene la prisi&oacute;n domiciliaria y para evitar mayores conflictos paso el mayor tiempo con ella.<\/p>\n<p>La psic&oacute;loga me recomienda pasar mayor tiempo en las actividades que le agradan para que deje su postura recia que obtuvo de la c&aacute;rcel.<\/p>\n<p>As&iacute; es como una tarde pasamos cultivando la huerta y llega el atardecer encontr&aacute;ndonos todos sucios y sudados.<\/p>\n<p>Luego cada uno por turno entra a la casa dejando las prendas sucias en la entrada de la casa.<\/p>\n<p>Primero se da un ba&ntilde;o mi madre, luego yo.<\/p>\n<p>Al salir de mi ba&ntilde;o quedo solo cubierto con una diminuta toalla que cubre mis partes nobles.<\/p>\n<p>Mi madre me espera afuera con unas copas de vino, me invita a pasar a su cuarto para darme una toalla m&aacute;s grande.<\/p>\n<p>Ella vestida solo con un deshabill&eacute; me hace pasar hasta llegar a donde tiene las toallas, all&iacute; comienza a secarme poco a poco.<\/p>\n<p>El cap&iacute;tulo anterior termina cuando mi madre se arrodilla frente a m&iacute; y sec&aacute;ndome desde los pies hacia arriba llega hasta mis test&iacute;culos.<\/p>\n<p>Sus manos rodean mi cadera y su cara se eleva hacia mis partes prohibidas.<\/p>\n<p>El rostro de mi madre hurga debajo de la diminuta toalla que cubre mi desnudez, y la levanta para tener acceso a mis test&iacute;culos.<\/p>\n<p>Siento la electricidad en mi cuerpo cuando sus labios y su lengua prueban uno de mis huevos.<\/p>\n<p>No puedo ver lo que hace porque la toalla que ata mi cintura cubre su rostro y lo que hace debajo de ella.<\/p>\n<p>Su lengua pasa por cada base de mis test&iacute;culos.<\/p>\n<p>Su boca se abre y sus labios se deslizan hasta darles la bienvenida a la boca de mi madre.<\/p>\n<p>Todo esto solo lo imagino y lo siento, pero no lo puedo ver. Solo veo el mover de la toalla sobre la cara de mi madre que con pericia logra dejar que la toalla llegue hasta sus ojos, dejando su mirada clavada en la m&iacute;a.<\/p>\n<p>Sus u&ntilde;as se clavan en mis muslos y ara&ntilde;an con fuerza mis nalgas.<\/p>\n<p>Termina de mamar mis huevos y comienza a probar la base del tronco de mi pene erecto.<\/p>\n<p>Siento sus labios y su lengua serpenteando. A&uacute;n no puedo ver nada, solo la toalla censurando lo que hace mi madre.<\/p>\n<p>Su boca quiere rodear el tronco, siento la saliva que se desliza. Y como el calor de mi miembro atrae la lengua de mi madre.<\/p>\n<p>Sube hasta llegar a la cabeza, al glande que estaba tirante de tanto esfuerzo por estar erecto.<\/p>\n<p>Es en ese momento cuando sus manos desanudan la toalla y dejan liberado el espect&aacute;culo.<\/p>\n<p>Mi pene est&aacute; enorme, palpitante, la boca de mi madre a escasos cent&iacute;metros.<\/p>\n<p>Me mira a los ojos como anticipandome que nada iba a detenerla hoy.<\/p>\n<p>Su boca se abre y junto con ella su lengua sale como para anticiparse.<\/p>\n<p>El aliento caliente de su boca me genera sensaciones como nunca antes y el primer contacto de su lengua en mi glande me hace bufar como un toro.<\/p>\n<p>Sus labios aprisionan el glande y lanza un fuerte suspiro mientras se dedica a recorrer cada cent&iacute;metro hasta abajo.<\/p>\n<p>En cada subir y bajar de su boca se escucha el estruendo de la saliva saliendo por los costados y su esfuerzo por respirar sin tener que sacarse mi miembro de su boca.<\/p>\n<p>Chupa como si quisiera extraer todo de m&iacute;, sus manos se apoyan en mis abdominales y en mis piernas.<\/p>\n<p>No se cuanto tiempo pasamos as&iacute; pero parec&iacute;a que el tiempo estaba detenido.<\/p>\n<p>Intento darle placer a ella bajando una mano a sus hombros para acercarme a sus tetas. Este movimiento fuerza a mi pene a salir de su boca y ella no me lo permite.<\/p>\n<p>Se pone de pie y me empuja hacia la cama con una fuerza violenta.<\/p>\n<p>Quedo en la cama boca arriba y ella sin mediar palabra se abalanza sobre m&iacute; y sigue chupando mi pija.<\/p>\n<p>Mis manos intentan jugar con sus tetas, esta vez si me lo permite, y noto que quiere girar, porque me da acceso a su espalda y sus nalgas.<\/p>\n<p>La invito con mis manos a que gire completamente, tambi&eacute;n quiero complacerla.<\/p>\n<p>As&iacute; es que ella pone cada una de sus rodillas entre mi cabeza. Mis manos invitan a que descienda para poder descubrir lo que hay debajo de ese deshabill&eacute;.<\/p>\n<p>Levantando a la cintura me doy con su culo maduro, grande, duro y una vagina con vello p&uacute;bico negro, corto, pero all&iacute; est&aacute;. No tiene inter&eacute;s en la moda de lo lampi&ntilde;o.<\/p>\n<p>Comienza a descender poco a poco, mientras chupa mi pija con m&aacute;s desenfreno.<\/p>\n<p>Mi lengua y mis labios tienen contacto con esa vulva, con esos labios grandes, el aroma es embriagante, y comienzo a chupar y meter lengua, a dar mordisquitos, a hundir mi nariz.<\/p>\n<p>Otro tiempo largo pasa mientras se nos escapan jadeos y gritos de placer.<\/p>\n<p>Pruebo la humedad de mi excitada madre y me gusta, cuando intento sacar mi boca para tomar aire ella baja m&aacute;s para que siga chupando.<\/p>\n<p>En un momento siento que estoy por venirme, se lo hago notar y ella aprieta a&uacute;n m&aacute;s sus piernas y se sienta sobre mi cara. Est&aacute; haciendo lo mismo que en el penal.<\/p>\n<p>Chupa y sus u&ntilde;as me ara&ntilde;an el abdomen y las piernas.<\/p>\n<p>Chupa y mientras ve que sigo inmovil aumenta la intensidad hasta que exploto dentro de su boca.<\/p>\n<p>Chorros de leche siento que llenan su boca y se caen a&uacute;n por el costado de sus labios.<\/p>\n<p>En ese instante tambi&eacute;n tiemblan sus piernas y desata sus jugos en mi cara y boca. Tambi&eacute;n ha tenido un orgasmo.<\/p>\n<p>Se levanta y la veo despeinada, con leche en su cara.<\/p>\n<p>Se acerca hacia m&iacute; y me besa meti&eacute;ndome la lengua con mi leche.<\/p>\n<p>Su lengua saborea sus jugos y yo saboreo mi propio semen.<\/p>\n<p>Se escapa por los costados y ella con la lengua los vuelve a meter dentro m&iacute;o.<\/p>\n<p>Pasamos varios minutos bes&aacute;ndonos hasta que ella se sienta y pone cada una de sus piernas al costado de mi abdomen.<\/p>\n<p>Su mano va hacia atr&aacute;s tomando mi miembro que estaba duro pero a&uacute;n buscando reponerse de la eyaculaci&oacute;n.<\/p>\n<p>Lo presiona desde la base y comienza a masturbarme buscando rigidez.<\/p>\n<p>Todo eso mir&aacute;ndome a los ojos, y cuando logra la m&iacute;nima rigidez se hace hacia atr&aacute;s hasta encontrar la entrada de su vagina madura.<\/p>\n<p>All&iacute; lo mete ella misma y cuando entra la cabeza mira hacia arriba pegando un grito que se debe haber escuchado en alguna casa vecina.<\/p>\n<p>Al meter cada cent&iacute;metro de mi miembro me mira a los ojos y me clava las u&ntilde;as en el pecho, agitando su pecho de la excitaci&oacute;n.<\/p>\n<p>Comienza a cabalgar, se escucha el chapoteo de sus jugos con la lubricaci&oacute;n que qued&oacute; en mi pene.<\/p>\n<p>Es un chapoteo ruidoso, aplausos de nuestros cuerpos que hacen indisimulable que estamos cogiendo como animales.<\/p>\n<p>Se saca el deshabill&eacute; de forma completa, estamos ambos desnudos, volviendo a transpirar despu&eacute;s de habernos dado un buen ba&ntilde;o.<\/p>\n<p>El brillo del sudor hace sexy sus pechos que suben y bajan por la gravedad.<\/p>\n<p>No resisto la tentaci&oacute;n de probarlos y me siento para poder comerlos.<\/p>\n<p>Mi madre acompa&ntilde;a mi cabeza con sus manos para que coma cada uno de ellos.<\/p>\n<p>&quot;chupa hijo, toma la teta de mam&aacute;&quot; me dice fuera de s&iacute; mientras sigue cabalgando.<\/p>\n<p>Mis manos toman cada una de sus nalgas ayud&aacute;ndole en la tarea de saltar sobre mi pija.<\/p>\n<p>Y le doy unas fuertes nalgadas que retumban en el cuarto.<\/p>\n<p>Siento que estoy tan caliente que necesito penetrarla m&aacute;s y m&aacute;s fuerte, as&iacute; que la levanto mientras sigo meti&eacute;ndola y de p&iacute;e la tomo de sus piernas, por debajo de las rodillas y ella sostenida de mi cuello comienza a sacudirse subiendo y bajando.<\/p>\n<p>Estamos as&iacute; un momento y la transpiraci&oacute;n hace m&aacute;s sonoro el chocar de nuestros cuerpos, mi pelo est&aacute; mojado, el cabello de mi madre tambi&eacute;n lo est&aacute;.<\/p>\n<p>&quot;segu&iacute; cogi&eacute;ndome as&iacute; de fuerte&quot; me grita mi madre.<\/p>\n<p>Y voy hasta la pared donde la apoyo y entonces tomo el control de la penetraci&oacute;n.<\/p>\n<p>Solo colgada de mi cuello es sostenida por mis brazos que debajo de sus rodillas y empujando a la pared la mantiene suspendida.<\/p>\n<p>All&iacute; comienzo a taladrar con fuerza como nunca antes, y los cuadros empiezan a caerse.<\/p>\n<p>&quot;esto quer&iacute;as putita&quot; le digo falt&aacute;ndole el respeto.<\/p>\n<p>Eso hace que apriete su vagina sobre mi miembro y una electricidad recorre su cuerpo haci&eacute;ndola venir por segunda vez, inundando mi pija de sus jugos.<\/p>\n<p>Parece que se va a desmayar, siento que sus brazos ceden su fuerza, pero no voy a dejarla hasta acabar.<\/p>\n<p>La sostengo como puedo con mis brazos mientras la embisto contra la pared. Y cuando parece que no soportar&eacute; m&aacute;s el peso muerto de mi madre, ella se pega a mi cuerpo mordi&eacute;ndome el hombro.<\/p>\n<p>Eso provoca mi segunda eyaculaci&oacute;n como si la primera no hubiera existido.<\/p>\n<p>Bombeo como puedo unos segundos m&aacute;s, pero mis piernas comienzan a temblar y nos deslizamos al suelo agitados tratando de recuperar el aire.<\/p>\n<p>Estamos ambos en el suelo buscando aire, transpirados, y con leche cayendo del interior de mi madre.<\/p>\n<p>Permanecemos unos minutos contemplandonos desnudos en el suelo.<\/p>\n<p>Pero decido ponerme de p&iacute;e y levantar a mi madre en mis brazos para acostarla en la cama.<\/p>\n<p>La tapo con la s&aacute;bana y me acuesto a su lado. Nos disponemos a dormir exhaustos por lo que hicimos las &uacute;ltimas horas.<\/p>\n<p>Estamos por caer vencidos por el sue&ntilde;o hasta que se acomoda poniendo su culo contra mi pija.<\/p>\n<p>Mi pene blando encaja entre sus nalgas fr&iacute;as y ella se acomoda de tal manera que comprime mi miembro entre ellas.<\/p>\n<p>Parece que se est&aacute; durmiendo pero se mueve, su movimiento es contra mi cuerpo y eso me impide dormir.<\/p>\n<p>Mi glande irritado sigue largando l&iacute;quido preseminal. Liquido que va cayendo en la raya de su culo.<\/p>\n<p>De repente siento la mano de mi madre en mi pene, esta mojada, llena de su saliva.<\/p>\n<p>Cada tanto la saca y vuelve a tocar mi pene con su mano ensalivada.<\/p>\n<p>Mi pija comienza a endurecerse, pero con debilidad.<\/p>\n<p>Mi madre toma mi miembro con determinaci&oacute;n y lo gu&iacute;a entre sus nalgas al &uacute;nico agujero que queda por probar.<\/p>\n<p>All&iacute; me susurra que abra sus nalgas mientras ella le indica a mi pene por donde ir&aacute;.<\/p>\n<p>Obedezco y cada mano separa esas nalgas maduras y grandes.<\/p>\n<p>El glande hace fuerza para entrar pero cuesta por la estrechez y por la falta de rigidez de mi miembro.<\/p>\n<p>Mi madre se esfuerza y empuja tambi&eacute;n para que entre de una buena vez.<\/p>\n<p>Lanza un grito desgarrador y le tiembla la mano que sosten&iacute;a mi pija, pero ya est&aacute; la cabeza adentro.<\/p>\n<p>&quot;no la saques, me duele, pero no la saques hijo&quot; me dice con voz temblorosa.<\/p>\n<p>Pasa sus dedos a su vagina tratando de sacar jugos y leche que qued&oacute; dentro y lo esparce en mi tronco.<\/p>\n<p>Me quedo inmovil y ella sola hace fuerza hacia atr&aacute;s meti&eacute;ndose cent&iacute;metro a cent&iacute;metro mi pija.<\/p>\n<p>Se dobla un poco y parece que se va a quebrar pero ella lo mantiene firme con su mano.<\/p>\n<p>Con mucha paciencia y muchos minutos llegamos hasta que mis huevos chocan contra sus muslos y mis abdominales con sus nalgas.<\/p>\n<p>All&iacute; nos movemos lentamente y mi madre pega su espalda a mi pecho y gira su cabeza buscando mi boca.<\/p>\n<p>Mis manos agarran sus pechos y mi lengua juega con su lengua de una forma caliente y perversa.<\/p>\n<p>Nos movemos muy lentamente, entra y sale con cuidado tratando de que no le duela.<\/p>\n<p>Comienza a gozar de tener la pija de su hijo adentro y los jadeos comienzan a ser m&aacute;s audibles.<\/p>\n<p>Nuevamente estoy erecto listo para seguir penetrando ese culo. Jam&aacute;s en mi vida hab&iacute;a tenido una sesi&oacute;n marat&oacute;nica de esta manera.<\/p>\n<p>Metia y sacaba y me calentaba escuchar mis bolas chocar con los muslos de mi madre.<\/p>\n<p>Pasamos de esa posici&oacute;n t&iacute;mida a ponerla en cuatro y all&iacute; mi madre se arquea poniendo su culo mas redondo a mi vista.<\/p>\n<p>La sostengo del cabello mientras taladro su enorme culo.<\/p>\n<p>&quot;si hijo, tratame como la puta que soy, llename de leche el culo&quot; me dice de una manera sucia.<\/p>\n<p>Y apoya su cabeza en el colch&oacute;n girando como puede para poder ver mi expresi&oacute;n de c&oacute;mo disfruto de met&eacute;rsela por detr&aacute;s.<\/p>\n<p>Han pasado tantas horas que amanece y los rayos de sol nos iluminan la cara.<\/p>\n<p>Esta vez no hay remordimiento, el sol no nos va a hacer entrar en raz&oacute;n, as&iacute; que sigo metiendosela.<\/p>\n<p>Me est&aacute; costando mucho terminar, es la tercera vez en una noche cuyas dos primeras fue una descarga brutal.<\/p>\n<p>Volvemos a transpirar, el sol calienta a&uacute;n m&aacute;s el cuarto donde estamos.<\/p>\n<p>Hay brillo en su culo, ese brillo de sudor, le doy unas nalgadas que hacen gritar a mi madre y la hacen mirarme a los ojos con lascivia.<\/p>\n<p>Esa mirada hace que mis huevos despidan lo &uacute;ltimo que me quedaba de reserva l&aacute;ctea.<\/p>\n<p>El bombeo comienza a relentizarse, y me dejo caer encima de mi madre.<\/p>\n<p>Ella no ha acabado as&iacute; que sigue empujando hacia atr&aacute;s a&uacute;n con mi pene desinfl&aacute;ndose.<\/p>\n<p>Lo hace con m&aacute;s fuerza y aprieta su ano para evitar que me salga.<\/p>\n<p>Me quejo del dolor que eso produce y eso parece gustarle as&iacute; que sigue haci&eacute;ndolo.<\/p>\n<p>Trato de acompa&ntilde;ar un t&iacute;mido bombeo pero ya no tengo m&aacute;s que ofrecer.<\/p>\n<p>Mi madre sigue insistiendo movi&eacute;ndose circularmente mientras mis manos tratan de compensar con su cl&iacute;toris y sus tetas.<\/p>\n<p>Es entonces que en esa estimulaci&oacute;n acaba por tercera vez mojando mis dedos y la cama.<\/p>\n<p>La s&aacute;bana ha quedado en el suelo y no hay fuerzas para levantarla.<\/p>\n<p>Nos dejamos vencer por el cansancio y nos recostamos sin sacar mi pene de su culo.<\/p>\n<p>Nos quedamos dormidos de esa manera.<\/p>\n<p>Pasa un tiempo y el sue&ntilde;o se interrumpe por un grito en la puerta del cuarto.<\/p>\n<p>Son la psic&oacute;loga y la enfermera. Ese d&iacute;a hab&iacute;a quedado en hacer tr&aacute;mites y pagos por lo que la enfermera que tiene llave llegar&iacute;a a cuidar a mi madre.<\/p>\n<p>Tamb&iacute;en ten&iacute;a turno con la psic&oacute;loga a quien la enfermera le dio permiso de entrada.<\/p>\n<p>Ellas vieron a una madre con su hijo dormidos en la misma cama, desnudos. Con mi pija dentro de su culo y el olor a sexo y sudor en toda la habitaci&oacute;n.<\/p>\n<p>S&aacute;banas tiradas, toallas tiradas, el deshabill&eacute; rojo sexy de mi madre tirado en el suelo.<\/p>\n<p>Cuadros ca&iacute;dos, la pared marcada con humedad y la cama llena de manchas.<\/p>\n<p>Nuestros cabellos desordenados, y las costras del semen, jugos y el sudor secos en nuestros cuerpos.<\/p>\n<p>&quot;son unos pervertidos&quot; gritan ambas y salen corriendo de la habitaci&oacute;n.<\/p>\n<p>Mi madre se levanta r&aacute;pidamente y va tras ellas. Yo busco una toalla para cubrirme.<\/p>\n<p>Mientras me anudo la toalla a la cintura escucho un grito y golpes.<\/p>\n<p>Salgo de la habitaci&oacute;n y veo a mi madre con una sart&eacute;n ensangrentada que hab&iacute;a golpeado a la enfermera.<\/p>\n<p>&quot;&iquest;qu&eacute; es lo que hiciste mam&aacute;?&quot; grito sin entender qu&eacute; pasa.<\/p>\n<p>&quot;solo forcejeamos y me defend&iacute; y se golpe&oacute; contra la pared&quot; dice mi madre mir&aacute;ndome a los ojos buscando complicidad.<\/p>\n<p>A lo lejos se escucha a la psic&oacute;loga gritando desde el port&oacute;n pidiendo auxilio.<\/p>\n<p>Mi madre sale corriendo hacia afuera con la sart&eacute;n en la mano completamente desnuda.<\/p>\n<p>Yo salgo tr&aacute;s de ella vestido solo con la toalla.<\/p>\n<p>Estaba por darle un sartenazo a la psic&oacute;loga que ped&iacute;a que alguien la rescate porque estaba el port&oacute;n cerrado para evitar que mi madre se fugue cuando lleg&oacute; a tiempo para tomarla del brazo.<\/p>\n<p>Mi madre estaba desencajada, gritaba que m&aacute;s le val&iacute;a a la psic&oacute;loga que no diga nada de lo que vi&oacute;.<\/p>\n<p>La psic&oacute;loga estaba en shock, en p&aacute;nico. Los vecinos se agolpan en la entrada del port&oacute;n.<\/p>\n<p>Llega la polic&iacute;a y dice que nos quedemos donde estamos apunt&aacute;ndonos con sus armas.<\/p>\n<p>El forcejeo con mi madre me despoja de la toalla y quedamos desnudos ante el p&uacute;blico que apunta con sus celulares y registra una noticia que se har&aacute; viral sin lugar a dudas.<\/p>\n<p>Mi madre es regresada a prisi&oacute;n. Ahora se la acusa del asesinato de la enfermera y de intento de homicidio de la psicologa.<\/p>\n<p>La psic&oacute;loga declar&oacute; que no vi&oacute; nada extra&ntilde;o entre nosotros, y que tampoco vi&oacute; que pas&oacute; con la enfermera.<\/p>\n<p>Hasta desisti&oacute; de querellar como v&iacute;ctima de intento de homicidio por lo que solo qued&oacute; firme la condena por la muerte de la enfermera.<\/p>\n<p>Cuando preguntaron porque est&aacute;bamos desnudos declaramos que est&aacute;bamos cada uno en su habitaci&oacute;n durmiendo y que mi madre crey&oacute; que la enfermera era un ladr&oacute;n y que por los medicamentos que toma no estaba l&uacute;cida para reconocer a la psic&oacute;loga.<\/p>\n<p>No alcanz&oacute;, ella fue presa, yo qued&eacute; libre.<\/p>\n<p>Los videos que grabaron los vecinos se hicieron tendencia en las redes sociales.<\/p>\n<p>Muchos rumoreaban de porque est&aacute;bamos desnudos m&aacute;s con los rumores que hab&iacute;an corrido en las penitenciarias con las guardias que hab&iacute;an sido testigos pero cuyo testimonio fue comprado a cambio de dos autos.<\/p>\n<p>Lo que queda es la fantas&iacute;a, el rumor popular de lo que hicimos mi madre y yo en esa noche final.<\/p>\n<p>Ya han pasado dos a&ntilde;os, y le quedan trece a&ntilde;os m&aacute;s en la c&aacute;rcel.<\/p>\n<p>Me ha llegado la notificaci&oacute;n de que accedi&oacute; al beneficio de visitas privadas en un cuarto y que mi madre solo quiere pasar tiempo con su hijo.<\/p>\n<p>As&iacute; que ah&iacute; me dirijo en unas horas.<\/p>\n<p>Fin<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 9<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>3 Anteriormente: Mi madre obtiene la prisi&oacute;n domiciliaria y para evitar mayores conflictos paso el mayor tiempo con ella. La psic&oacute;loga me recomienda pasar mayor tiempo en las actividades que le agradan para que deje su postura recia que obtuvo de la c&aacute;rcel. As&iacute; es como una tarde pasamos cultivando la huerta y llega el [&hellip;]<\/p>\n","protected":false},"author":10738,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-41082","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/41082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/10738"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=41082"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/41082\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=41082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=41082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=41082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}