{"id":44465,"date":"2024-01-21T23:00:00","date_gmt":"2024-01-21T23:00:00","guid":{"rendered":""},"modified":"2025-03-18T16:39:29","modified_gmt":"2025-03-18T15:39:29","slug":"micaela-y-sus-sobrinos-iv-hora-del-postre","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/micaela-y-sus-sobrinos-iv-hora-del-postre\/","title":{"rendered":"Micaela y sus sobrinos (4): Hora del postre"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"44465\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">7<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Anteriormente:<\/p>\n<p>Micaela ha visto a Marcos masturbarse tras la mampara empa\u00f1ada de la ducha, tambi\u00e9n ha visto parte de la desnudez de Agust\u00edn al entregarle la toalla.<\/p>\n<p>Ella vestida con una bata de raso bord\u00f3 corto y con vuelo permite la vista fugaz y prohibida a sus sobrinos j\u00f3venes de sus pechos, su cola y tal vez el relieve de su treinta\u00f1era vagina.<\/p>\n<p>Ya con sus sobrinos ba\u00f1ados y ella a\u00fan sin ba\u00f1arse se sientan a la mesa a comer.<\/p>\n<p>Micaela, la t\u00eda de 30 a\u00f1os de edad pasea alrededor de la mesa sirviendo personalmente vino a sus sobrinos dejando en esas posiciones ver a cada uno un poco de sus pezones, sus piernas y la parte de abajo de sus nalgas.<\/p>\n<p>Cenan y se miran entre los tres, se sonr\u00eden nerviosos los sobrinos e inventan temas de conversaci\u00f3n.<\/p>\n<p>Micaela solo tiene en mente seguir estimulando a sus hormonales sobrinos que apenas han pasado la adolescencia.<\/p>\n<p>Terminan de comer y los sobrinos que no parecen entender las indirectas de su t\u00eda solo se quedan haciendo chistes entre ellos y a lo sumo miran con disimulo tal vez guardando recuerdos para cuando se vayan a dormir.<\/p>\n<p>Agust\u00edn, el menor de los dos, decide tomar la iniciativa y se levanta con los platos para llevarlos y lavarlos.<\/p>\n<p>Marcos acompa\u00f1a levantando la mesa.<\/p>\n<p>Micaela los observa y se r\u00ede por dentro por la falta de inexperiencia con el sexo opuesto de sus sobrinos.<\/p>\n<p>Le entra culpa por sus sucios pensamientos y por todo lo que hizo para ensuciar la mente de sus sobrinos.<\/p>\n<p>Ella dice que va a darse una merecida ducha, mientras ellos lavan los platos.<\/p>\n<p>Busca una toalla y se va hacia la ducha, all\u00ed abre el agua y mientras cae por su cuerpo mira la mampara con detalle, esa donde su sobrino mayor acab\u00f3.<\/p>\n<p>Busca alg\u00fan rastro de la eyaculaci\u00f3n de su joven sobrino y se desilusiona al no encontrar nada. Marcos ha limpiado bien su obra.<\/p>\n<p>Mientras se enjabona el cuerpo, Micaela se pregunta si Marcos lo habr\u00e1 hecho pensando en ella, en su culo, en sus tetas, si habr\u00e1 pensado algo m\u00e1s perverso con su t\u00eda.<\/p>\n<p>De tanto pensar no da cuenta que sus dedos otra vez juegan con su cl\u00edtoris y con sus labios vaginales, buscando algo en su interior.<\/p>\n<p>Trata de salir del trance, arguyendo para s\u00ed que ya se masturb\u00f3 hace unas horas, como puede ser que quiera hacerlo de nuevo, \u00bfque clase de pervertida era?<\/p>\n<p>Sale al fin de la ducha, se seca un poco el cabello y el cuerpo.<\/p>\n<p>Solo vestida con la toalla sale y sus sobrinos que dormir\u00e1n en los sof\u00e1s, tienen solo una l\u00e1mpara encendida, y est\u00e1n con sus celulares.<\/p>\n<p>Micaela los saluda nuevamente mientras va a su cuarto.<\/p>\n<p>All\u00ed realiza su rutina de encremarse todo el cuerpo, nuevamente al tocar su piel y llegar hasta sus pechos los nota erectos, se mira en el espejo y sabe que est\u00e1 excitada, y es por los cuerpos juveniles de sus sobrinos de 19 y 21 a\u00f1os.<\/p>\n<p>Recuerda que ella hab\u00eda dejado su diminuta tanga roja de encaje sobre la cama del lado de frente. Ahora esta prenda estaba al rev\u00e9s. Alguien la hab\u00eda levantado.<\/p>\n<p>Tal vez Agust\u00edn, o Marcos, no se pudieron resistir y vieron la tanga de su t\u00eda sobre la cama y la examinaron.<\/p>\n<p>Ese morbo enciende m\u00e1s a Micaela quien se pone la tanga r\u00e1pidamente y ve que le queda cubriendo solo su vulva y a\u00fan as\u00ed se pueden divisar sus labios.<\/p>\n<p>por detr\u00e1s la transparencia no tapa lo poco de la l\u00ednea de su maduro culo, la tanga se pierde entre sus nalgas y sabe que est\u00e1 buena.<\/p>\n<p>Falta la parte superior y la busca en el caj\u00f3n y la encuentra, un corpi\u00f1o rojo con transparencia que trasluce los pezones rosados de Micaela.<\/p>\n<p>Vestida as\u00ed, se gusta, se ve linda. y no quiere ser linda solo para ella.<\/p>\n<p>Toma una bata de algod\u00f3n larga y blanca, decide salir.<\/p>\n<p>Pero en la puerta toma la decisi\u00f3n de dejar caer la bata y salir solo con sus prendas de ropa interior.<\/p>\n<p>\u00bfSu argumento de emergencia? Pensar\u00eda que sus sobrinos duermen.<\/p>\n<p>Al salir se encuentra con la escena de que se ponen nerviosos y se les cae el control remoto al suelo, y se abre la tapa donde est\u00e1n las bater\u00edas, que salen despedidas por debajo de un sof\u00e1.<\/p>\n<p>Hab\u00edan encendido el televisor y estaban mirando una pel\u00edcula subida de tono, de las que no son aptas para menores.<\/p>\n<p>All\u00ed Micaela no sabe qu\u00e9 reacci\u00f3n tomar y solo decide a decirles:<\/p>\n<p>&#8220;no vi nada, no se preocupen&#8221;<\/p>\n<p>Los sobrinos colorados, tratan de disculparse mientras Agust\u00edn se pone debajo del sof\u00e1 tratando de rescatar la bater\u00eda que falta para sacar el canal que miraban.<\/p>\n<p>Micaela camina con naturalidad hacia la heladera, sabiendo como va vestida y sus sobrinos dejan de mirar el televisor para ver la figura de su sexy t\u00eda modelando esa tanga que se pierde en su culo y la combinaci\u00f3n con ese corpi\u00f1o que invita a sac\u00e1rselo con los dientes.<\/p>\n<p>Ella les da la espalda mientras abre la heladera y busca algo.<\/p>\n<p>All\u00ed toma un pote de cerezas frescas y crema en aerosol.<\/p>\n<p>Cuando vuelve se acerca a sus sobrinos que no dejan de mirarla y les dice<\/p>\n<p>&#8220;\u00bfrecuerdan que les dije que hab\u00eda postre?&#8221;<\/p>\n<p>Agust\u00edn y Marcos est\u00e1n cada uno en su sof\u00e1 y no saben qu\u00e9 decir o hacer, de fondo la pel\u00edcula er\u00f3tica con sonidos e im\u00e1genes sugerentes.<\/p>\n<p>En medio de ellos su t\u00eda parada con esa sexy ropa interior, cerezas y crema sin sacarles los ojos de encima.<\/p>\n<p>Le pregunta a Marcos si quiere postre y este dice que s\u00ed, lo mismo con Agust\u00edn.<\/p>\n<p>Les dice que se sienten en el mismo sill\u00f3n, obedecen.<\/p>\n<p>Sus sobrinos est\u00e1n vestidos solos con sexys boxers al cuerpo que parecen van a reventar por los bultos que crecen en unos segundos.<\/p>\n<p>Micaela se arrodilla en frente de ellos y pone el pote de cerezas delante de sus rodillas.<\/p>\n<p>Toma una cereza y la llena de crema en aerosol, se acerca a Marcos, siempre arrodillada y pone una mano en su desarrollado cu\u00e1driceps para apoyarse.<\/p>\n<p>Se acerca buscando que Marcos abra sus piernas y as\u00ed lo hace, arrodillada se aproxima Micaela hasta que extiende su otra mano con la cereza con crema y la lleva a la boca de su sobrino.<\/p>\n<p>Ella abre la boca como mostr\u00e1ndole que debe abrirla como cuando eran peque\u00f1os y ella les daba de comer cuando los cuidaba.<\/p>\n<p>Marcos come la cereza mirando a su t\u00eda a los ojos.<\/p>\n<p>Micaela hace lo mismo con Agust\u00edn. Y al hacerlo se pone nervioso y se le escapa una risa que hace que la crema choque en sus labios y caiga un poco en su pectoral derecho.<\/p>\n<p>Micaela hace comer a Agust\u00edn la fruta y este quiere limpiarse y ella toma su mano impidi\u00e9ndoselo.<\/p>\n<p>Ella misma pasa su dedo limpiando la crema y se lleva esa crema a su boca mirando a los ojos a Agust\u00edn quien tiene peque\u00f1os temblores de nervios y excitaci\u00f3n.<\/p>\n<p>Vuelve con Marcos y esta vez a prop\u00f3sito Micaela pone exceso de crema y hace chocar los labios para que caiga por el costado de su barbilla y caiga en el pectoral.<\/p>\n<p>Marcos entiende que no debe limpiarse, no lo intenta.<\/p>\n<p>Micaela arrodillada entre las piernas de su sobrino mayor se acerca y mientras su mano izquierda se apoya en el muslo y el boxer usa su derecha para limpiar la crema de la barbilla, pero esta vez se lo hace comer a su sobrino de su dedo.<\/p>\n<p>Obediente Marcos lo hace y Micaela deja fluir un gemido, que es cubierto por los gemidos de la pel\u00edcula er\u00f3tica de fondo.<\/p>\n<p>Se acerca un poco m\u00e1s y al limpiar la crema del pecho se lo lleva a su boca, pero ha quedado algo, no lo ha limpiado bien.<\/p>\n<p>esa peque\u00f1a marca de crema blanca est\u00e1 all\u00ed a\u00fan, y Micaela se acerca pero esta vez con su boca, y pasa su lengua por el pecho joven de su sobrino para limpiar lo que falta.<\/p>\n<p>Lo hace lentamente, al acercarse pasa su lengua de tal manera que tanto Marcos como Agust\u00edn pueden ver la tarea de limpieza de la t\u00eda.<\/p>\n<p>Vuelve Micaela a su posici\u00f3n inicial, arrodillada entre sus sobrinos que est\u00e1n sentados esperando el pr\u00f3ximo paso.<\/p>\n<p>Ella le da las cerezas a Marcos y la crema a Agust\u00edn y dice:<\/p>\n<p>&#8220;ahora me tienen que dar el postre a mi&#8221;<\/p>\n<p>Marcos toma una cereza y se la acerca a la boca a su t\u00eda, ella abre la boca y saca su lengua para que la deposite all\u00ed. Sonr\u00ede a su sobrino al comerse la cereza y le devuelve el carozo a la mano.<\/p>\n<p>Mira a Agust\u00edn que ya sabe que tiene que darle crema con el aerosol.<\/p>\n<p>Micaela arrodillada pone la cabeza hacia arriba y abre la boca sacando la lengua esperando lo que Agust\u00edn le va a dar, cae la crema e inunda la boca de la perversa t\u00eda.<\/p>\n<p>Ella lo saborea y pasa su lengua por sus labios sacando todo resto mostrando que no va a perder ni una gota.<\/p>\n<p>Ahora les pide que se pongan de pie y ella seguir\u00e1 arrodillada, quiere que le den la cereza y la crema uno a cada lado.<\/p>\n<p>Marcos tiene una erecci\u00f3n de tal manera que infla su boxer de manera brutal a tal punto que la punta de su glande aparece por debajo.<\/p>\n<p>Agust\u00edn tambi\u00e9n esta erecto, pero se acomod\u00f3 de tal forma que su miembro adolescente hace su aparici\u00f3n por el el\u00e1stico superior.<\/p>\n<p>Micaela desde su posici\u00f3n de rodillas tiene la mejor vista de las cabezas de las enormes pijas de sus sobrinos. Ambas brillan en ese living y ella lo sabe.<\/p>\n<p>Marcos le da la cereza y Micaela la come muy cerca de su boxer, prueba tambi\u00e9n la crema de Agust\u00edn acerc\u00e1ndose con descaro casi para oler las bolas de su sobrino.<\/p>\n<p>Marcos toma la iniciativa y pone la cereza muy cerca de su impresionante cabeza de pene que sale por debajo del boxer.<\/p>\n<p>Micaela se eleva solo un poco, siempre arrodillada, y apoya una mano en cada muslo de cada sobrino.<\/p>\n<p>Intenta atrapar la cereza pero torpe su lengua sigue de largo y toca el glande lubricado de l\u00edquido preseminal de Marcos.<\/p>\n<p>Vuelve a intentar y esta vez sus labios y su lengua rodean la cabeza de ese joven pene.<\/p>\n<p>No quiere dejar a Agust\u00edn fuera del show y la mano que apoyaba su muslo, comienza a subir y se mete por debajo del boxer hasta que sus dedos alcanzan a tocar las enormes bolas cargadas de leche del sobrino menor.<\/p>\n<p>Ya la cereza est\u00e1 de m\u00e1s, Micaela ya rodea con su lengua el glande enorme de su sobrino, sus labios calientes y rojos ya se apresuran a intentar cubrir suavemente la enormidad de esa cabeza.<\/p>\n<p>Mientras su otra mano independiente de ella, sigue subiendo por dentro del boxer de Agust\u00edn y toma las bolas con suavidad, est\u00e1n depiladas, est\u00e1n calientes y hasta le pesan en la delicada mano de Micaela.<\/p>\n<p>La escena es totalmente er\u00f3tica.<\/p>\n<p>Luz tenue de un \u00fanico velador, los flashes de la pel\u00edcula er\u00f3tica de fondo<\/p>\n<p>Micaela arrodillada sumisa ante sus dos potentes sobrinos j\u00f3venes<\/p>\n<p>La boca de ella probando por primera vez la enorme cabeza de la pija de Marcos y su otra mano metida dentro del boxer midiendo las bolas de Agust\u00edn.<\/p>\n<p>Ya nada podr\u00e1 detenerlos.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>\u00bfQue les va pareciendo la historia? gracias por los comentarios, los voy teniendo en cuenta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>7 Anteriormente: Micaela ha visto a Marcos masturbarse tras la mampara empa\u00f1ada de la ducha, tambi\u00e9n ha visto parte de la desnudez de Agust\u00edn al entregarle la toalla. Ella vestida con una bata de raso bord\u00f3 corto y con vuelo permite la vista fugaz y prohibida a sus sobrinos j\u00f3venes de sus pechos, su cola [&hellip;]<\/p>\n","protected":false},"author":10738,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-44465","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/44465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/10738"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=44465"}],"version-history":[{"count":1,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/44465\/revisions"}],"predecessor-version":[{"id":58338,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/44465\/revisions\/58338"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=44465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=44465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=44465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}