{"id":47387,"date":"2024-05-30T22:00:00","date_gmt":"2024-05-30T22:00:00","guid":{"rendered":""},"modified":"2024-05-30T22:00:00","modified_gmt":"2024-05-30T22:00:00","slug":"eliana-e-isaac-otro-dia-madre-e-hijo","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/eliana-e-isaac-otro-dia-madre-e-hijo\/","title":{"rendered":"Eliana e Isaac otro d\u00eda (madre e hijo)"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"47387\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">23<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Hola Luis, buen d&iacute;a, quer&iacute;a que est&eacute;s al tanto de lo que estamos viviendo con mi mam&aacute;. Te env&iacute;o una nueva experiencia por si quer&eacute;s continuar el relato anterior o anexar este hermoso episodio que vivimos.<\/p>\n<p>Te recuerdo cual es el relato original: &quot;<a href=\"https:\/\/www.cuentorelatos.com\/archivos\/relato\/eliana-e-isaac-una-historia-de-amor-madre-hijo\/\">Eliana e Isaac una historia de amor (madre e hijo)<\/a>&quot;<\/p>\n<p>Recibimos un pedido de mi t&iacute;a abuela que vive en una ciudad pr&oacute;xima a la nuestra, para que la fu&eacute;ramos a cuidar hasta el regreso de su hija, ella estar&iacute;a fuera aproximadamente un semana. Su casa no es tan grande, pero preparo un cuarto para nosotros, con una sola cama, pero le dijimos que no hab&iacute;a problema, nos arreglar&iacute;amos.<\/p>\n<p>Esa misma noche hicimos una cena para los tres, mama y la t&iacute;a se hablaron todo, conversaci&oacute;n de mujeres, obvio que yo estaba m&aacute;s que aburrido y no hay peor cosa que Isaac aburrido&hellip;<\/p>\n<p>Le contaba de sus tres meses de embarazo y no falto la pregunta de rigor.<\/p>\n<p>&#8211; Hay nena, &iquest;Qui&eacute;n es el padre?<\/p>\n<p>&#8211; Mira t&iacute;a, la verdad es de un novio que ten&iacute;a, al enterarse que estaba embrazada, desapareci&oacute;.<\/p>\n<p>Como corresponde, le sacaron bien el cuero al &ldquo;novio&rdquo; dedic&aacute;ndole insultos varios.<\/p>\n<p>Mientras ellas hablaban, se me ocurri&oacute; una maldad, baj&eacute; mi mano para acariciar la pierna de mama, mientras acariciaba sus muslos y hacia pasadas por su vagina, a trav&eacute;s de la tela del pantal&oacute;n pude sentir, el calor que emanaba del templo de mi devoci&oacute;n.<\/p>\n<p>Eliana evitaba demostrar lo que las hormonas hab&iacute;an comenzado a hacer, teniendo que disimular. Su rostro hab&iacute;a tomado un color rojizo caracter&iacute;stico en ella cuando se excita, le costaba no moverse.<\/p>\n<p>La t&iacute;a noto algo raro en ella, cuando le pregunto, le contesto que ten&iacute;a ganas de orinar, pero como la conversaci&oacute;n estaba linda no quer&iacute;a ir al ba&ntilde;o, a lo que le dijo que valla porque era malo retener tanto tiempo la orina.<\/p>\n<p>A su regreso nos quedamos dialogando un rato m&aacute;s, creo que los gritos (debido a la sordera de la t&iacute;a) se escuchaban desde afuera de la peque&ntilde;a casa.<\/p>\n<p>Como toda persona mayor, ya el cansancio y el sue&ntilde;o hab&iacute;an empezado a hacer efecto, as&iacute; que, luego de ayudarla a acostarse nos fuimos a dormir nosotros tambi&eacute;n.<\/p>\n<p>Ingresamos al cuarto que nos hab&iacute;an acomodado para nosotros, peque&ntilde;o pero agradable, una cama de una plaza, un televisor viejo, pero en muy buen estado de uso y funcionamiento, un ropero de tres puertas, seguramente de su casamiento, con espejos en cada una, mesas de noche haciendo juego lo mismo que las dos sillas que se encontraban contra una pared.<\/p>\n<p>Nos sentamos sobre ese colch&oacute;n mullido, abrace Eliana y la bese tiernamente.<\/p>\n<p>&#8211; &iexcl;&iexcl;&iexcl;Isaac, no que nos puede escuchar la t&iacute;a!!!<\/p>\n<p>&#8211; Tranquila mama, de seguro no nos va a escuchar, tiene problemas de audici&oacute;n, est&aacute; muy sorda.<\/p>\n<p>&#8211; Ah&iacute; en la mesa te pasaste Isaac, me dejaste muy excitada.<\/p>\n<p>&#8211; Al igual que yo, me gusto la adrenalina.<\/p>\n<p>Eliana se arrodillo entre mis piernas, desabrochando mi pantal&oacute;n saco mi miembro, el que sali&oacute; disparado de la tela que lo conten&iacute;a. Lo introdujo en su boca para comenzar con otra de sus excelentes mamadas, tragando toda la extensi&oacute;n carnosa.<\/p>\n<p>Luego de su oral de pel&iacute;cula, se incorpor&oacute; para ponerla entre sus pechos y masturbarme con ellos, permiti&eacute;ndome sentir la calidez de sus senos acariciar la m&iacute;a.<\/p>\n<p>Debido a la incomodidad de la peque&ntilde;a cama, nos recostamos de lado, as&iacute; haciendo cucharita y al comp&aacute;s de sus ahogados gemidos y silenciados por su propia mano o apoyando la cara en la almohada para evitar que la t&iacute;a, a pesar de su disminuci&oacute;n auditiva pudiera escuchar algo, mi miembro se perdi&oacute; en el interior de la c&aacute;lida y h&uacute;meda vagina, al cabo de unos cuantos minutos de propiciarnos el amor sexual llego el momento de su cl&iacute;max, el que no se priv&oacute; de hac&eacute;rmelo saber, tensando sus piernas y enderezando su cuerpo para, como gran final tener un squirt, a la vez que deposite mi carga seminal dentro de ella.<\/p>\n<p>Al recuperar ambos las fuerzas, tratando de hacer el menor ruido posible hicimos lo posible por acomodar el desastre hecho sobre esa cama prestada.<\/p>\n<p>Abrazados nos dormimos hasta el d&iacute;a anterior.<\/p>\n<p>Al levantarme, ya mi madre se encontraba asistiendo a la t&iacute;a, aproveche la situaci&oacute;n para ba&ntilde;arme, riendo me met&iacute; al ba&ntilde;o.<\/p>\n<p>Mientras escuchaba que me dec&iacute;an.<\/p>\n<p>&#8211; Por fin se levant&oacute; el perezoso, vamos que se va el d&iacute;a.<\/p>\n<p>Luego de ese exquisito ba&ntilde;o me dispongo al desayuno, acerc&aacute;ndome para saludar.<\/p>\n<p>&#8211; Buen d&iacute;a Isaac, que hermoso lo pase noche.<\/p>\n<p>Me lo dijo susurrando. Por respuesta recibi&oacute; un gran masaje en su precioso trasero junto a un &ldquo;igual yo, como siempre&rdquo;<\/p>\n<p>Con el pasar de las aburridas horas, sab&iacute;a muy bien que cuidar una persona mayor no es tarea f&aacute;cil ni divertida, no hallaba que hacer, me encontraba como un oso enjaulado.<\/p>\n<p>Llego la hora en que la t&iacute;a duerme la siesta.<\/p>\n<p>Otro de mis momentos m&aacute;s esperados, ya me estaba gustando por dem&aacute;s lo peligroso de ser descubiertos, no se Eliana, pero yo ten&iacute;a tanto la libido como las hormonas a full.<\/p>\n<p>Cuando mi madre regreso de la pieza y ya en cama la t&iacute;a, me encontraba por preparar algo caliente para tomar, entro a la cocina abraz&aacute;ndome por detr&aacute;s d&aacute;ndome un fugaz beso en la nuca, girando sobre mi eje la abrazo para fundirnos en un c&aacute;lido y er&oacute;tico beso.<\/p>\n<p>&#8211; Eliana, tu culo esta entre mis planes (le dije susurrando)<\/p>\n<p>&#8211; No Isaac, tengo miedo de desgraciarme, no lo prepare acorde la situaci&oacute;n y no quiero tener un &ldquo;accidente&rdquo; justo aqu&iacute;.<\/p>\n<p>&#8211; Tranquila lo hago muy despacio.<\/p>\n<p>&#8211; Tranquilo vos, ya te voy a permitir ser el semental que sos, cuando estemos solos, sin que haya nadie cerca.<\/p>\n<p>&#8211; Se lo que te gusta.<\/p>\n<p>Bajando su jean hasta el piso observo lo hermosa que le queda su tanga, beso rozando suavemente con mis labios esos muslos apetitosos y sus gl&uacute;teos tersos a la vez que vos exponiendo su intimidad a medida que bajo esa tela que me impide acceder a pleno sobre el trofeo que quiero ganar.<\/p>\n<p>Comienzo por tomar entre mis manos sus gl&uacute;teos para separarlos, me pierdo en su espesura para apropiarme de su rosada presea. A partir de all&iacute; comenz&oacute; una danza sexual, yo hac&iacute;a mis juegos bucales en su ano y vagina y ella en mi verga sedienta de culo, altern&aacute;bamos por turnos que no establecimos, para disfrutar de nuestros genitales.<\/p>\n<p>Ah que rico el sabor de lo prohibido y el temor de ser descubiertos.<\/p>\n<p>Hasta el d&iacute;a de hoy, fui siempre suave y tomando el tiempo para todas mis acciones, pero hoy no s&eacute; qu&eacute; me pasaba, estaba como descontrolado.<\/p>\n<p>Sin previo aviso, se inclina sobre la fr&iacute;a mesada de m&aacute;rmol haciendo de lado las cosas que inertes yac&iacute;an sobre ella, sus tetas al hacer contacto con la marm&oacute;rea piedra, hizo que sus pezones se endurecieran por dem&aacute;s y su piel se erizara.<\/p>\n<p>Ya con el esf&iacute;nter expuesto tome mi dura verga y la clave casi sin piedad, hasta el fondo de sus entra&ntilde;as, ahogo un grito tapando su boca con una mano, s&eacute; que le dol&iacute;a, pero en ese momento no me importo. Al tomar conciencia de mi rudeza me detuve apoy&aacute;ndome sobre su espalda por un largo rato, pidiendo disculpas a su o&iacute;do.<\/p>\n<p>Pasado un rato comienzo a estimular su cl&iacute;toris haciendo que su cuerpo reaccionara, su cadera se meneaba al ritmo de la excitaci&oacute;n que iba creciendo al comp&aacute;s de mis caricias &ldquo;clitorianas&rdquo;.<\/p>\n<p>Luego de haber transcurrido aproximadamente unos diez minutos de un fogoso mete y saca, ambos llegamos al delicioso y esperado orgasmo, quien primero recibi&oacute; el placer fui yo, mi madre me acompa&ntilde;o como respuesta luego de sentir mi semen en el interior.<\/p>\n<p>A duras penas alcanzamos a limpiarnos como pudimos que la t&iacute;a llamo pues se hab&iacute;a despertado, al ir a levantarla me dice por lo bajo<\/p>\n<p>&#8211; Sos una porquer&iacute;a, todo tu semen se est&aacute; saliendo y corre por mis muslos, espero que la t&iacute;a no se d&eacute; cuenta.<\/p>\n<p>&#8211; Perd&oacute;n no fue mi intenci&oacute;n (lo dije riendo por dentro)<\/p>\n<p>&#8211; Entonces b&oacute;rrate esa sonrisa de la boca, te amo.<\/p>\n<p>D&aacute;ndome un cari&ntilde;oso beso fue rumbo a su tarea de cuidadora.<\/p>\n<p>El resto de los d&iacute;as que quedan hasta la llegada de la prima nos pasamos haciendo el amor a escondidas y en cuanto lugar se pudiera, &eacute;ramos dos adolescentes disfrutando de nuestra sexualidad a pleno en esta aventura que era cuidar la t&iacute;a.<\/p>\n<p>Ya habiendo regresado la prima, nos preparamos para partir al d&iacute;a siguiente, debo de reconocer que nos acostamos tarde, pero el morbo de saber que hab&iacute;a alguien m&aacute;s y tambi&eacute;n nos pod&iacute;a descubrir, encendi&oacute; m&aacute;s la llama de lo peligroso, si lo sumo a la camisa blanca transparente que me deja apreciar sus pechos hermosos y su tanga haciendo juego, decidimos un &uacute;ltimo round en casa ajena.<\/p>\n<p>Poniendo algo en la vieja T.V. a volumen bajo, me acost&eacute; boca arriba para que comience con su ritual, sabe que es una experta en el sexo oral y tambi&eacute;n que me encanta. Salta sobre m&iacute; para cabalgarme como solo ella sabe, tomado de sus gl&uacute;teos para acallar los &ldquo;aplausos&rdquo; que daban. Al ver que era inminente mi orgasmo, hizo otra cosa que sabe me encanta, saliendo de esa posici&oacute;n nuevamente introdujo mi verga en su boca para recibir su raci&oacute;n seminal.<\/p>\n<p>As&iacute; paso nuestra semana de cuidados intensivos, emprendiendo el viaje de regreso a la rutina de nuestro hogar, hablamos mucho de lo sucedido.<\/p>\n<p>&iquest;Qu&eacute; si lo repetir&iacute;amos? Por supuesto.<\/p>\n<p>Aunque ahora debemos cuidarnos un poco m&aacute;s debido a que el embarazo va en avance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>23 Hola Luis, buen d&iacute;a, quer&iacute;a que est&eacute;s al tanto de lo que estamos viviendo con mi mam&aacute;. Te env&iacute;o una nueva experiencia por si quer&eacute;s continuar el relato anterior o anexar este hermoso episodio que vivimos. Te recuerdo cual es el relato original: &quot;Eliana e Isaac una historia de amor (madre e hijo)&quot; Recibimos [&hellip;]<\/p>\n","protected":false},"author":24091,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-47387","post","type-post","status-publish","format-standard","category-amor-filial"],"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/47387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/24091"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=47387"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/47387\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=47387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=47387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=47387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}