{"id":47515,"date":"2024-06-11T22:00:00","date_gmt":"2024-06-11T22:00:00","guid":{"rendered":""},"modified":"2024-06-11T22:00:00","modified_gmt":"2024-06-11T22:00:00","slug":"desvirgando-a-mi-hija","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/desvirgando-a-mi-hija\/","title":{"rendered":"Desvirgando a mi hija"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"47515\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">63<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Soy padre soltero, siempre he sido la confidente de mi hija, pero al crecer se le hizo m&aacute;s dif&iacute;cil contarme sus cosas.<\/p>\n<p>Mi hija Camila tiene 19 a&ntilde;os, es una chica de 1.62 m, delgada, con cabello largo y ondulado de color negro azabache, piel trigue&ntilde;a y con lentes ovalados. Con un car&aacute;cter muy alegre y jovial. Usando mucho el sarcasmo, con una voz muy tierna. Su hobbie favorito es patinar, por lo que tiene movimientos gr&aacute;ciles, con piernas torneadas y firmes.<\/p>\n<p>No me hab&iacute;a en ella como mujer hasta hace poco cuando la vi en una falda, en un trabajo como animadora infantil. Pude ver sus curvas perfectas y sus piernas fuertes.<\/p>\n<p>Un d&iacute;a llegu&eacute; a casa y la encontr&eacute; llorando. Me dio mucha pena y fui a hablar con ella.<\/p>\n<p>&#8211; Pap&aacute;, no pasa nada.<\/p>\n<p>&#8211; &iquest;C&oacute;mo que nada? Si est&aacute;s hecha un mar de l&aacute;grimas.<\/p>\n<p>&#8211; Es algo muy personal. Es sobre mi novio.<\/p>\n<p>Me sorprend&iacute; porque no sab&iacute;a que mi peque&ntilde;a tuviera un novio, ni menos que le hab&iacute;a hecho da&ntilde;o.<\/p>\n<p>Le traje helado como cuando era muy peque&ntilde;a y se puso a llorar en mi hombro a moco tendido sin decir palabra hasta quedarse dormida. La cargu&eacute; y la llev&eacute; a su cama. Como cuando era peque&ntilde;a. Me dio pena, pero ya me contar&iacute;a cuando pueda.<\/p>\n<p>M&aacute;s tarde, por la noche, baj&oacute; al comedor.<\/p>\n<p>&#8211; Hola pap&aacute;, &iquest;C&oacute;mo llegu&eacute; a mi cuarto?<\/p>\n<p>&#8211; Yo te cargu&eacute;.<\/p>\n<p>Se sonroj&oacute; y me sonri&oacute; t&iacute;midamente.<\/p>\n<p>&#8211; Ahora si&eacute;ntate y come algo que te has deshidratado llorando. &mdash;le dije.<\/p>\n<p>&#8211; Gracias, papi.<\/p>\n<p>&#8211; Cuando est&eacute;s de humor me cuentas. No hay nada que ocultar.<\/p>\n<p>Comimos y vimos algo de televisi&oacute;n. Luego cada uno se fue a su cuarto.<\/p>\n<p>A la hora Camila toc&oacute; la puerta.<\/p>\n<p>&#8211; Papi, &iquest;puedo pasar?<\/p>\n<p>&#8211; S&iacute;, Cami. &mdash;Yo me encontraba leyendo unas noticias en mi Tablet.<\/p>\n<p>Ya m&aacute;s tranquila, se sent&oacute; a los pies de la cama y comenz&oacute; a contarme:<\/p>\n<p>&#8211; Papi, no te vayas a molestar. &mdash;dijo ella totalmente sonrojada.<\/p>\n<p>&#8211; Cu&eacute;ntame con confianza, hijita. &mdash;suspir&eacute; mentalmente sin tratar de darle importancia.<\/p>\n<p>&#8211; Lo que pasa es que mi novio me pidi&oacute; la prueba del amor. Pero yo nunca lo he hecho y s&eacute; que duele. Por eso me da miedo.<\/p>\n<p>&#8211; Tu novio no debe forzarte, Cami. Hacer el amor debes hacerlo cuando est&eacute;s en confianza contigo misma.<\/p>\n<p>&#8211; Cre&iacute; que estaba lista. Pero cuando &eacute;l quiso penetrarme me doli&oacute; y lo apart&eacute;. Me vest&iacute; r&aacute;pidamente y me fui. Ahora no quiero que me toque.<\/p>\n<p>&#8211; Mira Cami, tu novio tiene que entender que tiene que ser tierno y estimularte de diversas maneras para queee&hellip; este&hellip; la penetraci&oacute;n sea lo m&aacute;s f&aacute;cil posible.<\/p>\n<p>&#8211; &iquest;C&oacute;mo as&iacute;, papi? &mdash;dijo mi Cami con los ojos totalmente abiertos y el rostro enrojecido.<\/p>\n<p>&#8211; &Eacute;l debe estimularte, bes&aacute;ndote y acari&aacute;ndote. Tienes que estar lubricada para la penetraci&oacute;n. &mdash;dije con algo de fastidio y verg&uuml;enza. Es un tema dif&iacute;cil de tocar con tu hija.<\/p>\n<p>&#8211; &iquest;Podr&iacute;as ense&ntilde;arme, papi?<\/p>\n<p>&#8211; &iexcl;Ehhh! (tomando saliva)&hellip; Debes buscar tus lugares donde te dan mayor placer. &iquest;Alguna vez te has masturbado?<\/p>\n<p>&#8211; &iexcl;Nooo! -dijo Camila<\/p>\n<p>&#8211; &iexcl;Bueno! A tu madre le gustaba que le besara el cuello y bajara a su pecho.<\/p>\n<p>&#8211; Papito, &iquest;podr&iacute;as mostrarme? Por favor &mdash;dijo con voz melosa y suplicante.<\/p>\n<p>Empec&eacute; besando t&iacute;midamente sus orejas bajando por sus mejillas hacia su cuello. Su respiraci&oacute;n se hizo m&aacute;s intensa. Por lo que me anim&eacute; a seguir, con una erecci&oacute;n que se hac&iacute;a cada m&aacute;s evidente. Mi mano se desliz&oacute; por su pecho, se meti&oacute; a su brasier y empez&oacute; a masajear sus tetas. Sus pezones se pusieron erectos y su respiraci&oacute;n se hizo m&aacute;s intensa.<\/p>\n<p>&#8211; &iexcl;Ahhh! Papito. &iexcl;Para ya, por fa&rsquo;!<\/p>\n<p>Ella cay&oacute; rendida boca abajo en la cama. Yo tambi&eacute;n me puse caliente. Vi su culazo. Baj&eacute; su pantal&oacute;n de pijama, la cog&iacute; de las nalgas abri&eacute;ndolas ligeramente y empec&eacute; a lamerle la concha.<\/p>\n<p>Mi hija bufaba y gem&iacute;a, mordiendo la almohada, con los ojos en blanco.<\/p>\n<p>&#8211; &iexcl;Ohhh! &iexcl;Papi! Para, por favor, siento que algo me sale.<\/p>\n<p>Continu&eacute; chupando, sal&iacute;an m&aacute;s de sus jugos y el olor de su sexo se hizo m&aacute;s embriagante. Su sabor una mezcla de salado-amargo me hizo continuar. Sus gemidos se hicieron m&aacute;s fuertes y r&aacute;pidos.<\/p>\n<p>&#8211; &iexcl;Papito, lindo! &iexcl;Sigue! &iexcl;Sigue! &iexcl;Dame m&aacute;s!<\/p>\n<p>Hasta que se corri&oacute; en un abundante charco.<\/p>\n<p>&#8211; &iexcl;Lo siento! Creo que me orin&eacute; del gusto.<\/p>\n<p>&#8211; &iexcl;No, mi princesa! Te corriste. Las mujeres tambi&eacute;n se corren como los hombres.<\/p>\n<p>Ella mirando mi pene y mi erecci&oacute;n. Con una mirada amorosa me baj&oacute; el pantal&oacute;n y se puso a acariciarme el bulto. Luego se agach&oacute; y empez&oacute; a hacerme una paja lenta mirando mi pene como hipnotizada.<\/p>\n<p>&#8211; &iexcl;Qu&eacute; rico huele, papito!<\/p>\n<p>D&aacute;ndole un besito se lo meti&oacute; a la boca besando la punta de mi pene.<\/p>\n<p>&#8211; &iexcl;Me corro, princesa! &iexcl;Detente!<\/p>\n<p>Se detuvo de besar, pero no de pajearme con su mano. Mi semen cay&oacute; en su mano y ella lo oli&oacute; para luego probarlo.<\/p>\n<p>Luego se ech&oacute; en la cama boca arriba abriendo las piernas. Yo puse mi cabeza entre sus piernas viendo su co&ntilde;o cerrado con pelos abundantes. Me lo empec&eacute; a comer nuevamente. Luego, cambiando de posici&oacute;n. Puse mi pene a la altura de su cara sob&aacute;ndolo mientras continuaba con la comida de co&ntilde;o. Ella sac&oacute; mi verga y empez&oacute; a lamerla tiernamente. Luego de 20 minutos de placer nos corrimos en la cara de cada uno.<\/p>\n<p>&#8211; &iquest;Papi, me puedo a quedar a dormir contigo?<\/p>\n<p>&#8211; S&iacute;, mi amor.<\/p>\n<p>&#8211; Gracias, papito.<\/p>\n<p>Ella primero se acomod&oacute; en mi pecho, pero luego fue bajando m&aacute;s hasta apoyar su cabeza en mi pelvis.<\/p>\n<p>Al despertar vio mi verga con curiosidad. La sob&oacute; hasta que se fue parando.<\/p>\n<p>Luego la guie hasta la cabecera de la cama. Con mi cabeza apoyada en la almohada hice bajar su pelvis lentamente para saborear con mi lengua todas las partes de su vagina mientras con mi dedo recorr&iacute;a su cl&iacute;toris. Ella gem&iacute;a fuerte y se retorc&iacute;a.<\/p>\n<p>&#8211; &iexcl;Ya, papito! Toma mi virginidad.<\/p>\n<p>Se solt&oacute; de m&iacute; y empez&oacute; a empalarse lentamente en mi verga. Unas gotitas de sangre se deslizaron hacia las s&aacute;banas.<\/p>\n<p>Su cuerpo sub&iacute;a y bajaba al comp&aacute;s de sus gemidos. Yo intentaba de mover mi pelvis haciendo c&iacute;rculos para que sienta mi pene de lleno, mientras con mi mano le sobaba alternadamente las tetas y sus nalgas.<\/p>\n<p>Luego cambiando en la posici&oacute;n del misionero se la clav&eacute; lentamente tomando sus tobillos con mis manos para hacerlo cada vez m&aacute;s r&aacute;pido hasta correrme y terminar en su vientre.<\/p>\n<p>&#8211; &iexcl;Hay papito! Me has hecho muy feliz. He so&ntilde;ado con esto desde hace cinco a&ntilde;os. Mi cuerpo y alma te pertenecen por siempre.<\/p>\n<p>Desde ese d&iacute;a dormimos juntos. Ella apoyada en mi pecho. Pero como una peque&ntilde;a traviesa mueve sus manos a mi verga para luego ponerla en la posici&oacute;n del 69.<\/p>\n<p>A mi hija, al igual que a su difunta madre, su vagina se inflama y le duele las penetraciones que solo las podemos hacer una vez por semana. Por lo que siempre optamos por el sexo oral el resto de d&iacute;as.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>63 Soy padre soltero, siempre he sido la confidente de mi hija, pero al crecer se le hizo m&aacute;s dif&iacute;cil contarme sus cosas. Mi hija Camila tiene 19 a&ntilde;os, es una chica de 1.62 m, delgada, con cabello largo y ondulado de color negro azabache, piel trigue&ntilde;a y con lentes ovalados. Con un car&aacute;cter muy [&hellip;]<\/p>\n","protected":false},"author":29105,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-47515","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/47515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/29105"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=47515"}],"version-history":[{"count":0,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/47515\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=47515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=47515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=47515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}