{"id":52926,"date":"2024-08-16T10:41:53","date_gmt":"2024-08-16T08:41:53","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/?p=52926"},"modified":"2024-08-16T10:42:13","modified_gmt":"2024-08-16T08:42:13","slug":"ninfomano-capitulo-8-mis-hermanos-se-tragaron-mi-semen","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/ninfomano-capitulo-8-mis-hermanos-se-tragaron-mi-semen\/","title":{"rendered":"Ninf\u00f3mano (cap\u00edtulo 8): Mis hermanos se tragaron mi semen"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"52926\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">27<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Por fin recib\u00ed otra visita de mis hermanos Mauro y Carlos, como extra\u00f1\u00e9 a esos dos locos, desde nuestro \u00faltimo encuentro sexual no hab\u00edamos tenido mucha comunicaci\u00f3n, se perdieron por varias semanas a un viaje a no s\u00e9 d\u00f3nde, siempre de misteriosos esos dos.<\/p>\n<p>Recuerdo como fue nuestra primera vez, tantos nervios, una completa locura el tr\u00edo que hicimos despu\u00e9s de conversar entre hermanos tantas cosas (esa es una historia que ya he contado en cap\u00edtulos anteriores y que no te puedes perder, porque cr\u00e9eme, mis hermanos son hermosos y demasiado calientes).<\/p>\n<p>Llegaron de sorpresa a mi casa, ni un mensaje de texto fueron capaces de enviarme para avisarme de su visita, pero aun as\u00ed, yo los recib\u00ed tan contento, apenas abr\u00ed la puerta les salt\u00e9 encima y me los com\u00ed a besos.<\/p>\n<p>Entraron a la casa, me comieron a besos tambi\u00e9n y despu\u00e9s de ayudarlos a cargar sus maletas, nos sentamos en el sof\u00e1 de la sala a hablar durante m\u00e1s de una hora, nos contamos de todo, y pues, les parecer\u00e1 precipitado y extra\u00f1o lo que sucedi\u00f3 despu\u00e9s de la conversaci\u00f3n, pero es totalmente normal en mis hermanos.<\/p>\n<p>Al terminar de contarnos todo, Mauro puso su mano en mi pantal\u00f3n y Carlos puso la suya en el cierre de mi pantal\u00f3n; yo me los qued\u00e9 mirando y ellos sonrieron de manera p\u00edcara; en seguida les dije: &#8220;no cambian, son unos morbosos desesperados&#8221;.<\/p>\n<p>As\u00ed que la acci\u00f3n comenz\u00f3 justo en ese instante, Mauro tom\u00f3 mi pantal\u00f3n y lo baj\u00f3 por completo, y Carlos se encarg\u00f3 de bajar mi calz\u00f3n; a\u00fan segu\u00edamos sentados en la sala, y el lugar se prestaba para tener sexo muy sabroso.<\/p>\n<p>Despu\u00e9s de haberme dejado desnudo, ellos se quitaron la ropa, y la verdadera acci\u00f3n comenz\u00f3, no hicimos gran cosa a nivel sexual, pero la sensaci\u00f3n y el morbo fue muy intensa.<\/p>\n<p>Nos levantamos del sof\u00e1, luego mis hermanos se arrodillaron para chuparme los huevos y el pene, se turnaban, y mientras ellos me daban placer yo observaba todos sus movimientos, sus cuerpos totalmente desnudos a mis pies, sus penes erectos y velludos rozando el piso mientras sus lenguas tibias lamian mis huevos y mi pene.<\/p>\n<p>Mauro no aguant\u00f3 tanta excitaci\u00f3n y se levant\u00f3 r\u00e1pido para eyacular en la boca de Carlos que en ese preciso instante estaba chupando mi pene como un desesperado, el semen de Mauro call\u00f3 en su boca y tambi\u00e9n en mi pene.<\/p>\n<p>Pasaron unos pocos minutos y Carlos reaccion\u00f3 al morbo del semen, lo que le ocasion\u00f3 un orgasmo muy fuerte, pero no se levant\u00f3, se qued\u00f3 de rodillas chupando mis huevos y mi pene mientras se ven\u00eda, as\u00ed que llen\u00f3 de semen el piso y parte de mis pies.<\/p>\n<p>Yo ya estaba por venirme, as\u00ed que les hice se\u00f1as, se sentaron r\u00e1pido en el sof\u00e1, los dos bien juntos, acerqu\u00e9 mi pene a sus caras y despu\u00e9s de una peque\u00f1a masturbada acab\u00e9 en sus bocas, ambos se pegaron a mi pene como animalitos mamando los pechos de su madre, se besaron para compartir mi leche tibia y luego se tragaron todo.<\/p>\n<p>C\u00f3mo era de costumbre entre nosotros despu\u00e9s de tener sexo, nos abrazamos y nos dimos un beso de tres. Al caer la noche nos encerramos en mi cuarto a ver pel\u00edculas, comer chucher\u00edas y a hablar de nuestras travesuras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>27 Por fin recib\u00ed otra visita de mis hermanos Mauro y Carlos, como extra\u00f1\u00e9 a esos dos locos, desde nuestro \u00faltimo encuentro sexual no hab\u00edamos tenido mucha comunicaci\u00f3n, se perdieron por varias semanas a un viaje a no s\u00e9 d\u00f3nde, siempre de misteriosos esos dos. Recuerdo como fue nuestra primera vez, tantos nervios, una completa [&hellip;]<\/p>\n","protected":false},"author":27571,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":{"0":"post-52926","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-gays"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/52926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/27571"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=52926"}],"version-history":[{"count":1,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/52926\/revisions"}],"predecessor-version":[{"id":52927,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/52926\/revisions\/52927"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=52926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=52926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=52926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}