{"id":53189,"date":"2024-08-21T01:19:58","date_gmt":"2024-08-20T23:19:58","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/?p=53189"},"modified":"2024-08-21T05:26:35","modified_gmt":"2024-08-21T03:26:35","slug":"cuentos-cortos-exhibiendo-a-mi-esposa-1","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/cuentos-cortos-exhibiendo-a-mi-esposa-1\/","title":{"rendered":"Cuentos cortos exhibiendo a mi esposa (1)"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"53189\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">44<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Con mi esposa hemos hecho tr\u00edos, ha tenido amantes que me restriega en la cara y yo he tenido sexo con su hermana, somos liberales y descubrimos que nos gusta calentar a otras personas, la primera vez fue con un conductor de Uber, solicitamos el viaje por que and\u00e1bamos muy tomados, \u00edbamos a nuestra casa, quedaba a 1 hora del centro, el viaje era algo largo para esa zona, as\u00ed que mi mujer me empez\u00f3 a manosear el pito, me dijo que quer\u00eda ir a un hotel a coger, le dije que era buena idea pero que mejor esperara a llegar a casa, no se qued\u00f3 conforme y dijo:<\/p>\n<p>&#8211; si no quieres est\u00e1 bien vamos a la casa y yo me voy a coger con el chofer.<\/p>\n<p>El conductor qued\u00f3 sorprendido, lo vi a los ojos a trav\u00e9s del retrovisor, me disculp\u00e9, explicando que andaba muy tomada mi esposa, que no le hiciera caso.<\/p>\n<p>Mi esposa continu\u00f3 diciendo que era en serio, que si ninguno de los dos quer\u00eda iba a buscar a quien darle el culo, por que andaba muy cachonda y quer\u00eda que la cogieran duro.<\/p>\n<p>El chofer solo se quedaba en silencio inc\u00f3modo por la escena y solo se limitaba a conducir.<\/p>\n<p>Mi esposa empez\u00f3 a quitarse la chamarra, y a manosear las tetas muy provocativa, empez\u00f3 a susurrarle al o\u00eddo al chofer que quer\u00eda sentir su verga dentro, que lo har\u00eda correrse como nunca y se beber\u00eda toda su leche, yo super caliente le dije que lo convenciera como ella sab\u00eda, y se acerc\u00f3 al respaldo de su asiento, estir\u00f3 su brazo hasta que alcanz\u00f3 a tomar el trozo gordo que ten\u00eda entre las piernas, claramente emocionado por lo que pasaba, empez\u00f3 a acariciarlo y seguir susurrando al o\u00eddo como quiera que se la cogieran.<\/p>\n<p>\u00c9l se sac\u00f3 la verga del pantal\u00f3n y ella comenz\u00f3 a masturbarlo, le pidi\u00f3 que se pasara al asiento del copiloto, pero mi esposa no quiso, dijo que solo la iba a tener hasta que llegaran a un hotel, el chofer me pregunt\u00f3 que a cual hotel nos lleva, le dije que a ninguno, que termine el viaje y deje de hacerle caso a mi esposa.<\/p>\n<p>Mi esposa continu\u00f3 masturb\u00e1ndolo hasta que se corri\u00f3 a chorros, est\u00e1bamos llegando a nuestra casa cuando ella tom\u00f3 un poco de su semen y le dijo al chofer con voz sexy y provocativa: si te lo comes me voy contigo y cogemos hasta que te canses. Yo incr\u00e9dulo vi como dudaba, pero al final cedi\u00f3 el chofer y se meti\u00f3 a su boca los dedos llenos de semen de mi esposa.<\/p>\n<p>Ella se baj\u00f3 del auto fue hasta la puerta del conductor la abri\u00f3 y le dio un beso apasionado con lengua y todo, tomo su mano y la coloc\u00f3 en su pecho, \u00e9l la apretaba con lujuria, terminando le sonri\u00f3 y le dijo, creo que no ir\u00e9 contigo estoy cansada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>44 Con mi esposa hemos hecho tr\u00edos, ha tenido amantes que me restriega en la cara y yo he tenido sexo con su hermana, somos liberales y descubrimos que nos gusta calentar a otras personas, la primera vez fue con un conductor de Uber, solicitamos el viaje por que and\u00e1bamos muy tomados, \u00edbamos a nuestra [&hellip;]<\/p>\n","protected":false},"author":26883,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-53189","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-infidelidad"},"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/53189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/26883"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=53189"}],"version-history":[{"count":1,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/53189\/revisions"}],"predecessor-version":[{"id":53190,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/53189\/revisions\/53190"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=53189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=53189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=53189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}