{"id":56915,"date":"2025-01-25T00:54:47","date_gmt":"2025-01-24T23:54:47","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/?p=56915"},"modified":"2025-01-26T11:48:02","modified_gmt":"2025-01-26T10:48:02","slug":"4174-mi-frustrada-madre","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/4174-mi-frustrada-madre\/","title":{"rendered":"Mi frustrada madre"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"56915\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">41<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Me llamo Guillermo. Soy un chico de 20 a\u00f1os, de cuerpo atl\u00e9tico, muy sano, bien proporcionado y cuando digo esto, creo que es importante puesto que mi pene mide unos 21 cent\u00edmetros. Hace a\u00f1os que vengo teniendo relaciones con chicas, es decir que para m\u00ed el sexo es algo habitual.<\/p>\n<p>Sin embargo, s\u00e9 que las personas de otras generaciones como las de mis padres no han podido vivir de la forma que lo hacemos ahora. Mi madre por ejemplo, es una mujer todav\u00eda joven; tiene 40 a\u00f1os es muy guapa. Se cas\u00f3 con mi padre a los 20, cuando \u00e9ste ten\u00eda 40; es decir que es 20 a\u00f1os mayor que ella. Adem\u00e1s, cuando la conoci\u00f3 ya era calvo, regordete y bastante feo.<\/p>\n<p>Mi madre no se cas\u00f3 con \u00e9l por amor o por que le gustara sino porque ten\u00eda la necesidad de ello. Salir adelante. As\u00ed ha sido en muchas familias. Bueno, luego ha sido una madraza. Se ha dedicado a m\u00ed por completo. Nunca me ha faltado de nada. Mi presencia f\u00edsica, ya digo no tiene nada que ver con la de mi padre que tiene ahora 60 a\u00f1os.<\/p>\n<p>Creo que lo que mi madre ha tenido siempre es represi\u00f3n. Lo noto muchas veces cuando me mira paseando sin camisa, o a otros chicos j\u00f3venes. Tambi\u00e9n me he dado cuenta cuando alguna de mis amigas viene a casa, me acueste o no con ellas. A veces me parece que est\u00e1 muy tensa. Si suena el tel\u00e9fono da un respingo. Es como si estuviese disimulando su sufrimiento; como si tuviese celos y lo ocultase, incluso a si misma.<\/p>\n<p>A veces me he fijado que me mira en la entrepierna.<\/p>\n<p>Esto se lo he contado a una amiga muy inteligente, que me dijo que pod\u00eda hacer algo. Exhibirme desnudo un d\u00eda haciendo como que yo no me daba cuenta o algo as\u00ed. Darle una oportunidad de disfrutar. La verdad es que esta amiga es un poco extravagante, pero es as\u00ed.<\/p>\n<p>En mi habitaci\u00f3n hay una puerta corredera, que si la cierras del todo con un enganche, te pueden ver desde fuera. Quiero decir que se puede quedar ligeramente entreabierta. Si es por la parte derecha no pasa nada pero si es por la izquierda da a un pasillo y al sal\u00f3n, que es donde est\u00e1 el tel\u00e9fono. Si alguien est\u00e1 all\u00ed sentado en el sof\u00e1 hablando te puede ver tumbado en la cama. Esa ha sido mi gran preocupaci\u00f3n a la hora de hacerme pajas. Ese lado la puerta tiene que estar cerrada porque si no te ven.<\/p>\n<p>Una tarde quise hacer caso a mi amiga. Me estaba pajeando tumbado y desnudo sobre la cama con todo mi miembro viril. La puerta corredera estaba algo abierta por su lado izquierdo. Sab\u00eda que mi madre estaba en el sal\u00f3n.<\/p>\n<p>Son\u00f3 el tel\u00e9fono. Y me qued\u00e9 all\u00ed tumbado con toda naturalidad. O\u00ed a mi madre sent\u00e1ndose en el sof\u00e1 y descolgar el auricular.<\/p>\n<p>-No. Aqu\u00ed no es -me pareci\u00f3 o\u00edrle decir.<\/p>\n<p>Luego no se percib\u00eda ning\u00fan sonido. Los sof\u00e1s son viejos y siempre se oye cuando te sientas o te levantas. Deb\u00eda estar quieta. \u00bfMe estar\u00eda viendo? Posiblemente. \u00bfPor qu\u00e9 estar\u00eda haciendo caso a la loca de mi amiga? Yo me masturbaba muy despacio. Levant\u00e9 un poco la cabeza y por un momento me pareci\u00f3 ver a mi madre que miraba y luego o\u00ed el ruido del sof\u00e1.<\/p>\n<p>Dos d\u00edas despu\u00e9s volvi\u00f3 a pasar lo mismo. Son\u00f3 el tel\u00e9fono y yo estaba haciendo lo que estaba haciendo. Entonces vi que mi madre me miraba con una sonrisa y no se levantaba. Yo soy moderno, me levant\u00e9 completamente desnudo, entr\u00e9 en el sal\u00f3n, cog\u00ed de la mano a mi madre y la llev\u00e9 a mi habitaci\u00f3n. Esta vez si que cerr\u00e9 la puerta.<\/p>\n<p>En mi dormitorio hay dos camas. Me volv\u00ed a tumbar en la m\u00eda y me madre en la otra. &#8220;Rel\u00e1jate&#8221;, le dije. &#8220;No pasa nada&#8221;. Mi madre no dejaba de sonre\u00edr, mir\u00e1ndome. Entonces se quit\u00f3 el vestido. De todas las chicas que hab\u00eda conocido, mi madre ten\u00eda uno de los cuerpos m\u00e1s bonitos, mejor formados. Lleva el pelo corto y rubio. Sus pechos no son grandes, pero son puntiagudos. Su cara sigue pareciendo la de una ni\u00f1a. No hace aer\u00f3bic y sin embargo lo parece. Jam\u00e1s hab\u00eda sentido una erecci\u00f3n as\u00ed. Pero ella no se atrev\u00eda a tocarse. Yo si, arriba y abajo.<\/p>\n<p>Entonces se levant\u00f3 con su vista clavada en mi polla, y me pas\u00f3 la lengua; luego la beso; oso tocarla; la agarr\u00f3 con toda la mano; la agito; la volvi\u00f3 a lamer; y se la meti\u00f3 en la boca; aspiraba; mov\u00eda la lengua; la volvi\u00f3 a besar. Hizo un conato de levantarse, pero antes volvi\u00f3 a pasar su lengua. Le gustaba mucho mi capullo. Finalmente se levant\u00f3 y se fue.<\/p>\n<p>Me qued\u00e9 ah\u00ed tendido.<\/p>\n<p>Una media hora despu\u00e9s volvi\u00f3 a entrar en la habitaci\u00f3n. Sus ojos estaban encelados. Deb\u00eda haber estado masturb\u00e1ndose. Se volvi\u00f3 a quitar el vestido. Me dijo que me irguiese y me sentase en la cama. Entonces ella se arrodill\u00f3 y se la meti\u00f3 en la boca. Ahora la sub\u00eda y la bajaba con ella dentro, sujet\u00e1ndola con la mano izquierda. No dejaba de salivar. Yo todav\u00eda no me hab\u00eda corrido, pero lo que estaba haciendo me gustaba mucho. Estoy acostumbrado a aguantar el orgasmo para que la otra chica disfrute.<\/p>\n<p>Mi madre con la mano libre la derecha se estaba pajeando, se acariciaba el cl\u00edtoris y se met\u00eda los dedos. Su respiraci\u00f3n era cada vez m\u00e1s intensa; se convert\u00eda en jadeos; y luego como gemidos, hasta que en unos minutos pararon. Luego volvieron de nuevo. Debi\u00f3 tener dos orgasmos. Su boca estaba llena de mis jugos y su baba.<\/p>\n<p>Cuando se march\u00f3. Me fui al servicio y eyacul\u00e9 con fuerza.<\/p>\n<p>Dos semanas m\u00e1s tarde vino una novia a mi casa para despedirse de m\u00ed. Se iba de vacaciones a Holanda. El caso es que el adi\u00f3s fue definitivo. Rompimos en ese momento. Mi madre fue testigo de ello. De verdad que esa chica me gustaba bastante y me qued\u00e9 un poco deprimido.<\/p>\n<p>Estaba tumbado en la cama con los pantalones puestos. Entr\u00f3 mi madre. Me dijo que me los quitara. Pero yo no quer\u00eda. No estaba bien. Me fije que sus ojos estaban entornad\u00edsimos. Ante mi negativa sali\u00f3 de la habitaci\u00f3n.<\/p>\n<p>Una hora despu\u00e9s explot\u00f3 en m\u00ed el deseo m\u00e1s morboso. Le dije a mi madre que viniese. Me encontr\u00f3 desnudo con mi polla totalmente erecta, bamboleante. Ella se quit\u00f3 el vestido. Yo me sent\u00e9 como la \u00faltima vez y antes de que se la metiese en la boca, literalmente se le estaba cay\u00e9ndosele la baba. Se puso otra vez arrodillada en el suelo y con una mano se acariciaba la vagina.<\/p>\n<p>Parec\u00eda no tan remilgada como las veces anteriores. Me besaba, en el torso, pasaba su lengua, me mordisqueaba los pezones. Se mov\u00eda de forma muy agitada. Me lami\u00f3 el cuello, los hombros. Y se la meti\u00f3 en la boca. La chupaba de una forma muy acelerada, yo cerraba los ojos disfrutando locamente. Sus gemidos eran bestiales. Sonaban maullidos.<\/p>\n<p>-Cabr\u00f3n de hombre -me dijo.<\/p>\n<p>Me beso en la boca y me meti\u00f3 la lengua. Luego otra vez a por mi polla. Fue bajando hasta mis test\u00edculos; apret\u00f3 con su boca uno de ellos, pero me hac\u00eda da\u00f1o y se lo dije. Entonces me lo lami\u00f3, pero segu\u00eda doli\u00e9ndome igual.<\/p>\n<p>-Levanta las piernas -me dijo-. Su voz parec\u00eda haber perdido el control.<\/p>\n<p>Hice eso y se tir\u00f3 a por mi sucio culo.<\/p>\n<p>-Mama. No -le dije.<\/p>\n<p>Esto ya lo hab\u00eda hecho en alguna ocasi\u00f3n con alguna amiga pero los dos nos hab\u00edamos puesto antes enemas.<\/p>\n<p>No me hizo caso. Mordisqueaba los gl\u00fateos y luego me lami\u00f3 el ano. Met\u00eda su lengua, me lo com\u00eda. Se apretaba como si fuera a exprimirlo. Le encantaba. Y con la mano izquierda me masturbaba, sub\u00eda y bajaba mi pene. Me sent\u00eda incapaz de aguantarme con lo que estaba haciendo. Me chupaba el culo mientras me pajeaba y ella se masturbaba. Tuve dos espasmos, se me escaparon dos flatos, sali\u00f3 un chorrazo de semen. Puse la cama, la sabana, mi cuerpo y el suyos perdidos. El suelo estaba empapado de todo lo que hab\u00eda soltado ella. No s\u00e9 si incluso se hab\u00eda llegado a mear.<\/p>\n<p>Mi madre lo limpi\u00f3 todo antes de que llegara mi padre.<\/p>\n<p>No recuerdo haberlo hecho despu\u00e9s con tanta pasi\u00f3n.<\/p>\n<p>Sigo saliendo con otras chicas y alguna vez dejo que mi madre disfrute conmigo. Nunca hemos hecho el coito.<\/p>\n<p>Lo que venimos haciendo \u00faltimamente es masturbarnos cada uno en una cama, mir\u00e1ndonos mutuamente.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_56915\" class=\"pvc_stats total_only  \" data-element-id=\"56915\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Entonces se levant\u00f3 con su vista clavada en mi polla, y me pas\u00f3 la lengua; luego la bes\u00f3; os\u00f3 tocarla; la agarr\u00f3 con toda la mano; la agit\u00f3; la volvi\u00f3 a lamer; y se la meti\u00f3 en la boca; aspiraba; mov\u00eda la lengua; la volvi\u00f3 a besar. Hizo un conato de levantarse, pero antes volvi\u00f3 a pasar su lengua. Le<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_56915\" class=\"pvc_stats total_only  \" data-element-id=\"56915\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1698,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-56915","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":true,"total_views":12404,"today_views":3},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/56915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/1698"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=56915"}],"version-history":[{"count":1,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/56915\/revisions"}],"predecessor-version":[{"id":56916,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/56915\/revisions\/56916"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=56915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=56915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=56915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}