{"id":57104,"date":"2025-02-05T00:47:27","date_gmt":"2025-02-04T23:47:27","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/?p=57104"},"modified":"2025-02-05T23:43:01","modified_gmt":"2025-02-05T22:43:01","slug":"1507-por-fin-me-converti-en-su-putita","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/1507-por-fin-me-converti-en-su-putita\/","title":{"rendered":"Zorrita infiel y sumisa (3)"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"57104\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">20<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 7<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Despu\u00e9s de aquel fin de semana con el jefe de mi marido, ya no volv\u00ed a ser la misma. Me ten\u00eda completamente subyugada y estaba dispuesta a hacer lo que \u00e9l me dijera. Me estaba convirtiendo en su puta, algo que escapaba a mi entendimiento pero que no pod\u00eda ni quer\u00eda remediar.<\/p>\n<p>Pasado un mes mi marido me dijo un jueves, que deb\u00eda pasar algunos d\u00edas fuera porque Pedro, su jefe, le enviaba a un congreso, pero que en esta ocasi\u00f3n no pod\u00eda acompa\u00f1arle. Yo ya me imaginaba que aquello era realmente una maniobra de Pedro para tenerme a su disposici\u00f3n durante varios d\u00edas. Y efectivamente, el viernes por la ma\u00f1ana al poco de irse mi marido, son\u00f3 mi m\u00f3vil:<\/p>\n<p>-Hola zorrita. -Reconoc\u00ed al instante la voz de Pedro.<\/p>\n<p>-Hola, -le contest\u00e9<\/p>\n<p>-\u00bfYa se ha ido el cornudo?, -me pregunt\u00f3<\/p>\n<p>-Si, -le dije<\/p>\n<p>-Bien dentro de una hora paso a recogerte.<\/p>\n<p>A las once en punto estaba all\u00ed. Yo ya estaba vestida y preparada. Le abr\u00ed a puerta y entr\u00f3. Me mir\u00f3 de arriba abajo, me sob\u00f3 a su antojo y yo me dejaba hacer.<\/p>\n<p>-Estas muy guapa, -me dijo-, pero puedes estarlo m\u00e1s. Vamos a tu habitaci\u00f3n que te voy a ayudar a elegir el vestuario.<\/p>\n<p>-\u00bfNo te gusto as\u00ed?<\/p>\n<p>-Si, mucho, pero quiero que te vistas m\u00e1s sexy, m\u00e1s provocativa. Quiero que sepan que eres mi puta.<\/p>\n<p>Yo le obedec\u00ed sin rechistar y le llev\u00e9 a mi habitaci\u00f3n. Abr\u00ed la puerta del armario para que eligiese mi vestuario. Me sac\u00f3 unos minishorts blancos que apenas me pon\u00eda por atrevidos y un top muy fino de tirantes, muy escotado, muy ce\u00f1ido tambi\u00e9n blanco, que resaltaba mucho sobre mi piel todav\u00eda morena.<\/p>\n<p>-As\u00ed estar\u00e1s bien ahora, -me dijo.<\/p>\n<p>Me quit\u00e9 lo que llevaba puesto, qued\u00e1ndome con el tanga y el sujetador, delante de \u00e9l. Me iba a poner lo que me hab\u00eda elegido, pero me dijo:<\/p>\n<p>-Eh, nada de ropa interior, ya sabes.<\/p>\n<p>Me quite el sujetador y el tanga mientras \u00e9l me miraba.<\/p>\n<p>-Joder, que buena est\u00e1s, -me dec\u00eda-, pero te har\u00e9 unos retoques para que est\u00e9s m\u00e1s rica todav\u00eda.<\/p>\n<p>-\u00bfQue retoques? -Le pregunt\u00e9<\/p>\n<p>-Ya lo ver\u00e1s.<\/p>\n<p>Me puse la ropa sin nada debajo. Los pantalones me estaban muy ajustados, de forma que se me met\u00edan en la rajita marc\u00e1ndola completamente. Los pezones y las areolas tambi\u00e9n se me notaban. Me daba algo de verg\u00fcenza salir as\u00ed a la calle, sobre todo en mi vecindario, pero a la vez me excitaba much\u00edsimo y me estaba empezando a mojar. Pedro lo not\u00f3 y meti\u00f3 los dedos en mi co\u00f1o.<\/p>\n<p>-Vaya, \u00bfno dec\u00edas que te daba reparo vestirte as\u00ed? Est\u00e1s chorreando -me dec\u00eda mientras mojaba sus dedos en mi flujo y me los hac\u00eda chupar.<\/p>\n<p>-Menuda guarra eres, \u00bfc\u00f3mo te gusta esto eh?<\/p>\n<p>-Si, me encanta.<\/p>\n<p>Salimos a la calle y nos montamos en su coche. Durante el camino me fue metiendo mano por las tetas, sac\u00e1ndolas del top y sin dejar que las volviera a meter. En los sem\u00e1foros los otros conductores alucinaban y alguno me dec\u00eda obscenidades a las que yo respond\u00eda con una sonrisa.<\/p>\n<p>Llegamos a un local que se anunciaba como &#8220;Sal\u00f3n de Est\u00e9tica&#8221; y le pregunt\u00e9 que hac\u00edamos all\u00ed.<\/p>\n<p>-Me gusta que mis putitas est\u00e9n marcadas y me gusta que tu tengas un aspecto determinado que resaltar\u00e1 tu condici\u00f3n de zorra.<\/p>\n<p>Entramos al local y Pedro salud\u00f3 a varias personas. Estuvo hablando con ellos y luego me pasaron a una peluquer\u00eda donde me cortaron el pelo dej\u00e1ndome una melenita peque\u00f1a y rapada por la nuca. Me ti\u00f1eron el pelo de rubio platino. Luego me inyectaron un poco de silicona en los labios y me maquillaron, pero no dejaron que me viera hasta el final. El resultado era bastante bueno, aunque un poco exagerado. Me hab\u00eda quedado un aspecto de &#8220;calentona&#8221; inimaginable por mi marido. No s\u00e9 lo que dir\u00eda cuando me viera, pero no me preocupaba. Adem\u00e1s, todav\u00eda no hab\u00edan acabado conmigo. Cuando sal\u00ed de la pulquer\u00eda vi c\u00f3mo Pedro me miraba satisfecho.<\/p>\n<p>-Que bien la vas a chupar ahora, en conmigo, -me dijo<\/p>\n<p>Bajamos a un piso inferior d\u00f3nde hab\u00eda una sala de tatuajes. Entramos en una habitaci\u00f3n donde hab\u00eda un t\u00edo que le pregunt\u00f3 a Pedro:<\/p>\n<p>-\u00bfD\u00f3nde se lo hago, en las tetas o en el culo?<\/p>\n<p>-En el culo, -le respondi\u00f3.<\/p>\n<p>-Vamos zorrita, ens\u00e9\u00f1ame ese culo tan bonito, -me dijo el tatuador.<\/p>\n<p>Me baj\u00e9 los pantalones hasta los tobillos y me coloco apoyada en los codos y en las rodillas en una camilla. El tatuador empez\u00f3 a sobarme el culo hasta que eligi\u00f3 el sitio (la parte alta de mi nalga izquierda) y empez\u00f3 a tatuarme.<\/p>\n<p>Aquello me estaba poniendo como una moto. Pedro estaba cambiando mi aspecto sin consultarme y me ten\u00eda all\u00ed con el culo expuesto a un desconocido que adem\u00e1s de tatuarme aprovechaba para meter sus dedos por entre mis nalgas y en mi co\u00f1o. Pedro sab\u00eda que me estaba calentando as\u00ed que se puso delante de m\u00ed y empez\u00f3 a tocarme las tetas, primero meti\u00e9ndome mano por debajo de mi top pero luego acab\u00f3 quit\u00e1ndomelo dej\u00e1ndome all\u00ed con las tetas al aire. Se sac\u00f3 la polla y dijo:<\/p>\n<p>-Vamos a estrenar esos labios<\/p>\n<p>Me cogi\u00f3 de la nuca y me la meti\u00f3 en la boca.<\/p>\n<p>-Venga, chupa<\/p>\n<p>Yo se la chupaba con frenes\u00ed. El tatuador ya hab\u00eda acabado y me estaba haciendo una paja desde atr\u00e1s. Me besaba el culo y me met\u00eda los dedos en el co\u00f1o a la vez que me sobaba el cl\u00edtoris lo que hizo que me corriera.<\/p>\n<p>-Dale por culo si quieres, -le dijo Pedro-. As\u00ed te pagar\u00e1 el arreglito que le hemos hecho<\/p>\n<p>El tatuador se sac\u00f3 la polla y comenz\u00f3 a restregarla entre mis nalgas. Me llen\u00f3 el culo de saliva y me la meti\u00f3. Mientras Pedro se corri\u00f3 en mi boca cosa que me provoc\u00f3 de nuevo un orgasmo tremendo. El tatuador me la sac\u00f3 del culo, se sent\u00f3 en la camilla y me hizo arrodillarme delante de \u00e9l.<\/p>\n<p>-Ahora con las tetas, cerda, que las tienes muy bonitas.<\/p>\n<p>Yo frotaba su verga con mis pezones, la met\u00eda entre mis tetas y me la met\u00eda en la boca, le chupaba los huevos y as\u00ed hasta que se corri\u00f3 llen\u00e1ndome la cara y las tetas de semen.<\/p>\n<p>-Esta si que es buena, -le dijo a Pedro-. \u00bfDe d\u00f3nde la has sacado?<\/p>\n<p>-Su marido es empleado m\u00edo, -le contest\u00f3-, pero no la da ca\u00f1a<\/p>\n<p>-Ya lo veo. \u00bfQuieres ver su tatuaje?<\/p>\n<p>-Si<\/p>\n<p>-Venga guarrita, date un paseito<\/p>\n<p>Me hicieron pasear por la habitaci\u00f3n desnuda llena de semen para ver mi tatuaje.<\/p>\n<p>-Te queda muy bien, -me dec\u00edan mientras se re\u00edan<\/p>\n<p>Cuando me lo mir\u00e9 vi la causa de sus risas: era una especie serpiente-pene muy sexy, muy er\u00f3tico y muy &#8220;guarro&#8221;, que se dirig\u00eda serpenteante hacia mi culo.<\/p>\n<p>-\u00bfY mi marido que dir\u00e1?<\/p>\n<p>-Tu ver\u00e1s zorr\u00f3n, -segu\u00edan diciendo entre carcajadas.<\/p>\n<p>-Ven que todav\u00eda no hemos acabado.<\/p>\n<p>Me hicieron salir de la habitaci\u00f3n desnuda y me llevaron a otra donde me sentaron en otra camilla boca arriba y con las piernas abiertas. Me llenaron el co\u00f1o de espuma de afeitar y me lo depilaron dej\u00e1ndome una especie de Y, que quedaba fenomenal.<\/p>\n<p>-Bueno, ya hemos acabado, -dijo Pedro, v\u00edstete.<\/p>\n<p>Lo hice. Al ponerme el pantal\u00f3n vi que parte del tatuaje quedaba fuera y se ve\u00eda, cosa que me gustaba. Pedro me llev\u00f3 a mi casa y me dijo que pasar\u00eda a por m\u00ed por la tarde y que no me vistiese hasta que no volviera. Sub\u00ed a casa y me desnud\u00e9. Me mir\u00e9 al espejo y la verdad es que, entre los labios, el tatuaje y el chochito que me hab\u00edan dejado ten\u00eda una pinta de put\u00f3n que no pod\u00eda con ella, pero me gustaba y me gustaba que no me hubiera consultado. No s\u00e9 si a mi marido le gustar\u00eda, pero no me importaba.<\/p>\n<p>A las siete en punto Pedro vino a buscarme. Le abr\u00ed desnuda. Al entrar pas\u00f3 su lengua por mis labios, me dio la vuelta y me palme\u00f3 el culo.<\/p>\n<p>-Ahora si que eres mi putita, -me dijo-. V\u00edstete con esto que te he tra\u00eddo, vas a ser la reina de la fiesta.<\/p>\n<p>Me trajo un top de sat\u00e9n negro, una mini de cuero negro abierta por los lados y unos pantys de red negros tambi\u00e9n. Me lo puse. El top me quedaba de vicio, pero era tan corto que si levantaba los brazos se me sal\u00edan las tetas por debajo y a\u00fan sin levantarlos como mis tetas son grandes desde abajo se me ve\u00edan. Adem\u00e1s, era muy escotado y muy suelto de forma que con cualquier movimiento las exhib\u00eda. Me puso tambi\u00e9n una gargantilla de cuero con aros de plata. La falda llevaba de cintur\u00f3n una cadenita de plata. La quit\u00f3 y la uni\u00f3 a un aro de la gargantilla y me hizo pasear como si me llevara atada.<\/p>\n<p>-\u00bfVes para que sirve este cintur\u00f3n?. Para que te lleve como a una perrita, \u00bfte gusta?<\/p>\n<p>-Me encanta -le contest\u00e9<\/p>\n<p>-A ver si es verdad.<\/p>\n<p>Y me empez\u00f3 a sobar el co\u00f1o que estaba mojad\u00edsimo.<\/p>\n<p>-Uf, ya lo creo que te gusta, perra. Venga v\u00e1monos<\/p>\n<p>-\u00bfD\u00f3nde vamos?<\/p>\n<p>-A la fiesta de cumplea\u00f1os de mi amigo Miguel, don Miguel para ti.<\/p>\n<p>-\u00bfY no voy demasiado descocada?<\/p>\n<p>-No, le gustar\u00e1s mucho. Y t\u00fa eres mi regalo para \u00e9l as\u00ed que espero que te dejes hacer lo que quiera.<\/p>\n<p>Cuando llegamos a la casa de don Miguel, ya hab\u00eda bastante gente, muchos de los cuales conoc\u00eda por mi marido y claro se sorprend\u00edan de verme all\u00ed sin \u00e9l y con Pedro, aunque dada la fama de Pedro ya se supon\u00edan lo que ocurr\u00eda. Me present\u00f3 a don Miguel que era un hombre muy atractivo de unos cincuenta a\u00f1os.<\/p>\n<p>-Mira Miguel, esta es la putita de la que te habl\u00e9<\/p>\n<p>-Ah si, la esposita de Andr\u00e9s \u00bfno?<\/p>\n<p>-Si, \u00bfte gusta?<\/p>\n<p>-Joder, est\u00e1 muy buena, -le dec\u00eda mientras me acariciaba el cuello y bajaba su mano hasta mi cintura y la volv\u00eda a subir meti\u00e9ndola por debajo del top y sob\u00e1ndome las tetas, all\u00ed delante de todos-. Luego veremos que sabes hacer con ellas, -me volvi\u00f3 a decir.<\/p>\n<p>La fiesta fue pasando y yo me iba exhibiendo cada vez m\u00e1s. A medida que transcurr\u00eda el tiempo notaba las miradas de los t\u00edos mas lascivas y yo estaba cada vez m\u00e1s caliente. Ya quedaba poca gente cuando Pedro se acerc\u00f3 a mi me quit\u00f3 la cadena de la cintura y me la puso en la gargantilla, y tirando de mi me llev\u00f3 a unos sillones un poco apartados. De camino vimos como don Miguel estaba magreando a una mujer de otro empleado<\/p>\n<p>-Vamos Elenita, ponme cachondo, -me dijo, mientras me sentaba en sus rodillas<\/p>\n<p>Empezamos a besarnos y a sobarnos. Baj\u00f3 las hombreras de mi top y me sac\u00f3 las tetas. Me quit\u00f3 la falda y bajo un poco mis pantys, me sent\u00f3 de espaldas a \u00e9l en sus rodillas y empez\u00f3 a masturbarme, mientras ve\u00edamos como humillaban a la otra mujer don Miguel y los otros. Ella no quer\u00eda, pero la dec\u00edan que si no quer\u00eda ver a su marido en el paro ten\u00eda que comer polla. La met\u00edan mano, la sobaban y le restregaban sus paquetes por la cara, mientras otros le daban azotes en el culo. Yo me corr\u00ed con aquel espect\u00e1culo y limpi\u00e9 los dedos de Pedro con mi boca.<\/p>\n<p>Don Miguel vino donde est\u00e1bamos y me dijo:<\/p>\n<p>-Traenos bebida, puta.<\/p>\n<p>As\u00ed lo hice. Me levante medio desnuda pero no permitieron que me vistiera. Fui al otro lado del sal\u00f3n con las tetas fuera y los pantys medio bajados. Se me ve\u00eda el co\u00f1o y el tatuaje del culo. Durante el camino varios t\u00edos me metieron mano , me dijeron obscenidades y me llev\u00e9 mas de un cachetazo en el culo. Volv\u00ed con unas cervezas y me sent\u00e9 entre ellos, que terminaron de desnudarme. Don Miguel se levant\u00f3, se quit\u00f3 los pantalones y los calzoncillos. Cogi\u00f3 estos y me los restreg\u00f3 por la cara mientras me sujetaba de la nuca.<\/p>\n<p>-\u00bfTe gusta como huele?<\/p>\n<p>-Siii, -le contest\u00e9<\/p>\n<p>-Pues ahora vas a saber a lo que sabe. -Se puso de rodillas en el sill\u00f3n y me dijo- Ch\u00fapame el culo.<\/p>\n<p>Pedro me agarr\u00f3 de la cadena bien corta y me arrim\u00f3 la cara al culo de don Miguel. Empec\u00e9 a pasar la lengua entre sus nalgas y acab\u00e9 meti\u00e9ndosela en el culo. Pedro me cogi\u00f3 una mano y me la puso en la polla de don Miguel.<\/p>\n<p>-As\u00ed, cerda, hazme una paja mientras, -me dijo<\/p>\n<p>As\u00ed estuvimos un rato hasta que se dio la vuelta.<\/p>\n<p>-Tienes unos labios preciosos, -hazme una paja con ellos<\/p>\n<p>Se lo hac\u00eda como me ordenaba, le pasaba mis labios arriba y abajo de su polla. Le lam\u00eda los cojones y el culo mientras Pedro me estaba follando por detr\u00e1s. Cuando not\u00e9 su leche llenando mi culo, me met\u00ed la polla de don Miguel en la boca y tard\u00f3 poco en correrse dentro de ella.<\/p>\n<p>-Pedrito, le dijo a Pedro, \u00e9sta si que es buena y ambos se estuvieron riendo un buen rato.<\/p>\n<p>Me cogieron de la cadena de la gargantilla, me dejaron atada a la pared y llamaron a los que estaban con la otra t\u00eda que ya hab\u00eda dejado de llorar y disfrutaba como una perra de lo que la estaban haciendo.<\/p>\n<p>-Aqu\u00ed ten\u00e9is otra guarra -les dijeron.<\/p>\n<p>Me miraban con ojos de deseo mientras yo les provocaba con mi culo y mi boca.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_57104\" class=\"pvc_stats total_only  \" data-element-id=\"57104\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 7<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>As\u00ed lo hice. Me levant\u00e9 medio desnuda pero no permitieron que me vistiera. Fui al otro lado del sal\u00f3n con las tetas fuera y los pantys medio bajados. Se me ve\u00eda el co\u00f1o y el tatuaje del culo. Durante el camino varios t\u00edos me metieron mano, me dijeron obscenidades y me llev\u00e9 m\u00e1s de un cachetazo en el culo. Volv\u00ed<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_57104\" class=\"pvc_stats total_only  \" data-element-id=\"57104\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30467,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-57104","post","type-post","status-publish","format-standard","category-infidelidad"],"a3_pvc":{"activated":true,"total_views":6188,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/57104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30467"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=57104"}],"version-history":[{"count":1,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/57104\/revisions"}],"predecessor-version":[{"id":57105,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/57104\/revisions\/57105"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=57104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=57104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=57104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}