{"id":57648,"date":"2025-02-23T01:05:35","date_gmt":"2025-02-23T00:05:35","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=57648"},"modified":"2025-02-24T08:26:40","modified_gmt":"2025-02-24T07:26:40","slug":"4443-atormentado","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/4443-atormentado\/","title":{"rendered":"Obsesionado por los grandes pechos de mi hermana"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"57648\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">42<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Esta es la palabra exacta que define mi historia. Primero tengo que decir que tengo una novia que se llama M\u00f3nica; una chica atractiva, majilla. Y luego que tengo una hermana llamada Sandra -y con perd\u00f3n por ser su hermano- que tiene un par de melones por pechos.<\/p>\n<p>He salido s\u00f3lo con dos chicas. Con la que estoy ahora y con una anterior llamada Patricia. El caso (y voy a ser muy sincero) es que siempre me ha obsesionado el que mis parejas no tuviesen ese cuerpazo que tiene mi hermana. Creo que la culpa de este pensamiento obsesivo la han tenido mis padres que me educaron consinti\u00e9ndomelo todo.<\/p>\n<p>Mi hermana en cambio ha tenido muchas m\u00e1s relaciones que yo, es como he o\u00eddo alguna vez que se dice, &#8220;promiscua&#8221;. Desde luego que no me extra\u00f1a.<\/p>\n<p>Debo decir que mi vida sexual con mi novia es excelente pero siempre he tenido una gran pasi\u00f3n irrefrenable por Sandra.<\/p>\n<p>Lo que voy a contar ocurri\u00f3 en un momento especialmente delicado. Es el azar el que te conduce a las situaciones m\u00e1s insospechadas. M\u00f3nica me hab\u00eda sido infiel y me lo hab\u00eda contado todo. Se sent\u00eda culpable y quer\u00eda favorecerme de alguna manera. Y a mi hermana le hab\u00eda abandonado su novio, cosa que le hab\u00eda producido un estado depresivo bastante grande. M\u00f3nica que la aprecia mucho me preguntaba constantemente por ella.<\/p>\n<p>Bueno, pues coincidimos en cierta ocasi\u00f3n los tres solos en casa. No recuerdo de que est\u00e1bamos hablando y no s\u00e9 si fue M\u00f3nica o Sandra la que sac\u00f3 el tema de que pod\u00edamos ba\u00f1arnos los tres juntos. He de decir que ambas son muy ingenuas y que no ten\u00edan presente el sexo en ese mismo momento.<\/p>\n<p>Nuestra ba\u00f1era es grande y pueden caber hasta tres personas. Nos desnudamos y nos metimos. Yo disimulaba, haciendo como que no ve\u00eda los tetones de mi hermana (ya se los hab\u00eda visto otras veces).<\/p>\n<p>Me sent\u00e9 en un borde, lleg\u00e1ndome el agua hasta la cintura, mi novia en medio y Sandra en el otro lado. Lo de que se trataba realmente era de lavarnos mutuamente la cabeza; as\u00ed mi novia enjabon\u00f3 mi pelo y empez\u00f3 a restregar. Luego me echaba el agua encima para aclararme. Tengo que decir que yo estaba empalmad\u00edsimo. No s\u00e9 c\u00f3mo ni de qu\u00e9 manera me levant\u00e9 un poco y se me vio la polla dura.<\/p>\n<p>-Vaya -Dijo M\u00f3nica.- En que momento te ha ido a suceder esto. Si est\u00e1 tu hermana. -Entonces me bes\u00f3 en la boca-. A esto habr\u00e1 que ponerle remedio.<\/p>\n<p>Entonces mi hermana se levant\u00f3 y se march\u00f3.<\/p>\n<p>-Os dejo chicos que os divirt\u00e1is -nos dijo.<\/p>\n<p>Me puse en cuclillas y enjabon\u00e9 la cabeza de M\u00f3nica. Me levante con mi polla recta. Se la meti\u00f3 en la boca. As\u00ed mientras frotaba su cabeza ella me la chupaba. Me estaba volviendo loco. Lav\u00e1ndole la cabeza.<\/p>\n<p>Cuando estaba a punto de correrme o\u00edmos un tel\u00e9fono. Mi hermana golpe\u00f3 con los nudillos en la puerta.<\/p>\n<p>-Es para ti M\u00f3nica&#8230; llaman de tu casa.<\/p>\n<p>Sali\u00f3 de la ba\u00f1era, se pas\u00f3 una toalla para secarse, y se la arroll\u00f3 para no salir desnuda.<\/p>\n<p>Y entr\u00f3 mi hermana.<\/p>\n<p>-\u00bfHab\u00e9is terminado? -me dijo.<\/p>\n<p>-Si -le ment\u00ed.<\/p>\n<p>As\u00ed que se volvi\u00f3 a meter en la ba\u00f1era. Con sus bamboleantes senos. El agua me llegaba a la cintura y no se me ve\u00eda el pene tapado por el agua gris\u00e1cea y jabonosa.<\/p>\n<p>-L\u00e1vame el pelo anda -me dijo.<\/p>\n<p>Se acerc\u00f3 a m\u00ed, notando su aliento en mi boca. Se lo enjabon\u00e9 y comenc\u00e9 a frotar. Sus pechos estaban frente a m\u00ed y me estaba quedando bizco. Y no pude aguantar m\u00e1s. Me ergu\u00ed sacando mi larga polla y ech\u00e9 el cuerpo de mi hermana hacia m\u00ed. Apretuj\u00e9 mi polla contra uno de sus senos hasta que logr\u00e9 meterla entre los dos.<\/p>\n<p>-\u00a1Vaya! -me dijo.<\/p>\n<p>Yo suspir\u00e9. Estaba muy colorado. Se dio cuenta. Entonces se apretuj\u00f3 los senos aplastando mi polla.<\/p>\n<p>-No pasa nada. Vale. No pasa nada -me dec\u00eda mene\u00e1ndomela con sus pechos. Hac\u00eda esto mientras yo toqueteaba su pezones.<\/p>\n<p>Me corr\u00ed llenando su cuerpo de esperma que se enjuag\u00f3 r\u00e1pidamente con el agua.<\/p>\n<p>-\u00a1Qu\u00e9 no vuelva a suceder m\u00e1s! -me dijo.<\/p>\n<p>Yo me qued\u00e9 aliviado.<\/p>\n<p>En ese momento entr\u00f3 mi novia. Terminamos de aclararnos.<\/p>\n<p>-Lo dejamos para otro momento -me dijo M\u00f3nica- pensando que todav\u00eda estar\u00eda deseoso de sexo.<\/p>\n<p>As\u00ed sucedi\u00f3 todo.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_57648\" class=\"pvc_stats total_only  \" data-element-id=\"57648\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Se acerc\u00f3 a m\u00ed, notando su aliento en mi boca. Se lo enjabon\u00e9 y comenc\u00e9 a frotar. Sus pechos estaban frente a m\u00ed y me estaba quedando bizco. Y no pude aguantar m\u00e1s. Me ergu\u00ed sacando mi larga polla y ech\u00e9 el cuerpo de mi hermana hacia m\u00ed. Apretuj\u00e9 mi polla contra uno de sus senos hasta que logr\u00e9 meterla<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_57648\" class=\"pvc_stats total_only  \" data-element-id=\"57648\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1698,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-57648","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":true,"total_views":13778,"today_views":11},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/57648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/1698"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=57648"}],"version-history":[{"count":1,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/57648\/revisions"}],"predecessor-version":[{"id":57649,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/57648\/revisions\/57649"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=57648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=57648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=57648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}