{"id":58033,"date":"2025-03-08T00:04:50","date_gmt":"2025-03-07T23:04:50","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=58033"},"modified":"2025-03-07T18:04:28","modified_gmt":"2025-03-07T17:04:28","slug":"convenci-a-noemi-de-prostituirse","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/convenci-a-noemi-de-prostituirse\/","title":{"rendered":"Convenc\u00ed a Noemi de prostituirse"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"58033\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">18<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Como ya hab\u00eda comentado en el relato \u201cGordo polic\u00eda hizo a mi esposa su puta\u201d, yo me llamo Santiago y tengo 33 a\u00f1os y mi esposa, una morocha tetona, con culito manzana y una boca que con verla te alucina qu\u00e9 te la chupe.<\/p>\n<p>Mi trabajo consiste en auxilio a camiones con la parte el\u00e9ctrica y algunas cosas de mec\u00e1nica. Es as\u00ed que un 24 de diciembre, cuando pens\u00e1bamos ir de compras por eso andaba con Noemi, me llaman porque un cami\u00f3n rompi\u00f3 una manguera de aire, algo sencillo, pero como era el que activa el pulm\u00f3n llevar\u00eda aproximadamente una hora repararlo.<\/p>\n<p>Siempre se llama para coordinar donde verlo que sea c\u00f3modo tanto para el ch\u00f3fer como para m\u00ed.<\/p>\n<p>Es as\u00ed que llame y no me atiende, pero al rato me manda un audio diciendo que lo vea cerca de la costanera, era un lugar tranquilo, adem\u00e1s de andar varias prostitutas que es lo que el tipo buscaba. Fue ah\u00ed que se me prende la l\u00e1mpara y hago escuchar el audio a mi esposa, diciendo a la vez, te pod\u00e9s ganar unos pesos, ella enojada me dice, porque no lo haces vos el servicio, ah\u00ed para que afloje le digo, solo un pete y listo.<\/p>\n<p>Cuando est\u00e1bamos cerca yo ya no le insist\u00eda cuando dice, bueno, pero solo sexo oral, a lo que mi contestaci\u00f3n fue, vos arreglas con \u00e9l, a m\u00ed no me conoces.<\/p>\n<p>Fue as\u00ed que la deje a la vuelta de la esquina y me fui al cami\u00f3n.<\/p>\n<p>Cuando llegue, miraba de reojo cuando ven\u00eda caminando entonces me acomode de forma que el la vea, a lo que exclam\u00f3 mira esa putita, as\u00ed me gustan, hasta el culo te piden que le hagas.<\/p>\n<p>Yo me re\u00eda pensando que era obvio si el pagaba pero que a la vez esta vez solo le chupar\u00eda. Empec\u00e9 a reparar lo del cami\u00f3n cuando viene el Jos\u00e9, as\u00ed se llama el chofer, tipo grande de origen boliviano, a preguntar si ten\u00eda que entrar a la cabina, a lo que contesto que no y ah\u00ed me confirma que ella est\u00e1 en el cami\u00f3n.<\/p>\n<p>A los 15 minutos siento que el cami\u00f3n se meneaba, lo que me llamo la atenci\u00f3n ya que era chupar, ya pr\u00e1cticamente hab\u00eda terminado, as\u00ed que me asome, mirando un espect\u00e1culo pornogr\u00e1fico por el espejo, la ten\u00eda patita al hombro, y la clavaba como si fuera atravesar, Jos\u00e9 ten\u00eda tremendo pedazo y se la hac\u00eda sentir, al mismo tiempo que la besaba y pega un alarido provocado por un orgasmo descomunal.<\/p>\n<p>Le hace chupar nuevamente su pija, un rato, y la hace poner el cuatro, ella estaba en modo sumisa, hacia todo lo que el dec\u00eda, aprovecho Jos\u00e9 para meter la lengua donde m\u00e1s le complac\u00eda, y luego poni\u00e9ndose bien atr\u00e1s de ella, penetra su culito haciendo que ella pegue un grito, apoyando todo su cuerpo en la espalda de ella. Noemi no daba cr\u00e9dito como se la estaba cogiendo, si bien yo ya estaba con la temperatura a full, cuando el, hace decir que le gusta como la coje, por poco me acabo ah\u00ed mismo.<\/p>\n<p>Fue esta vez cinco minutos m\u00e1s cuando se para y le termino sobre la cara de Noemi, entrando tambi\u00e9n en la boca.<\/p>\n<p>Yo antes de que salgan fui de nuevo bajo el cami\u00f3n cerr\u00e9 todo y sal\u00ed, cuando justo Jos\u00e9 aparece y me dice.<\/p>\n<p>-Que linda cogida le pegu\u00e9, quer\u00eda solo chupar, cuando se descuid\u00f3 la puse patita al hombro y despu\u00e9s me ped\u00eda que no se la saque.<\/p>\n<p>Otra vez a full me puse, y me fui al auto, mientras Jos\u00e9 se iba, qued\u00e9 asombrado porque mi esposa se dej\u00f3 coger, y ahora no estaba.<\/p>\n<p>Me fui hasta la estaci\u00f3n de servicio pensando que se hab\u00eda ido a limpiar, pero no era as\u00ed, al rato la veo entrar, con el pelo revuelto y pelo mojado, cuando le pregunt\u00f3 que paso, me dice, ese forro me forz\u00f3, pero me gusto, y despu\u00e9s le chupe la pija a un pendejo, nos fuimos a comprar y pasamos una noche buena espectacular, sobre todo ella.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58033\" class=\"pvc_stats total_only  \" data-element-id=\"58033\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>A los 15 minutos siento que el cami\u00f3n se meneaba, lo que me llam\u00f3 la atenci\u00f3n ya que era chupar, ya pr\u00e1cticamente hab\u00eda terminado, as\u00ed que me asom\u00e9, mirando un espect\u00e1culo pornogr\u00e1fico por el espejo, la ten\u00eda patita al hombro, y la clavaba como si fuera a atravesar, Jos\u00e9 ten\u00eda tremendo pedazo y se la hac\u00eda sentir, al mismo tiempo<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58033\" class=\"pvc_stats total_only  \" data-element-id=\"58033\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30731,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-58033","post","type-post","status-publish","format-standard","category-confesiones"],"a3_pvc":{"activated":true,"total_views":5735,"today_views":5},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30731"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=58033"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58033\/revisions"}],"predecessor-version":[{"id":58035,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58033\/revisions\/58035"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=58033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=58033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=58033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}