{"id":58189,"date":"2025-03-13T00:02:28","date_gmt":"2025-03-12T23:02:28","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=58189"},"modified":"2025-03-12T18:54:22","modified_gmt":"2025-03-12T17:54:22","slug":"mi-hijo-pequeno-y-mi-companera-sara","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/mi-hijo-pequeno-y-mi-companera-sara\/","title":{"rendered":"Mi hijo peque\u00f1o y mi compa\u00f1era Sara"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"58189\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">85<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 8<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Alguno de los trabajadores de seguridad de mi edificio hab\u00eda definido a mi compa\u00f1era Sara como una vacaburra fea pero con mucho morbo, y era cierto, es una mujer que aparenta una edad mucho mayor de la que tiene, es unos diez a\u00f1os mayor que yo, pero parecemos de la misma edad, con un cuerpo desproporcionado y unos rasgos nada armoniosos, pero resulta atractiva para muchos hombres, el que dijo eso de ella intentaba verla mientras se cambiaba, era viuda desde que hac\u00eda unos a\u00f1os, su marido hab\u00eda muerto en un accidente de coche.<\/p>\n<p>Hab\u00eda tenido sus aventuras y un d\u00eda cometi\u00f3 el error de contarme su fantas\u00eda, desvirgar a un joven, y eso encendi\u00f3 mi imaginaci\u00f3n, se lo pod\u00eda hacer con mi hijo el peque\u00f1o, \u00e9l no era virgen lo hab\u00eda desvirgado yo no hac\u00eda mucho, pero si \u00e9l no dec\u00eda nada, jajaja, ella no lo notaria.<\/p>\n<p>Y la oportunidad se dio un d\u00eda mi compa\u00f1era me cont\u00f3 que ten\u00eda que arreglar un armario en su casa, se estaba descentrando, y yo la ofrec\u00ed que mi hijo fuera a hacerle el arreglo, y se lo hizo, jajaja, ya que era bastante manitas, y amiga comprender\u00eda cuanto, jajaja.<\/p>\n<p>A \u00e9l le expliqu\u00e9 que si se hac\u00eda el virgen tendr\u00eda f\u00e1cil follar, y le puse como condici\u00f3n que ten\u00eda que cont\u00e1rmelo todo con el m\u00e1ximo detalle, ya empezaba a aplicarle la misma pol\u00edtica que a su hermano, si quer\u00eda seguir follando conmigo. Y esto fue lo que me cont\u00f3, la primera vez que nos quedamos solos antes de follar,<\/p>\n<p>Llegu\u00e9 al piso de tu compa\u00f1era, con mi caja de herramientas, y cuando esta abri\u00f3 la puerta me encontr\u00e9 con una mujer que me atra\u00eda mucho, llevaba una falda gris, por encima de las rodillas, una blusa roja que mostraba una gran parte de sus tetas, y una parte de su sujetador rosa con figuritas, me mando pasar, me ofreci\u00f3 un refresco y tras una conversaci\u00f3n normalita, aunque yo no pod\u00eda dejar de mirar su escote y creo que ella me miraba con ganas me dijo:<\/p>\n<p>-\u00bfSabes tu madre siempre me habla de su hijo como si fuera un ni\u00f1o?, Pero a m\u00ed me pareces un chico guapo, seguro que tendr\u00e1s enamoradas a muchas compa\u00f1eras de clase en la universidad.<\/p>\n<p>Record\u00e9 tus instrucciones y me hice el t\u00edmido, y la dije que no ten\u00eda novia que las chicas me daban miedo, ella dijo:<\/p>\n<p>-Eso te lo quitaba yo de un polvo.<\/p>\n<p>Me volv\u00ed a hacer el t\u00edmido, y ella me dijo:<\/p>\n<p>-Bueno ser\u00e1 mejor que te pongas manos a la obra. Porque si no se te va a hacer muy tarde.<\/p>\n<p>Y me llev\u00f3 hasta el sitio donde estaba el armario, era su habitaci\u00f3n ella iba delante de m\u00ed, y yo estaba embelesado vi\u00e9ndola mover su culo, mi polla se puso dura. Cuando llegamos, me mostr\u00f3 el armario, el arreglo era muy f\u00e1cil y lo hice en poco tiempo, mientras ella me trajo una cerveza y me dijo:<\/p>\n<p>-Ya que estas aqu\u00ed, me gustar\u00eda conocer tu opini\u00f3n sobre el conjunto de lencer\u00eda que llev\u00f3 puesto, este fin de semana salgo con un amigo y no quiero que se desilusione cuando me desnude.<\/p>\n<p>Y dicho esto se quit\u00f3 la blusa sus tetas quedaron al aire tapadas solo por un peque\u00f1o sujetador que apenas tapaba una parte de ellas, despu\u00e9s de manera lenta, con algo de baile se quit\u00f3 la falda, unas bragas rositas de tama\u00f1o mediano quedaron a mi vista, en ese momento me pregunt\u00f3.<\/p>\n<p>-Crees que gustare a mi amigo.<\/p>\n<p>Yo estaba nervioso y balbucee. Pero ella mirando mi pantal\u00f3n dijo:<\/p>\n<p>-Parece que tu polla me dice que si, y veo que no es la polla de un ni\u00f1o sino la de un hombre.<\/p>\n<p>En ese momento ella me puso una mano sobre mi polla y se puso a acarici\u00e1rmela, esto hizo que me empalmara y ella al verlo dijo:<\/p>\n<p>-Por lo que se nota aqu\u00ed veo que realmente eres un hombre.<\/p>\n<p>Me la sigui\u00f3 acariciando, mi polla creci\u00f3 hasta que casi no me cab\u00eda en el pantal\u00f3n, ella al verlo sonri\u00f3 p\u00edcaramente y dijo:<\/p>\n<p>-Creo que es mejor que liberemos al pajarito de su jaula.<\/p>\n<p>Y llevando su mano a mi cintur\u00f3n me lo desabroch\u00f3, luego hizo lo mismo con mi pantal\u00f3n y cogiendo mi polla con su mano la sac\u00f3 del b\u00f3xer, despu\u00e9s dijo:<\/p>\n<p>-Decididamente esto es de un hombre, y de un hombre bien dotado, jovencito.<\/p>\n<p>Se inclin\u00f3 hacia mi polla, que manten\u00eda sujeta con una mano y se la llev\u00f3 a su boca, dando comienzo una mamada.<\/p>\n<p>-Que polla tan rica tienes, dijo, \u00bfNo me iras a decir que voy a ser la primera en mam\u00e1rtela?<\/p>\n<p>Recordando las instrucciones de mi madre le dije que s\u00ed, ella se puso a chup\u00e1rmela, se notaba que, como me hab\u00eda dicho mi madre, no era la primera polla que chupaba, lo hac\u00eda divinamente, aunque que mi madre me lo hiciera me gustaba m\u00e1s, pero el caso es que ella me estaba haciendo pasar un rato divino. A\u00fan no se como pero el caso es que sin sac\u00e1rsela de la boca me hizo levantarme para quitarme los Pantalones y el b\u00f3xer, qued\u00e1ndome completamente desnudo de cintura para abajo, ella se la sac\u00f3 se quit\u00f3 la blusa y la falda qued\u00e1ndose en ropa interior, y despu\u00e9s saco sus enormes tetas del sujetador, aqu\u00ed me volvi\u00f3 a preguntar:<\/p>\n<p>-\u00bfNunca te han hecho una cubanita?<\/p>\n<p>La verdad es que yo sab\u00eda lo que era eso, pero como mi madre me hab\u00eda dado la instrucci\u00f3n de hacerme pasar por alguien completamente virgen, le dije que no, ella me pidi\u00f3 que me tumbara sobre la cama, con las piernas en el suelo, de manera que mi polla quedara en el borde, se arrodill\u00f3 delante de m\u00ed, llev\u00f3 sus tetas hasta mi polla e hizo que esta se situara entre ellas, despu\u00e9s las apret\u00f3 de manera que mi polla se qued\u00f3 bien apretada entre ellas, como si fuera un co\u00f1o. Me sonr\u00edo y me pregunt\u00f3:<\/p>\n<p>-\u00bfTe gustan mi ni\u00f1o?<\/p>\n<p>Aqu\u00ed no tuve que mentirle, claro que me gustaban, era algo divino, ella comenz\u00f3 a moverse como su fuera un co\u00f1o o una boca y eso hizo que mi excitaci\u00f3n aumentara.<\/p>\n<p>-No sabes lo maravilloso que es para m\u00ed desvirgar a un macho como t\u00fa, vas a causar mucho furor entre las chicas, bien sean de tu edad, o las viejunas de la m\u00eda, jaja.<\/p>\n<p>En esta postura estuvimos un tiempo hasta que ella dijo:<\/p>\n<p>-Creo que es hora de que me desnude del todo.<\/p>\n<p>Y levant\u00e1ndose se quit\u00f3 primero el sujetador y luego las bragas, una vez desnuda me pregunt\u00f3:<\/p>\n<p>-\u00bfMi ni\u00f1o, alguna vez le has comido el co\u00f1o a una mujer?<\/p>\n<p>Otra vez record\u00e9 las instrucciones de mi madre y aunque hab\u00eda chupado el co\u00f1o de esta contest\u00e9 que no.<\/p>\n<p>-La t\u00eda Sara te va a ense\u00f1ar, me dijo.<\/p>\n<p>Se tumb\u00f3 en la cama con las piernas bien abiertas y me dijo:<\/p>\n<p>-Ven aqu\u00ed.<\/p>\n<p>Lo hice, llev\u00e9 mi boca hasta su co\u00f1o e introduje en \u00e9l mi lengua, mi madre me hab\u00eda ense\u00f1ado a hacerlo, pero deb\u00eda parecer que no sab\u00eda, as\u00ed que hice que me dejaba llevar por sus instrucciones, pero lo que de verdad recordaba eran las ense\u00f1anzas de mi madre, le met\u00ed la lengua dentro de su co\u00f1o y procur\u00e9 lamer cada cent\u00edmetro de \u00e9l, ella comenz\u00f3 a gemir de una manera muy intensa, mientras dec\u00eda:<\/p>\n<p>-Para ser tu primera vez lo haces muy bien mi amor vas a volver locas a muchas mujeres.<\/p>\n<p>Yo segu\u00ed chup\u00e1ndoselo hasta que logre\u00e9 que se corriera, y tragu\u00e9 sus l\u00edquidos que me encantaron, poco despu\u00e9s ella se fij\u00f3 en mi polla que estaba dur\u00edsima, la cogi\u00f3 con su mano y la acaricio, me dijo:<\/p>\n<p>-Ya es hora de que este pollon tan precioso disfrute de su primer co\u00f1o, ven aqu\u00ed mi amor.<\/p>\n<p>Sigui\u00f3 con su co\u00f1o bien abierto, me incit\u00f3 a acercarme y poner mi polla cerca de mi co\u00f1o, me lo agarr\u00f3 y acaricio, para ponerlo bien duro. Cuando lo hubo logrado abri\u00f3 bien sus piernas, hasta ponerme una de ellas en mi hombro y me dijo:<\/p>\n<p>-Mi amor aqu\u00ed tienes mi co\u00f1o bien abierto para recibir una polla tan deliciosa como la tuya, m\u00e9temela.<\/p>\n<p>Yo estaba impresionado, el asunto es que ten\u00eda ganas de meterla y un poco nervioso llev\u00e9 mi polla hasta la entrada de su co\u00f1o y la penetr\u00e9, ella al sentirlo dijo:<\/p>\n<p>-Muy bien mi amor. Pese a tu inexperiencia lo haces muy bien, como te he dicho antes vas a volver locas a muchas mujeres, quiz\u00e1s, si quieres te presente a alguna amiga, pero no le digas nada a tu madre.<\/p>\n<p>Por supuesto no le dije que lo iba a hacer, jajaja, segu\u00ed movi\u00e9ndome dentro del co\u00f1o de Sara, me recordaba al de mi madre, pero en cierta manera era diferente, estuve movi\u00e9ndome dentro de \u00e9l, mientras ella gem\u00eda, y yo tambi\u00e9n, ella gem\u00eda cada vez m\u00e1s fuerte hasta que se corri\u00f3, en ese momento dijo:<\/p>\n<p>-Eres un buen follador y la t\u00eda Sara te ense\u00f1ara a hacerlo mejor, ya montaras a otras mujeres, y a m\u00ed m\u00e1s veces si te apetece. Pero ahora deja que la t\u00eda sea quien llev\u00e9 el ritmo, t\u00fambate en la cama.<\/p>\n<p>Primero me quit\u00e9 la camisa para quedarme completamente desnudo y luego me tumb\u00e9 en la cama, y siguiendo sus indicaciones junt\u00e9 bien mis piernas, ella se puso encima de m\u00ed y llev\u00f3 mi polla hasta el interior de su co\u00f1o y dijo:<\/p>\n<p>-Deja que la t\u00eda Sara te de mucho amor.<\/p>\n<p>Y comenz\u00f3 a moverse arriba y abajo, demostr\u00e1ndome que sab\u00eda llevar el ritmo adecuado para volver loco de placer a un t\u00edo, adem\u00e1s ten\u00eda sus tetas encima de m\u00ed, eran enormes no pude aguantarme las ganas y se las acarici\u00e9:<\/p>\n<p>-\u00bfTe gustan las tetas de la t\u00eda?, me pregunt\u00f3 mientras gem\u00eda.<\/p>\n<p>-Si t\u00eda, le dije yo.<\/p>\n<p>-Cari\u00f1o pues no te cortes acar\u00edcialas todo o que te apetezca.<\/p>\n<p>Estuve un rato acarici\u00e1ndoselas, pero de repente mi imaginaci\u00f3n fue hacia su culo, le ten\u00eda encima de m\u00ed, a pocos cent\u00edmetros de mi cuerpo, as\u00ed que soltando sus tetas llev\u00e9 mis manos hacia los acachetes de su culo y me puse a sob\u00e1rselos.<\/p>\n<p>-Que bien lo haces cari\u00f1o, dijo ella si esta es tu primera vez no quiero ni pensar en c\u00f3mo lo har\u00e1s cuando tengas un poco de experiencia, pero entonces ya ni te acordaras de tu t\u00eda que te desvirg\u00f3.<\/p>\n<p>No era verdad, ni ella me hab\u00eda desvirgado, ni me iba a olvidar de ella esto \u00faltimo se lo dije:<\/p>\n<p>-No t\u00eda no me olvidare de ti te prometo venir a follarte mientras t\u00fa quieras.<\/p>\n<p>-Eso espero mi amor, dijo ella, o eso o m\u00e1ndame a alg\u00fan amiguito, me encanta la idea de desvirgar jovencitos.<\/p>\n<p>Sara no era mi t\u00eda, pero el hecho de jugar a que lo fuera se hab\u00eda convertido en una parte de nuestra relaci\u00f3n, y la idea de enviarle a alg\u00fan amigo me daba morbo, as\u00ed que la dije:<\/p>\n<p>-De acuerdo t\u00eda, pero a condici\u00f3n de que me dejes mirar y me presentes a alguna amiga que folle tanto como t\u00fa.<\/p>\n<p>Sara se dio la vuelta y sigui\u00f3 cabalg\u00e1ndome, ahora ten\u00eda la visi\u00f3n de su maravilloso culo, lo cual me resultaba muy morboso, y me respondi\u00f3:<\/p>\n<p>-Cari\u00f1o nadie folla como yo, pero si, te presentare a alguna amiga que este muy salida para que te la folles, pero eso s\u00ed no le digas nada a tu madre.<\/p>\n<p>Yo acept\u00e9 la oferta, aunque la \u00faltima parte no la iba a cumplir s\u00ed que ten\u00eda varios amigos que estar\u00edan encantados de que una madura les desvirgara, e incluso estar\u00edan dispuestos a pagar por ello.<\/p>\n<p>Ella me sigui\u00f3 follando hasta que vi que me ven\u00eda en ese momento se lo dije:<\/p>\n<p>-T\u00eda me corro.<\/p>\n<p>-Tranquilo cari\u00f1o, dijo ella, hazlo dentro de m\u00ed, pensar que la leche que entra en mi co\u00f1o es la primera que manda un joven a ese lugar me da mucho morbo.<\/p>\n<p>Tras sus palabras no tuve ning\u00fan prejuicio en correrme y un aut\u00e9ntico reguero de leche, como pocas veces sal\u00eda de mi polla, sali\u00f3 derecho hacia el co\u00f1o de Sara, llen\u00e1ndole con mi semen.<\/p>\n<p>Ella se sali\u00f3 yo la hice una se\u00f1al para que se acercara, ella arrim\u00f3 sus labios a los m\u00edos y yo la dije:<\/p>\n<p>-Muchas gracias, t\u00eda me has hecho muy feliz.<\/p>\n<p>-Mi amor, dijo ella, para m\u00ed s\u00ed que ha sido maravilloso, cuando una folla con un joven siente rejuvenecer.<\/p>\n<p>Pero en ese momento volv\u00ed a pensar en su trasero, ese que acababa de ver moverse mientras me corr\u00eda y le dije:<\/p>\n<p>-\u00bfT\u00eda, me dar\u00edas tu culo?<\/p>\n<p>-Caramba con el chico t\u00edmido, dijo ella riendo.<\/p>\n<p>-Es que contigo es muy f\u00e1cil expresarse, le respond\u00ed.<\/p>\n<p>-Bueno pues si el nene quiere inaugurar su polla por los tres agujeros el mismo d\u00eda \u00bfQui\u00e9n soy yo para neg\u00e1rselo?, dijo ella ri\u00e9ndose.<\/p>\n<p>Y poni\u00e9ndose a cuatro patas a\u00f1adi\u00f3:<\/p>\n<p>-Aqu\u00ed me tienes, soy toda tuya.<\/p>\n<p>La contemplaci\u00f3n de su trasero en esa posici\u00f3n tan especial me result\u00f3 espectacular, si hab\u00eda pensado en follarme ese culo, su visi\u00f3n en este plano hizo que mi excitaci\u00f3n fuera en aumento, decididamente ese culo tan incre\u00edble deb\u00eda de ser m\u00edo, ella apoy\u00f3 sus brazos sobre la cama, hundi\u00f3 su cabeza y dijo:<\/p>\n<p>-Aqu\u00ed me tienes cari\u00f1o<\/p>\n<p>Aunque anteriormente me hab\u00eda follado el culo de mi madre, la idea de hacerlo con el de Sara me resultaba muy morbosa, me acerqu\u00e9 hasta \u00e9l, me puse de rodillas, y de un golpe introduje mi polla, que en ese momento se encontraba dur\u00edsima, dentro del divino agujero de esa diosa.<\/p>\n<p>Ella al sentir mi polla en su trasero gimi\u00f3 de una manera muy intensa, no hab\u00eda rastro alguno de dolor, al contrario, parec\u00eda estar gozando a tope, ella dijo:<\/p>\n<p>-Que bien lo haces amor, resulta incre\u00edble que esta sea tu primara vez.<\/p>\n<p>En realidad, no lo era, jajaja, pero si pensar que ella me hab\u00eda desvirgado la resultaba agradable, \u00bfPorque la iba a llevar la contraria?<\/p>\n<p>Mi polla comenz\u00f3 a moverse hacia delante y hacia atr\u00e1s, Sandra ten\u00eda un culo muy agradable para follar, as\u00ed que comenc\u00e9 a moverme, sus gemidos me indicaban que ritmo deb\u00eda de llevar para que ella disfrutara a tope, llev\u00e9, tal y como mi madre me hab\u00eda ense\u00f1ado a hacer, una de mis manos dentro de su co\u00f1o y comprob\u00e9 que estaba muy h\u00famedo, al sacarla, sin dejar de follar su culo, me llev\u00e9 los dedos a mi boca y el sabor que se desprend\u00eda del co\u00f1o me result\u00f3 muy agradable, mientras ella dec\u00eda:<\/p>\n<p>-Sigue mi amor, me estas volviendo loca de placer.<\/p>\n<p>Sus palabras me excitaban, pero yo intentaba contener mi eyaculaci\u00f3n, no quer\u00eda que ese momento terminara. Disminu\u00ed un momento el ritmo, para contenerme y luego lo reanud\u00e9, esto me permiti\u00f3 resistir un poco m\u00e1s, pero finalmente no pude evitar correrme y mi leche inundo su culo. Cuando me sal\u00ed, ella dijo:<\/p>\n<p>-Voy a llamar a mi amigo ya follaremos otro d\u00eda hoy contigo he tenido bastante.<\/p>\n<p>Cuando sal\u00eda de su casa, pensaba en la maravillosa tarde que hab\u00eda pasado y en lo bueno que es que sea tu madre la que te guie en el terreno sexual.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58189\" class=\"pvc_stats total_only  \" data-element-id=\"58189\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 8<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Recordando las instrucciones de mi madre le dije que s\u00ed, ella se puso a chup\u00e1rmela, se notaba que, como me hab\u00eda dicho mi madre, no era la primera polla que chupaba, lo hac\u00eda divinamente, aunque que mi madre me lo hiciera me gustaba m\u00e1s, pero el caso es que ella me estaba haciendo pasar un rato divino. A\u00fan no s\u00e9<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58189\" class=\"pvc_stats total_only  \" data-element-id=\"58189\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30008,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-58189","post","type-post","status-publish","format-standard","category-sexo-con-maduras"],"a3_pvc":{"activated":true,"total_views":12316,"today_views":1},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30008"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=58189"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58189\/revisions"}],"predecessor-version":[{"id":58191,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58189\/revisions\/58191"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=58189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=58189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=58189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}