{"id":58274,"date":"2025-03-16T00:04:26","date_gmt":"2025-03-15T23:04:26","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=58274"},"modified":"2025-03-15T20:13:34","modified_gmt":"2025-03-15T19:13:34","slug":"4058-la-visita-de-mi-sobrino","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/4058-la-visita-de-mi-sobrino\/","title":{"rendered":"La visita de mi sobrino"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"58274\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">73<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 15<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Nosotros acostumbrados a estar solos nos paseamos desnudos por la casa, y como hemos contado antes incluso cuando esta la sirvienta o criada, y es habitual en nosotros que de repente tengamos relaciones en cualquier parte de la casa, ambos gozamos a plenitud el sexo, adem\u00e1s de la excelente comunicaci\u00f3n que tenemos.<\/p>\n<p>Mi esposa es de 34 a\u00f1os y yo de 38, ambos nos conservamos bastante bien.<\/p>\n<p>Bueno, un d\u00eda recibo el llamado de un primo que vive fuera de la capital para solicitarme si podemos recibir a su hijo en nuestra casa, ya que viene a la capital a dar unos ex\u00e1menes para la Universidad, obviamente no ponemos objeci\u00f3n, pues muchas veces nosotros hemos sido recibidos en casa de ellos.<\/p>\n<p>Lleg\u00f3 Rub\u00e9n a la casa un d\u00eda s\u00e1bado por la tarde, muchacho alto bien formado, no atl\u00e9tico, pero de contextura delgada, un poco corto de genio, pero si observador, ya que miraba mucho a Ver\u00f3nica.<\/p>\n<p>Y eso me hizo pasarme una infinidad de pel\u00edculas morbosas por la mente, sintiendo unos deseos locos de mostrar a Ver\u00f3nica desnuda para que \u00e9l se calentara incluso que tuviera relaciones con ella.<\/p>\n<p>Nosotros ven\u00edamos llegando de andar en el ajetreo de las compras del fin de semana y \u00e9l estaba esperando en la puerta de la casa, entramos, Ver\u00f3nica lo llev\u00f3 al dormitorio de visitas donde le prepar\u00f3 la cama mientras yo conversaba con \u00e9l en la puerta de la pieza, mientras sacaba sus cosas de un bolso de viaje.<\/p>\n<p>Como Ver\u00f3nica ten\u00eda que agacharse para poner las s\u00e1banas yo ve\u00eda que se le sub\u00eda la falda y sin querer estaba mostrando sus exquisitos muslos, Rub\u00e9n peg\u00f3 la mirada en las piernas de Ver\u00f3nica qued\u00e1ndose callado por unos segundos, ah\u00ed se me acrecent\u00f3 el morbo de verle las piernas al aire a mi esposa delante de un hombre que se la com\u00eda con la vista, posiblemente excit\u00e1ndolo, pas\u00f3 eso y seguimos conversando hasta que Ver\u00f3nica termin\u00f3 de armar la cama.<\/p>\n<p>Nos fuimos a nuestro dormitorio a cambiarnos de ropa, Ver\u00f3nica me pidi\u00f3 que cerrara la puerta que por costumbre nunca lo hacemos, a rega\u00f1adientes acept\u00e9.<\/p>\n<p>Me desvest\u00ed poni\u00e9ndome un short y una polera, cuando ella se sac\u00f3 el vestido que tra\u00eda y quedo en sost\u00e9n y calz\u00f3n, de esos con filo dental, se me vino a la mente la imagen anterior, me acerqu\u00e9 a ella y la abrac\u00e9 bes\u00e1ndola por todos lados soltando su sost\u00e9n dej\u00e1ndola con las tetas libres las que tom\u00e9 y empec\u00e9 a acariciar, \u201cespera a la noche -me dijo ella-, que tengo que preparar algo de comer para nosotros y Rub\u00e9n\u201d.<\/p>\n<p>La dej\u00e9 y quiso abrocharse el sost\u00e9n a lo que r\u00e1pidamente se lo quit\u00e9 y lo tir\u00e9 dentro del closet, dej\u00e1ndola solamente con el filo dental, \u201cmi amor como voy a andar as\u00ed si no estamos solos\u201d, me dice, \u201cponte ese vestido con el que andas siempre en la casa\u201d, dije, \u201cpero no te pongas el sost\u00e9n, t\u00fa sabes que me encanta que andes as\u00ed\u201d.<\/p>\n<p>Se puso un vestido de casa que le queda un poco corto, muy rico, lo que hace que se le vean bien sus muslos y se le marque el potito, sus pechos sueltos, daba gusto mirarla.<\/p>\n<p>Me dice, \u201c\u00bfno es demasiado sugerente?, ahora que est\u00e1 Rub\u00e9n\u201d, \u201cno mi amor anda as\u00ed que te ves exquisita\u201d, mi morbo hizo que se me empezara a producir una erecci\u00f3n que ella not\u00f3, coment\u00e1ndome, \u201ca ver que te sucede que ya se te par\u00f3 y quieres que ande de esta manera habiendo alguien m\u00e1s en casa, que locura se te meti\u00f3 en cabeza\u201d.<\/p>\n<p>\u201cNada es que t\u00fa no te diste cuenta de antes cuando hac\u00edas la cama se te vieron los muslos completamente y Rub\u00e9n qued\u00f3 petrificado mir\u00e1ndote, y eso es lo que me ha producido morbo muy especial, as\u00ed que al verte con esa indumentaria yo creo que acabar\u00e1 solo\u201d.<\/p>\n<p>\u201cComo se te ocurre pensar en eso, como puedes pretender que me exponga delante de tu sobrino, est\u00e1s loco\u201d.<\/p>\n<p>\u201cBueno como yo me expongo delante de las empleadas, hemos tenido relaciones con ellas y eso te ha hecho gozar mucho, porque yo no puedo tener esta fantas\u00eda contigo\u201d.<\/p>\n<p>\u201cPero es que me da cosa nunca hemos hecho nada con un hombre, salvo mostrar las piernas en los restoranes o en el auto, mostrar los senos y el poto en la playa, no s\u00e9 no me atrevo\u201d.<\/p>\n<p>\u201cQu\u00e9date tranquila y veamos qu\u00e9 pasa. As\u00ed como est\u00e1s con esa ropa te ves muy rica\u201d, dije, tom\u00e1ndola de la cintura y d\u00e1ndole un tremendo beso le met\u00ed la mano por debajo del vestido haci\u00e9ndole cari\u00f1o en su chorito, que me di cuenta estaba un poco h\u00famedo, se\u00f1a que sent\u00eda algo de morbo al igual que yo.<\/p>\n<p>Salimos del dormitorio rumbo a la cocina y al pasar por el dormitorio de Rub\u00e9n nos percatamos que tambi\u00e9n se hab\u00eda cambiado de ropa, quedando en short y polera, seguimos hacia la cocina en donde la tom\u00e9 por atr\u00e1s y la empec\u00e9 a clavar para irla calentando, llam\u00e9 a Rub\u00e9n para ofrecerle bebida y miraba por atr\u00e1s a Ver\u00f3nica con su vestidito corto luciendo sus ricas piernas y un potito redondito que me invit\u00f3 a tocarlo en el preciso momento que entraba mi sobrino que debe haber alcanzado a v\u00e9rselo.<\/p>\n<p>No s\u00e9 si yo por el morbo que ten\u00eda que Rub\u00e9n se calentara con ella que me imaginaba cosas, pues Ver\u00f3nica no se inmut\u00f3 cuando \u00e9l entr\u00f3 y yo le estaba tocando y mirando su trasero.<\/p>\n<p>Nos servimos un vaso de bebida con Pisco cada uno de nosotros, en ese momento Ver\u00f3nica sali\u00f3 de la cocina y pas\u00f3 entre Rub\u00e9n y yo, como estaba un poco estrecho donde ocup\u00e1bamos el pasillo, su busto se refreg\u00f3 en mi pecho y su poto pas\u00f3 por el pico de mi sobrino, qui\u00e9n t\u00edmidamente se ech\u00f3 para atr\u00e1s.<\/p>\n<p>Enseguida nos fuimos los tres al living a conversar, Ver\u00f3nica se sent\u00f3 en un sill\u00f3n frente a nosotros que nos sentamos en el sof\u00e1, desde donde ten\u00edamos una vista espectacular de sus piernas bronceadas, su vestido corto dejaba poco a la imaginaci\u00f3n, yo miraba a Rub\u00e9n cuando Ver\u00f3nica le conversaba y su vista estaba siempre clavada en sus piernas, que con o sin querer ella las mov\u00eda al ritmo de la m\u00fasica que escuch\u00e1bamos, permitiendo as\u00ed una mejor visi\u00f3n hacia adentro.<\/p>\n<p>De repente se par\u00f3 para ir a la cocina, por lo que descruz\u00f3 las piernas dejando ver el calz\u00f3n metido en su chuchita, ah\u00ed fue el tope para Rub\u00e9n, quedo casi bizco con la vista de esa rajita que ya se tragaba el calz\u00f3n.<\/p>\n<p>Seguimos conversando de sus estudios cuando volvi\u00f3 Ver\u00f3nica diciendo que pas\u00e1ramos a comer, nos sentamos a la mesa y lleg\u00f3 ella con los platos le sirvi\u00f3 a Rub\u00e9n primero y se dio vuelta para servirme a m\u00ed, momento en que lo mir\u00e9 y ten\u00eda los ojos clavados en el trasero de Ver\u00f3nica, que cuando se acerc\u00f3 a m\u00ed, aprovech\u00e9 de meterle la mano por debajo del vestido y le toqu\u00e9 su vagina, la cual ya se encontraba mojad\u00edsima.<\/p>\n<p>Pens\u00e9 para mis adentros, esta se est\u00e1 calentando con la idea de excitar al muchacho. Cuando se la apret\u00e9 me mir\u00f3 y me gui\u00f1\u00f3 un ojo.<\/p>\n<p>La conversaci\u00f3n fue de un lado a otro, de los estudios, la familia y sali\u00f3 el tema de las mujeres, le pregunt\u00e9 a Rub\u00e9n si ten\u00eda novia, me dice que no por el momento, le pregunto si ha tenido relaciones sexuales con alguna mujer, se puso rojo de verg\u00fcenza, mir\u00f3 a Ver\u00f3nica, trag\u00f3 saliva y reconoci\u00f3 que a\u00fan no hab\u00eda tenido contacto con ninguna, ella le dijo en tono muy maternal tom\u00e1ndole la cara, \u201cno te preocupes ya llegar\u00e1 y cuando llegue ser\u00e1 muy rico\u201d, se seren\u00f3 y se rio con Ver\u00f3nica.<\/p>\n<p>Continu\u00f3 la conversaci\u00f3n preferentemente sobre el mismo tema, que yo me preocupaba de mantener.<\/p>\n<p>Terminamos de comer y ambos le ayudamos a llevar los platos a la cocina, volv\u00ed con Rub\u00e9n al living haciendo que se sentar\u00e1 de tal manera que de ah\u00ed pudiera ver lo que pasaba en la cocina, ya que yo hab\u00eda dejado la puerta abierta intencionalmente.<\/p>\n<p>Con el pretexto de preparar otro trago fui a la cocina poni\u00e9ndome detr\u00e1s de Ver\u00f3nica meti\u00e9ndole la mano por debajo del vestido levant\u00e1ndolo lo suficiente para que se vieran los muslos y el nacimiento de las nalgas haciendo como que no me daba cuenta que del living Rub\u00e9n miraba con tama\u00f1os ojos el nuevo espect\u00e1culo, hice girar a Ver\u00f3nica dej\u00e1ndola de espaldas a la puerta y comenc\u00e9 a besarla en la boca siempre con la mano metida en su trasero, y con la otra por delante le tocaba su chorito, que estaba espectacularmente mojado, \u201c\u00bfqu\u00e9 te pasa?\u201d, le pregunt\u00e9 al o\u00eddo, \u201cme he calentado mucho el andar as\u00ed y mostrarme delante de Rub\u00e9n, me excit\u00f3 mucho cuando me abr\u00ed de piernas en el living\u201d.<\/p>\n<p>\u201cBueno ahora exc\u00edtate m\u00e1s que mientras te levanto el vestido \u00e9l est\u00e1 mirando desde el living, has como que no nos damos cuenta y s\u00edgueme\u201d.<\/p>\n<p>Al parecer eso la calent\u00f3 m\u00e1s aun ya que se me peg\u00f3 al cuerpo y se mov\u00eda sintiendo el pico que ya se me reventaba, la gir\u00e9 y la puse agachada con su est\u00f3mago en la mesa de la cocina, de ah\u00ed no se ve\u00eda el living, le levant\u00e9 el vestido y le saqu\u00e9 los calzones, meti\u00e9ndole poco a poco, mil\u00edmetro a mil\u00edmetro, el pico en su zorrita mojada y caliente.<\/p>\n<p>Ella se dej\u00f3 hacer, con mi movimiento lento comenz\u00f3 a moverse ella tambi\u00e9n, cuando present\u00ed que le ven\u00eda el orgasmo, se lo saqu\u00e9, reclam\u00f3 que porqu\u00e9 lo hac\u00eda, es para que te mantengas excitada al m\u00e1ximo, la tom\u00e9 de la mano y salimos al living donde estaba Rub\u00e9n tratando de disimular lo parado que ten\u00eda el pico.<\/p>\n<p>Ver\u00f3nica prepar\u00f3 otra corrida de tragos y se sent\u00f3 de lado con las piernas encogidas junto a Rub\u00e9n y se inclin\u00f3 para encender una l\u00e1mpara de una mesita lateral, permitiendo que Rub\u00e9n le viera pr\u00e1cticamente todo el poto y yo tambi\u00e9n, entonces fui y me sent\u00e9 detr\u00e1s de ella, dej\u00e1ndola al medio de Rub\u00e9n y yo.<\/p>\n<p>La conversaci\u00f3n nuevamente se deriv\u00f3 al sexo, mientras yo iba metiendo la mano bajo el vestido de Ver\u00f3nica, pero ya en forma descarada, despu\u00e9s de lo que hab\u00eda visto Rub\u00e9n desde el living a la cocina, no hab\u00eda que andar con demasiado recato, apres\u00e9 la zorra de Ver\u00f3nica con la mano iniciando una masturbaci\u00f3n suave, al principio ella se cort\u00f3 un poco comenc\u00e9 a besarle el cuello, siempre por detr\u00e1s y ah\u00ed se entreg\u00f3 por entera a lo que yo quisiera hacer, pues dejo de resistirse retomando la conversaci\u00f3n, Rub\u00e9n apresur\u00f3 su trago como si quisiera refrescar la calentura que sent\u00eda.<\/p>\n<p>En la medida que iba toc\u00e1ndole su chorito le iba levantando un poco el vestido, dejando ver medio muslo y mi mano acariciando su pubis.<\/p>\n<p>Rub\u00e9n miraba con cara de idiotizado.<\/p>\n<p>Para calmar un poco o subir m\u00e1s los \u00e1nimos, Ver\u00f3nica le puso una mano en el muslo y le dijo, \u201cdisculpa a Ra\u00fal, pero es tremendo, anda todo el d\u00eda toca que toca\u201d.<\/p>\n<p>Rub\u00e9n cuando sinti\u00f3 la mano de Ver\u00f3nica en su muslo, casi cercana a su pico, peg\u00f3 un brinco, y yo empujando el codo de Ver\u00f3nica le hice llevar la mano hac\u00eda el bulto que emerg\u00eda en el short de Rub\u00e9n, hasta que se lo roz\u00f3 y le dijo, \u201cque pasa que est\u00e1s tiritando como una hoja, c\u00e1lmate mi vida me imagino que est\u00e1s que ardes, se te nota aqu\u00ed\u201d dijo poni\u00e9ndole la mano encima del paquete y apret\u00e1ndoselo, Rub\u00e9n balbuce\u00f3, \u201cno t\u00eda estoy tranquilo\u201d, y Ver\u00f3nica le tom\u00f3 una mano y se la puso en el muslo de ella muy cerca de la m\u00eda que se encontraba metida en su zorra que estilaba de jugos de calentura, mientras segu\u00eda acarici\u00e1ndole el pico por encima del short.<\/p>\n<p>\u201c\u00bfTe gusta?\u201d le pregunt\u00e9 a Rub\u00e9n, \u201ctu t\u00eda te subir\u00e1 a los cielos\u201d.<\/p>\n<p>Ya el pobre chico no hablaba, casi no respiraba volvi\u00f3 a balbucear, \u201csi t\u00edo ya no doy m\u00e1s\u201d.<\/p>\n<p>Saqu\u00e9 la mano del chorito de Ver\u00f3nica y tom\u00e9 la mano de Rub\u00e9n llev\u00e1ndola a donde yo la ten\u00eda antes haciendo que le tocara los pelitos mojados por los jugos de Ver\u00f3nica, ella empez\u00f3 a suspirar de gustito mientras yo le besaba el cuello y las orejas y le empezaba a tocar los pechos.<\/p>\n<p>Rub\u00e9n se fue entusiasmando en la medida que sent\u00eda la zorrita caliente y mojada de Ver\u00f3nica, le dije al o\u00eddo, s\u00e1caselo, corri\u00f3 el short y le sac\u00f3 el pico tremendamente parado, era un poco m\u00e1s delgado y corto que el m\u00edo, pero para Ver\u00f3nica el hecho de estar tomando otro pico que no fuera el m\u00edo y con mi consentimiento, la estimul\u00f3 de una manera muy especial, se dio vuelta y me dio un tremendo beso, diciendo, \u201cexquisito mi amor, no me imagin\u00e9 nunca que hacer esto contigo iba a ser tan de mi agrado y estimulante\u201d.<\/p>\n<p>\u201cDesinh\u00edbete has lo que quieras lo tienes todo permitido\u201d, dije, luego le empuj\u00e9 un poco la cabeza hacia abajo, adivinando ella inmediatamente lo que yo quer\u00eda, as\u00ed que se agach\u00f3 y se ech\u00f3 el pico de Rub\u00e9n a la boca, comenzando un chupa \u2013 lame, chupa \u2013 lame.<\/p>\n<p>Mir\u00e9 la cara de mi sobrino, ten\u00eda cerrados los ojos y bufaba, era su primera vez y \u00e9l actuaba como un mero espectador, que se dejaba hacer y tocar, la zorra de Ver\u00f3nica, le pregunto, \u201c\u00bfes mejor que hacerse la paja?\u201d, \u201csi t\u00edo -me contest\u00f3- much\u00edsimo m\u00e1s rico\u201d, Ver\u00f3nica se sac\u00f3 el pico de la boca y le dice, \u201cespera que falta mucho y a\u00fan lo mejor\u201d y continu\u00f3 chupando que era un gusto.<\/p>\n<p>Como yo estaba por detr\u00e1s de Ver\u00f3nica le empec\u00e9 a sacar el vestido dej\u00e1ndola totalmente desnuda, ella le hizo se\u00f1as a Rub\u00e9n para que se sacara el short, que ya ten\u00eda pr\u00e1cticamente abajo y la polera, para no ser menos yo tambi\u00e9n me desnud\u00e9, quedando los tres en pelota, le par\u00e9 el culito a Ver\u00f3nica y se lo comenc\u00e9 a meter, encontr\u00e1ndome con un choro tan mojado que se fue solo el pico para adentro, dos movidas y le vino ese orgasmo que hab\u00eda quedado interrumpido en la cocina.<\/p>\n<p>Como grit\u00f3 de gusto, se retorc\u00eda y buscaba la forma de tenerlo m\u00e1s metido.<\/p>\n<p>De repente Rub\u00e9n se empez\u00f3 a poner tenso y a decir, \u201c\u00a1ay, t\u00eda por favor para que voy a acabar\u201d, ella hizo caso omiso a la advertencia de \u00e9l y aceler\u00f3 sus movimientos, amas\u00e1ndole los test\u00edculos y haci\u00e9ndole cosquillas con un dedo en el ano, de s\u00fabito Rub\u00e9n grit\u00f3, \u201cayayaicito, ayayay, estoy acabando, ay que rico\u201d.<\/p>\n<p>Yo miraba como a Ver\u00f3nica se le sal\u00eda de la boca el semen que no pod\u00eda tragar, todo eso deriv\u00f3 en un nuevo orgasmo tan violento como el anterior.<\/p>\n<p>Ella cuando est\u00e1 muy caliente tiene m\u00faltiples orgasmos, por lo que pude dimensionar lo caliente que estaba en ese momento, teniendo un pico metido y chupando otro pico virgen, que nunca hab\u00eda recibido ese tratamiento que ella le estaba dando.<\/p>\n<p>Sigui\u00f3 movi\u00e9ndose y chupando hasta que Rub\u00e9n se ech\u00f3 para atr\u00e1s totalmente rendido por la tremenda acabada que se hab\u00eda pegado.<\/p>\n<p>Yo segu\u00eda pegado al trasero de Ver\u00f3nica gozando por lo caliente de la zorra de ella, como tambi\u00e9n por el espect\u00e1culo que estaba presenciando y lo excitada que estaba mi esposa, y le dije, \u201cquieres ir al dormitorio que estaremos m\u00e1s c\u00f3modos\u201d, \u201cbueno vamos\u201d, partimos yo abraz\u00e1ndola por la espalda y manoseando sus pechos y ella pr\u00e1cticamente tirando del pico a Rub\u00e9n.<\/p>\n<p>Llegamos al dormitorio y la hice tenderse en la cama, tom\u00e9 a Rub\u00e9n y le dije, \u201ccomo t\u00fa no tienes ninguna experiencia te vamos a ense\u00f1ar, por lo que debes hacer todo lo que te digamos\u201d, \u201cbueno t\u00edo lo que Uds. Digan\u201d, \u201cm\u00edrame a m\u00ed y luego t\u00fa haces lo mismo\u201d.<\/p>\n<p>Tom\u00e9 las piernas de Ver\u00f3nica, las abr\u00ed y met\u00ed mi cara en su choro chup\u00e1ndolo, bes\u00e1ndolo y lami\u00e9ndolo hasta llegar a tomarle el cl\u00edtoris, segu\u00ed en esa funci\u00f3n un buen rato, vi como gozaba se retorc\u00eda y me dec\u00eda, dale mi amor, dale que ya me voy de nuevo, e inicia un orgasmo violento que se tomaba la cabeza y gritaba cosas que no se le entend\u00edan, pero eran de m\u00e1ximo placer.<\/p>\n<p>Me salgo y tomo a Rub\u00e9n y le digo, \u201csigue t\u00fa\u201d, inmediatamente se ubic\u00f3 y comenz\u00f3 a pasar la lengua como si estuviera tomando un helado por esa zorra anhelante de goce, ella le tom\u00f3 la cabeza y lo fue guiando, \u201cno amorcito, tienes que meter tu lengua adentro y trata de tomar este pedacito de carne que est\u00e1 aqu\u00ed\u201d, toc\u00e1ndose ella el cl\u00edtoris, al parecer se lo tom\u00f3 muy bien porqu\u00e9 peg\u00f3 un salto y un gritito, \u201csigue, sigue, sigue, as\u00ed sigue que voy a acabar de nuevo\u201d, tom\u00e1ndole la cabeza a Rub\u00e9n apret\u00e1ndola hacia su entrepiernas, casi ahogando al pobre muchacho.<\/p>\n<p>Yo me deleitaba viendo el espect\u00e1culo y pensaba para mis adentros, cuan caliente debe estar ella que est\u00e1 multiorg\u00e1smica, que ya ha tenido al parecer cinco orgasmos seguidos, mientras jugaba con sus pechos.<\/p>\n<p>Cuando ya recobr\u00f3 la respiraci\u00f3n, tom\u00f3 a Rub\u00e9n y lo fue llevando hasta sus tetas y le ense\u00f1aba como pasarle la lengua a los pezones y mamarlos como una guagua, el muchacho feliz, dado su juventud y todo lo que estaba haciendo, ten\u00eda parado el pico como si nunca hubiera acabado, ella le acariciaba la cabeza mientras le chupaba las tetas, creo que descansando un poco de los violentos y seguidos orgasmos que tuvo.<\/p>\n<p>Con la otra mano me tomo el pico y comenz\u00f3 una suave masturbaci\u00f3n, \u201cd\u00e9jame met\u00e9rtelo, -dije-, que quiero sentir ese chorito\u201d, \u201cbueno m\u00e9temelo, que quiero acabar con el pico metido que es lo que m\u00e1s me gusta\u201d.<\/p>\n<p>Le di en el gusto y se lo met\u00ed de un viaje, pues yo tambi\u00e9n lo quer\u00eda tener metido tanto como ella, empec\u00e9 con un movimiento lento pero sostenido, ella le tom\u00f3 el pico a Rub\u00e9n y lo atrajo hasta ech\u00e1rselo a la boca, donde empez\u00f3 a chuparlo con frenes\u00ed, mientras yo me mov\u00eda y chupaba sus pechos.<\/p>\n<p>Como yo estaba encima de ella, corrido solo un tanto para el lado, ten\u00eda en primer plano la visi\u00f3n de la boca de Ver\u00f3nica trag\u00e1ndose el pico de Rub\u00e9n, como chupaba la caliente, de repente sacaba la boca y me daba un beso con lengua y luego volv\u00eda a meterse el pico a la boca continuando su funci\u00f3n, Rub\u00e9n se quejaba gozando una barbaridad, \u201cay ti\u00edta que voy a acabar de nuevo\u201d, \u201cmu\u00e9vete mi amor\u201d, me dec\u00eda ella con el pico de Rub\u00e9n a medio meter en su boca, \u201cno pares por favor no pares\u201d, iniciando el en\u00e9simo orgasmo, empez\u00f3 a acariciar los test\u00edculos de Rub\u00e9n y a meterle el dedo en el ano.<\/p>\n<p>El muchacho se qued\u00f3 quieto al sentir esas caricias y empez\u00f3 a soltar semen como la primera vez, en esta ocasi\u00f3n Ver\u00f3nica no se lo alcanz\u00f3 a tragar todo y ech\u00f3 la cabeza para un lado salpic\u00e1ndose de l\u00edquidos el cuello y los senos, obviamente que tambi\u00e9n mi cara, dado que yo se los estaba chupando.<\/p>\n<p>Acto seguido se meti\u00f3 el pico de nuevo a la boca y le hizo los \u00faltimos movimientos para que terminara de acabar y enseguida le tom\u00f3 las manos a Rub\u00e9n para que las pasara donde estaba el resto del semen en su cuerpo, as\u00ed que \u00e9l le sobaba las tetas que daba un gusto, ella empez\u00f3 a pasar su lengua por mi cara para limpiarme el semen de Rub\u00e9n, que me hab\u00eda saltado, ri\u00e9ndose alegremente de lo sucedido, pues ten\u00eda por toda la cara esparramado el l\u00edquido caliente y viscoso, daba un leng\u00fcetazo y una carcajada que fue contagiando a Rub\u00e9n que re\u00eda a no m\u00e1s dar, contagi\u00e1ndome a m\u00ed tambi\u00e9n.<\/p>\n<p>Cuando ten\u00eda casi un lado de la cara limpio con su lengua, me empez\u00f3 a besar en la boca sintiendo en mi lengua un gusto \u00e1cido que en un principio me desagrad\u00f3, no dije nada, pero ella solt\u00f3 una nueva carcajada, dici\u00e9ndome, \u201cte gust\u00f3 mi amor, si no es malo, cuanto me has hecho tragar t\u00fa en la vida\u201d, dije, \u201cme ha gustado todo lo que hemos hecho\u201d.<\/p>\n<p>Sigui\u00f3 limpi\u00e1ndome la cara y d\u00e1ndome besos en la boca, ya hasta encontraba sabroso el semen de Rub\u00e9n, ella como a\u00fan conservaba tomado el pico de Rub\u00e9n cerca de su boca, empez\u00f3 a alternar, lengua en mi cara, beso en mi boca, chupada de pico, lengua en mi cara, beso en mi boca y succionada de pico, sigui\u00f3 as\u00ed por un buen rato, mientras yo con el pico metido me mov\u00eda lentamente.<\/p>\n<p>Mi sobrino con una calentura enorme a cuestas, se le comenz\u00f3 a parar de nuevo dentro de la boca de Ver\u00f3nica, la que inici\u00f3 una sucesi\u00f3n de movimientos con su lengua, de mi cara a mi boca, de mi boca al pico de Rub\u00e9n, del pico de Rub\u00e9n a mi boca y as\u00ed continu\u00f3, yo manten\u00eda el ritmo de movimiento con el pico metido en su chorito, cosa que ella acompa\u00f1aba con sus caderas.<\/p>\n<p>En uno de esos intercambios que hac\u00eda con su lengua me tom\u00f3 la cabeza y me la empez\u00f3 a acercar m\u00e1s a su cara, quedando a un cent\u00edmetro escaso del pico de Rub\u00e9n, \u201cb\u00e9saselo\u201d me dijo al o\u00eddo, \u201cno eso si que no\u201d dije yo, ella reclam\u00f3, \u201ccomo me hiciste hacer lo mismo con Pilar, dame en el gusto a mi ahora\u201d, y empuj\u00f3 mi cabeza el cent\u00edmetro que faltaba para llegar al pico de Rub\u00e9n, ella con sus labios lo empuj\u00f3 hasta ubicarlo en los m\u00edos, mientras presionaba mi cabeza hacia su boca quedando ambas separadas solo por el pico de Rub\u00e9n.<\/p>\n<p>Al principio me produjo una sensaci\u00f3n rara, mezcla de sentirme rebajado en mi hombr\u00eda y mezcla de verg\u00fcenza ante ella y mi sobrino, yo no s\u00e9 si presinti\u00f3 mis sentimientos, me conoce mejor que yo a m\u00ed, que me dijo, \u201cmi amor me encanta lo que estamos haciendo, me est\u00e1s volviendo loca de gusto, no creas que voy a pensar mal de ti\u201d, acompa\u00f1ando sus dichos con el inicio de un nuevo orgasmo violent\u00edsimo, hizo tal presi\u00f3n en mi nuca para que se me metiera todo el pico en la boca, lo logr\u00f3 y ah\u00ed cambiaron mis sensaciones, pues se me vino a la mente como se chupaban las conchas con Pilar y como gozaba yo, as\u00ed que me dije, dale en el gusto a tu mujer, si t\u00fa la metiste en esto ahora aguanta y empec\u00e9 a chuparle el pico a Rub\u00e9n mientras Ver\u00f3nica se lo sujetaba con la mano para que no se saliera de ah\u00ed.<\/p>\n<p>Ella se tranquiliz\u00f3 del violento orgasmo y me motivaba con caricias para que siguiera chup\u00e1ndolo.<\/p>\n<p>Comenc\u00e9 a hacer lo que siempre vi y lo que a m\u00ed me gusta que me hagan.<\/p>\n<p>As\u00ed que recorr\u00eda el pico con mi lengua por el lado del frenillo, bajaba hasta sus test\u00edculos me lo met\u00eda de nuevo en la boca, se lo apretaba con los labios y le corr\u00eda su cuero para abajo y para arriba, Ver\u00f3nica ayudaba con una masturbaci\u00f3n con la punta de los dedos y caricias en los test\u00edculos y en el ano, pues las dos veces anteriores que hab\u00eda acabado hab\u00eda sido con ese tipo de caricias.<\/p>\n<p>De repente sent\u00ed que el pico se le pon\u00eda m\u00e1s duro de lo que lo ten\u00eda, me dije capaz que ahora acabe, justo en ese momento se pone a soltar semen como si jam\u00e1s en su vida hubiera acabado.<\/p>\n<p>Me llen\u00f3 la boca de semen as\u00ed que de inmediato la saqu\u00e9 para atr\u00e1s, tomando la cara de Ver\u00f3nica para que siguiera, ella continu\u00f3 chup\u00e1ndoselo hasta que termin\u00f3 de acabar, le traspas\u00e9 todo el semen que ten\u00eda en la boca a la boca de ella, qui\u00e9n lo recibi\u00f3 feliz, pues consider\u00f3, as\u00ed lo supe despu\u00e9s, que lo que me hizo hacer en ese momento, era la haza\u00f1a m\u00e1s grande que ella hab\u00eda logrado, pues nunca se hab\u00eda atrevido a propon\u00e9rmelo siquiera, pero era una tremenda fantas\u00eda que ten\u00eda ella guardada.<\/p>\n<p>Yo a\u00fan no hab\u00eda acabado y manten\u00eda el pico metido en el chorito de Ver\u00f3nica, y le dije, \u201cquieres que ahora Rub\u00e9n te lo meta para que se descartuche\u201d, \u201cpor supuesto que si, si quiero ver que se siente con un hombre virgen\u201d, acto seguido comenz\u00f3 a tomarle el pico y a darle besos y masturbarlo, claro su juventud respondi\u00f3 r\u00e1pidamente y nuevamente se le empez\u00f3 a parar, qui\u00e9n volviera a tener su edad, pens\u00e9 para mis adentros.<\/p>\n<p>Me retir\u00e9 de encima de Ver\u00f3nica y le dije a Rub\u00e9n, \u201cponte como estaba yo\u201d, le tom\u00e9 las piernas a ella y se las flect\u00e9 para que quedaran encogidas alrededor de la cintura de Rub\u00e9n y le met\u00ed una almohada doblada en dos bajo las caderas, quedando con la pelvis bien levantada, as\u00ed pod\u00eda apreciar mejor cuando le entrara el pico del muchacho, este se acomod\u00f3 como pudo por su falta de experiencia, la cual supl\u00eda con su calentura.<\/p>\n<p>Yo le tom\u00e9 el pico y se lo empec\u00e9 a refregar en el choro de Ver\u00f3nica arranc\u00e1ndole gritos de placer a ambos, ella dijo \u201cm\u00e9telo\u201d, as\u00ed que lo enfrent\u00e9 a ese hoyo ansioso y el resto corri\u00f3 por cuenta de Rub\u00e9n ya que peg\u00f3 una embestida tremenda, parec\u00eda un perrito con un mete y saca a todas fuerzas, Ver\u00f3nica lo par\u00f3 y le dijo, \u201ccalmado yo te voy a ense\u00f1ar como lo debes hacer\u201d y tom\u00e1ndolo de las caderas lo fue guiando como deb\u00eda moverse, acompa\u00f1ando con los movimientos de ella.<\/p>\n<p>Yo pens\u00e9, aqu\u00ed est\u00e1 mi venganza, al ver el culo parado de Rub\u00e9n, as\u00ed que le tom\u00e9 la mano a Ver\u00f3nica e hice que le empezara a meter un dedo en el poto, como lo hab\u00eda hecho cuando se lo chupaba, para eso le fui echando la crema que estaba en el velador y cuando ya le ten\u00eda casi dos dedos enteros metidos, ella empez\u00f3 su no s\u00e9 qu\u00e9 n\u00famero de orgasmo, aumentando todos sus movimientos y haciendo m\u00e1s presi\u00f3n con los dedos en el poto de Rub\u00e9n.<\/p>\n<p>Este instintivamente o por placer se dejaba hacer de todo y se mov\u00eda como loco, as\u00ed que me ubiqu\u00e9 detr\u00e1s de \u00e9l y apunt\u00e9 mi pico a su ano retirando la mano de Ver\u00f3nica que me hac\u00eda que no lo hiciera, le tom\u00e9 las nalgas y se las separ\u00e9, viendo un hoyo un poco dilatado por los dedos de ella, as\u00ed que le puse m\u00e1s crema y apoy\u00e9 la punta de mi pico iniciando una presi\u00f3n lenta pero firme y sostenida sintiendo como iba entrando, se quiso salir, alegando que le dol\u00eda, pero cuando se movi\u00f3 hacia atr\u00e1s y yo empuj\u00e9 para delante, le entr\u00f3 hasta la mitad y como \u00e9l se lo ten\u00eda metido a Ver\u00f3nica, que a la vez lo aprisionaba por la cintura, prefiri\u00f3 quedarse quieto.<\/p>\n<p>Ver\u00f3nica se segu\u00eda moviendo, yo quieto, pero con el movimiento de \u00e9l y de ella mi pico se mov\u00eda solo en el poto de Rub\u00e9n, esper\u00e9 pacientemente que comenzara a acabar, pues ah\u00ed le vendr\u00eda lo m\u00e1ximo de calentura y llevar\u00eda a cabo mi venganza por haberle chupado su pico y hubiera acabado dentro de mi boca.<\/p>\n<p>As\u00ed fue que cuando empez\u00f3 a acabar se mov\u00eda como un loco, produci\u00e9ndome una sensaci\u00f3n tan exquisita que tambi\u00e9n me dieron ganas de acabar, sent\u00ed los gritos de Rub\u00e9n, los quejidos y gritos de placer de Ver\u00f3nica produci\u00e9ndome un morbo de ten\u00e9rselo entero metido que acab\u00e9 con tanto o m\u00e1s gritos que ellos dos juntos.<\/p>\n<p>Ver\u00f3nica tuvo dos orgasmos seguidos, le rasgu\u00f1o la espalda al pobre Rub\u00e9n que segu\u00eda movi\u00e9ndose sin importarle lo que le estaba pasando por atr\u00e1s.<\/p>\n<p>Ca\u00edmos los tres agotados en la cama resollando como si hubi\u00e9ramos corrido una marat\u00f3n.<\/p>\n<p>Con Ver\u00f3nica nos abrazamos muy pero muy apretados y nos besamos en se\u00f1al de mucho amor, ella me susurr\u00f3 al o\u00eddo, \u201cte pasaste loco degenerado\u201d, enseguida se dio vueltas y tom\u00e1ndole la cara a Rub\u00e9n le dio un beso en la boca preguntando, \u201c\u00bfte ha gustado t\u00fa iniciaci\u00f3n?\u201d, \u201csi mucho, pero lo que me hizo el t\u00edo no tanto, pues me arde un poco\u201d, \u201cpobrecito -le dijo ella-, ya se te pasar\u00e1, lo importante es que te gust\u00f3, ya haremos m\u00e1s\u201d, inmediatamente la golosa nos tom\u00f3 el pico a los dos empezando a moverlos con mucho arte logrando que mi erecci\u00f3n fuera primero que la de Rub\u00e9n, bueno la m\u00eda era la segunda y la de \u00e9l era la cuarta.<\/p>\n<p>Cuando vio que lo ten\u00eda duro de nuevo se mont\u00f3 encima meti\u00e9ndoselo de golpe y comenz\u00f3 a cabalgar con frenes\u00ed.<\/p>\n<p>\u201cNo te cansas\u201d, dije, \u201ct\u00fa me has hecho as\u00ed, t\u00fa me formaste, me excitaste tanto que quiero m\u00e1s y m\u00e1s\u201d.<\/p>\n<p>Sigui\u00f3 una noche de sexo incre\u00edble, nos quedamos dormidos los tres en la cama, por la ma\u00f1ana al despertarnos comenc\u00e9 a tener sexo con Ver\u00f3nica e inmediatamente quiso tener con Rub\u00e9n, ah\u00ed los dej\u00e9 solos para que lo disfrutaran al m\u00e1ximo, perd\u00ed la cuenta de los orgasmos que tuvo ella, contra los dos de \u00e9l y los dos m\u00edos, uno en el choro de ella y el otro de nuevo en el ano de Rub\u00e9n, que no reclam\u00f3 para nada, m\u00e1s creo que le gusto bastante.<\/p>\n<p>La fiesta continu\u00f3 esa tarde, luego el lunes \u00e9l a su Universidad y nosotros al trabajo, luego de ah\u00ed \u00e9l volv\u00eda al campo y estamos a la espera de que regrese para repetir la historia.<\/p>\n<p>Todo lo que pas\u00f3 lo recordamos por las noches y cuando hacemos el amor nos excitamos de una manera.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58274\" class=\"pvc_stats total_only  \" data-element-id=\"58274\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 15<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Mi sobrino con una calentura enorme a cuestas, se le comenz\u00f3 a parar de nuevo dentro de la boca de Ver\u00f3nica, la que inici\u00f3 una sucesi\u00f3n de movimientos con su lengua, de mi cara a mi boca, de mi boca al pico de Rub\u00e9n, del pico de Rub\u00e9n a mi boca y as\u00ed continu\u00f3, yo manten\u00eda el ritmo de movimiento<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58274\" class=\"pvc_stats total_only  \" data-element-id=\"58274\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30624,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-58274","post","type-post","status-publish","format-standard","category-amor-filial"],"a3_pvc":{"activated":true,"total_views":17495,"today_views":1},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30624"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=58274"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58274\/revisions"}],"predecessor-version":[{"id":58276,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58274\/revisions\/58276"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=58274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=58274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=58274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}