{"id":58369,"date":"2025-03-20T00:04:16","date_gmt":"2025-03-19T23:04:16","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=58369"},"modified":"2025-03-19T13:28:20","modified_gmt":"2025-03-19T12:28:20","slug":"vacaciones-en-zuana-bech-resort","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/vacaciones-en-zuana-bech-resort\/","title":{"rendered":"Vacaciones en Zuana Bech Resort"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"58369\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">23<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Mi esposa Luz Stella de 1.7 m de estatura, 60 kg de peso con un par de tetas coronadas de unos pezones listos para ser chupados y con un culo de campeonato, yo su esposo un ingeniero de 1.75 m de estatura, 70 kg, la naturaleza me doto con un pene de 23 cm en erecci\u00f3n, que mi esposa gusta de mamar.<\/p>\n<p>Viajamos a Estados Unidos a visitar amigos y a divertirnos, en nuestra Colombia tenemos algunos amigos muy queridos, entre ellos la fantas\u00eda de mi esposa su amigo Manuel, que siempre quiso foll\u00e1rselo, no s\u00e9 por qu\u00e9 no se lo foll\u00f3, al menos yo no lo s\u00e9.<\/p>\n<p>Porque Manuel siempre le acompa\u00f1aba al apartamento hacia las 11 de la noche, ven\u00edan de las t\u00edpicas reuniones en la administraci\u00f3n del conjunto, en el apto yo hab\u00eda instalado c\u00e1maras para vigilar lo que suced\u00eda en su interior, y muchas veces al entrar por el cuarto piso se besaban, Manuel le magreaba las tetas y el culo, y ella le sobaba la verga por encima de su pantal\u00f3n, ah\u00ed hab\u00eda dos alcobas con sus camas, pero ellos solo se morreaban y nunca follaron dentro del apto. Si follaron, tuvieron que salir a fornicar en alg\u00fan motel.<\/p>\n<p>A mi esposa se le ocurri\u00f3 invitar a su amigo a pasar una semana en Zuana Beach Resort, pues en agosto tenemos la semana para disfrutar, de paso celebrarle a Manuel el cumplea\u00f1os, cuando le llame para invitarlo a instancias de mi esposa, ella le dijo le partir\u00eda el biscocho. Despu\u00e9s le coment\u00e9 a mi esposa: \u201cManuel no tiene biscocho, el tiene es un par de huevos\u201d; a lo que ella me respondi\u00f3: \u201clo s\u00e9, entonces que \u00e9l me parta el biscocho y yo le rompo los huevos para chupar esa miel deliciosa que tendr\u00e1\u201d, y le dije: \u201cpor lo que dice, lo que quiere usted es follarse a Manuel y chuparle la verga y tragarse su semen\u201d, ella solo sonri\u00f3 enigm\u00e1tica.<\/p>\n<p>El domingo 18 de agosto d\u00eda que Manuel cumple a\u00f1os lleg\u00f3 Manuelito a Zuana hacia las 10 de la ma\u00f1ana, mi esposa y yo le esper\u00e1bamos en el lobby, mi esposa muy nerviosa, se saludaron de abrazo y Manuel la beso, beso que fue correspondido con apretada de culo por ambas partes, conmigo un apret\u00f3n de manos, y subimos a la suite a dejar la maleta del cumplea\u00f1ero, esperamos que se pusiera el ba\u00f1ador y bajamos a la piscina.<\/p>\n<p>Hacia la 1 de la tarde pasamos al comedor y almorzamos, para finalizar le cantamos el happybirth Day y reparti\u00f3 una torta, y nos fuimos a la playa nos recostamos en las tumbonas y conversamos de todo, luego pedimos unas cervezas a la mesa de la piscina al igual que unos cocos locos, unos cupitos y a jugar en la piscina. Hacia las 7 de la tarde fuimos a la suite nos duchamos y nos vestimos a ir a la disco a celebrar.<\/p>\n<p>En la disco se pidi\u00f3 una botella de whisky y una botella de vino para mi esposa, se sirvieron los vasos y copa y se brind\u00f3 por el cumplea\u00f1ero, copas vac\u00edas y segunda ronda y as\u00ed, beb\u00edamos muy r\u00e1pido hasta la quinta ronda, Manuel invit\u00f3 a bailar a mi mujer, ella se colg\u00f3 a su cuello y muy apretaditos bailaban, Manuel le acariciaba la espalda y bajaba hasta su culo y se lo apretaba, mientras ella con disimulo le acariciaba la polla y se besaban.<\/p>\n<p>Despu\u00e9s de cuatro piezas volvieron a la mesa y bebieron a fondo blanco, pasadas tres canciones baile con mi mujer, la abrace la aprete y la bese, le aprete el culo y le dije entonces la celebraci\u00f3n es en grande, te vas a follar a Manuel y me dijo que si, que ten\u00eda la verga super parada y ella ya estaba cachonda con la chocha super h\u00fameda, le dije: te duchas y te pones un vestido sin nada debajo. Hacia las 11 de la noche subimos a la suite.<\/p>\n<p>Nos duchamos y cambiamos para seguir la celebraci\u00f3n, ronda de tragos a fondo blanco, ya est\u00e1bamos bastante contentos, nos pusimos a bailar los tres con mi mujer en s\u00e1ndwich, nos morre\u00e1bamos y nos besamos y le acarici\u00e1bamos todo a la putica de mi mujercita. En un momento yo le deslice las tiras del vestido por los hombros, el vestido cay\u00f3 y mi putica quedo desnuda entre los dos, Manuel le besaba, le chupaba las tetas y mord\u00eda sus pezones, yo me baje met\u00ed mi cara entre sus nalgas y le lamia el culo y el chocho, Manuel se arrodill\u00f3 y comenz\u00f3 a comerle el chocho y le meti\u00f3 dos dedos ensalivados en su vagina, ella gem\u00eda.<\/p>\n<p>Yo me retir\u00e9 y les observaba, Manuel la acost\u00f3 boca arriba y se meti\u00f3 entre sus piernas le chupaba el cl\u00edtoris y le follaba con al lengua y sus dedos, ella le dijo que se girara para chuparle la verga, hicieron un 69 estupendo mientras yo me pajeaba, \u00e9l le dijo si me sigues chupando as\u00ed me voy a correr Luz Stella, ella dijo no importa quiero tu semen dentro de m\u00ed, en mi boca o en mi chocho pero bien dentro, tambi\u00e9n me voy a correr en tu boca Manuelito, quiero tu verga en mi chocho, follame, follame por favor.<\/p>\n<p>\u00c9l se gir\u00f3 le abri\u00f3 m\u00e1s la piernas y se lo meti\u00f3 de un solo envi\u00f3n y ella gritaba: oh que rico me estoy corriendo en tu verga, h\u00e1game m\u00e1s, follame fuerte, m\u00e1s duro, r\u00f3mpame el chocho, ahh ahh, me estoy corriendo de nuevo, pr\u00e9\u00f1ame, pr\u00e9\u00f1ame, despu\u00e9s de 10 minutos de meter y sacar su verga del chocho de mi mujer Manuelito lleg\u00f3 al orgasmo y le lleno el chocho de semen a mi mujer y simult\u00e1neamente ella tuvo su tercer orgasmo y yo eyacul\u00e9 cayendo mi semen al piso. Se besaban y acariciaban dejando que su respiraci\u00f3n se normalizara.<\/p>\n<p>Me miraron sonrientes, serv\u00ed una ronda y brindamos por el polvo y por el cumplea\u00f1ero, Manuelito se gir\u00f3 y comenz\u00f3 un nuevo 69, chupaba el chocho de mi mujer y se com\u00eda todos los flujos que sal\u00edan de esa vagina, Hasta que dejo el chocho limpio de flujos y ella le dejo la verga limpia y reluciente, adem\u00e1s Manuel y yo las ten\u00edamos tiesas y duras listas para el segundo polvo.<\/p>\n<p>Manuel se qued\u00f3 boca arriba, y mi esposa lo monto, toda una amazona se daba buenos sentones, sus tetas rebotaban por el movimiento, me puse detr\u00e1s de ellos, incline a la zorra de mi mujer sobre Manuel y comenc\u00e9 a comerle el culo y a dilat\u00e1rselo con lubricante, hasta tres dedos le met\u00ed en el culo, cog\u00ed mi verga que estaba como una roca y se la puse en el ano y comenc\u00e9 a empujar despacio, fue entrando sin problemas y yo empujaba mis 23 cent\u00edmetros de verga, hasta que mis huevos chocaron con su chocho.<\/p>\n<p>Y comenzamos en sincron\u00eda un meter y sacar del culo y del chocho, mi mujer gritaba, gem\u00eda, y dec\u00eda me est\u00e1n matando cabrones, que rico sentir y disfrutar de sus pollas, los dos d\u00e1ndome verga, oh Dios que rico, me corro, me corro y seguimos serruchando el chocho y el culo como por 15 minutos y tuvimos un orgasmo simult\u00e1neo, por segunda vez Manuel le llenaba el chocho a la putica de mi esposa y yo le llenaba el culo de semen, ella ten\u00eda su nuevo orgasmo, quedamos los tres acostados descansando mi mujercita entre los dos.<\/p>\n<p>Mi esposita comenz\u00f3 de nuevo a chupar nuestras vergas alternadamente, Manuel girado le com\u00eda el chocho y sus fluidos y su propio semen, yo le met\u00ed dos dedos en su culo y mi semen le sal\u00eda del culo por entre mis dedos ensuciando las s\u00e1banas, yo me sent\u00e9 recostado en el cabecero de la cama para que mi mujer siguiera chupando mi verga.<\/p>\n<p>Manuel se dedic\u00f3 a comerle el chocho y el culo a mi mujer dej\u00e1ndole los orificios muy limpios, mi esposa en cuatro mamando mi la verga y Manuel se la meti\u00f3 por el culo, los dos gem\u00edan, bufaban, dec\u00edan vulgaridades y despu\u00e9s de 20 minutos Manuel le lleno los intestinos de semen a mi putica preferida y yo me derrame en su boca trag\u00e1ndose mi semen. Nos quedamos dormidos los tres desnudos con nuestras vergas fl\u00e1cidas, mi mujer con su culo y vagina inflamados de tanto follar.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58369\" class=\"pvc_stats total_only  \" data-element-id=\"58369\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Y comenzamos en sincron\u00eda un meter y sacar del culo y del chocho, mi mujer gritaba, gem\u00eda, y dec\u00eda \u201cme est\u00e1n matando cabrones, que rico sentir y disfrutar de sus pollas, los dos d\u00e1ndome verga, oh Dios que rico, me corro, me corro\u201d y seguimos serruchando el chocho y el culo como por 15 minutos y tuvimos un orgasmo simult\u00e1neo<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58369\" class=\"pvc_stats total_only  \" data-element-id=\"58369\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30848,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-58369","post","type-post","status-publish","format-standard","category-trios"],"a3_pvc":{"activated":true,"total_views":4584,"today_views":1},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30848"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=58369"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58369\/revisions"}],"predecessor-version":[{"id":58371,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58369\/revisions\/58371"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=58369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=58369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=58369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}