{"id":58575,"date":"2025-03-27T00:05:52","date_gmt":"2025-03-26T23:05:52","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=58575"},"modified":"2025-03-26T12:31:05","modified_gmt":"2025-03-26T11:31:05","slug":"4318-el-don-juan","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/4318-el-don-juan\/","title":{"rendered":"Tr\u00edo con mi madre y mi hermana"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"58575\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">87<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Me llamo Rafael y soy un don Juan. D\u00e9jenme que les explique mi historia. S\u00ed. Soy un seductor. Mi edad es de 25 a\u00f1os y he perdido la cuenta de las chicas con las que he salido. Ni siquiera soy capaz de recordar las caras de algunas de mis conquistas, ni sus nombres. En cierta ocasi\u00f3n me escribi\u00f3 una de ellas recordando nuestro amor\u00edo y yo no sab\u00eda qui\u00e9n era.<\/p>\n<p>L\u00f3gicamente soy muy atractivo y bien dotado. Mi pene alcanza los 25 cent\u00edmetros.<\/p>\n<p>He de confesar algo. No siempre las consigo a todas, lo que no quiere decir que esa noche no termine en los brazos de una. Si la chica m\u00e1s o menos guapa no quiere si he de pasar la noche con otra, bueno ya me entend\u00e9is, &#8220;que no est\u00e9 tan bien&#8221;, pues me voy con ella.<\/p>\n<p>A todas les digo lo mismo; que tengo novia, pero que \u00e9sta realmente no me gusta. No es mi mujer ideal, aunque sea muy atractiva. Luego tambi\u00e9n te tienes que adaptar a la psicolog\u00eda de cada una de ellas.<\/p>\n<p>Hay una fantas\u00eda que he tenido y tengo. Estar con dos mujeres a la vez. Y no lo he podido conseguir. Una vez estaba de vacaciones en el chalet de mi madre, enrabietado por no haber podido conseguir este objetivo y mi cerebro hac\u00eda clic. Mi madre es una mujer de 46 a\u00f1os, delgada y atl\u00e9tica. Muy atractiva. Lleva el pelo muy corto, te\u00f1ido de rubio, albino. Lleva un tatuaje en su brazo derecho. Es una mujer muy liberal. Se ha divorciado dos veces y ahora vive con un hombre. Est\u00e1 un poco &#8220;loquilla&#8221; que es como la llamamos cari\u00f1osamente. Habla con nosotros abiertamente de sexo; creo que he salido a ella bastante.<\/p>\n<p>Y all\u00ed estaba tambi\u00e9n mi hermana, que tiene unos 20 a\u00f1os. Es verdaderamente bonita. De pelo casta\u00f1o, ojos marrones y una figura muy bonita. Se parece a alguna actriz italiana estilo Claudia Cardinale. Ella es diferente a mi madre y a m\u00ed. Es t\u00edmida y desde luego que ha estado con hombres, pero por ejemplo ahora no sale con ninguno. Habr\u00e1 estado con uno o con dos, en alguna fiesta creo. Est\u00e1 esperando que venga el hombre de su vida, pero dentro de ella se que hay una fogosidad reprimida.<\/p>\n<p>Ya digo. Est\u00e1bamos los tres en el chalet pasando las vacaciones. Yo alterado por fracasar en lo del tr\u00edo con dos mujeres y est\u00e1bamos viendo la tele, una pel\u00edcula. Y la polla la ten\u00eda dura. Cuando me pasa esto delante de las dos me da mucha verg\u00fcenza e intento disimular, pero ahora me desinhib\u00eda. Mostraba todo mi esplendor en mis pantalones cortos. A ellas parec\u00eda que no les importaba. Fue en ese momento cuando me di cuenta de que estaba desesperado por estar con ellas dos y ten\u00eda que urdir un plan.<\/p>\n<p>Esa noche baj\u00e9 al pueblo y me ligu\u00e9 a una. La sub\u00eda a la casa y a m\u00ed habitaci\u00f3n. Era de las t\u00edas que chillan en la cama. Tambi\u00e9n es verdad que yo pon\u00eda todo mi empe\u00f1o para que as\u00ed fuese. Sab\u00eda que mi madre y mi hermana lo estar\u00edan oyendo. No s\u00e9 qu\u00e9 es lo que me dir\u00edan al d\u00eda siguiente.<\/p>\n<p>Baj\u00e9 a desayunar y les present\u00e9 a la chica. A mi hermana le cay\u00f3 muy bien. Pero mi madre me ech\u00f3 una reprimenda en cuanto pudo verme a solas.<\/p>\n<p>\u2014No traigas a las chicas a esta casa. No te da verg\u00fcenza. \u2014me dijo<\/p>\n<p>\u2014Har\u00e9 lo que me digas.<\/p>\n<p>\u2014Como sois los hombres.<\/p>\n<p>\u2014Pero ella no me gusta realmente.<\/p>\n<p>\u2014Entonces \u00bfqui\u00e9n te gusta? \u2014me dijo airada.<\/p>\n<p>\u2014S\u00f3lo puedo decirte que ninguna de las chicas con las que salgo me aprecia.<\/p>\n<p>Entonces se qued\u00f3 mi madre mir\u00e1ndome muy pensativa. Le hab\u00eda hecho clic su cerebro como a m\u00ed. La muy loquilla.<\/p>\n<p>Le dije a mi ligue que se marchara y se qued\u00f3 muy sorprendida. Y no menos que mi hermana.<\/p>\n<p>\u2014Es mi madre. No le gust\u00f3 nada lo de anoche \u2014le dije.<\/p>\n<p>Entonces la chica se ruboriz\u00f3 y se march\u00f3.<\/p>\n<p>\u2014No es justo \u2014me dijo mi hermana\u2014 nuestra madre nunca cambiar\u00e1.<\/p>\n<p>\u2014Pero tiene raz\u00f3n \u2014le dije yo\u2014 Esa chica iba a lo que iba. No es como t\u00fa.<\/p>\n<p>Hab\u00eda conseguido echar el lazo.<\/p>\n<p>Siendo mi madre, la iniciativa la tomo ella. Se meti\u00f3 en mi cama de noche y me hizo un pajote dici\u00e9ndome todo el rato: &#8220;cari\u00f1o, cari\u00f1o, \u00bfqu\u00e9 te he hecho?&#8221;. Deje la s\u00e1bana perdida.<\/p>\n<p>Pero con mi hermana fui yo. Deje la puerta del cuarto de ba\u00f1o sin echar el pestillo, &#8220;por error&#8221;. Al entrar se encontr\u00f3 con mi virilidad de 25 cent\u00edmetros. Me estaba masturbando. Ella si cerr\u00f3 y se puso a chup\u00e1rmela. \u00a1Que tirones pegaba! Su saliva se mezclaba con mis secreciones. &#8220;Qu\u00e9 bueno est\u00e1s hermanito&#8221;, me dijo. Mi corrida puso perdido el lavabo.<\/p>\n<p>Esa noche le com\u00ed el co\u00f1o a la &#8220;loquilla&#8221; y luego me la foll\u00e9. Los jadeos de mi madre me llevaron al \u00e9xtasis. Su lujuria era peor que la m\u00eda.<\/p>\n<p>La tarde siguiente le dije a mi hermana que iba a hacer con ella lo que quisiera. Le mand\u00e9 ponerse un enema, le unt\u00e9 de aceite hasta en las orejas y se la met\u00ed por el culo. Lo sent\u00ed muy estrecho, y ella disfrutaba, aunque fuese su primera vez. Era una explosi\u00f3n de su morbo. No dejaba de toquetearse el cl\u00edtoris. Cuando la saqu\u00e9 sali\u00f3 semen con algo de agua y restos.<\/p>\n<p>Pero la tarde siguiente fue la que yo tanto estaba esperando. Yo estaba tumbado en la cama y mi hermana me la estaba chupando. Luego nos fuimos al borde de la piscina. Yo sentado y ella dentro que segu\u00eda chup\u00e1ndomela. All\u00ed nos pillar\u00eda nuestra madre.<\/p>\n<p>Efectivamente nos vio. Se acerc\u00f3 por detr\u00e1s y me beso en la boca mientras acariciaba mi pecho. Esto me volvi\u00f3 loco. Quise cogerla de la mano y que se metiese en el agua, pero no quiso y se meti\u00f3 dentro en el sal\u00f3n.<\/p>\n<p>Ella segu\u00eda chup\u00e1ndomela roci\u00e1ndome con el agua de sus cabellos. La cog\u00ed de la mano y la saqu\u00e9 de la piscina siguiendo el rastro de nuestra madre. Camin\u00e1bamos los dos agarrados de la mano, dentro de la casa, mirando de habitaci\u00f3n en habitaci\u00f3n, pero no hab\u00eda nadie. Mi l\u00edvido estaba a punto de saltar por los aires. Estoy seguro de que se hab\u00eda encerrado en el servicio, pero no era as\u00ed. La vi a trav\u00e9s de una ventana. Estaba hablando con don \u00c1ngel su amigo y amante. Los dos se dirig\u00edan hacia la casa.<\/p>\n<p>Me met\u00ed en mi dormitorio con mi &#8220;amante&#8221; y volv\u00ed a foll\u00e1rmela mientras la pareja estaban abajo hablando.<\/p>\n<p>O\u00ed los pasos de mi madre que se dirig\u00edan a la habitaci\u00f3n, supongo que para decirme que dejase de estar haciendo lo que estaba haciendo con mi hermana. Aproveche ese momento para correrme impregnado la cama.<\/p>\n<p>Lo hice a prop\u00f3sito.<\/p>\n<p>\u2014Y este es el macho \u2014me dijo mi hermana\u2014 todav\u00eda suspirando por mi potencia sexual.<\/p>\n<p>En ese momento abri\u00f3 la puerta mi madre, que hab\u00eda visto toda la escena y hab\u00eda o\u00eddo esas palabras desde\u00f1osas contra m\u00ed.<\/p>\n<p>\u2014Tenemos visita, cerdo \u2014me dijo mi madre y cerr\u00f3 la puerta. Detr\u00e1s fue mi hermana ignor\u00e1ndome totalmente.<\/p>\n<p>Cuando se march\u00f3 don \u00c1ngel baj\u00e9 al sal\u00f3n con los ojos enrojecidos como si hubiese estado llorando. Se notaba mi miembro viril por debajo del pantaloncito. Cog\u00ed a mi hermana de la mano y la llev\u00e9 al servicio. Nos metimos en la ducha y se puso a chup\u00e1rmela.<\/p>\n<p>\u2014\u00bfQu\u00e9 tal lo hago? \u2014Me dijo con ojos enloquecidos por la lujuria.<\/p>\n<p>En ese momento golpearon la puerta. Mi coraz\u00f3n se aceler\u00f3 casi hasta estallar. Era mi madre. Llevaba solo una bata que dejo caer al suelo y cerr\u00f3 la puerta. La cog\u00ed de la mano y nos metimos. Los tres bajo el chorro. Mi madre, mi hermana y yo. Me la chupaban. Primero una luego la otra. Mi hermana apretaba m\u00e1s y me daba con los dientes. Mi madre usaba m\u00e1s la lengua y los labios; lo hac\u00eda m\u00e1s despacio.<\/p>\n<p>Despu\u00e9s las dos a la vez. Como jadeaba yo. Dientes, lengua, labios, fragancias, manos, fuerza. Obligu\u00e9 a mi madre a ponerse detr\u00e1s de m\u00ed para besarme el culo. Mi hermana succionaba y mi madre met\u00eda su lengua en mi ano. Luego las cambiaba cogi\u00e9ndolas del pelo. Mi madre jugueteando con mi polla en su boca y mi hermana enloquec\u00eda por mi trasero, lamiendo y toqueteando con sus dedos.<\/p>\n<p>La corrida fue bestial. Las puse perdidas y luego les daba besos en la cara y me frotaba con sus caras: &#8220;os quiero&#8221;, les dec\u00eda. &#8220;Es de verdad porque me quer\u00e9is&#8221;.<\/p>\n<p>Sal\u00ed de la ducha y ambas se estaban masturbando cada una en su rinc\u00f3n de la ba\u00f1era, con los ojos cerrados.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58575\" class=\"pvc_stats total_only  \" data-element-id=\"58575\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>En ese momento golpearon la puerta. Mi coraz\u00f3n se aceler\u00f3 casi hasta estallar. Era mi madre. Llevaba solo una bata que dejo caer al suelo y cerr\u00f3 la puerta. La cog\u00ed de la mano y nos metimos. Los tres bajo el chorro. Mi madre, mi hermana y yo. Me la chupaban. Primero una luego la otra. Mi hermana apretaba m\u00e1s<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_58575\" class=\"pvc_stats total_only  \" data-element-id=\"58575\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1698,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-58575","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":true,"total_views":38768,"today_views":53},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/1698"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=58575"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58575\/revisions"}],"predecessor-version":[{"id":58577,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/58575\/revisions\/58577"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=58575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=58575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=58575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}