{"id":60035,"date":"2025-06-04T00:02:29","date_gmt":"2025-06-03T22:02:29","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=60035"},"modified":"2025-06-03T18:36:53","modified_gmt":"2025-06-03T16:36:53","slug":"6114-orgia-en-una-sauna-naturista","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/6114-orgia-en-una-sauna-naturista\/","title":{"rendered":"Org\u00eda en una sauna naturista"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"60035\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">28<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Hab\u00eda tenido un d\u00eda de trabajo estresante, con algunos asuntos que hab\u00edan exigido mi atenci\u00f3n de forma especial. Era media tarde y me encontraba cansado y tenso, pens\u00e9 que lo mejor era salir del despacho y descansar del d\u00eda agotador en una sauna.<\/p>\n<p>Conoc\u00eda un local naturista, con excelentes instalaciones, donde podr\u00eda buscar ese descanso necesario y adem\u00e1s alegrar la vista con algunos cuerpos desnudos esculturales que seguro podr\u00eda admirar, as\u00ed que me dirig\u00ed all\u00ed. Ya hab\u00eda estado en alguna ocasi\u00f3n y siempre disfrut\u00e9 de buenos momentos, incluso cab\u00eda la posibilidad de practicar sexo si ten\u00eda la suerte de encontrar a la persona o personas adecuadas.<\/p>\n<p>Despu\u00e9s de pagar la entrada, pas\u00e9 a los vestuarios para desvestirme, guard\u00e9 la ropa en la taquilla asignada y sal\u00ed cubierto con el albornoz y las zapatillas que la casa entrega a cada cliente.<\/p>\n<p>Pas\u00e9 por la piscina climatizada, donde me ba\u00f1\u00e9 y disfrut\u00e9 un buen rato contemplando alguna dama de buen ver y alg\u00fan adonis con cuerpo bien trabajado, mientras tomaba un refresco que hab\u00eda adquirido al entrar. De all\u00ed me dirig\u00ed al jacuzzi, bastante amplio, ocupado por tres parejas, que repasaron mi cuerpo con la mirada, al quitarme el albornoz para entrar en el agua.<\/p>\n<p>Me sent\u00ed observado por unos instantes y una de las mujeres sigui\u00f3 observ\u00e1ndome y cambiando miradas insinuantes conmigo. Era atractiva, rondando los 50, con unas bonitas tetas algo ca\u00eddas por la edad. Su acompa\u00f1ante, que deb\u00eda ser su marido, de la misma edad. Al no darme por aludido ante su insistente mirada, acab\u00f3 por invitarme a sentarme a su lado, cosa que hice sin tardanza.<\/p>\n<p>Me present\u00e9 a ambos y nada m\u00e1s sentarme su mano ya estaba encima de mi muslo, lo que me dio pie para besarla. Me ofreci\u00f3 la boca con lengua y su mano, bajo el agua, fue directa a mi polla para acariciarla. Yo hice lo propio con sus tetas que acarici\u00e9 y sob\u00e9 sin dejar de morrearla a conciencia, ante la mirada de su marido que observaba como calentaba a su mujer. Opt\u00e9 por llevar mi mano a su co\u00f1o y me encontr\u00e9 con una raja enorme, bordeada por dos grandes labios que se abr\u00edan al tacto de mis dedos, invit\u00e1ndome a entrar en aquella enorme cueva.<\/p>\n<p>Despu\u00e9s de penetrarla con dos dedos y viendo la amplitud de aquella boca sexual, le penetr\u00e9 con la mano entera. Aquella puta seguro hab\u00eda sido follada por numerosas vergas y hab\u00eda parido un mont\u00f3n de veces. El cl\u00edtoris lo ten\u00eda en consonancia con su co\u00f1o y lo encontr\u00e9 erecto, fuera del capuch\u00f3n, de unos 3cts. que me permit\u00edan paje\u00e1rselo entre los dedos pulgar y coraz\u00f3n. Lleg\u00f3 un momento que la zorra estaba tan salida que propuso ir a un reservado.<\/p>\n<p>Entramos en uno en el que hab\u00eda un enorme colch\u00f3n con cabida para varias parejas. Al llegar encontramos a una joven follando con un maduro. Supuse ser\u00eda alg\u00fan cabr\u00f3n con su secretaria. La casada se tumb\u00f3 y me cogi\u00f3 la polla para llevarla a la boca, mientras su marido se baj\u00f3 a comerle el co\u00f1o. No tard\u00f3 en pedirme me tumbara para sentarse en mi boca d\u00e1ndome a comer aquel chochazo de yegua en celo, capaz de tragarse la verga de un caballo. Le met\u00ed toda la lengua y la mov\u00eda d\u00e1ndole gusto, en estas sent\u00ed me mamaban la polla, era su marido; el cabr\u00f3n la mamaba bien, as\u00ed que opt\u00e9 por dejarle hacer en recompensa a que \u00e9l me dejaba disfrutar de su puta.<\/p>\n<p>La muy guarra llevaba la voz cantante y pronto necesit\u00f3 sentir mi polla dentro. Se puso en cuatro y sin perder tiempo se la clav\u00e9 en aquel chochazo enorme rezumando fluidos. Entr\u00f3 sin rozar y pr\u00e1cticamente apenas notaba el roce de sus paredes vaginales, pod\u00eda estar horas d\u00e1ndole sin correrme ante la falta de estimulaci\u00f3n. Ella s\u00ed deb\u00eda sentir bien mi verga dura dentro porque ped\u00eda m\u00e1s y m\u00e1s y gem\u00eda sin cesar diciendo zafiedades como si fuera un camionero. Su marido empez\u00f3 a darme pollazos en mis nalgas y no tard\u00f3 en buscar mi ojete con su capullo. Al notar que empezaba a introducirlo le dije se pusiera un cond\u00f3n.<\/p>\n<p>Mi culo no hab\u00eda sido perforado desde la juventud. No era pr\u00e1ctica de mi agrado, pero el ambiente estaba tan elevado de temperatura sexual que no me importaba en aquel momento me penetraran. Una vez se coloc\u00f3 el preservativo, volvi\u00f3 a mi culo y empez\u00f3 a introducir su capullo. Su verga era m\u00e1s bien peque\u00f1a y no tard\u00f3 en meterla toda. Pronto nos acompasamos disfrutando los tres de una follada descomunal, en la que la puta de su mujer gem\u00eda y gritaba de gusto pidiendo m\u00e1s polla, lo que hac\u00eda excitarnos m\u00e1s. A diferencia del co\u00f1o de la casada, mi culo era apretado y no tard\u00e9 en sentir los espasmos del cornudo en mi culo mientras se corr\u00eda.<\/p>\n<p>Al lado la joven y el maduro se hab\u00edan corrido y estaban super cachondos viendo el espect\u00e1culo. Ella hab\u00eda conseguido recuperar la polla de su amigo que estaba con ganas de meterla. El tipo se acerc\u00f3 y propuso me colocara tumbado boca arriba, con la casada de espaldas sobre m\u00ed y mi polla dentro del co\u00f1o. Le abri\u00f3 bien las piernas y la meti\u00f3 junta a mi polla, una vez bien ensamblados los dos, empezamos a darle fuertes pollazos que le hac\u00edan estremecer de gusto. Sent\u00eda junto a la m\u00eda la polla del maduro, lo que me ocasionaba mayor morbo y excitaci\u00f3n. La guarra disfrutaba de las embestidas de los dos pollones de buen tama\u00f1o ensartados en su co\u00f1o a la vez.<\/p>\n<p>La joven mientras, le com\u00eda la polla al casado en un intento de levant\u00e1rsela, y le daba a comer su chocho a la casada lo que aprovech\u00e9 desde mi posici\u00f3n para sobarle las tetas. El conjunto de fornicadores que hab\u00edamos formado dejaba en mal lugar al Kama Sutra. Los gemidos de las zorras, nuestros jadeos, el sudor de los cuerpos y el olor a sexo, creaban un ambiente t\u00f3rrido y sexual irrespirable.<\/p>\n<p>Ten\u00eda ya la polla a punto de explotar y viendo que el co\u00f1o de la jovencita era muy apetecible, me zaf\u00e9 de la posici\u00f3n que ocupaba debajo de la casada, la tumb\u00e9 sobre el colch\u00f3n, puse sus piernas sobre mis hombros dejando de par en par su co\u00f1o para meter mi polla hasta el fondo de una embestida.<\/p>\n<p>Cog\u00ed con las dos manos sus nalgas atray\u00e9ndola contra mi polla oblig\u00e1ndola a arquear su cuerpo, as\u00ed empec\u00e9 un mete y saca violento, chocando su culo contra mis huevos, mientras la zorrita gozaba sintiendo su co\u00f1o lleno de polla, a la vez que yo disfrutaba de aquella vagina apretada que me ten\u00eda a punto de explotar. No aguant\u00e9 mucho y solt\u00e9 un chorro que inund\u00f3 su co\u00f1o mientras sent\u00edamos al un\u00edsono mis espasmos con sus palpitaciones vaginales.<\/p>\n<p>Mientras el marido ya empalmado follaba el culo de la guarra de su mujer y el maduro de la joven segu\u00eda foll\u00e1ndole el co\u00f1o a la casada.<\/p>\n<p>As\u00ed los dej\u00e9 y satisfecho de la follada que me hab\u00edan regalado las dos parejas, me fui a la ducha.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60035\" class=\"pvc_stats total_only  \" data-element-id=\"60035\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Al lado la joven y el maduro se hab\u00edan corrido y estaban super cachondos viendo el espect\u00e1culo. Ella hab\u00eda conseguido recuperar la polla de su amigo que estaba con ganas de meterla. El tipo se acerc\u00f3 y propuso me colocara tumbado boca arriba, con la casada de espaldas sobre m\u00ed y mi polla dentro del co\u00f1o. Le abri\u00f3 bien las<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60035\" class=\"pvc_stats total_only  \" data-element-id=\"60035\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30889,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":{"0":"post-60035","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-intercambios"},"a3_pvc":{"activated":true,"total_views":8090,"today_views":1},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30889"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=60035"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60035\/revisions"}],"predecessor-version":[{"id":60037,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60035\/revisions\/60037"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=60035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=60035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=60035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}