{"id":60409,"date":"2025-06-22T00:13:02","date_gmt":"2025-06-21T22:13:02","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=60409"},"modified":"2025-06-21T20:15:26","modified_gmt":"2025-06-21T18:15:26","slug":"5369-sodomizada-por-un-alto-ejecutivo-parte-1","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/5369-sodomizada-por-un-alto-ejecutivo-parte-1\/","title":{"rendered":"Sodomizada por un alto ejecutivo (1)"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"60409\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">26<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Proven\u00eda de una familia aristocr\u00e1tica, se le reconoc\u00eda una fortuna considerable y hab\u00eda sido formado en prestigiosos colegios ingleses y universidades del Reino Unido y EEUU. Conocido playboy en su juventud, en la que se le atribuyeron romances con modelos y famosas, siendo protagonista de alg\u00fan esc\u00e1ndalo recogido en revistas del coraz\u00f3n de la \u00e9poca. En sus c\u00edrculos \u00edntimos era conocido como Conrad y obligada su presencia en las fiestas de sociedad.<\/p>\n<p>Actualmente, rondando los 50, es el responsable del \u00e1rea de negocio exterior, de la multinacional en la que trabaja mi marido, actividad que desempe\u00f1a con mucho \u00e9xito. Hombre culto, simp\u00e1tico, atractivo, educado, seductor, con un halo novelesco del que se cuentan historias que le hacen m\u00e1s interesante para las mujeres. Como soltero de oro, las empleadas suspiran a su paso y lo ven como un personaje de leyenda inalcanzable.<\/p>\n<p>Se conforman con que su mirada se fije en sus tetas o culo, a sabiendas que es a lo m\u00e1ximo que pueden aspirar, aunque ciertos rumores afirman que m\u00e1s de una ha salido satisfecha sexualmente de su despacho. En cuanto a las esposas de los directivos, las hay que manifiestan que no se dejar\u00edan tocar un pelo de un depravado sexual, hasta las que dicen sin recato que se bajar\u00edan las bragas para \u00e9l sin pensarlo.<\/p>\n<p>Hace escasos meses fuimos invitados a la boda de la hija del Presidente de la Compa\u00f1\u00eda. Nos correspondi\u00f3 la mesa en la que estaba Conrad, acompa\u00f1ado de una dama elegante, al parecer Presidenta de una Compa\u00f1\u00eda mexicana, con la que hace importantes negocios para la empresa. Invitada a la boda aprovech\u00f3 para visitar Espa\u00f1a y Conrad se ofreci\u00f3 para hacer de cicerone y ser su acompa\u00f1ante en el enlace. Las mesas eran circulares y amplias, nos toc\u00f3 sentarnos enfrente de \u00e9l sin que la distancia nos permitiera mantener conversaci\u00f3n alguna. Se limit\u00f3 a cruzar alguna mirada y sonre\u00edrme en alguna ocasi\u00f3n a lo largo de la cena, a lo que correspond\u00ed.<\/p>\n<p>La fiesta se alarg\u00f3 hasta avanzada la madrugada. En un momento en el que mi marido conversaba con otros invitados y yo con esposas de otros directivos, se acerc\u00f3 y me pidi\u00f3 bailar. No tuve opci\u00f3n y me vi en medio de la pista con sus manos en mi cintura y apretada a su cuerpo. Mis brazos los colgu\u00e9 de sus hombros a sabiendas que mi actitud cari\u00f1osa iba a ser objeto de cr\u00edticas de los invitados m\u00e1s conocidos. Quiz\u00e1s los efectos del alcohol me hac\u00edan m\u00e1s desinhibida dej\u00e1ndome llevar del momento. Sent\u00eda su proximidad y su cara pegada a la m\u00eda me produc\u00eda sensaciones excitantes.<\/p>\n<p>Me susurraba halagos y palabras agradables al o\u00eddo, algunas subidas de tono. Al no rehuirlo me apretaba m\u00e1s contra \u00e9l y sent\u00eda la dureza de su verga entre el monte de venus y el ombligo, a pesar de mi 1.72 m\u00e1s los 10 cm de tac\u00f3n. Su elevada estatura imped\u00eda que aquel bulto delicioso encajara donde me hubiera gustado sentirlo.<\/p>\n<p>A pesar de eso, mi humedad aumentaba por momentos y el sentirme entre sus brazos me trasportaba a un estado de excitaci\u00f3n que me hac\u00eda vulnerable, deseaba sentirme suya. Volv\u00ed a la realidad al terminar de bailar y o\u00edr su voz dici\u00e9ndome: &#8220;Me gustar\u00eda conocerte mejor, eres una mujer maravillosa y seguro tenemos cosas en com\u00fan que descubrir. Me gustar\u00eda me dieras tu n\u00famero de m\u00f3vil&#8221;. Como una aut\u00f3mata fui enumerando los d\u00edgitos.<\/p>\n<p>Si el viernes noche fue la fiesta, pas\u00e9 el fin de semana alterada, repasando en mi mente todo lo que hab\u00eda sucedido. Me inquietaba su llamada porque sab\u00eda que no tendr\u00eda fuerza de voluntad para negarme a lo que me pidiera. Una parte de mi lo deseaba, pero la otra me hac\u00eda temer las consecuencias de una cita con \u00e9l.<\/p>\n<p>Pas\u00f3 el lunes, martes, a medida que pasaban los d\u00edas me fui tranquilizando en la creencia de que se hab\u00eda olvidado de m\u00ed, que lo ocurrido solo fue una forma de jugar conmigo, aprovechando una peque\u00f1a debilidad m\u00eda por efecto de mi alegre estado de \u00e1nimo debido a la fiesta.<\/p>\n<p>Continuar\u00e1.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60409\" class=\"pvc_stats total_only  \" data-element-id=\"60409\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>A pesar de eso, mi humedad aumentaba por momentos y el sentirme entre sus brazos me trasportaba a un estado de excitaci\u00f3n que me hac\u00eda vulnerable, deseaba sentirme suya. Volv\u00ed a la realidad al terminar de bailar y o\u00edr su voz dici\u00e9ndome: &#8220;Me gustar\u00eda conocerte mejor, eres una mujer maravillosa y seguro tenemos cosas en com\u00fan que descubrir. Me gustar\u00eda<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60409\" class=\"pvc_stats total_only  \" data-element-id=\"60409\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30646,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-60409","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-infidelidad"},"a3_pvc":{"activated":true,"total_views":6564,"today_views":1},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30646"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=60409"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60409\/revisions"}],"predecessor-version":[{"id":60411,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60409\/revisions\/60411"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=60409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=60409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=60409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}