{"id":60412,"date":"2025-06-22T00:12:40","date_gmt":"2025-06-21T22:12:40","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=60412"},"modified":"2025-06-21T20:23:43","modified_gmt":"2025-06-21T18:23:43","slug":"7934-el-hotel-del-todo-incluido","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/7934-el-hotel-del-todo-incluido\/","title":{"rendered":"El hotel del todo incluido"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"60412\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">32<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Con motivo de un viaje de negocios, acompa\u00f1\u00e9 a mi marido varios d\u00edas a una convenci\u00f3n m\u00e9dica que se celebraba en Benidorm. Yo no quer\u00eda ir por considerarlo un viaje cansado para pocos d\u00edas, pero \u00e9l se empe\u00f1\u00f3 y al final acept\u00e9 ir.<\/p>\n<p>El hotel donde nos alojamos estaba muy bien, pero para m\u00ed que hab\u00eda venido de acompa\u00f1ante, no me quedaba m\u00e1s remedio que aburrirme tomando el sol en la piscina o marcharme a la playa hasta que llegara mi marido bien entrada la tarde. Como la playa quedaba algo distante opt\u00e9 por quedarme en la piscina. Me puse un bikini llamativo y armada de toalla de ba\u00f1o y crema bronceadora baj\u00e9 a la piscina.<\/p>\n<p>Tumbada indolentemente en la tumbona, tomando el sol en topless, estaba pensando en mis cosas cuando vino un camarero, me pregunt\u00f3 si quer\u00eda tomar algo, lo mir\u00e9 descaradamente desde detr\u00e1s de las gafas de sol y me fij\u00e9 tendr\u00eda sobre 30 a\u00f1os, guapo, fuerte, cuerpo de gimnasio, estaba para com\u00e9rselo.<\/p>\n<p>Le dije que me trajera un refresco y al momento me lo estaba poniendo sobre una mesita pegada a la tumbona. Le di las gracias y me pregunt\u00f3 si quer\u00eda algo m\u00e1s. Le dije que mi marido estaba en una convenci\u00f3n y volv\u00eda al anochecer, me aburr\u00eda de estar sola y que pod\u00eda hacer en el hotel. Me coment\u00f3, que, si me parec\u00eda bien, cuando acabara su turno de trabajo, me iba a ense\u00f1ar algunas cosas interesantes que me gustar\u00edan y que estaban en el \u201ctodo\u201d Incluido del hotel. Como os pod\u00e9is figurar, ante semejante proposici\u00f3n, sonriendo le di mi n\u00famero de habitaci\u00f3n y le dije que lo esperaba encantada.<\/p>\n<p>Pasadas las 4 de la tarde llam\u00f3 a la puerta de mi habitaci\u00f3n, abr\u00ed y all\u00ed estaba el camarero. Encantada le indiqu\u00e9 que pasara, lo recib\u00ed liada en un pareo como \u00fanica ropa, \u00e9l ven\u00eda vestido con camiseta, short y n\u00e1uticos. Nos sentamos en el amplio sof\u00e1 y le invit\u00e9 a tomar un wisky. Me dijo que no tomaba alcohol, ya que se cuidaba mucho, se machacaba en un gimnasio, no fumaba y procuraba llevar una vida sana. Nos servimos unos zumos.<\/p>\n<p>Lo observaba y, a pesar de tener 30 a\u00f1os, aparentaba menos edad y vi que se me presentaba una bonita oportunidad para abandonar mi aburrimiento y pas\u00e1rmelo bien con este yogurcito. Una oportunidad muy bonita para aprovecharla una mujer como yo mayor de 40 a\u00f1os y ansiosa de disfrutar y gozar en la cama.<\/p>\n<p>Me quit\u00e9 el pareo y me mostr\u00e9 desnuda a sus ojos, a continuaci\u00f3n, lo fui despojando lentamente de toda su ropa y, una vez desnudo, apret\u00e1ndome contra el comenc\u00e9 a excitarme. Not\u00e9 su cuerpo, fibroso, cuidado, joven, todo depiladito, morenito, como a m\u00ed me gusta. Como digo, se dejaba hacer de todo, era lo ideal para una mujer sedienta de amor y de sexo, y yo, ansiosa por disfrutar de su maravilloso cuerpazo, recorro y gozo toda su piel con las manos, con los labios y con la boca.<\/p>\n<p>Le mordisqueo los pezones, mi boca bajaba despacio saboreando cada cent\u00edmetro de su tostada piel, con las manos le sobaba los gemelos, los gl\u00fateos, los dorsales, los muslos fuertes y apretados con unos cu\u00e1driceps perfectos al tiempo que con la boca y la nariz saboreaba el olor de su pubis. A tan corta distancia, el olor maravilloso que me llegaba de su sexo me excitaba a\u00fan m\u00e1s.<\/p>\n<p>Le palp\u00e9 el escroto y notando la hermosura de los test\u00edculos, gorditos y sin nada de pelo, se los bes\u00e9, uno a uno me los introduje en la boca varias veces, le palp\u00e9 el pene, no estaba muy erecto, pero estaba de pecado, me lo introduje con avidez una y otra vez en la boca, lo lam\u00ed muchas veces, lo bes\u00e9, lo quer\u00eda todo para m\u00ed. Con delectaci\u00f3n y lujuria saboree su glande, el tronco de su cipote entra y sale de mi boca y lo disfruto muchas veces y, gozando con ese manjar, me agit\u00e9, me asfixi\u00e9, no pudiendo m\u00e1s y me corr\u00ed como una colegiala.<\/p>\n<p>Pero no me conform\u00e9 con eso, quer\u00eda gozar con este efebo propio de un escultor griego. Quer\u00eda sentirlo dentro de m\u00ed, de mi vagina, que entrara su miembro gordo y erecto todo dentro de m\u00ed, quer\u00eda sentir sus achuchones, su bombeo de mete y saca. Quer\u00eda que inundara con su leche todo mi ser.<\/p>\n<p>Comenc\u00e9 acarici\u00e1ndole la espalda, bes\u00e1ndole los ri\u00f1ones y bajando hasta los gl\u00fateos, despu\u00e9s me volv\u00ed a comerle muchas veces su maravillosa polla, de abajo arriba y a llenarme la boca con tan rico y excitante manjar.<\/p>\n<p>Como ahora s\u00ed que la ten\u00eda gorda y tiesa, le ped\u00ed, le supliqu\u00e9 que me la metiera, que me la metiera hasta que me hartara y acto seguido, obedeciendo mi orden, seguramente al verme cara de esposa lujuriosa y viciosa, me penetr\u00f3 con la fuerza de un toro, inici\u00f3 un mete y saca cuyas fricciones cada vez me pon\u00eda m\u00e1s excitada y cachonda notando una de las sensaciones m\u00e1s maravillosas que he sentido nunca. Indudablemente, este camarero sab\u00eda follar a una mujer mayor aburrida y deseosa de sexo.<\/p>\n<p>Ahora en un dulce vaiv\u00e9n, como si estuviera meciendo a un beb\u00e9, me arranc\u00f3 gemidos que me enloquec\u00edan, yo at\u00e9 mis piernas a su cintura para sentirlo m\u00e1s fuerte, m\u00e1s dentro y notar mejor su duro pene dentro de mi cuerpo. Sus embestidas son cada vez m\u00e1s fuertes y noto que estoy llegando al cl\u00edmax, que no puedo aguantar mucho m\u00e1s, que me voy a correr, s\u00ed, s\u00ed, me voy a correr otra vez.<\/p>\n<p>\u00c9l tambi\u00e9n lo not\u00f3 y apret\u00f3 todav\u00eda un poco m\u00e1s el bombeo, tambi\u00e9n se iba a correr\u2026 s\u00ed, s\u00ed, quiero que inundes de tu semen todo mi interior, quer\u00eda sentir el borbot\u00f3n de tu leche caliente saliendo inagotable, quise fundirme con su orgasmo. Y as\u00ed entre mil gemidos nos corrimos los dos al mismo tiempo en un acto de gozo y placer como pocas veces he sentido. Aquella fue una corrida gloriosa.<\/p>\n<p>Al d\u00eda siguiente baj\u00e9 tempranito a la piscina y respir\u00e9 tranquila pues all\u00ed, a lo lejos, divis\u00e9 a mi camarero. Sol\u00edcito vino hacia m\u00ed, nos saludamos y le ped\u00ed un zumo fresquito. Me lo trajo r\u00e1pidamente y al preguntarme si deseaba algo m\u00e1s, con la mejor de mis sonrisas y, lanz\u00e1ndole p\u00edcaramente un beso, le rogu\u00e9 que volviera a mi habitaci\u00f3n cuando terminara su turno para aplicarme el todo incluido\u2026 \u00a1y la verdad es que tambi\u00e9n me lo aplic\u00f3 maravillosamente aquella tarde y las siguientes!<\/p>\n<p>Cuando lleg\u00f3 mi marido me dijo si me hab\u00eda aburrido y yo le contest\u00e9: \u00abcari\u00f1o: en estos hoteles del todo incluido hay cosas para no aburrirse\u00bb.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60412\" class=\"pvc_stats total_only  \" data-element-id=\"60412\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Le palp\u00e9 el escroto y notando la hermosura de los test\u00edculos, gorditos y sin nada de pelo, se los bes\u00e9, uno a uno me los introduje en la boca varias veces, le palp\u00e9 el pene, no estaba muy erecto, pero estaba de pecado, me lo introduje con avidez una y otra vez en la boca, lo lam\u00ed muchas veces, lo<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60412\" class=\"pvc_stats total_only  \" data-element-id=\"60412\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30643,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-60412","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-infidelidad"},"a3_pvc":{"activated":true,"total_views":6240,"today_views":3},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30643"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=60412"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60412\/revisions"}],"predecessor-version":[{"id":60414,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60412\/revisions\/60414"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=60412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=60412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=60412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}