{"id":60497,"date":"2025-06-28T00:02:07","date_gmt":"2025-06-27T22:02:07","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=60497"},"modified":"2025-06-27T18:16:38","modified_gmt":"2025-06-27T16:16:38","slug":"cambio-justo","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/cambio-justo\/","title":{"rendered":"Cambio justo"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"60497\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">23<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>La fiesta de los L\u00f3pez termin\u00f3 antes de lo que cre\u00edamos y aquel s\u00e1bado pasar\u00eda desapercibido de no ser por Alicia la mujer de Mario, que con algunos Martini encima admiti\u00f3 sin tapujos qu\u00e9 hab\u00edan interactuado sexualmente con otras parejas, hac\u00eda algunos a\u00f1os atr\u00e1s ante la desesperada e in\u00fatil reacci\u00f3n de Mario por callarla.<\/p>\n<p>Emilia y yo ten\u00edamos poco m\u00e1s de cuarenta, dos hijos adolescentes, una vida tranquila y una fantas\u00eda que pocas veces confes\u00e1bamos. Hacer un swinger. Era algo que nos elevaba y por alguna raz\u00f3n, m\u00e1s que nada \u00e9tica no lo hab\u00edamos hecho. Eran como las once de la noche, las pocas personas que concurrieron se hab\u00edan marchado y nosotros viv\u00edamos a dos casas. Mi mujer revel\u00f3 que alguna vez estuvimos al borde de lograrlo y finalmente echamos para atr\u00e1s y Mario se sorprendi\u00f3, ante el inesperado desvelamiento.<\/p>\n<p>\u2013A, \u00faltima hora abortamos la idea. \u2013Dijo Emilia, mirando a Mario y agreg\u00f3\u2013 A veces me pregunto \u00bfc\u00f3mo hubiera sido?&#8230;<\/p>\n<p>Alicia baj\u00f3 sutilmente la luz del living, y Mario me mir\u00f3 sentado en el extremo del sof\u00e1 qu\u00e9 compart\u00edamos y arqueando una ceja aconsej\u00f3 \u2013Y es algo verdaderamente excitante, hay que tener las cosas claras y abrirse a algo nuevo.<\/p>\n<p>El silencio se hizo hondo, las miradas se cruzaron, pod\u00edamos habernos ido pero no lo hicimos, eso no era lo peor, lo peor era que no quer\u00edamos hacerlo.<\/p>\n<p>Ellos eran m\u00e1s grandes pasaban los cincuenta, Mario era canoso y estaba algo sobre pasado de peso, pose\u00eda una barba cuidada y era oficial de polic\u00eda, Alicia era flaca, de grandes ojos miel escudados en gafas estrafalarias, cabello enrulado y te\u00f1ido en varios tonos de amarillo. Vest\u00eda un corto vestido a\u00f1il, ce\u00f1ido a su figura fr\u00e1gil, compacta, pechos peque\u00f1os, piernas finas y un culito acorde a su figura. No era modelo ni mucho menos, era vendedora de electrodom\u00e9sticos.<\/p>\n<p>Una nube de morbo invisible flotaba en el ambiente, una m\u00fasica ac\u00fastica lenta empez\u00f3 a sonar con delicadeza y los L\u00f3pez comenzaron a bailar abrazados a tres metros de nosotros. Mi esposa se acerc\u00f3 y los imitamos lentamente, en cada giro los mir\u00e9 y ellos tambi\u00e9n, pens\u00e1bamos lo mismo estoy seguro Alicia y yo, y mi esposa con el polic\u00eda. \u2013Somos vecinos. Le susurre a Emilia.<\/p>\n<p>\u2013\u00bfY?&#8230; Mejor, los conocemos hace m\u00e1s de diez a\u00f1os. Argument\u00f3. La empleada estatal, morocha de ojos negros y grandes tetas qu\u00e9 ten\u00eda pegadas a m\u00ed.<\/p>\n<p>\u2013\u00bfEstas segura? Pregunte en medio de la improvisada pista.<\/p>\n<p>Emilia no contesto y segundos despu\u00e9s se despeg\u00f3 para invitar a Mario a bailar, \u00e9l por supuesto que acept\u00f3 y Alicia se me aproxim\u00f3, como si fuera un contrato silencioso. El perfume diferente me excit\u00f3, pero no m\u00e1s que la vista de las siluetas de mi mujer y el barbado, que mec\u00edan sus cuerpos al comp\u00e1s lento de las melod\u00edas.<\/p>\n<p>Mi pene estaba agujereando mis pantalones y Alicia lo sinti\u00f3.<\/p>\n<p>\u2013Santo cielo, Lucas. Dijo con malicia roz\u00e1ndome m\u00e1s.<\/p>\n<p>Baj\u00f3 una de mis manos qu\u00e9 posaban su cintura hasta sus nalgas y Mario hizo lo mismo. Ambos sob\u00e1bamos el culo de la mujer del otro, en la penumbra artificial del living. Comenzamos a besarnos con la vecina y supongo que ellos tambi\u00e9n y digo supongo porque no lo recuerdo. Lo que si recuerdo es estar tumbado en la alfombra, a orillas del sill\u00f3n con la cincuentona succion\u00e1ndome la verga y las bolas y tambi\u00e9n recuerdo a Mario en un mar de gemidos recibiendo el mismo tratamiento por parte de mi mujer.<\/p>\n<p>Es inenarrable la brutal ola de calentura que me produc\u00eda aquella visi\u00f3n quim\u00e9rica, el gordito velludo con su miembro erecto, regocij\u00e1ndose, con la cabeza de mi mujer subiendo y bajando entre sus piernas a un par de metros de nosotros, mientras Alicia se atragantaba con mi verga.<\/p>\n<p>\u2013\u00bfVecina, la est\u00e1 pasando bien con mi marido?&#8230; Pregunt\u00f3 Emilia completamente desnuda.<\/p>\n<p>\u2013De, maravillas. Contest\u00f3 la cincuentona. Mientras mi mujer se sentaba en la verga enforrada de la ley y lanzaba al aire sus primeros gemidos.<\/p>\n<p>Por el contrario dedique mi tiempo en explorar en profundidad el cuerpito menudo de mi vecina, y como creo en la reciprocidad le gast\u00e9 la conchita delicadamente depilada a leng\u00fcetazos furtivos entre gemidos confundidos con los de Emilia y Mario que cada tanto confesaba lo mucho que deseaba cabalgar a mi mujer.<\/p>\n<p>\u2013Por, fin Emi, \u00a1no sabe las ganas que ten\u00eda de tenerla as\u00ed! Murmuraba mientras le hund\u00eda la pija, una y otra vez.<\/p>\n<p>Cuando ya la hab\u00eda acabado un par de veces con la boca, \u00a1la ensarte! Despacio, con miedo de quebrarla, pero que va, la vecina era un potro desbocado e insaciable.<\/p>\n<p>\u2013Cogeme!&#8230; Cogeme!&#8230; Gritaba una y otra vez mientras se balanceaba a toda velocidad.<\/p>\n<p>Hicimos de todo, todos. Gozamos por igual, acabamos varias veces. Pero cuando las pusimos a las dos de a perrito una al lado de la otra y las taladramos desde atr\u00e1s, fue perfecto. El culo voluminoso de mi esposa, a la deriva y el de Alicia (bastante menos ostentoso debo decir) desperdigados en la alfombra, con las piernas ligeramente abiertas y nosotros entre ellas, encastrando nuestros miembros en la mujer ajena fue sencillamente sublime. Escuchar a mi esposa decir<\/p>\n<p>\u2013Si, papi&#8230; \u00a1As\u00ed! Mientras Mario la arremet\u00eda con fuerza al lado m\u00edo no tiene comparaci\u00f3n, imagino que el sinti\u00f3 algo parecido al escuchar a Alicia con sus gritos hist\u00e9ricos y entrecortados avisando el cl\u00edmax. Fue una experiencia realmente placentera.<\/p>\n<p>Hubo otras, veces con ellos. Quiz\u00e1 no como esa vez, quiz\u00e1 porque fue la primera, no lo s\u00e9. El hecho de ser vecinos tambi\u00e9n como que influy\u00f3 en derribar la continuidad de aquellos encuentros pero francamente fue una experiencia, alucinante.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60497\" class=\"pvc_stats total_only  \" data-element-id=\"60497\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Baj\u00f3 una de mis manos qu\u00e9 posaban su cintura hasta sus nalgas y Mario hizo lo mismo. Ambos sob\u00e1bamos el culo de la mujer del otro, en la penumbra artificial del living. Comenzamos a besarnos con la vecina y supongo que ellos tambi\u00e9n y digo supongo porque no lo recuerdo. Lo que si recuerdo es estar tumbado en la alfombra<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60497\" class=\"pvc_stats total_only  \" data-element-id=\"60497\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":31202,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":{"0":"post-60497","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-intercambios"},"a3_pvc":{"activated":true,"total_views":6182,"today_views":6},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/31202"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=60497"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60497\/revisions"}],"predecessor-version":[{"id":60499,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60497\/revisions\/60499"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=60497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=60497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=60497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}