{"id":60724,"date":"2025-07-08T00:24:05","date_gmt":"2025-07-07T22:24:05","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=60724"},"modified":"2025-07-07T22:31:41","modified_gmt":"2025-07-07T20:31:41","slug":"8278-peludita-y-natural-asi-me-gusta-que-tenga-la-cosita-los-cuernos-saben-mejor","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/8278-peludita-y-natural-asi-me-gusta-que-tenga-la-cosita-los-cuernos-saben-mejor\/","title":{"rendered":"Peludita y natural"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"60724\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">123<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Esta historia lleva dos a\u00f1os de estacionamiento emocional, por consiguiente, las culpas han prescripto y las costas familiares saldadas.<\/p>\n<p>Como dec\u00eda hace dos a\u00f1os Doris y quien relata, adornamos la testa de Gustavo, con un buen par de cuernos.<\/p>\n<p>Gustavo, cu\u00f1ado en ese momento, compa\u00f1ero del f\u00fatbol sabatino, se ufana de tener una relaci\u00f3n abierta con su mujer, me ten\u00eda harto de alabarse de lo bien que lo pasaban y sobre todo de tan buena que es en la cama y que tiene la \u201ccosa\u201d tan peluda.<\/p>\n<p>Tanto as\u00ed que me daba por pensar que la estaba promocionando o era un ofrecimiento encubierto, pero nunca me anim\u00e9 a avanzar sobre esa tem\u00e1tica, un tanto escabrosa como para hablarlo tan de frente.<\/p>\n<p>Un s\u00e1bado, como tantos, pas\u00e9 a buscarlo, Doris me hizo pasar, bata entreabierta, hasta bien arriba, exhibe generosa porci\u00f3n de ese cuerpazo tan esbelto y tan blanco. Tacones altos, algo poco usual para esas horas de la ma\u00f1ana de un s\u00e1bado hacen m\u00e1s estilizadas sus bellas piernas, me conduce al living meneando sus caderas. Tom\u00e9 asiento mientras espero al amigo, se sienta sobre el brazo del sill\u00f3n, frente de m\u00ed, para acomodarse uno de los zapatos, en la acci\u00f3n, accidentalmente, se le abri\u00f3 m\u00e1s la bata y \u201cla selva negra\u201d p\u00fabica retuvo toda mi atenci\u00f3n, ojos incr\u00e9dulos escudri\u00f1an m\u00e1s all\u00e1 de la imprudencia, absorto por esa intimidad que me ten\u00eda atrapado.<\/p>\n<p>\u2014\u00bfUn&#8230; caf\u00e9? \u2014Sonri\u00f3, cerr\u00f3 la bata con osada y morosa lentitud, jugando al gato y el rat\u00f3n.<\/p>\n<p>\u2014S\u00ed, s\u00ed&#8230; lo que digas.<\/p>\n<p>Caf\u00e9 mediante, hablando cualquier cosa, ella que no era nada tonta, hab\u00eda notado cierta turbaci\u00f3n en mi \u00e1nimo y alguna muestra inevitable en m\u00ed de ese momento de latencia masculina, sab\u00eda que estaba ansioso esperando ver otro poco, deseando que el marido demorara una eternidad en volver, sus gestos dec\u00edan tanto de una mujer que sabe c\u00f3mo manejar la seducci\u00f3n y jugar con la ansiedad del hombre.<\/p>\n<p>\u2014\u00a1Ah!&#8230;, casi olvido, decirte que Gustavo, no est\u00e1\u2026 Sali\u00f3 anoche, un viaje de apuro, falleci\u00f3 la t\u00eda, reci\u00e9n vuelve ma\u00f1ana por la noche.<\/p>\n<p>Recostada sobre el brazo del sill\u00f3n, dir\u00eda que una pose art\u00edsticamente estudiada para propiciar que la indiscreta abertura de la bata exponga la renegrida vellosidad enrulada, su nada inocente descuido permite mi deleite lascivo y perderme en arrobada admiraci\u00f3n.<\/p>\n<p>\u2014\u00bfQu\u00e9 pasa?<\/p>\n<p>\u2014Nunca vi tanto&#8230; y\u2026 \u00a1tan negro!<\/p>\n<p>\u2014\u00a1Ah!&#8230; y\u2026 \u00bfQu\u00e9 te parece? A Gustavo lo enloquece, \u00bfy a vos? \u2014Desafi\u00f3, un albur para elevar la apuesta, est\u00e1 mostrando sus cartas y espera&#8230;<\/p>\n<p>Acept\u00e9 el reto, descubierto, no tuve m\u00e1s remedio que mostrar las cartas, los calores que me sub\u00edan desde los genitales taparon la prudencia, la excitaci\u00f3n solt\u00f3 el freno y aceler\u00f3 la acci\u00f3n. De s\u00fabito, de pie, entre sus piernas tom\u00e9 la cara entre mis manos y la bes\u00e9. Nos besamos de lengua. El calor h\u00famedo de su boca me subi\u00f3 en la espiral de la excitaci\u00f3n, deshice el lazo de la bata, despoj\u00e9 de la c\u00e1scara de raso, blanca piel se deja a la caricia y al beso ardiente.<\/p>\n<p>La erecci\u00f3n oprimida en el jean se frota contra la espesura negra de su \u201ccosa\u201d, vibra y sacude al contacto. Abre sus piernas para favorecer el contacto, que sienta el calor interior del peludo orgullo del cornudo ausente.<\/p>\n<p>En el camino a la cama perd\u00ed la ropa, desnudos y abrazados nos revolcamos. Las bocas intercambiaron salivas y mimos, los dedos exploran la selva negra, tragados por el abismo h\u00famedo recorren el interior de la caverna, las delicias del contacto digital la hacen vibrar y aullar como los lobos a la luna llena. Sus gemidos llenan de m\u00fasica, el aroma que emana su cosa peluda embriaga los sentidos y enciende la hoguera del deseo m\u00e1s ardiente. Ella me agarra del miembro, juega paje\u00e1ndola para incrementar a full las ganas de cogerla.<\/p>\n<p>Levant\u00f3 las piernas, abri\u00f3 del todo, el matorral piloso qued\u00f3 en primer plano, la jugosa valva rezuma jugos que brillan a la sombra del vello deliciosamente enrulado. Qu\u00e9 raz\u00f3n ten\u00eda el cornudo de Gustavo, poder llenarse los ojos de una cosita sabrosa condimentada de vellos tupidos y emprolijados aportan el valor agregado del deseo, compiten y salen ganando en la comparaci\u00f3n de tantas cosas lampi\u00f1as, que encontrar una de este porte es algo digno de admirar y apreciar entre las delicias gourmet como el mejor alimento afrodis\u00edaco del comensal lujurioso.<\/p>\n<p>El choto, erecto, la incipiente calentura asomando desde el ciclope de su cabezota brillante, desbroza el suave vello, se lanza con vehemencia a lo profundo de la caverna, pasionalmente salvaje, a lo bestia, tal como impone el manual de la calentura repentina.<\/p>\n<p>\u2014\u00a1As\u00ed, as\u00ed! \u00a1Quiero m\u00e1s! \u2014A\u00falla sin freno, desbocada, perdiendo los estribos, levando las anclas para navegar en el mar de la infidelidad y naufragar en los cuernos a manos de su cu\u00f1ado. Sonr\u00eda mientras pensaba, que todo quedaba en familia.<\/p>\n<p>Lujuria avasalladora, m\u00e1quina de coger, sin l\u00edmites ni contenci\u00f3n, insaciable a la hora del placer, dos orgasmos largu\u00edsimos, agarrada de mis nalgas quer\u00eda meterme m\u00e1s adentro de los l\u00edmites f\u00edsicos. No par\u00f3 de gemir y aullar, rostro desencajado en loco goce, le daba para que \u201ctenga y guarde\u201d, atravesarla con el choto, sent\u00eda el fondo del \u00fatero, autista en el goce, segu\u00eda en lo suyo.<\/p>\n<p>\u2014 M\u00e1s, m\u00e1s, \u00a1m\u00e1s!<\/p>\n<p>Consecuente y obediente estaba para cumplir sus deseos m\u00e1s ardientes, elev\u00e9 su pierna izquierda, subido el pie junto a mi cara, asido del muslo con mis manos, colocado casi en una tijera, pod\u00eda entrarle todo el grosor de mi poronga, bastante m\u00e1s gorda que la del cornudo ausente con aviso, le doy el sexo salvaje. Los gemidos agradecen el tratamiento brusco y desmedido, la calentura promueve otro orgasmo, y van\u2026 hasta perderse en el fragor de la cogida estruendosa.<\/p>\n<p>En medio del carnaval de acabadas de Doris, eyacul\u00e9 con todo, dentro, sin aviso previo, me dej\u00e9 perder en su cosa peluda.<\/p>\n<p>\u2014\u00a1S\u00ed, as\u00ed, \u00a1qu\u00e9 lindo, m\u00e1s, m\u00e1s! \u2014El chorro incentiv\u00f3 sus vibraciones y hasta un postrer orgasmo a modo de coronaci\u00f3n de una estruendosa acabada.<\/p>\n<p>Extasiado por un delicioso polvo, que como todos sabemos, cuando se producen fuera de programa, siempre son los que nos llenan de placer. Doris, vuelve del ba\u00f1o, como dios la trajo al mundo, la cosa peluda resalta contra la blancura extrema de la piel, mis recuerdos solo tienen archivo de vellos recortados o depilados, esta visi\u00f3n realza y enriquece la memoria visual de un calent\u00f3n. Focaliza mi fantas\u00eda, me \u201caboco\u201d sobre la fronda a buscar el manantial de jugos, hurgu\u00e9 con la lengua y retornaron los aullidos, el cl\u00edtoris qued\u00f3 atrapado en mi boca, el shock la sacudi\u00f3, me atenaz\u00f3 entre los muslos.<\/p>\n<p>Despu\u00e9s del segundo lingual, breve paseo por el 69, se arrodilla, de bruces sobre la almohada, se entrega permisiva y sumisa. Piernas separadas, labios gruesos barnizados de jugo, el culo elevado incita ser pose\u00eddo en cogida impetuosa y desaforada, la zona anal la tiene deliciosamente tratada, es evidente que la \u201ctira de cola\u201d se rob\u00f3 hasta el m\u00ednimo vello de la zona \u201cdel marr\u00f3n\u201d.<\/p>\n<p>Comenzamos por la peludita, pero en el metisaca resbal\u00f3 \u201cpor accidente\u201d y \u201cse\u201d entr\u00f3 por el orto, sin llamar, y se le escurri\u00f3 bien adentro. Con la escasa lubricaci\u00f3n se puede sentir el fragor de piel a piel con toda la intensidad, goce del macho y molestoso goce de la hembra, el mejor combo para un polvo de antolog\u00eda por el culo de esta belleza tan blanca y ardorosa.<\/p>\n<p>La cabeza se mand\u00f3 por el canal, sin pedir permiso. Intent\u00f3 salirse, en vano, volqu\u00e9 todo el peso sobre ella para asegurar la ocupaci\u00f3n ilegal. Meta y ponga intenso, consum\u00e9 el derecho de goce a fuerza y calentura, me demor\u00e9 en gozarla omitiendo puteadas y reclamos de la sometida. En ese momento pensamos en Gustavo y le dije mientras le entraba de forma algo m\u00e1s salvaje, \u201ccoronado de gloria a morir\u201d, acompa\u00f1ando con un par de ruidosas nalgueadas, enterrando toda la verga dentro de mi puta cu\u00f1ada.<\/p>\n<p>\u2014Hijo de puta, \u00a1m\u00e1s despacio que me mat\u00e1s! \u00a1Despacio guacho! \u00a1me lo vas a desgarrar puto de mierda! \u2014vocifera y putea a discreci\u00f3n, mientras el macho responde con nalgadas, enterr\u00e1ndose en lo profundo del culo de Doris.<\/p>\n<p>Los gritos y sacudidas me recalientan, nuevos br\u00edos, le doy \u201ca todo trapo\u201d, respondo cada insulto con una nalgada, cada gemido con un empuj\u00f3n. Nos dejamos llevar en la vor\u00e1gine \u201cculinaria\u201d est\u00e1bamos cocinando un exquisito polvete anal, y ella apunto de tragarse mi leche.<\/p>\n<p>Culmina la culeada cuando descargo la enema de esperma con toda la fuerza. A pesar de la violencia ejercida en el tramo final, concluy\u00f3 del mejor modo, aunque la \u201cguacha\u201d qued\u00f3 reprochando haberle reventado el culo y dejado ardiendo y marcadas mis manoplas en sus nalgas. Sonre\u00edmos por el delicioso deleite de compartirnos en el placer de un polvo, tan urgente como imprevisto, pero digno de volver a repetirlo.<\/p>\n<p>\u2014\u00a1Me gustaron tus nalgadas! \u00a1Que se repintan! esta noche estoy sola\u2026<\/p>\n<p>La respuesta qued\u00f3 flotando, las ganas navegando en las tranquilas aguas del relax y los cuernos coronando la testa de mi cu\u00f1ado.<\/p>\n<p>Nazareno Cruz<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60724\" class=\"pvc_stats total_only  \" data-element-id=\"60724\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Consecuente y obediente estaba para cumplir sus deseos m\u00e1s ardientes, elev\u00e9 su pierna izquierda, subido el pie junto a mi cara, asido del muslo con mis manos, colocado casi en una tijera, pod\u00eda entrarle todo el grosor de mi poronga, bastante m\u00e1s gorda que la del cornudo ausente con aviso, le doy el sexo salvaje. Los gemidos agradecen el tratamiento<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_60724\" class=\"pvc_stats total_only  \" data-element-id=\"60724\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":5964,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-60724","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":true,"total_views":16096,"today_views":6},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/5964"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=60724"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60724\/revisions"}],"predecessor-version":[{"id":60726,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/60724\/revisions\/60726"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=60724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=60724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=60724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}