{"id":61144,"date":"2025-07-28T00:22:35","date_gmt":"2025-07-27T22:22:35","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=61144"},"modified":"2025-07-27T16:38:01","modified_gmt":"2025-07-27T14:38:01","slug":"termino-dentro-de-mi-novia-irene-y-mi-prima-blanca-se-da-cuenta","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/termino-dentro-de-mi-novia-irene-y-mi-prima-blanca-se-da-cuenta\/","title":{"rendered":"Termino dentro de mi novia Irene y mi prima Blanca se da cuenta"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"61144\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">75<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Pas\u00f3 m\u00e1s tiempo y debo admitir que mis sentimientos hacia Irene cobraron mucho m\u00e1s fuerza de lo que en un principio cre\u00ed. \u00c9ramos la pareja perfecta. Siempre la pasaba muy bien con ella e incluso la hab\u00eda presentado con mis padres -evento que hizo que Blanca se pusiera celosa y no me abriera las piernas durante toda una semana-. Ella tambi\u00e9n me present\u00f3 con su familia, quienes me trataban como un rey ya que era el tipo m\u00e1s decente con el que su hija hab\u00eda salido. Ese era otro tema.<\/p>\n<p>Cuando empezamos a ser novios, los comportamientos coquetos de Irene con casi todos los compa\u00f1eros eran evidentes, aunque a m\u00ed no me import\u00f3 en ese momento ya que s\u00f3lo era mi tapadera. Pero poco a poco esas actitudes de zorrita comenzaron a desaparecer. Ya no ten\u00eda jueguitos de contacto f\u00edsico con otros compa\u00f1eros y no les respond\u00eda los mensajes por WhatsApp. Esa mujer, creo, estaba enamorada de m\u00ed. Y yo de ella. La \u00faltima noche de la semana en la que Blanca me dej\u00f3 en sequ\u00eda por sus celos, mientras yac\u00edamos entrelazados despu\u00e9s de una cogida tierna, al fin Irene me comparti\u00f3 una idea que llevaba semanas rond\u00e1ndola.<\/p>\n<p>\u2014Te amo, Enrique.<\/p>\n<p>Record\u00e9 la vez en la playa en que entr\u00e9 en Blanca por primera vez y me dijo lo mismo. El amor de una mujer es la droga m\u00e1s intoxicante que existe. La felicidad me embarg\u00f3.<\/p>\n<p>\u2014Yo tambi\u00e9n, flaquita. Me tienes loco \u2014confes\u00e9, girando para besarla.<\/p>\n<p>Volvimos a hacer el amor dici\u00e9ndonos las cosas m\u00e1s hermosas con cada embestida y con cada beso. Al final, cuando eyacul\u00e9 en el cond\u00f3n, fue la primera vez que Blanca estuvo ausente de mis pensamientos.<\/p>\n<p>Una vez m\u00e1s volvimos a estar abrazados, mirando el techo.<\/p>\n<p>\u2014Oye, flaquito \u2014me dijo acariciando mi pecho con la yema de su \u00edndice \u2014Y si&#8230;<\/p>\n<p>\u2014\u00bfY si qu\u00e9&#8230;? \u2014respond\u00ed ante su silencio.<\/p>\n<p>\u2014Pues ya llevamos varios meses de novios y no he estado con nadie m\u00e1s, \u00bfy t\u00fa?<\/p>\n<p>Sent\u00ed un fr\u00edo recorrer mi espalda. Si fuese sincero la felicidad se esfumar\u00eda. Decid\u00ed mentir.<\/p>\n<p>\u2014Nunca, flaquita. S\u00f3lo tuyo.<\/p>\n<p>\u2014Estaba pensando que ya que somos exclusivos, dejemos de usar cond\u00f3n.<\/p>\n<p>No pod\u00eda creer lo que estaba proponiendo.<\/p>\n<p>\u2014\u00bfEst\u00e1s segura?<\/p>\n<p>\u2014S\u00ed, me muero de sentir la verga de mi novio entrar en m\u00ed sin nada entre nosotros.<\/p>\n<p>La idea potenci\u00f3 una nueva erecci\u00f3n.<\/p>\n<p>\u2014Me encantar\u00eda, mi amor, lo he pensado desde hace semanas pero no quer\u00eda dec\u00edrtelo. Pero, \u00bfy del tema de embarazos?<\/p>\n<p>\u2014Tengo un DIU. Cuando cumpl\u00ed dieciocho mi mam\u00e1 me llev\u00f3 a la gine para que lo implantara, todo va a estar bien.<\/p>\n<p>Se la quise meter al natural en ese mismo momento pero me detuve. Blanca volvi\u00f3 a mis pensamientos.<\/p>\n<p>\u2014S\u00ed, flaquita, eso quisiera m\u00e1s que nada, \u00bfte parece bien, para empezar esta nueva etapa de la relaci\u00f3n, que nos hagamos pruebas de enfermedades ven\u00e9reas? Lo digo para estar seguros y comenzar con la mayor confianza&#8230;<\/p>\n<p>Irene dud\u00f3 un segundo, pude sentir su indignaci\u00f3n. Despu\u00e9s de unos segundos, habl\u00f3.<\/p>\n<p>\u2014S\u00ed, est\u00e1 bien, \u00bfCu\u00e1ndo vamos?<\/p>\n<p>\u2014Ma\u00f1ana mismo, hay un laboratorio que te entrega los resultados el mismo d\u00eda por la tarde, los manda por correo electr\u00f3nico. De ser as\u00ed, ma\u00f1ana mismo podr\u00edamos estar disfrutando juntos.<\/p>\n<p>\u2014De acuerdo, flaquito.<\/p>\n<p>Nos quedamos dormidos sin ropa y con las ventanas abiertas. Era verano.<\/p>\n<p>Mis pap\u00e1s estaban encantados con mi relaci\u00f3n y dejaban que Irene se quedara a dormir. Era maravilloso no tener que ocultar una relaci\u00f3n. Pasearnos, besarnos, darnos mimos y pasar tiempo con nuestras familias. Era mi sue\u00f1o cumplido. Aunque lo hab\u00eda so\u00f1ado con Blanca.<\/p>\n<p>Las pruebas salieron todas negativas, por suerte. Me estaba enamorando de Irene, pero su pasado de puta en la escuela no se pod\u00eda borrar as\u00ed de f\u00e1cil. Pero como dije, todo estuvo bien. Nos hicimos las pruebas juntos, en ayunas y muy temprano. Luego nos fuimos a disfrutar del d\u00eda. Por la noche nos llegaron los resultados a mi celular. Nos abrazamos.<\/p>\n<p>\u2014No te la vas a acabar al rato, cabr\u00f3n \u2014dijo con un tono de puta que me volvi\u00f3 loco. Por fin esa mujer ser\u00eda totalmente m\u00eda.<\/p>\n<p>Decidimos pasar la noche en su casa ya que sus padres estaban fuera de la ciudad. Servimos vino y comenzamos a besarnos.<\/p>\n<p>\u2014Te amo, Irene \u2014dije cuando le quit\u00e9 la blusa para liberar esas tetas en ensue\u00f1o.<\/p>\n<p>\u2014Yo a ti, flaquito. Ap\u00farate, te necesito dentro de m\u00ed.<\/p>\n<p>Not\u00e9 la diferencia que ambos ten\u00edamos en el enfoque de esa noche. Por mi lado, yo buscaba una experiencia tierna y llena de amor. Irene, que qui\u00e9n sabe cu\u00e1nto tiempo hab\u00eda estado sin tener una verga sin cond\u00f3n dentro de ella, quer\u00eda tener la m\u00eda lo m\u00e1s pronto posible. No la iba a defraudar.<\/p>\n<p>Me desnud\u00e9 en pocos movimientos y la llev\u00e9 a su cama. Bes\u00e9 sus tetas, la abr\u00ed de piernas y me hund\u00ed en ella. Qu\u00e9 sensaci\u00f3n.<\/p>\n<p>\u2014Esc\u00fapeme en la boca, cabr\u00f3n.<\/p>\n<p>\u2014\u00bfQu\u00e9? \u2014Abr\u00ed los ojos, me agarr\u00f3 con la guardia baja.<\/p>\n<p>\u2014Que me escupas.<\/p>\n<p>Nunca hab\u00eda vivido algo as\u00ed con Blanca. Me pareci\u00f3 muy raro pero obedec\u00ed.<\/p>\n<p>\u2014As\u00ed, papi \u2014dijo en un gemido \u2014cachet\u00e9ame las tetas.<\/p>\n<p>\u2014Irene&#8230;<\/p>\n<p>\u2014Hazlo, cabr\u00f3n, c\u00f3geme, hazme tuya, rell\u00e9name de tu lechita, llevo meses esper\u00e1ndolo.<\/p>\n<p>Vi entonces lo verdaderamente viciosa que pod\u00eda ser Irene. Segu\u00ed obedeciendo.<\/p>\n<p>\u2014Ah\u00f3rcame.<\/p>\n<p>Dios m\u00edo, esa mujer estaba loca y yo m\u00e1s por estar dispuesto a obedecerla. Con cada orden cumplida, mi verga se hinchaba m\u00e1s dentro de ella.<\/p>\n<p>\u2014C\u00f3geme, no pares, no pares&#8230; \u2014intu\u00ed la inminencia de su orgasmo y aument\u00e9 la fuerza de mis embestidas.<\/p>\n<p>\u2014Desl\u00e9chate, papi, ll\u00e9name el co\u00f1o de su semen&#8230; \u2014grit\u00f3 al venirse.<\/p>\n<p>Volv\u00ed a obedecer. Vaciarme en Irene fue indescriptible. Llevaba todo el d\u00eda deseando hacerlo y cuando logr\u00e9 mezclar mi semen con sus fluidos, me sent\u00ed realizado. No la saqu\u00e9 hasta que estuvo fl\u00e1cida de nuevo. Quer\u00eda disfrutar de la sensaci\u00f3n de las paredes vaginales de mi novia el mayor tiempo posible. Cuando sal\u00ed de ella, me qued\u00e9 un momento observando su co\u00f1o. Quer\u00eda ver mi gran cantidad de semen gotear de su co\u00f1ito. Me tumb\u00e9 junto a ella y la abrac\u00e9. Ese fin cogimos tantas veces que mi glande se irrit\u00f3 al igual que sus paredes, pero nos daba igual. Nos despedimos con mucho amor antes de que regresara a mi casa a dormir antes de volver a la universidad el lunes.<\/p>\n<p>Si las cosas con Irene marchaban de maravilla, con Blanca iban empeorando. La semana siguiente s\u00f3lo cogimos una vez y fue m\u00e1s porque ambos est\u00e1bamos calientes que por el amor que nos ten\u00edamos. Descargu\u00e9 mi leche en ella con potencia, pero en realidad imagin\u00e9 que lo hac\u00eda dentro de Irene. Mi actitud sospechosa levant\u00f3 las alarmas de mi prima.<\/p>\n<p>\u2014\u00bfQu\u00e9 te traes? \u2014dijo con hostilidad mientras se vest\u00eda.<\/p>\n<p>No pude con la culpa y confes\u00e9.<\/p>\n<p>\u2014Eres un cerdo, cabr\u00f3n, un mentiroso, \u00a1me lo prometiste, Enrique, lo prometiste! \u2014chill\u00f3 entre llantos.<\/p>\n<p>La quise abrazar pero me dio una cachetada y se fue del hotel a pie. Fui a buscarla a su casa pero no estaba ah\u00ed. Manej\u00e9 por la ciudad busc\u00e1ndola sin \u00e9xito. Dos horas despu\u00e9s al fin me escribi\u00f3 por whatsapp. Quedamos de vernos de nuevo en el hotel.<\/p>\n<p>Su actitud era diferente. Ya no se notaba devastada, al contrario, parec\u00eda en control de la situaci\u00f3n.<\/p>\n<p>\u2014Si\u00e9ntate, mi amor \u2014me dijo en un tono seductor. Pens\u00e9 que hab\u00eda recapacitado y sobre todo recordado nuestro amor y que la tapadera de Irene y Samuel fue su idea.<\/p>\n<p>Puso m\u00fasica en una bocina y comenz\u00f3 a bailar sensualmente, despoj\u00e1ndose de su ropa hasta quedar s\u00f3lo en bragas.<\/p>\n<p>\u2014Qu\u00edtamelas, t\u00fa \u2014orden\u00f3.<\/p>\n<p>Al hacerlo me llev\u00e9 una sorpresa. De su co\u00f1o goteaba el semen de Samuel.<\/p>\n<p>\u2014\u00bfQu\u00e9 te pasa, Blanca? Qu\u00e9 asco.<\/p>\n<p>\u2014No tienes derecho a reclamarme. As\u00ed como t\u00fa descargaste tu preciada leche en la puta de Irene, yo dej\u00e9 que otro hombre me rellenara \u2014explic\u00f3 con malicia.<\/p>\n<p>Ard\u00ed de celos, pero no tuve ning\u00fan argumento en mi defensa. Ella no hab\u00eda acabado.<\/p>\n<p>\u2014\u00bfMe amas, primito?<\/p>\n<p>\u2014Claro que te amo, Blanca, quiero estar junto a ti para siempre.<\/p>\n<p>\u2014Demu\u00e9stralo. Demuestra que nada se puede interponer entre nosotros. Entra en m\u00ed aunque mi co\u00f1o ya haya sido invadido por otra semilla.<\/p>\n<p>Me puse de pie. El grotesco espect\u00e1culo no impidi\u00f3 mis ganas de cogerme a Blanca. Al contrario, si esa era mi realidad, decid\u00ed que por el bien de nuestro amor, era mi deber eyacular m\u00e1s semen todav\u00eda, marcar mi territorio. La lanc\u00e9 sobre la cama, le abr\u00ed las piernas y la penetr\u00e9.<\/p>\n<p>La cog\u00ed con la misma fuerza que a Irene, cacheteando sus peque\u00f1as tetitas, ahorc\u00e1ndola. Fue un instinto salvaje, que quiz\u00e1 se remontaba a nuestra \u00e9poca de las cavernas, el que me oblig\u00f3 a dejar mi semen dentro de Blanca para asegurarme que mis genes fueran los que pasaran a la siguiente generaci\u00f3n y no los de Samuel. Avis\u00e9 con un gru\u00f1ido mi eyaculaci\u00f3n. Blanca me rode\u00f3 con sus piernas.<\/p>\n<p>El resultado fue satisfactorio. Despu\u00e9s de aquella maniobra de poder, Blanca volvi\u00f3 a ser la primita tierna de la que me hab\u00eda enamorado.<\/p>\n<p>\u2014Ahora s\u00e9 que verdaderamente me amas, primito. Pero debes entender que si yo debo compartirte con aquella puta, t\u00fa deber\u00e1s compartirme con Samuel. Al menos hasta que hagas las cosas bien \u2014apunt\u00f3.<\/p>\n<p>\u2014\u00bfA qu\u00e9 te refieres? \u2014dije<\/p>\n<p>Ella s\u00f3lo movi\u00f3 su anular izquierdo en mi cara.<\/p>\n<p>\u2014Proponme matrimonio, imb\u00e9cil. Hazme tu mujer de verdad. Como lo hemos planeado por meses. Ya va siendo hora. Si no, me seguir\u00e9 cogiendo a Samuel y lo dejar\u00e9 terminar en m\u00ed todas las veces, al fin y al cabo, \u00e9l es mi verdadero novio&#8230;<\/p>\n<p>Tragu\u00e9 saliva. Blanca iba en serio. Me sent\u00ed abrumado, ni siquiera hab\u00edamos terminado la universidad, adem\u00e1s los sentimientos hacia Irene eran muy fuertes, \u00bfcon cu\u00e1l mujer deb\u00eda quedarme?<\/p>\n<p>Decid\u00ed que a\u00fan ten\u00eda tiempo para pensarlo y mientras lo hac\u00eda, seguir\u00eda disfrutando de ambos co\u00f1os por separado y de ser posible, al mismo tiempo.<\/p>\n<p>Muchas gracias por leerme, los relatos continuar\u00e1n&#8230;<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_61144\" class=\"pvc_stats total_only  \" data-element-id=\"61144\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Volv\u00ed a obedecer. Vaciarme en Irene fue indescriptible. Llevaba todo el d\u00eda deseando hacerlo y cuando logr\u00e9 mezclar mi semen con sus fluidos, me sent\u00ed realizado. No la saqu\u00e9 hasta que estuvo fl\u00e1cida de nuevo. Quer\u00eda disfrutar de la sensaci\u00f3n de las paredes vaginales de mi novia el mayor tiempo posible. Cuando sal\u00ed de ella, me qued\u00e9 un momento observando<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_61144\" class=\"pvc_stats total_only  \" data-element-id=\"61144\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":31441,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-61144","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":true,"total_views":10230,"today_views":10},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/61144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/31441"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=61144"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/61144\/revisions"}],"predecessor-version":[{"id":61146,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/61144\/revisions\/61146"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=61144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=61144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=61144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}