{"id":61668,"date":"2025-08-23T00:05:17","date_gmt":"2025-08-22T22:05:17","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=61668"},"modified":"2025-08-22T18:40:32","modified_gmt":"2025-08-22T16:40:32","slug":"ardiente-inicio-con-mi-prima-la-mayor","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/ardiente-inicio-con-mi-prima-la-mayor\/","title":{"rendered":"Ardiente inicio con mi prima la mayor"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"61668\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">49<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Hace a\u00f1os cuando a\u00fan \u00e9ramos muy j\u00f3venes yo de 18 a\u00f1os, en unas vacaciones fue la primera vez que mi prima y yo despertamos una atracci\u00f3n muy fuerte el uno por el otro.<\/p>\n<p>En aquel momento solo nos ve\u00edamos durante las vacaciones cada 2 o incluso 3 a\u00f1os ya que ella viv\u00eda en otra ciudad que estaba a m\u00e1s de 12 horas en bus\u2026<\/p>\n<p>Recuerdo que mi prima llego a la ciudad con sus pap\u00e1s, hac\u00eda varios a\u00f1os que no la ve\u00eda y en cuanto la vi pude ver lo mucho que hab\u00eda cambiado; era una chica muy guapa de piel morena clara, de pechos grandes muy grandes, un trasero moderado nada exagerado pero bien firme, piernas largas, vientre plano, cabello oscuro, ojos y boca grandes y siempre ten\u00eda esa mirada de saber lo que ten\u00eda y que acaparaba miradas, debo aclarar que con ella algo me sacaba de control ya que a m\u00ed siempre me gustaron m\u00e1s las rubias, pero ella ten\u00eda algo que me atra\u00eda casi con locura.<\/p>\n<p>Los primeros d\u00edas en casa pasaron casi normales pero despu\u00e9s de una semana durante una noche, nuestros padres estaban ya dormidos y los primos est\u00e1bamos jugando en mi recamara despu\u00e9s de un rato mis primos ya cansados cayeron rendidos y dorm\u00edan, ahora solo mi prima mayor y yo est\u00e1bamos despiertos, comenzamos a platicar de forma m\u00e1s candente, con ese t\u00edpico cachondeo y no faltaban las risitas de repente de alguna forma terminamos ambos debajo de una s\u00e1bana en mi cama; mientras mis otros primos dorm\u00edan en el otro extremo de la habitaci\u00f3n.<\/p>\n<p>Yo estaba sumamente nervioso eran mis primeras experiencias sexuales por as\u00ed decirlo, ella estaba super cerca de m\u00ed, pod\u00eda sentir sus preciosos pechos en el m\u00edo y su agitada respiraci\u00f3n, mientras nos mir\u00e1bamos fijamente a veces instintivamente ambos baj\u00e1bamos la mirada y nos mir\u00e1bamos los labios como invit\u00e1ndonos a avanzar de pronto como si nos hubi\u00e9ramos coordinado comenzamos a besarnos, aqu\u00ed debo acotar que ella es dos a\u00f1os mayor, as\u00ed que para m\u00ed no solo era el hecho de que una mujer hermosa estaba junto a m\u00ed, sino adem\u00e1s una mujer mayor a m\u00ed y todav\u00eda m\u00e1s intenso que ese alguien era mi prima, estaba sintiendo un morbo y una excitaci\u00f3n terribles, casi incontrolables.<\/p>\n<p>Comenc\u00e9 a tocar esas hermosas tetas y a besarle el cuello, ella lanzaba unos peque\u00f1os gemidos casi ahogados, despu\u00e9s de varios minutos de besos y de frotar el cuerpo uno con otro, de acariciarnos le abr\u00ed la blusa y saqu\u00e9 uno de esos impresionantes pechos eran m\u00e1s grandes que mi cara, casi de inmediato comenc\u00e9 a mamar uno de sus pezones, lo mord\u00eda, lo estiraba le pasaba la lengua en el pez\u00f3n, en eso ella (supongo que presa de la excitaci\u00f3n) se acomod\u00f3 de manera que solita saco su otro pecho y me lo ofreci\u00f3 sin decirme una sola palabra solo con su mirada me indicaba que le urg\u00eda que hiciera lo mismo en aquel pecho.<\/p>\n<p>As\u00ed que yo proced\u00ed ahora con ambos pechos, me los turnaba con una mano tocaba uno y con la boca estimulaba el otro y ella se quejaba y luego se re\u00eda y me miraba con deseo.<\/p>\n<p>\u00a1En este punto yo estaba al mil!&#8230; ella bajo su mano y comenz\u00f3 a tocarme por encima del short, nunca hab\u00eda tenido el pene tan duro y erecto como ese d\u00eda, acto seguido en un movimiento que me pareci\u00f3 super alocado sin decirme nada ella se mont\u00f3 sobre m\u00ed y comenz\u00f3 a frotarse sobre mi pene con una fuerza y velocidad tremenda, se notaba que estaba excitad\u00edsima, yo sent\u00eda en el tronco de mi pene algo caliente.<\/p>\n<p>La tom\u00e9 de las nalgas ella ten\u00eda puesto solo un short de licra sin ropa interior, trataba de llevarle el ritmo pero ella se mov\u00eda de forma casi fren\u00e9tica, en uno de esos movimientos mi pene se movi\u00f3 un poco y literal choco con algo m\u00e1s suave entre sus piernas, sent\u00ed como a pesar de tener las ropas puestas casi atravieso la tela de licra de su short, sent\u00ed como si algo caliente abrasara la cabeza de mi pene solo por ese instante sent\u00ed un calor en la punta del pene que no quer\u00eda que terminara, as\u00ed que trate de empujar lo m\u00e1s que pude el pene hasta donde dio la flexible tela y al mismo tiempo con mis manos detuve su movimiento atray\u00e9ndola a mi lo m\u00e1s que se pudo.<\/p>\n<p>Yo intentaba prolongar ese sentimiento y en eso ella emiti\u00f3 un quejido fuerte que me asusto pens\u00e9 que levantar\u00eda a todo el mundo, pero ella sigui\u00f3 luego de unos tres movimientos con la cabeza de mi pene ah\u00ed mismo cay\u00f3 encima m\u00edo respiraba cansada, temblaba y le daban como espasmos, se comenz\u00f3 a re\u00edr y me dijo en el o\u00eddo que nunca hab\u00eda sentido algo as\u00ed antes.<\/p>\n<p>Yo estaba a\u00fan super excitado entonces baje la mano y note que mi ropa estaba toda mojada pero no eran l\u00edquidos m\u00edos, mi prima quito mi mano meti\u00f3 la suya por debajo de mi ropa y comenz\u00f3 a masturbarme con delicadeza mientras me susurraba al o\u00eddo \u201c\u00bfte gusta? \u00bfquieres sentir tambi\u00e9n? Que rico lo tienes primito\u201d me dec\u00eda&#8230;<\/p>\n<p>Yo apenas pod\u00eda articular palabra solo asent\u00eda con la cabeza, de repente comenc\u00e9 a sentir como el cuerpo se me estremec\u00eda y despu\u00e9s de varios espasmos comenc\u00e9 a eyacular mucha pero mucha leche toda la sabana, mi ropa, la mano y brazo de mi prima quedo llena de mis l\u00edquidos, ella con una sonrisa de oreja a oreja me dio un beso en la boca y sali\u00f3 corriendo de la habitaci\u00f3n yo aun no pod\u00eda creer lo que hab\u00eda pasado, me quede ah\u00ed acostado disfrutando el momento.<\/p>\n<p>Ese fue el principio de unas incre\u00edbles vacaciones de verano y cuando pens\u00e9 que nada podr\u00eda igualar esa noche lleg\u00f3 un viaje pero todo lo que paso ah\u00ed es para otra historia.<\/p>\n<p>\u00a1Ciao!<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_61668\" class=\"pvc_stats total_only  \" data-element-id=\"61668\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Comenc\u00e9 a tocar esas hermosas tetas y a besarle el cuello, ella lanzaba unos peque\u00f1os gemidos casi ahogados, despu\u00e9s de varios minutos de besos y de frotar el cuerpo uno con otro, de acariciarnos, le abr\u00ed la blusa y saqu\u00e9 uno de esos impresionantes pechos, eran m\u00e1s grandes que mi cara, casi de inmediato comenc\u00e9 a mamar uno de sus<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_61668\" class=\"pvc_stats total_only  \" data-element-id=\"61668\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":31646,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-61668","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":true,"total_views":13352,"today_views":2},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/61668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/31646"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=61668"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/61668\/revisions"}],"predecessor-version":[{"id":61670,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/61668\/revisions\/61670"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=61668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=61668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=61668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}