{"id":61791,"date":"2025-08-29T00:01:45","date_gmt":"2025-08-28T22:01:45","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=61791"},"modified":"2025-08-28T18:14:21","modified_gmt":"2025-08-28T16:14:21","slug":"mi-hijo-pequeno-y-mi-cunada","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/mi-hijo-pequeno-y-mi-cunada\/","title":{"rendered":"Mi hijo peque\u00f1o y mi cu\u00f1ada"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"61791\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">59<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 8<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Tras mi trio con mis hijos, y la aclaraci\u00f3n de las relaciones que manten\u00eda con ellos tuvimos una agradable conversaci\u00f3n, en las que nos contamos lo que hasta ese momento no nos hab\u00edamos contado, y hubo una cosa que sorprendi\u00f3 a mi hijo peque\u00f1o:<\/p>\n<p>-\u00bfDe verdad follais con la t\u00eda?, Nos pregunt\u00f3<\/p>\n<p>Tambi\u00e9n lee contamos nuestra idea de llevarla al incesto con su hijo, cosa que a \u00e9l pareci\u00f3 encantarle, pero antes ten\u00eda un deseo.<\/p>\n<p>-Quiero follarmela yo primero, nos dijo.<\/p>\n<p>Tanto a mi hijo mayor como a m\u00ed nos pareci\u00f3 una buena idea, y le sugerimos ideas para llevarlo a cabo, \u00e9l llam\u00f3 a su t\u00eda, dici\u00e9ndole que quer\u00eda conocer su opini\u00f3n sobre una cosa, pero que era algo \u00edntimo, y era mejor que estuvieran solos, quedaron para la tarde siguiente, dejemos que sea \u00e9l quien cuente lo sucedido:<\/p>\n<p>Hab\u00eda quedado esa tarde con mi t\u00eda, pese a que hab\u00eda tenido experiencias con mujeres maduras, estaba igual que nervioso que se hubiera sido mi primera vez, fui muy puntual y llegu\u00e9 a la hora convenida, la t\u00eda me abri\u00f3 la puerta, y sonri\u00e9ndome me dijo que efectivamente est\u00e1bamos solos, por lo que pod\u00edamos hablar con tranquilidad, despu\u00e9s me invit\u00f3 a pasar al sal\u00f3n y sentarme en el sof\u00e1, llevaba una blusa de rayas blancas y negras y una falda, de este \u00faltimo color, que dejaba ver sus preciosas piernas y unas medias de color carne, nada m\u00e1s sentarnos me pregunt\u00f3:<\/p>\n<p>-Cu\u00e9ntame lo que te ocurre, cari\u00f1o.<\/p>\n<p>-Veras t\u00eda, le dije, es que tengo 18 a\u00f1os y a\u00fan no he hecho nada con las chicas, l ment\u00ed jajaja, pero quiero empezar a salir con ellas y me preocupa una cosa, \u00bfTu crees que mi polla es lo bastante grande para atraer a las chicas?, le pregunt\u00e9.<\/p>\n<p>Y antes de que ella tuviera tiempo de reaccionar me baje los pantalones y el short dejando mi polla al aire, ella se qued\u00f3 mir\u00e1ndola, se la notaba que le gustaba, me dijo:<\/p>\n<p>-Cari\u00f1o, tienes una polla de buen tama\u00f1o, seguro que va a gustar mucho a las chicas.<\/p>\n<p>-Pero t\u00eda, dije yo, a\u00fan no la tengo bien dura, acar\u00edciamela, para que se me ponga en condiciones y luego opinas.<\/p>\n<p>Mi t\u00eda sonri\u00f3 y dijo:<\/p>\n<p>-Est\u00e1 bien mi ni\u00f1o, pero este debe ser nuestro secreto, si se entera tu t\u00edo nos mata.<\/p>\n<p>Llev\u00f3 su mano hasta mi polla y comenz\u00f3 a acariciarla, mi polla se puso a tope, mi t\u00eda estaba excitada y llev\u00f3 su cabeza hacia la m\u00eda, y nos fundimos n un beso profundo y apasionado, por fin se iba a hacer realidad uno de mis sue\u00f1os pajilleros, parece ser que tambi\u00e9n el de mi hermano mayor, jajaja, tras el beso yo le ped\u00ed:<\/p>\n<p>-Tiita querida, \u00bfPor qu\u00e9 no me la chupas, como seguro que se la chupas a mi t\u00edo?<\/p>\n<p>-Est\u00e1 bien mi amor, dijo ella, lo hare, pero te repito que este debe de ser nuestro secreto.<\/p>\n<p>A continuaci\u00f3n, me pidi\u00f3 que me pusiera de pie, ella se desabroch\u00f3 la blusa, dejando al descubierto un precioso conjunto de lencer\u00eda azul, me parec\u00eda la mujer m\u00e1s sexy del mundo y me dijo:<\/p>\n<p>-Como voy a disfrutar comi\u00e9ndome esta polla tan rica.<\/p>\n<p>Primero se quit\u00f3 el sujetador dejando al aire sus impresionantes tetas. Despu\u00e9s me pas\u00f3 su lengua a lo largo de toda mi polla, ni en mis pajas m\u00e1s calientes hab\u00eda disfrutado tanto, as\u00ed que comenc\u00e9 a gemir, ella al verlo me pregunt\u00f3:<\/p>\n<p>-\u00bfTe gusta lo que te hace tu t\u00eda?<\/p>\n<p>La verdad es que estaba disfrutando a tope, y as\u00ed se lo dije y luego a\u00f1ad\u00ed:<\/p>\n<p>-Mi t\u00edo debe de pasarlo de maravilla, si le haces esto todos los d\u00edas.<\/p>\n<p>Ella dej\u00f3 de chup\u00e1rmela un momento, se rio y me respondi\u00f3:<\/p>\n<p>-Cari\u00f1o, con tu t\u00edo esto casi ni lo hago, la verdad es que su polla ya no me apetece tanto.<\/p>\n<p>Y me la sigui\u00f3 chupando, en ese momento me sent\u00eda en la gloria, pero mi polla deseaba pasar a la fase siguiente, ella pareci\u00f3 adivinarlo y me dijo:<\/p>\n<p>-Cari\u00f1o, \u00bfTe apetece que la t\u00eda te desvirgue?<\/p>\n<p>Yo me sent\u00eda en la gloria, no pensaba decirle que ya ten\u00eda cierta experiencia, as\u00ed que acept\u00e9 su oferta, ella dejo de chup\u00e1rmela y me pidi\u00f3, que me quedar\u00e1 sentadito, muy relajado, le indiqu\u00e9 que ten\u00eda un cond\u00f3n en uno de los bolsillos de mi pantal\u00f3n, ella lo cogi\u00f3 y me lo puso, despu\u00e9s se subi\u00f3 encima de m\u00ed e introdujo mi polla en el interior de su co\u00f1o, llevaba raz\u00f3n mi hermano cuando me dijo que el co\u00f1o de la t\u00eda era muy caliente, ella se puso a cabalgarme a un ritmo divino, desde luego, pese a lo que ella dijera el t\u00edo me daba envidia.<\/p>\n<p>Cuando se cans\u00f3 de cabalgarme en esta postura, sin sac\u00e1rmela se dio la vuelta y sigui\u00f3 follandome, en esta postura no pide evitar llevar mis manos a sus tetas y comenc\u00e9 a acariciarlas, ella al ver como lo hac\u00eda me dijo:<\/p>\n<p>-So cabr\u00f3n, me has mentido, tocas las tetas tan bien que esta claro que no soy la primera mujer a la que se lo haces, se rio y a\u00f1adi\u00f3, pero me encanta como lo haces.<\/p>\n<p>Yo tambi\u00e9n me re\u00ed y segu\u00ed acarici\u00e1ndola sus divinas tetas, mientras la dec\u00eda, t\u00eda te adoro.<\/p>\n<p>Despu\u00e9s baj\u00e9 una de mis manos y me puse a acariciar sus muslos, ella gemida de una manera muy intensa, mientras segu\u00eda ocup\u00e1ndose de mi polla, yo estaba alucinando, ella me dijo:<\/p>\n<p>-Mi amor me corro.<\/p>\n<p>Fio un fuerte gemido y sent\u00ed como su co\u00f1o se humedec\u00eda de una manera muy intensa, se sali\u00f3, se puso a cuatro patas y sonriendo me dijo:<\/p>\n<p>-So sinverg\u00fcenza, ya que o eres virgen demu\u00e9strame lo que otras te han ense\u00f1ado.<\/p>\n<p>Y se puso a a cuatro patas encima del sof\u00e1, dej\u00e1ndome en primer plano una visi\u00f3n maravillosa de su co\u00f1o y de su culo, por supuesto se trataba de un regalo que no iba a desaprovechar, as\u00ed que me puse detr\u00e1s de ella y de un golpe la introduje mi polla, nuevamente, en el interior de su co\u00f1o, y comenc\u00e9 a moverme, ella al sentirme se puso a gemir y dijo:<\/p>\n<p>-Que bien follas so cerdo, jajaja<\/p>\n<p>Yo me puse a marcar el ritmo que tanto encantaba a mi madre, y ella se puso a gemir de una manera muy intensa, no hab\u00eda duda de que la t\u00eda era una mujer muy sensual y que mi hermano mayor hab\u00eda acertado al seducirla, ella me dijo:<\/p>\n<p>-Quien lo hubiera pensado de un mocoso como t\u00fa.<\/p>\n<p>Note como su excitaci\u00f3n iba en aumento, hasta que se corri\u00f3, mientras yo continuaba con mi polla en su interior, ella debi\u00f3 de notar que me iba a correr, pues dijo:<\/p>\n<p>-Mi amor, me encantar\u00eda que nuestra primera vez fuera entre mis tetas.<\/p>\n<p>Las tetas de mi t\u00eda eran impresionantes, as\u00ed que me decid\u00ed a complacerla, me sal\u00ed de su co\u00f1o y me puse de pie, ella se levant\u00f3 del sof\u00e1 y se coloc\u00f3 de rodillas a mi lado, yo me quit\u00e9 el cond\u00f3n y me puse a acariciarme la polla con la mano, hasta que me corr\u00ed y mi leche fue a parar a sus tetas.<\/p>\n<p>-Ella se la restreg\u00f3 por su piel y volvi\u00e9ndome a sonre\u00edr me propuso:<\/p>\n<p>-Cari\u00f1o, vay\u00e1monos a mi cama.<\/p>\n<p>Cogidos de la mano me condujo al piso superior del chale, donde estaba su dormitorio., all\u00ed se tumb\u00f3 en la cama, yo le ped\u00ed que abriera bien sus piernas, me tumb\u00e9 sobre la cama, y arromando mi cabeza a su co\u00f1o, introduje mi lengua dentro de este, mi t\u00eda al sentirlo dijo:<\/p>\n<p>-So cabr\u00f3n que bien lo haces, desde luego, para nada eres virgen, pero lo comes tan bien<\/p>\n<p>Mi lengua saboreaba cada uno de los rincones de ese apetitoso co\u00f1o, me encantaba com\u00e9rselo, hasta que ella dijo:<\/p>\n<p>-Cari\u00f1o, me est\u00e1s haciendo muy feliz, deja que te devuelva el regalo.<\/p>\n<p>Apart\u00f3 mi boca de su co\u00f1o y me hizo tumbarme boca arriba sobre la cama, en esta ocasi\u00f3n fue ella la que acerc\u00f3 su boca a mi polla y dijo;<\/p>\n<p>-No sabes las ganas que tengo de comerme esa polla tan deliciosa.<\/p>\n<p>Y cogiendo mi polla con su mano la llev\u00f3 hasta su boca, y la introdujo en su interior, lo que me hizo sentir en ese momento era m\u00e1s propio de una diosa, su lengua parec\u00eda entrenada para volver loco de placer a cualquier macho, yo le dije:<\/p>\n<p>-T\u00eda eres divina, que envidia me da el t\u00edo, seguro que se la comes todos los d\u00edas.<\/p>\n<p>Ella se rio y dijo:<\/p>\n<p>-Cari\u00f1o, de joven lo era, pero ahora se esta haciendo viejo y estas coas le apetecen cada vez menos. Y luego cari\u00f1o, parece que tu polla ya esta obra vez en forma, debemos de volver a follar<\/p>\n<p>En ese momento abri\u00f3 un caj\u00f3n de su mesilla y dijo:<\/p>\n<p>-Esta vez invito yo.<\/p>\n<p>Le pregunt\u00e9 si no ten\u00eda miedo de que mi t\u00edo se diera cuenta, ella me respondi\u00f3:<\/p>\n<p>-Para nada, mi amor, el no se fija en eso, no sabe si hay mucho o pocos,<\/p>\n<p>Cogiendo uno me lo puso en mi polla, y tras hacerlo se puso encima de m\u00ed, y, nuevamente coloc\u00f3 mi polla a la entrada de su co\u00f1o y comenz\u00f3 a moverse, lo hac\u00eda de una manera alucinante, me estaba volviendo loco de placer, yo sent\u00eda que la adoraba, ella se agach\u00f3 un poco y nuestros labios se juntaron y nos besamos apasionadamente, Estuvimos en esta posici\u00f3n un rato, not\u00e9 como ella se corr\u00eda, y la humedad de su co\u00f1o lleg\u00f3 hasta mi polla, pese al cond\u00f3n, pero ella sigui\u00f3 encima de m\u00ed, hasta que logro que me corriera, cuando vio que estaba a punto, se levant\u00f3 y se arrodill\u00f3 en el suelo.<\/p>\n<p>Yo comprend\u00ed que quer\u00eda que yo hiciera lo mismo, cuando me tuvo de pie, agarr\u00f3 mi polla con sus manos y dio, riendo:<\/p>\n<p>-Vaya con el ni\u00f1ato virgen, eres un gran follador, de virgen nada, jajaja.<\/p>\n<p>Despu\u00e9s me quit\u00f3 el cond\u00f3n y se puso a chuparme la polla hasta que me corr\u00ed, se trag\u00f3 toda la leche que pudo, despu\u00e9s se la sac\u00f3 y con su lengua se puso a chup\u00e1rmela, era extremadamente delicioso, me la dej\u00f3 completamente limpia, pero ante este tratamiento mi polla reaccion\u00f3 y se puso nuevamente dura. Ella dio:<\/p>\n<p>-Parece que tu cosa quiere seguir jugando.<\/p>\n<p>Se tumb\u00f3 en la cama con las piernas bien abiertas, yo me puse otro cond\u00f3n, ella me pidi\u00f3 que me la follara estando de pie, yo lo hice y desde esta postura volv\u00ed a meter mi polla en ese lugar tan delicioso, ella volvi\u00f3 a gemir de una manera muy intensa, mientras me dec\u00eda:<\/p>\n<p>-Eres un follador incre\u00edble, mi amor, me estas volviendo loca de placer.<\/p>\n<p>Yo segu\u00eda follandomela, comprend\u00eda porque mi hermano estaba encantado de hacerlo. Me agach\u00e9, quer\u00eda chupar sus tetas, que ten\u00eda cerca de m\u00ed, en ese momento ella me dijo:<\/p>\n<p>-\u00bfEstas cansado? cari\u00f1o?<\/p>\n<p>\u00bfC\u00f3mo iba a estar cansado de follar con ella? Yo ten\u00eda ganas de seguir haci\u00e9ndolo hasta que mi polla me dijera que no pod\u00eda m\u00e1s, pero pensando el motivo de su pregunta la cuestion\u00e9 al respecto, ella me dijo:<\/p>\n<p>-\u00bfSo cabron te apetece follarme de espaldas? aqu\u00ed me tienes.<\/p>\n<p>Ten\u00eda ganas de hacerlo en cualquier postura, as\u00ed que acept\u00e9. Me sal\u00ed de ella, y mi tia se dio la vuelta y levant\u00f3 un poco las piernas para dejar al descubierto, desde su espalda, su co\u00f1o, era un espect\u00e1culo maravilloso, yo me puse detr\u00e1s de ella, de pie y desde esa postura introduje mi polla en el interior de su co\u00f1o y me dispuse a llevar el ritmo que mi madre me hab\u00eda ense\u00f1ado, ella gem\u00eda, y me dijo:<\/p>\n<p>-Cada vez me sorprendes m\u00e1s, follas como un experto,<\/p>\n<p>Y mientras segu\u00eda gimiendo, mientras me dec\u00eda cosas, como:<\/p>\n<p>-Mi amor me vuelves loca, te adoro,<\/p>\n<p>Yo segu\u00eda atacando su co\u00f1o desde atr\u00e1s, y me sent\u00eda el hombre m\u00e1s afortunado del mundo.<\/p>\n<p>Not\u00e9 como ella se corr\u00eda y segu\u00ed d\u00e1ndole ca\u00f1a, adoraba ese co\u00f1o, y notar como mi polla chocaba con los cachetes de su culo le daba m\u00e1s excitaci\u00f3n al asunto, y segu\u00eda as\u00ed hasta que una sensaci\u00f3n de gran placer, en ese momento mi t\u00eda me dio una nueva sorpresa cuando me propuso:<\/p>\n<p>-\u00bfTe gustar\u00eda met\u00e9rmela por el culo?<\/p>\n<p>Sab\u00eda que se lo hab\u00eda con mi hermano, pero deb\u00eda de hacerme el sorprendido y le dije:<\/p>\n<p>-\u00bfTiita lo haces por ah\u00ed?<\/p>\n<p>-Mi amor, dijo ella, a mi me gusta hacerlo por todos los sitios.<\/p>\n<p>Acto seguido se tumb\u00f3 sobre la cama y levantando sus brazos y sus piernas se puso a cuatro patas, parec\u00eda una leona, me puse detr\u00e1s de ella, y una maravillosa visi\u00f3n de su culo, mi polla al contemplarlo se puso a mil, as\u00ed que me puse detr\u00e1s de ella, de rodillas y de un golpe se la met\u00ed:<\/p>\n<p>Nada m\u00e1s recibirla ella se puso a gozar, se ve que mi hermanito, o alg\u00fan otro hab\u00edan abierto muy bien el camino, sus gemidos fueron aumentando, demostr\u00e1ndome lo mucho que le gustaba tener mi polla en su interior, as\u00ed que segu\u00ed movi\u00e9ndome, sus gemidos iban en aumento, hasta que lleg\u00f3 un momento en que me dijo:<\/p>\n<p>-Mi amor me corro.<\/p>\n<p>Continue follandole el culo, pero llev\u00e9 una de mis manos hasta su co\u00f1o e introduje dos de mis dedos en \u00e9l, estaba extremadamente mojado, parec\u00eda que su due\u00f1a se estaba ba\u00f1ando en el mar.<\/p>\n<p>Fio un fuerte gemido, se\u00f1al de que se estaba corriendo, consider\u00e9 necesario parar, me sal\u00ed de su culo y me tumb\u00e9 en la cama, ella me bes\u00f3 cari\u00f1osamente y me dijo;<\/p>\n<p>-Muchas gracias, mi amor, llevaba mucho tiempo sin sentir algo as\u00ed,<\/p>\n<p>Tard\u00f3 un momento en recuperarse, y llev\u00f3 una de sus manos hacia mi polla y la acarici\u00f3, despu\u00e9s a\u00f1adi\u00f3:<\/p>\n<p>-Tu polla no ha descargado dentro de mi culo, y me muero de ganas de que lo haga, pero deja que yo elija la postura.<\/p>\n<p>Me pidi\u00f3 que me tumbara sobre la cama, y sub saber c\u00f3mo, a la vez que se sentaba, volv\u00eda a encajar mi polla en uno fr sus agujeros, en este caso el culo, y sentada sobre mi, comenz\u00f3 a subir y bajar su trasero, llevaba un ritmo maravilloso, yo estaba experimentando una sensaci\u00f3n de placer incre\u00edble<\/p>\n<p>Mientras yo ve\u00eda sus tetas, que eran divinas, y otra vez, no pude resistir la tentaci\u00f3n de acarici\u00e1rselas, ella gem\u00eda de una manera muy intensa, pero en ese momento sent\u00ed la necesidad de ser yo quien llevara el ritmo, y la ped\u00ed que se pusiera debajo, para mi sorpresa pudimos hacer el cambio, sin que mi polla abandonara el para\u00edso de su culo, nuevamente sent\u00ed la necesidad de besar su boca y despu\u00e9s la dije:<\/p>\n<p>-T\u00eda te adoro.<\/p>\n<p>Mientras la dec\u00eda esto segu\u00eda follando con ella, intentaba no correrme porque quer\u00eda que este momento se prolongara lo m\u00e1ximo posible., pero todo tiene un l\u00edmite y no pude evitar correrme y mi semen inund\u00f3 su polla, ella al sentirlo me bes\u00f3 nuevamente y me dijo:<\/p>\n<p>-Mi amor me has hecho muy feliz, espero que sepas guardar nuestro secreto, y as\u00ed lo podremos hacer de vez en cuando.<\/p>\n<p>-Por supuesto t\u00eda, le respond\u00ed.<\/p>\n<p>Sab\u00eda que mi primo se lo hacia con mi madre y en cierta manera esta era una forma de vengarme, pero era una manera deliciosa.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_61791\" class=\"pvc_stats total_only  \" data-element-id=\"61791\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 8<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Mientras yo ve\u00eda sus tetas, que eran divinas, y otra vez, no pude resistir la tentaci\u00f3n de acarici\u00e1rselas, ella gem\u00eda de una manera muy intensa, pero en ese momento sent\u00ed la necesidad de ser yo quien llevara el ritmo, y la ped\u00ed que se pusiera debajo, para mi sorpresa pudimos hacer el cambio, sin que mi polla abandonara el para\u00edso<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_61791\" class=\"pvc_stats total_only  \" data-element-id=\"61791\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30008,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-61791","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":true,"total_views":19876,"today_views":9},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/61791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30008"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=61791"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/61791\/revisions"}],"predecessor-version":[{"id":61793,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/61791\/revisions\/61793"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=61791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=61791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=61791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}