{"id":62456,"date":"2025-10-02T00:02:08","date_gmt":"2025-10-01T22:02:08","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=62456"},"modified":"2025-10-01T13:17:29","modified_gmt":"2025-10-01T11:17:29","slug":"las-amistades-peligrosas","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/las-amistades-peligrosas\/","title":{"rendered":"Las amistades \u00bfpeligrosas?"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"62456\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">18<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 10<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>La vida de casado, con hijos, trabajo, perro, lleva a la monoton\u00eda y el letargo, y vas aparcando los peque\u00f1os placeres de pareja, escapadas, fines de semana, juegos sexuales, y al final el sexo m\u00e1s corriente. Los encuentros se vuelven m\u00e1s espaciados en el tiempo, y al final, te acostumbras tanto a no tenerlo, que el d\u00eda que cae, es una fiesta. Nos fuimos metiendo en a\u00f1os, rondando casi los 50, y la vida va pasando no s\u00e9 si lenta o r\u00e1pida, pero aburrida. Vivimos en una urbanizaci\u00f3n a las afueras de una peque\u00f1a ciudad del norte.<\/p>\n<p>Mi mujer, Lara, es encargada de una conocida cadena de tiendas a nivel nacional, y yo, Miguel, jefe de ventas en un concesionario de veh\u00edculos. La urbanizaci\u00f3n ha ido creciendo en los 12 a\u00f1os que llevamos en ella. Es una zona muy tranquila, con mucho espacio verde, zonas para hacer deporte, para los ni\u00f1os, los perros, zona de restauraci\u00f3n, etc. Mucha gente ha ido dejando el centro para comprar casas aqu\u00ed, adosada, que son la mayor\u00eda, o peque\u00f1os chalets independientes, los primeros que vinimos. De esta \u00faltima hornada, ha venido una pareja con la que hemos hecho gran amistad, Pablo y Bel\u00e9n.<\/p>\n<p>Las mujeres han hecho buenas migas, y nosotros, con muchas aficiones similares, y pasi\u00f3n por los perros, pues m\u00e1s de lo mismo. Su amistad, nos ha sacado un poco de la monoton\u00eda, hemos empezado a quedar y salir alg\u00fan fin de semana, y este a\u00f1o, hemos planeado las vacaciones juntos, los 4, sin hijos ni mascotas. De edad similar a la nuestra, Pablo y yo somos de constituci\u00f3n fuerte, aunque \u00e9l es un poco m\u00e1s alto que yo, ronda el metro noventa, trabajamos gimnasio 5 d\u00edas por semana, y a pesar de nuestra edad nos mantenemos agiles y fuertes, pero sin decir no a los placeres de la vida, como un buen vino o una buena comida. Pablo, es subinspector de la polic\u00eda y un amante de la pesca desde embarcaci\u00f3n.<\/p>\n<p>Bel\u00e9n es totalmente contraria a Lara. Lara apenas mide metro 60 y pesa unos 48 Kg, no hace casi deporte y aun as\u00ed, la gen\u00e9tica es generosa con ella. A pesar de sus a\u00f1os, tiene la piel tersa y firme, sus peque\u00f1os pechos talla 85, totalmente erguidos como una adolescente, y un culito resping\u00f3n y proporcionado. Bel\u00e9n, sin embargo, Directora de una marca de seguros, mide cerca del metro setenta y cinco, y aunque se machaca en Pilates y camina m\u00e1s de 2 horas diarias, le sobra alg\u00fan kilo. Aun as\u00ed, viste bastante ajustada, y cuando vamos a caminar o al gimnasio, suele llevar mallas, que le hacen un culo tremendo, y tiene un generoso pecho, calculo 95 o m\u00e1s.<\/p>\n<p>Reconozco que he fantaseado con ella en m\u00e1s de una ocasi\u00f3n, sobre todo desde el fin de semana que fuimos en el peque\u00f1o barco de Pablo a pescar. Las dos mujeres se dispusieron a tomar el sol, y Bel\u00e9n, pregunto si nos importaba que hiciera topless, pues odiaba las marcas del bikini. Tras no saber muy bien que decir, Lara contest\u00f3 que no, y yo tambi\u00e9n, a lo que inmediatamente Bel\u00e9n respondi\u00f3 quit\u00e1ndose la parte de arriba. Como yo cre\u00eda, menudo par de melones se gastaba, con unos pezones grandes y oscuros, erguidos por la brisa del barco. Anim\u00f3 a Lara a hacer lo mismo.<\/p>\n<p>-Venga mujer, aqu\u00ed no hay nadie, y los que estamos somos como familia ya<\/p>\n<p>-De acuerdo, dijo Lara mir\u00e1ndome, como pidiendo mi aprobaci\u00f3n, a lo que asent\u00ed con la cabeza<\/p>\n<p>Bel\u00e9n tomo la crema solar y comenz\u00f3 a ponerse a Lara, aplicando generosamente sobre sus pechos, que respondieron irguiendo los pezones, duros como piedras. Bel\u00e9n rodeo por detr\u00e1s a Lara, y le aplico crema en la espalda, y desde detr\u00e1s, volvi\u00f3 a masajear sus tetas, cogiendo sus pezones y gir\u00e1ndolos un poco, a lo que Lara respondi\u00f3 con leve jadeo. Bel\u00e9n sonri\u00f3 y continu\u00f3 aplic\u00e1ndole la crema por el vientre, entrando ligeramente con la mano en la escasa tela del tanga, y despu\u00e9s paso a las nalgas. Estaba embobado mirando y la voz de Pablo me sobresalt\u00f3:<\/p>\n<p>-Vamos a preparar los aparejos, o voy a tener que terminar haci\u00e9ndome una paja, dijo, con una mano dentro del ba\u00f1ador atrapando el tremendo bulto que se dejaba notar a trav\u00e9s de la tela, y creo que no soy el \u00fanico, dijo con una sonrisa, indicando mi entrepierna<\/p>\n<p>Un poco ruborizado, me di cuenta de la erecci\u00f3n que mi ba\u00f1ador ya no disimulaba, pero es que la escena era excitante al m\u00e1ximo. Las chicas nos miraron riendo, mientras Lara aplicaba la crema ahora a Bel\u00e9n de la misma excitante manera que antes se lo hab\u00eda hecho a ella, y se tumbaron en la proa, a broncearse. Pablo y yo nos fuimos a popa, a preparar las ca\u00f1as.<\/p>\n<p>-Lara est\u00e1 muy buena, me dijo sin tapujos, y parece receptiva. Creo que si Bel\u00e9n insiste mas, se la lleva al huerto<\/p>\n<p>Un poco incr\u00e9dulo por el comentario, acert\u00e9 a decir:<\/p>\n<p>-Ayer te habr\u00eda dicho que no, sin pensarlo, pero despu\u00e9s de lo visto, igual tienes raz\u00f3n, de todos modos, no te quejes, Bel\u00e9n es un mujeron<\/p>\n<p>-\u00bfTe pone verdad? Me he fijado como la miras<\/p>\n<p>-Repito que es un mujeron, lo siento si te he ofendido por mirarla, es tan distinta a Lara<\/p>\n<p>-No te disculpes idiota, yo tambi\u00e9n miro a la tuya, y he fantaseado con ella muchas veces, hasta lo he comentado con Bel\u00e9n.<\/p>\n<p>-\u00bfC\u00f3mo?<\/p>\n<p>-Si, hemos hablado de c\u00f3mo ser\u00eda follar los 4 juntos, intercambiando parejas, he incluso verlas a ellas dos solas. Bel\u00e9n te tiene ganas y a Lara ni te cuento, y yo, vamos, lo que har\u00eda con ella. \u00bfAcaso t\u00fa no te follarias a mi mujer si tuvieras oportunidad? Ni\u00e9game que has fantaseado con ello.<\/p>\n<p>-No te lo niego, pero de pensarlo a hacerlo\u2026<\/p>\n<p>-La oportunidad es hoy y aqu\u00ed, solos los 4, sin opci\u00f3n de que nadie nos vea. Solo si estamos todos de acuerdo.<\/p>\n<p>-Me excita pensarlo, la verdad, pero no creo que Lara acepte.<\/p>\n<p>-Eso d\u00e9jaselo a Bel\u00e9n, es muy persuasiva, jajaja<\/p>\n<p>-No lo dudo, viendo lo visto<\/p>\n<p>Seguimos pescando y hablando del tema, ya sin ning\u00fan tapujo, alabando cada uno las virtudes de la mujer del otro, lo que m\u00e1s nos gustaba hacerles y que nos hicieran, as\u00ed como lo que menos o lo que nunca hab\u00edamos hecho. Acab\u00e9 reconociendo que nuestra vida sexual era muy mon\u00f3tona y aburrida comparada con la de mis amigos, que incluso hab\u00edan probado locales de intercambio, y un hotel de tem\u00e1tica Sado, en Barcelona.<\/p>\n<p>Varias piezas despu\u00e9s, de buen tama\u00f1o, que nos garantizaban comida y cena para un par de d\u00edas, decidimos dejar de pescar e ir a por unas cervezas, pues el sol apretaba, y de paso ver que hac\u00edan nuestras parejas. Pablo, que iba delante por el paso lateral de la embarcaci\u00f3n, se detuvo, y me mando acercar despacio y en silencio. En la proa del barco, que ten\u00eda un peque\u00f1o espacio de sol\u00e1rium, con colchonetas que formaban un acogedor y c\u00f3modo triangulo, estaba Lara, tumbada, completamente desnuda, con Bel\u00e9n encima, desnuda tambi\u00e9n, con su cabeza enterrada entre las piernas de mi mujer, que se contoneaba y jadeaba, retorci\u00e9ndose los pezones con ambas manos.<\/p>\n<p>Bel\u00e9n manten\u00eda con sus manos las piernas de Lara separadas, y se ve\u00eda su lengua recorrer su vagina de arriba abajo. Solt\u00f3 una de las piernas e introdujo varios dedos dentro de ella, mientras segu\u00eda lamiendo, a lo que Lara respondi\u00f3 arqueando la espalda y teniendo un sonoro orgasmo, tras el cual qued\u00f3 tendida. Bel\u00e9n acomodo un coj\u00edn bajo la cabeza de Lara, y se puso a horcajadas con su depilado sexo a escasos mil\u00edmetros de la boca de mi mujer, la miro y le dijo:<\/p>\n<p>-Venga, me toca, hazlo como te ense\u00f1e<\/p>\n<p>Lara, sin mediar palabra, rodeo con sus brazos a Bel\u00e9n, agarr\u00f3 su culo con ambas manos y comenz\u00f3 a comerle el co\u00f1o a su amiga, que tard\u00f3 menos de un minuto en correrse tambi\u00e9n, gritando como una loca, cogiendo la cabeza de Lara por la coleta, para que no se separara ni se detuviera.<\/p>\n<p>Cuando las dos parecieron relajarse, nos acercamos.<\/p>\n<p>-Veo que os lo est\u00e1is pasando genial sin nosotros, dijo Pablo<\/p>\n<p>-S\u00ed, creo que estas dos son un poco ego\u00edstas, \u00bfno? Dije yo<\/p>\n<p>-Hab\u00eda mucha tensi\u00f3n sexual en este barco, solo liberamos un poco, dijo Bel\u00e9n<\/p>\n<p>-Si, afirmo Lara, pero acercaros, que se os ve tensos, mirando p\u00edcaramente a su amiga<\/p>\n<p>Pablo sea cerco a Bel\u00e9n desnudo ya, y yo me quite el ba\u00f1ador para ir tambi\u00e9n. Bel\u00e9n y Lara se pusieron de rodillas para esperarnos, y seg\u00fan llegamos, cada una tom\u00f3 nuestras pollas en su boca y comenzaron a chuparlas golosamente. Lara, a pesar de ser bastante \u201ccl\u00e1sica\u201d en el sexo, hac\u00eda unas mamadas de esc\u00e1ndalo. A Bel\u00e9n, le costaba tragarse el aparto de Pablo, de generosas proporciones y m\u00e1s largo que el m\u00edo, aunque menos grueso. Tras unos minutos, y perfectamente compenetradas, intercambiaron posiciones. Ver a mi mujer con la polla de mi amigo en su boca, mientras Bel\u00e9n se com\u00eda la m\u00eda, me puso a 1000.<\/p>\n<p>Pablo agarraba la cabeza de Lara y le follaba la boca lentamente, disfrutando de cada cent\u00edmetro de mamada, y yo hac\u00eda lo mismo con Bel\u00e9n. Incremente el ritmo, porque estaba a punto de correrme, le mir\u00e9 a los ojos pidiendo permiso, algo que entendi\u00f3 muy bien, respondiendo con un parpadeo, y solt\u00e9 toda mi descarga directo al fondo de su garganta, un par de disparos mas, abundantes, y la deje retirarse un poco, mientras lamia y succionaba el resto de mi corrida.<\/p>\n<p>Mir\u00e9 a Pablo y Lara, este ten\u00eda su polla en la mano, mientras varios chorros de semen se deslizaban en la cara y tetas de mi mujer, as\u00ed como en el pelo. Bel\u00e9n se le acerc\u00f3 a terminar de limpiarlo, y despu\u00e9s, con la lengua, recogi\u00f3 todo lo que pudo del cuerpo de Lara. Yo, estaba at\u00f3nito y en \u00e9xtasis tras lo ocurrido. Ni en mis m\u00e1s h\u00famedos sue\u00f1os hubiera imaginado esta situaci\u00f3n. Bel\u00e9n tomo de la mano a Lara, y dijo:<\/p>\n<p>-Vamos a ba\u00f1arnos, preparar algo de comer mientras, que el finde es largo, y necesitaremos fuerzas<\/p>\n<p>Lara me miro, me gui\u00f1o un ojo, y me lanz\u00f3 un beso sonriendo, mientras saltaban al mar<\/p>\n<p>-Miguel, obedezcamos, que este finde no lo vamos a olvidar, te lo prometo, mi mujer esta desatada, y la tuya, no le va a la zaga, dijo Pablo<\/p>\n<p>-Ya lo veo, respond\u00ed, esto promete<\/p>\n<p>Preparamos un poco de ensalada, un par de hermosas lubinas reci\u00e9n pescadas y abrimos una botella de Albari\u00f1o bien frio. Las chicas subieron por popa, totalmente desnudas y mojadas. Lara me rodeo con sus brazos y me dio un morreo meti\u00e9ndome la lengua hasta el fondo. Despu\u00e9s tomo una copa de vino y le dio un sorbo. No sol\u00eda beber, pero este fin de semana era completamente distinta, y eso me estaba gustando. Bel\u00e9n y Pablo estaban fundidos en un beso profundo mientras este masajeaba el voluptuoso culo de su mujer y separa sus nalgas, dejando descubierto su rosado ano, que invitaba a penetrarlo directamente. Una nueva erecci\u00f3n creci\u00f3 en m\u00ed, a la cual Lara no fue indiferente, tomando mi miembro con su mano, e iniciando un movimiento firme pero suave, de masturbaci\u00f3n.<\/p>\n<p>-Chicos, chicos, vamos a comer que nos calentamos nosotros pero se enfr\u00eda el pescado, dijo Pablo riendo<\/p>\n<p>-No s\u00e9 si podr\u00e9 sentarme as\u00ed, jajaja respond\u00ed yo<\/p>\n<p>Nos sentamos los 4 a la mesa y comimos con ganas, hablando de cosas triviales, mientras termin\u00e1bamos la primera botella de vino. Pablo bajo a la cabina a por otra. Belen me mir\u00f3 y me comento:<\/p>\n<p>-Me dice Lara que te tiene muy abandonado, y que este finde es para que veas que te quiere y que todo va a cambiar. Sabe de tus fantas\u00edas y de su dejadez y est\u00e1 muy orgullosa de que la hayas respetado y no le pusieras los cuernos por ah\u00ed, aunque lo entender\u00eda<\/p>\n<p>-Es cierto, dijo Lara, llevo unas cuantas terapias con Bel\u00e9n, en secreto, y me han cambiado mucho, soy otra. Y quiero hacerte este regalo, que llevamos preparando los 3 algo de tiempo ya.<\/p>\n<p>-\u00bfVaya, as\u00ed que esto estaba preparado? Pregunte, pues me encanta la sorpresa.<\/p>\n<p>-\u00bfYa se lo hab\u00e9is contado? Dijo Pablo saliendo de la cabina con la botella en la mano<\/p>\n<p>-Si, respondieron ambas al un\u00edsono<\/p>\n<p>-\u00bfHab\u00edas pensado alguna vez en ver a esta belleza follar con otro? Dijo Pablo, mientras levantaba a Lara de su silla y la giraba sobre si misma, como en un paso de baile<\/p>\n<p>-No, la verdad, respond\u00ed, la mera idea me repugnaba, sin embargo, esta situaci\u00f3n es completamente distinta, y admito que verla chup\u00e1rtela mientras tu mujer me lo hac\u00eda a mi, me excit\u00f3 much\u00edsimo<\/p>\n<p>Bel\u00e9n, que a\u00fan estaba sentada, se levant\u00f3, tom\u00f3 las cabezas de Pablo y Lara y los junt\u00f3, a lo que respondieron fundi\u00e9ndose en un profundo beso. Bel\u00e9n retir\u00f3 un poco a Lara para tomar ella el lugar de Pablo en su boca, y alternaba esta con la de su marido. Pablo estaba, al igual que yo, completamente empalmado. Su hombr\u00eda se aplastaba contra el vientre de mi mujer.<\/p>\n<p>La gir\u00f3 sobre si misma y deslizo desde detr\u00e1s su polla, entre sus piernas, saliendo un buen trozo entre los labios vaginales de Lara. Bel\u00e9n se arrodillo y comenz\u00f3 a chupar y lamer el glande de su marido, que se mov\u00eda atr\u00e1s y adelante, haciendo que mi mujer comenzara a jadear presa de la excitaci\u00f3n. Bel\u00e9n aprovechaba cuando \u00e9l se retiraba para lamer la vagina y el cl\u00edtoris de Lara. Pablo ten\u00eda presos los dos pechos de Lara, y jugueteaba con sus inhiestos pezones, duros como piedras.<\/p>\n<p>-\u00bfVas a seguir embobado mirando? O me vas a ayudar con estas dos fieras, me dijo Pablo<\/p>\n<p>Me acerque a Bel\u00e9n por detr\u00e1s, me puse a un lado, Lara apres\u00f3 mi polla con su mano y la dirigi\u00f3 a la boca de Bel\u00e9n, que comenz\u00f3 a darnos placer a los 3, alternando de uno a otro, durante un buen rato. Decid\u00ed tomar la iniciativa. Puse a Lara tumbada boca arriba, y a Bel\u00e9n sobre ella a horcajadas. Inmediatamente ambas comenzaron a comerse los co\u00f1os mutuamente. Me coloque detr\u00e1s de Bel\u00e9n y comenc\u00e9 a frotar mi polla en su vagina, haciendo que la lengua de Lara tambi\u00e9n me la lamiese, y en cuanto not\u00e9 que Bel\u00e9n estaba bastante h\u00fameda, se la met\u00ed dentro. Su co\u00f1o me acogi\u00f3 dentro c\u00e1lidamente.<\/p>\n<p>Vi como Pablo, que llevaba todo este tiempo, recibiendo una mamada de su mujer, que alternaba la polla de su hombre con el co\u00f1o de mi mujer, se retiraba y se acomodaba, para penetrar vaginalmente a Lara. Separ\u00f3 las piernas de esta, levanto un poco su pelvis acomodando sus muslos sobre los suyos, y vi como hund\u00eda lentamente todo ese pedazo de carne, en la vagina que hasta hace unas horas, solo hab\u00eda probado yo. Me retir\u00e9 un poco de Bel\u00e9n para ver la cara de mi mujer, que abri\u00f3 los ojos, y al ver mi polla delante suyo, la tomo con las manos y se la meti\u00f3 en la boca, estaba fuera de s\u00ed.<\/p>\n<p>Pablo comenz\u00f3 a bombear dentro suyo y cada envite hacia que mi mamada fuera cada vez m\u00e1s profunda, llegando a provocarle alguna arcada. Deje la boca de mi mujer para volver al co\u00f1ito que tantas pajas me hab\u00eda sacado, pensando en c\u00f3mo ser\u00eda. Y all\u00ed lo ten\u00eda a mi completo servicio, empapado, latente, esperando que me lo follara. Lentamente, volv\u00ed a meter mi miembro, hasta el fondo, deleit\u00e1ndome con cada cent\u00edmetro, mientras Lara volv\u00eda a chupar y lamer con avidez el co\u00f1o de Bel\u00e9n, y tambi\u00e9n mis bolas y polla cuando la sacaba, impregnada de los flujos de nuestra amiga, que parec\u00eda que no iba a tardar mucho en correrse. Un par de minutos despu\u00e9s, as\u00ed lo anunciaba<\/p>\n<p>-\u00a1Aaaah! \u00a1Me corro, me corro, aaah!<\/p>\n<p>Seg\u00fan sacaba mi polla de su interior, un potente chorro transparente de flujo impacto en mi pelvis, arrollando todo sobre la cara de Lara, que ten\u00eda la cara desencajada del placer que Pablo y Bel\u00e9n le ofician simult\u00e1neamente<\/p>\n<p>-Yo tambi\u00e9n me corro, seguir, seguir \u00a1aaah!<\/p>\n<p>Me qued\u00e9 vi\u00e9ndola correrse con los envites de Pablo, que met\u00eda toda su polla hasta el fondo de mi mujer mientras la suya lam\u00eda con avidez su cl\u00edtoris. Le arrancaron un tremendo orgasmo entre los dos. Sin perder tiempo, Bel\u00e9n tom\u00f3 un bote de lubricante, y se lo pas\u00f3 a su marido, que se lo puso en el culo, metiendo primero un dedo, luego dos, hasta que este empez\u00f3 a dilatar. Pablo se tumbo en el suelo, y Bel\u00e9n se puso sobre el, meti\u00e9ndose todo su miembro en el co\u00f1o. Se ech\u00f3 sobre su torso, poniendo el culo en pompa y me dijo:<\/p>\n<p>-Ven, m\u00e9temela, quiero que me folleis los dos<\/p>\n<p>Obedec\u00ed sin pensarlo, el culo que tanto hab\u00eda imaginado bajo las mallas, estaba lubricado y abierto esperando que me lo follara. Separ\u00e9 un poco aquel impresionante par de nalgas, acomod\u00e9 mi prepucio, y comenc\u00e9 a met\u00e9rselo dentro. Entr\u00f3 sin demasiado esfuerzo, a pesar de que tengo un di\u00e1metro bastante considerable, aunque no el largo de la de Pablo, que pod\u00eda ser unos 8 cm mayor que la m\u00eda. Pablo indic\u00f3 a Lara que se aproximara y se acomodara en su cara, as\u00ed mientras los dos nos follabamos a Bel\u00e9n, el, la deleitaba con un delicioso cunnilingus.<\/p>\n<p>Yo estaba a mil, y no tardar\u00eda en correrme. La escena era excitante al m\u00e1ximo, y lo prieto del culo que me estaba follando, as\u00ed como sentir dentro la otra polla a trav\u00e9s de la fina pared de piel que las separaba, daba un placer indescriptible. Tome las dos tetas de Bel\u00e9n con mis manos, pellizcando y retorciendo sus pezones. Pablo simplemente se dejaba llevar por el ritmo que yo impon\u00eda, mientras el tambi\u00e9n jugueteaba con las tetas de Lara. Bel\u00e9n no tard\u00f3 en exclamar:<\/p>\n<p>-\u00a1Me vais a romper hijos de puta, aahh! \u00a1Que placer, seguir as\u00ed, seguir!<\/p>\n<p>-\u00a1Ahhhh!<\/p>\n<p>Tras correrse se quedo exhausta, y Pablo dijo:<\/p>\n<p>-Quiero terminar dentro de ti, mirando a Lara<\/p>\n<p>-Por supuesto. Follarme tambi\u00e9n los dos<\/p>\n<p>Volvimos a acomodarnos, esta vez yo abajo. Lara me cabalgo sin esfuerzo, estaba empapada. Pablo se deleito lubricando su ano y dilatando su esf\u00ednter, con lubricante abundante y sus dedos, preparando el estrecho y poco usado culo de mi mujer para albergar el tama\u00f1o de su imponente miembro. Cuando crey\u00f3 que pod\u00eda estar, cogi\u00f3 a Lara por la cadera, esta se inclin\u00f3 sobre m\u00ed, como hab\u00eda visto hacer a Bel\u00e9n, y Pablo se dispuso a penetrarla analmente. Le cost\u00f3 pasar el glande, mi mujer ten\u00eda una mueca de dolor en la cara.<\/p>\n<p>Para aliviar un poco intente moverme dentro de ella para darle algo de placer. Bel\u00e9n se acerc\u00f3 tambi\u00e9n, puso lubricante en su mano, la deslizo entre nosotros y sent\u00ed como comenzaba a estimularle el cl\u00edtoris. Lara entonces comenz\u00f3 a jadear y Pablo por detr\u00e1s, y poco a poco comenz\u00f3 a moverse. Un par de minutos despu\u00e9s, la mueca de dolor se convirti\u00f3 en cara de placer y lujuria. Levante mis manos para juguetear con sus hermosas tetas. Pablo anuncio que no pod\u00eda mas:<\/p>\n<p>-\u00a1Me voy a correr, que placer, me voy a correr! Tenso su cuerpo, y descarg\u00f3 todo su semen dentro del culo de Lara. La cara de placer de mi mujer era indescriptible, y casi al un\u00edsono, comenzamos a jadear los dos, para tener un gran orgasmo simult\u00e1neo.<\/p>\n<p>-\u00a1Joder si, siii, siii, me corro otra vez, si, siii!<\/p>\n<p>-\u00a1Yo tambi\u00e9n, ahhh, ahhhh!<\/p>\n<p>Pablo y yo segu\u00edamos dentro de Lara, que yac\u00eda sobre mi pecho, terminando de descargar, con leves espasmos, los \u00faltimos restos de nuestra hombr\u00eda. Cuando por fin se retiro, esta se hizo a un lado y yo me levante. Estaba cubierta de sudor, y el semen sal\u00eda de sus dos agujeros abundantemente, mezcl\u00e1ndose con sus propios fluidos. Bel\u00e9n, que estaba tumbada, se arrodillo frente a nosotros y termino de limpiar nuestras pollas con la boca. Nos tumbamos alrededor de Lara y nos dormimos, completamente ajenos a la embarcaci\u00f3n que ha escasos 50 metros hab\u00eda fondeado a babor de la nuestra. \u00bfEstar\u00edan pescando? \u00bfO habr\u00edan visto todo el espect\u00e1culo?<\/p>\n<p>Continuar\u00e1.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_62456\" class=\"pvc_stats total_only  \" data-element-id=\"62456\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 10<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>Volvimos a acomodarnos, esta vez yo abajo. Lara me cabalgo sin esfuerzo, estaba empapada. Pablo se deleit\u00f3 lubricando su ano y dilatando su esf\u00ednter, con lubricante abundante y sus dedos, preparando el estrecho y poco usado culo de mi mujer para albergar el tama\u00f1o de su imponente miembro. Cuando crey\u00f3 que pod\u00eda estar, cogi\u00f3 a Lara por la cadera, esta<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_62456\" class=\"pvc_stats total_only  \" data-element-id=\"62456\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":20282,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-62456","post","type-post","status-publish","format-standard","category-intercambios"],"a3_pvc":{"activated":true,"total_views":10646,"today_views":1},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/62456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/20282"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=62456"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/62456\/revisions"}],"predecessor-version":[{"id":62458,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/62456\/revisions\/62458"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=62456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=62456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=62456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}