{"id":64987,"date":"2026-03-18T00:03:24","date_gmt":"2026-03-17T23:03:24","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=64987"},"modified":"2026-03-17T12:29:20","modified_gmt":"2026-03-17T11:29:20","slug":"7641-las-vacaciones-de-mi-hijo-en-casa-de-su-abuela-2","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/7641-las-vacaciones-de-mi-hijo-en-casa-de-su-abuela-2\/","title":{"rendered":"Las vacaciones de mi hijo en casa de su abuela (2\/2)"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"64987\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">51<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Hola a todos, soy Manuela, esta es la segunda parte de la historia de las vacaciones de mi hijo en casa de su abuela. Como ya recuerdan yo me tuve que ir de viaje a Madrid por motivos de trabajo y mi hijo pasar\u00eda el resto de las vacaciones en casa de su abuela. Pare entender mejor este relato es necesario haber le\u00eddo el anterior:<\/p>\n<p><a href=\"https:\/\/www.cuentorelatos.com\/archivos\/relato\/6681-las-vacaciones-de-mi-hijo-en-casa-de-su-abuela\/\">Las vacaciones de mi hijo en casa de su abuela (1\/2)<\/a><\/p>\n<p>\u2014Abuela antes de nadar voy a jugar un poco a la play en la habitaci\u00f3n si no te importa.<\/p>\n<p>\u2014Claro hijo, haz lo que quieras, cuando vayas a nadar, av\u00edsame y si he acabado de preparar la comida voy contigo.<\/p>\n<p>\u2014Vale.<\/p>\n<p>As\u00ed pues, mi hijo se fue a jugar a la consola y mi madre a hacer las tareas cuando minutos m\u00e1s tarde llego Pili la vecina.<\/p>\n<p>\u2014Pens\u00e9 que estar\u00edais en la piscina, \u00bfo es que era una broma lo de tu nieto?<\/p>\n<p>\u2014Habla despacio que tengo una idea. Ven conmigo a la cocina y te cuento. No era ninguna broma y te lo voy a demostrar. \u00c9l no sabe que estas aqu\u00ed, se ir\u00e1 a nadar de un momento a otro, ahora est\u00e1 jugando, lo \u00fanico que tienes que hacer es desnudarte y meterte conmigo desnuda en la piscina.<\/p>\n<p>\u2014\u00a1\u00bfComo?! \u00a1\u00bfDesnuda?! Ni loca mujer, eso es demasiado, solo he venido a comprobar si era real.<\/p>\n<p>\u2014Jajaja el problema es que cuando lo veas vas a querer probar.<\/p>\n<p>Antes de que Pili pudiese responder Dani grit\u00f3:<\/p>\n<p>\u2014\u00a1Abuela! Me voy a nadar un rato \u00bfhas acabado?<\/p>\n<p>\u2014\u00a1No me queda mucho! En unos minutos voy, puedes ir ya que luego voy.<\/p>\n<p>As\u00ed pues, mi hijo Dani se meti\u00f3 en la piscina desnudo, con su miembro fl\u00e1cido colgando y mi madre y su vecina Pili se fueron a la habitaci\u00f3n a verle detr\u00e1s de la ventana.<\/p>\n<p>\u2014Dios, mujer, s\u00ed que lo tiene grande.<\/p>\n<p>\u2014Pues espera que se le pare, ahora solo esta fl\u00e1cido.<\/p>\n<p>\u2014\u00a1\u00bfDe verdad?!<\/p>\n<p>\u2014\u00a1Claro! Yo no te obligo a nada, pero si quieres probar este es el plan a seguir, nos metemos desnudas y yo hago el resto.<\/p>\n<p>\u2014Ufff no s\u00e9, tengo ganas, pero no quiero que lo sepa mi marido\u2026 A ver si nos va a ver alguien.<\/p>\n<p>\u2014Tranquila mujer, empezamos ah\u00ed y el resto lo hacemos dentro as\u00ed nadie te ve ni te escucha \u00bfte parece bien?<\/p>\n<p>\u2014\u00bfY mi marido?<\/p>\n<p>\u2014Nadie se lo va a decir a tu marido tranquila.<\/p>\n<p>As\u00ed pues, mi madre y la se\u00f1ora Pili se desnudaron y entraron en la piscina ante el asombro de mi hijo Dani. Ya sab\u00e9is como es mi madre f\u00edsicamente, mantiene un buen cuerpo, con alg\u00fan que otro kilito de m\u00e1s, pero sin llegar a estar rellenita y con dos pechos y trasero tremendos. Pili ten\u00eda los pechos m\u00e1s peque\u00f1os y ca\u00eddos, pero ten\u00eda un trasero muy grande. Al ver la cara de asombro de mi hijo, mi madre dijo:<\/p>\n<p>\u2014Daniel no te importa que mi vecina se ba\u00f1e con nosotros \u00bfverdad? Es que su piscina tiene un problema y hace mucho calor as\u00ed que quer\u00eda refrescarse.<\/p>\n<p>\u2014Eeeeh no, no claro que no por m\u00ed no hay ning\u00fan problema, si quer\u00e9is me puedo ir y dejaros solas<\/p>\n<p>\u2014No no qu\u00e9date, si no nos molestas. Adem\u00e1s, hace calor, mejor estar dentro del agua.<\/p>\n<p>Mi madre se alej\u00f3 un poco y se puso a hablar con Pili suavemente:<\/p>\n<p>\u2014S\u00edgueme el juego<\/p>\n<p>\u2014\u00bfDe que hablas?<\/p>\n<p>\u2014Tu solo s\u00edgueme el juego.<\/p>\n<p>\u2014Vale.<\/p>\n<p>\u2014\u00a1Daniel! Nos aburrimos, t\u00fa que eres joven \u00bfconoces alg\u00fan juego que se haga en la piscina?<\/p>\n<p>\u2014\u00bfUn juego? Bueno, se puede jugar con una pelota, pero no hay. Tambi\u00e9n est\u00e1 el Marco Polo, el juego al que jugamos ayer, como el escondite, pero en el agua y con los ojos cerrados.<\/p>\n<p>\u2014\u00a1Ah s\u00ed! \u00a1Se me olvidaba ese juego! Bueno pues jugamos a ese entonces, \u00bfqui\u00e9n quiere empezar?<\/p>\n<p>Nadie respond\u00eda, los dos estaban cortados por la timidez, as\u00ed que mi madre tom\u00f3 la iniciativa y dijo:<\/p>\n<p>\u2014Bueno, est\u00e1 bien empiezo a contar yo, voy a cerrar los ojos.<\/p>\n<p>As\u00ed pues, mi hijo y Pili se pusieron cada uno en una esquina de la piscina y esperaron a que mi madre los encontrara. La primera persona a la que toc\u00f3 mi madre fue mi hijo Dani, as\u00ed que esa vez le tocar\u00eda a \u00e9l. Cerr\u00f3 los ojos y se dispuso a buscar a las dos mujeres, lo primero que toco fue un brazo, luego sigui\u00f3 por el brazo hasta llegar a los pechos y casi sin querer los toc\u00f3, ah\u00ed le parecieron peque\u00f1os as\u00ed que ya sab\u00eda que no era su abuela, sino que era Pili la vecina.<\/p>\n<p>Al saber que estaba tocando los pechos de Pili por primera vez, mi hijo empez\u00f3 a tener una erecci\u00f3n y esos 18 cm pronto se convirtieron en 26. Pili no se dio cuenta de la erecci\u00f3n, pero era su turno de cerrar los ojos y as\u00ed lo hizo para empezar a buscar a cualquiera de los dos, iba por el agua poco a poco con miedo de chocar con el borde de la piscina cuando sinti\u00f3 algo duro chocando contra su barriga.<\/p>\n<p>\u2014Jajaja Concha no vale tocar, te tengo que tocar yo a ti no t\u00fa a m\u00ed que si no es muy f\u00e1cil. Dijo agarrando lo que pens\u00f3 que era un brazo, pero al ver que era mucho m\u00e1s fino que un brazo abri\u00f3 los ojos y se encontr\u00f3 con el pene de mi hijo en las manos. \u00a1Uy perdona hijo no sab\u00eda que eras t\u00fa!<\/p>\n<p>\u2014Eeeeh no pasa nada es el juego.<\/p>\n<p>\u2014Dani te propongo una cosa \u2014interrumpi\u00f3 mi madre\u2014 Pero vamos dentro as\u00ed lo hablamos tranquilamente.<\/p>\n<p>Entraron dentro de la casa y mi madre continu\u00f3:<\/p>\n<p>\u2014\u00bfTe gust\u00f3 el regalo que te hice ayer? \u2014Dijo refiri\u00e9ndose al anal.<\/p>\n<p>\u2014Ehhh claro que me gust\u00f3 \u2014dijo mi hijo ruborizado.<\/p>\n<p>\u2014Bueno pues entonces te propongo volver a hacerlo esta noche si antes le ense\u00f1as a Pili lo que es una buena polla.<\/p>\n<p>\u2014Pero abuela yo\u2026 esto\u2026 no s\u00e9 igual ella no quiere.<\/p>\n<p>\u2014Ella se muere de ganas de hacerlo \u00bfverdad Pili?<\/p>\n<p>\u2014Mujer no me digas esas cosas delante del chico que me ruborizo.<\/p>\n<p>\u2014Lo ves, ella tambi\u00e9n quiere, as\u00ed que si no te importa ayuda a Pili a calmar ese apetito que tiene.<\/p>\n<p>Al ver que ninguno se mov\u00eda una vez m\u00e1s mi madre volvi\u00f3 a tomar la iniciativa:<\/p>\n<p>\u2014Mira Pili ven conmigo, esto se hace as\u00ed, mira \u2014dijo poni\u00e9ndose de rodillas y empezando a lamer el m\u00e1stil de mi hijo.<\/p>\n<p>Pili dej\u00f3 de lado el miedo y la verg\u00fcenza y se arrodill\u00f3 y empez\u00f3 a hacerle una buena mamada a mi hijo.<\/p>\n<p>\u2014Vamos a la cama que estaremos m\u00e1s c\u00f3modos.<\/p>\n<p>Ya en la cama y con mi hijo tumbado, Pili segu\u00eda haci\u00e9ndole una mamada, mientras mi madre se sent\u00f3 en su cara. Despu\u00e9s de varios minutos de sexo oral Pili dijo:<\/p>\n<p>\u2014Esto es genial pero no me entra ni la mitad por la boca jajaja. A ver si me entra en otra parte \u2014dijo Pili sent\u00e1ndose poco a poco sobre el miembro de mi hijo totalmente erecto.<\/p>\n<p>\u2014Aaaah uuuuf espera poco a poco que no estoy acostumbrada a algo as\u00ed.<\/p>\n<p>\u2014Lo ves c\u00f3mo te gusta, \u00a1te lo dije!<\/p>\n<p>\u2014Esto es geniaaal uuuuf.<\/p>\n<p>No tard\u00f3 mucho en llegar el primer orgasmo de Pili que se estaba volviendo loca con ese miembro. Cambiaron de posici\u00f3n y esta vez fue mi madre la que estaba siendo penetrada por mi hijo mientras mi hijo le hac\u00eda oral a Pili. Se volvi\u00f3 a correr Pili y minutos m\u00e1s tarde mi madre mientras mi hijo segu\u00eda aun con todas las fuerzas del mundo.<\/p>\n<p>\u2014Ufff Concha yo no estoy acostumbrada a tanto, ya no puedo m\u00e1s estoy cansad\u00edsima.<\/p>\n<p>\u2014La verdad es que yo tambi\u00e9n estoy cansad\u00edsima, con el sol, la piscina y esto, que llevamos casi una hora y adem\u00e1s quiero guardar energ\u00edas para esta noche. \u00bfQu\u00e9 te parece si le hacemos acabar con la boca?<\/p>\n<p>\u2014Claro, \u00e9l tambi\u00e9n tiene que acabar.<\/p>\n<p>\u2014Venga, pero te aviso, prep\u00e1rate para llevarte una buena ducha de leche.<\/p>\n<p>\u2014Jajaja normal, con el tama\u00f1o que tiene es normal que se corra mucho. Bueno vamos al lio.<\/p>\n<p>Se pusieron a lamer las dos juntas el tronco de mi hijo, alternando cabeza, base y huevos, le pusieron el pene entre los senos y le masturbaron un largo rato cuando se estaba acercando al cl\u00edmax lo dijo.<\/p>\n<p>\u2014\u00bfPili quieres probar un poco de leche bien rica?<\/p>\n<p>\u2014Uy que va, yo nunca he hecho eso.<\/p>\n<p>\u2014Te aseguro que es de lo mejor que vas a probar en a\u00f1os.<\/p>\n<p>\u2014Bueno igual un poquito, pero muy poquito.<\/p>\n<p>\u2014\u00a1Aaaah ah\u00ed va!<\/p>\n<p>Mi hijo se corri\u00f3 llen\u00e1ndole la cara a Pili y la boca a mi madre.<\/p>\n<p>\u2014Vamos toma, prueba un poco \u2014dijo mi madre d\u00e1ndole un trozo de semen que hab\u00eda ca\u00eddo en sus pechos.<\/p>\n<p>\u2014Mmmmm pues no esta tan mal<\/p>\n<p>\u2014Te acabaras acostumbrando al sabor y no podr\u00e1s vivir sin el jajaja.<\/p>\n<p>\u2014Ufff hijo pues s\u00ed que te corres mucho. Por cierto, una pregunta, ahora que hay confianza entre nosotros, \u00bfqu\u00e9 es eso de la sorpresa de esta noche?<\/p>\n<p>\u2014Pues que me va a hacer anal, como ayer.<\/p>\n<p>\u2014Hacer \u00bfqu\u00e9?<\/p>\n<p>\u2014Que me la va a meter por el culo.<\/p>\n<p>\u2014Que dices, \u00a1pero si eso no entra ah\u00ed!!<\/p>\n<p>\u2014Entero, entero, no, pero casi entero y disfruto un mont\u00f3n y \u00e9l tambi\u00e9n.<\/p>\n<p>\u2014Uy pues tienes que hacerme probar eso tambi\u00e9n.<\/p>\n<p>\u2014Pues si quieres venir esta noche eres la bienvenida.<\/p>\n<p>\u2014Lo siento, pero esta noche no puedo, viene mi hijo y su familia a casa a cenar y se quedaran a dormir. Pero ma\u00f1ana si se van pronto vengo y lo hacemos si no os molesta.<\/p>\n<p>\u2014\u00a1\u00bfC\u00f3mo nos va a molestar?! Daniel est\u00e1 encantado de poder ayudar \u00bfverdad hijo?<\/p>\n<p>\u2014Si abuela, yo aqu\u00ed para lo que haga falta.<\/p>\n<p>\u2014Jajaja eres un cielo. Bueno pues me voy a limpiar, vestirme y me voy que ya he tardado bastante. Si puedo vuelvo ma\u00f1ana.<\/p>\n<p>\u2014\u00a1Aqu\u00ed estaremos!<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_64987\" class=\"pvc_stats total_only  \" data-element-id=\"64987\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>No tard\u00f3 mucho en llegar el primer orgasmo de Pili que se estaba volviendo loca con ese miembro. Cambiaron de posici\u00f3n y esta vez fue mi madre la que estaba siendo penetrada por mi hijo mientras mi hijo le hac\u00eda oral a Pili. Se volvi\u00f3 a correr Pili y minutos m\u00e1s tarde mi madre mientras mi hijo segu\u00eda aun con<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_64987\" class=\"pvc_stats total_only  \" data-element-id=\"64987\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":30514,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-64987","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":true,"total_views":16112,"today_views":9},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/64987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/30514"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=64987"}],"version-history":[{"count":1,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/64987\/revisions"}],"predecessor-version":[{"id":64988,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/64987\/revisions\/64988"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=64987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=64987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=64987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}