{"id":65053,"date":"2026-03-23T00:05:06","date_gmt":"2026-03-22T23:05:06","guid":{"rendered":"https:\/\/www.cuentorelatos.com\/archivos\/?p=65053"},"modified":"2026-03-22T20:24:36","modified_gmt":"2026-03-22T19:24:36","slug":"perdido-por-mama-3","status":"publish","type":"post","link":"https:\/\/www.cuentorelatos.com\/archivos\/relato\/perdido-por-mama-3\/","title":{"rendered":"Perdido por mam\u00e1 (3)"},"content":{"rendered":"<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Like\" data-post-id=\"65053\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\" style=\"border: 1px solid #d5d5d5;padding: 10px 15px;\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n            \t\t<span class=\"pld-like-count-wrap pld-count-wrap\">35<\/span>\r\n    <\/a>\r\n    \r\n<\/div><\/div><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 12<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span><p>Me despert\u00f3 el timbrazo del m\u00f3vil, como cada ma\u00f1ana de lunes. A pesar de que eran las siete y media, baj\u00e9 animado a la cocina, mi madre estaba all\u00ed, tomando un caf\u00e9. La cog\u00ed por detr\u00e1s nada m\u00e1s verla, ella me apart\u00f3 un segundo antes de que mi padre entrase en la cocina, anud\u00e1ndose la corbata.<\/p>\n<p>El desayuno fue fugaz, y apenas nadie habl\u00f3, mi madre fue la primera en irse, apenas dos minutos despu\u00e9s mi padre, yo recog\u00ed mis cosas y me dirig\u00ed a la parada de las cercan\u00edas para llegar a la facultad. Me hab\u00eda imaginado que en cuanto lleg\u00e1semos a casa mam\u00e1 y yo podr\u00edamos dar rienda suelta a todos nuestros deseos, pero mientras el tren traqueteaba en las v\u00edas me di cuenta que la rutina iba a ser un escollo dif\u00edcil de romper.<\/p>\n<p>Antes de las ocho de las ma\u00f1ana todos hab\u00edamos salido de casa, mi madre sol\u00eda ser la primera. Despu\u00e9s, yo estaba en la facultad hasta las tres y media, com\u00eda all\u00ed y muchas tardes me quedaba en la biblioteca. Tanto daba que pasase la tarde en casa, pues mi madre no llegaba hasta pasadas las seis, y m\u00e1s o menos en media hora aparec\u00eda mi padre.<\/p>\n<p>El mi\u00e9rcoles yo ya me sub\u00eda por las paredes, apenas hab\u00eda robado un par de magreos y besos a mi madre. Ella se dio cuenta de mi situaci\u00f3n y as\u00ed esa ma\u00f1ana, antes de que sonase el despertador ella me despert\u00f3 con una caricia.<\/p>\n<p>\u2013\u00bfMam\u00e1?<\/p>\n<p>Entre abr\u00ed mis so\u00f1olientos ojos y la vi, llevaba una camiseta de tirantes azul muy clara, las tiras del sujetador se liaban con las de la camiseta, de cintura para abajo solo vest\u00eda unas braguitas, algo m\u00e1s largas que las de d\u00edas pasados, la cubr\u00edan m\u00e1s de media nalga, eran bonitas de color amarillo.<\/p>\n<p>\u2013\u00bfQu\u00e9 pasa, me he dormido? Me incorpor\u00e9 y frot\u00e9 los ojos, busqu\u00e9, a tientas, el m\u00f3vil sobre la mesilla, para mirar la hora, eran las seis.<\/p>\n<p>\u2013No, tranquilo. Me quit\u00f3 el tel\u00e9fono de la mano y lo dej\u00f3 de nuevo en su sitio.<\/p>\n<p>\u2013Ya que los dos \u00faltimos d\u00edas no hemos tenido un momento para nosotros, se me ha ocurrido robarle algo de tiempo al d\u00eda, \u00bfNo te importar\u00e1 el madrug\u00f3n? Se inclin\u00f3 sobre m\u00ed y me bes\u00f3.<\/p>\n<p>\u2013Para nada. Contest\u00e9 cuando sus labios me dejaron, ya estaba casi despierto del todo, aunque pens\u00e9 que tal vez era todo un sue\u00f1o.<\/p>\n<p>\u2013\u00bfPap\u00e1?<\/p>\n<p>\u2013Tu padre aun duerme, as\u00ed que no podemos hacer ruido. Me quit\u00f3 de encima la ropa de cama. Vio el bulto en mis pantalones de pijama.<\/p>\n<p>\u2013No soy tan buena, as\u00ed que imagino que te levantas siempre as\u00ed.<\/p>\n<p>\u2013Bueno, ya que estamos aprovech\u00e9moslo.<\/p>\n<p>Mis manos empezaron a buscar su cuerpo, le quit\u00e9 la camiseta y ella qued\u00f3 en sujetador, era amarillo, igual que la tanga.<\/p>\n<p>Ella se subi\u00f3 en la cama, se sent\u00f3 sobre sus rodillas, encima de mis piernas, nos besamos, fue el beso m\u00e1s largo que nos hab\u00edamos dado hasta la fecha. Nuestras lenguas se buscaban, anudaban y separaban, cuando nos separamos casi nos faltaba el aire.<\/p>\n<p>Baj\u00f3 mi pijama un poco, por encima de mis calzoncillos ya asomaba mi polla. Cuando qued\u00f3 libre apunt\u00f3 al techo, mi madre lami\u00f3 su mano derecha y la llev\u00f3 a mi rabo, empez\u00f3 a masturbarme despacio.<\/p>\n<p>\u2013Dime cari\u00f1o, \u00bfc\u00f3mo lo llevas? Me miraba a los ojos desde arriba, ella quedaba por encima de m\u00ed, a pesar de que yo estaba algo incorporado.<\/p>\n<p>\u2013Esto, muy bien. Me encantaba el tacto de su piel, el masaje al que somet\u00eda a mi rabo era puro \u00e9xtasis.<\/p>\n<p>\u2013Me refiero a todo. S\u00e9 que estos d\u00edas no he podido estar contigo todo lo nos hubiese gustado.<\/p>\n<p>Asent\u00ed, si por m\u00ed hubiese sido no habr\u00edamos salido de la cama.<\/p>\n<p>\u2013Pero con el trabajo y tu padre, no cre\u00ed que fuese a ser tan dif\u00edcil la verdad. Pero no te preocupes, me voy a asegurar de que lo pasemos tan bien como te promet\u00ed.<\/p>\n<p>\u2013No me importa madrugar todos los d\u00edas mam\u00e1. La hice re\u00edr.<\/p>\n<p>\u2013No creo que sea necesario, pero hoy le sacaremos partido.<\/p>\n<p>Se ech\u00f3 hacia atr\u00e1s y casi a c\u00e1mara lenta se dobl\u00f3 sobre m\u00ed, hasta que su boca cay\u00f3 sobre mi polla. Cerr\u00f3 sus labios justo antes del primer contacto, con lo que este fue un beso, despu\u00e9s su lengua rode\u00f3 la punta en un r\u00e1pido movimiento.<\/p>\n<p>Yo me agarraba al coch\u00f3n con fuerza cuando ella ya tragaba mi rabo. Mi madre llevaba su melena recogida en una coleta, no pude resistirme a echar mano de la cola de caballo mientras su cabeza sub\u00eda y bajaba.<\/p>\n<p>No le tir\u00e9 del pelo, ni aument\u00e9 el ritmo de la felaci\u00f3n, pues hasta el momento mi madre no hab\u00eda dado signos de que le gustase el sexo duro y francamente, yo no quer\u00eda ni por asomo hacerle da\u00f1o involuntariamente.<\/p>\n<p>Sin embargo, s\u00ed la tuve que dar un tironcito para avisarla de que estaba a punto de correrme, ella detuvo la mamada, me mir\u00f3.<\/p>\n<p>\u2013\u00bfPuedes aguantar un poco m\u00e1s?<\/p>\n<p>Su mano izquierda llevaba un rato dentro de sus bragas, pero no me percat\u00e9 de que jugaba con sigo misma hasta que volvi\u00f3 a incorporarse.<\/p>\n<p>\u2013Claro, vamos. Hice adem\u00e1n de levantarme, ella me detuvo.<\/p>\n<p>\u2013Yo encima mi ni\u00f1o. Se deshizo de la tanga, las ech\u00e9 mano, me las llev\u00e9 a la nariz y aspir\u00e9 su aroma.<\/p>\n<p>\u2013Que guarro eres.<\/p>\n<p>Se puso en cuclillas un segundo, agarrando mi polla la dirigi\u00f3, despu\u00e9s se dej\u00f3 caer lentamente. La penetraci\u00f3n fue m\u00e1s profunda que en nuestra primera vez, en el ba\u00f1o de casa de la abuela, o al menos me dio esa sensaci\u00f3n.<\/p>\n<p>Ella se coloc\u00f3 de nuevo de rodillas, esa postura le era m\u00e1s c\u00f3moda. Mi madre busc\u00f3 mis manos, yo intentaba quitarle el sujetador, las llev\u00f3 a sus caderas.<\/p>\n<p>Empez\u00f3 a moverse, ligera, con una mezcla de adelante atr\u00e1s y arriba abajo. Era maravilloso tener el contoneo hipn\u00f3tico de mi madre sobre m\u00ed, acarici\u00e9 todo su cuerpo.<\/p>\n<p>Ella tuvo el control todo el tiempo, marc\u00f3 el ritmo. Cuando estuvo cerca del orgasmo se movi\u00f3 m\u00e1s r\u00e1pida, daba ligeros botes sobre m\u00ed, su duro culo sonaba ligeramente al chocar contra mis piernas.<\/p>\n<p>Yo me vine primero, mi madre aprovech\u00f3 mi erecci\u00f3n hasta el final, ella sigui\u00f3 movi\u00e9ndose hasta llegar al orgasmo, esta vez hizo m\u00e1s ruido que en casa de la abuela, aun con esas no creo que mi padre nos oyese.<\/p>\n<p>\u2013Muy bien mi ni\u00f1o. Se dobl\u00f3 sobre m\u00ed y me bes\u00f3.<\/p>\n<p>\u2013Me voy a duchar que tengo que se me hace tarde. Me dio un par de palmaditas en el pecho y se levant\u00f3.<\/p>\n<p>\u2013\u00bfNos duchamos juntos? Pregunt\u00e9 sonriente.<\/p>\n<p>\u2013Otro d\u00eda cari\u00f1o.<\/p>\n<p>Se levant\u00f3 y se puso la camiseta, se la estir\u00f3 hasta que le cubri\u00f3 medio culo y su concha, lleno de mi leche. Sali\u00f3 de mi habitaci\u00f3n con cuidado, mirando por si hab\u00eda alguien.<\/p>\n<p>Se dej\u00f3 la tanga en mi cuarto, las guard\u00e9 en un caj\u00f3n de mi escritorio, me pareci\u00f3 gracioso y excitante tener esa prenda de ella guardada para mi uso y disfrute, esa misma tarde cay\u00f3 una paja con ellas.<\/p>\n<p>A veces encontraba m\u00e1s placer en el juego que en la acci\u00f3n, si bien mi madre aun me ten\u00eda reservadas unas cuantas sorpresas.<\/p>\n<p>Mi padre ese d\u00eda fue el \u00faltimo en despertarse, no se hab\u00eda enterado de nada. No me preocupaba mucho por \u00e9l, m\u00e1s bien prefer\u00eda alejar todo pensamiento de mi mente, lo que hac\u00eda con mi madre era un traici\u00f3n directa a \u00e9l, pero no quer\u00eda parar.<\/p>\n<p>Mi padre, por cierto, se llama Juan Carlos, es un buen tipo, abogado de carrera, trabaja en una empresa multinacional, en los servicios jur\u00eddicos.<\/p>\n<p>El resto del d\u00eda fue una repetici\u00f3n de la rutina habitual, todos coincidimos en casa para la cena.<\/p>\n<p>Mi madre hab\u00eda preparado algo, y yo con la escusa de ayudarla, aprovechando que mi padre ten\u00eda que revisar unas cosas del trabajo, estuve incordi\u00e1ndola cari\u00f1osamente.<\/p>\n<p>Me sent\u00e9 a la mesa con un buen calent\u00f3n, mi madre en frente, ella tambi\u00e9n estaba animada, pues su pie descalzo empez\u00f3 pronto a subirme por la pierna, le di franco acceso a mi paquete para que me lo sobase.<\/p>\n<p>Mi padre tuvo que subir la voz para que le atendi\u00e9semos, nos hab\u00edamos abstra\u00eddo por completo.<\/p>\n<p>\u2013Pues eso, tengo que irme a Londres ma\u00f1ana. Me hab\u00eda perdido el principio de la conversaci\u00f3n.<\/p>\n<p>\u2013\u00bfMa\u00f1ana ya? Mi madre r\u00e1pidamente volvi\u00f3 su atenci\u00f3n, y su cabeza a mi padre, su pie segu\u00eda sobre m\u00ed.<\/p>\n<p>\u2013No queda otra, Pel\u00e1ez no puede as\u00ed que me tendr\u00e9 que hacerme cargo yo.<\/p>\n<p>\u2013Que malo es ser jefe. Coment\u00e9 sarc\u00e1stico.<\/p>\n<p>\u2013Lo malo es ser jefe y tener un jefe, hijo. Me replic\u00f3 mi padre.<\/p>\n<p>\u2013El caso es que ya que me pasar\u00e9 all\u00ed hasta el viernes, siento que sea tan apresurado pero no queda otra, ma\u00f1ana me acercas al aeropuerto y te llevas el coche. Me dijo a m\u00ed, asent\u00ed.<\/p>\n<p>\u2013Pod\u00edas venir y pasamos el fin de semana en Londres, cari\u00f1o. Extendi\u00f3 su mano hasta coger la de mi madre, me dio un ligero ataque de celos, ella lo not\u00f3, o esa fue mi impresi\u00f3n.<\/p>\n<p>\u2013No lo s\u00e9, yo tambi\u00e9n tengo muchas cosas que hacer.<\/p>\n<p>Se libr\u00f3 de \u00e9l y me mir\u00f3, su mirada tranquilizo el repentino gesto de enfado que hab\u00eda asomado a mi cara. Mi padre pareci\u00f3 algo deca\u00eddo el resto de la cena, yo por el contrario estaba feliz, sin \u00e9l en casa podr\u00edamos por fin dar rienda suelta a todas nuestras fantas\u00edas mi madre y yo.<\/p>\n<p>Si bien yo no fantaseaba m\u00e1s all\u00e1 de poder acostarme con ella cuando me apeteciese, algo me dec\u00eda que ella ten\u00eda mejores ideas.<\/p>\n<p>A la ma\u00f1ana siguiente mi madre no me hizo ninguna visita, normal, teniendo en cuenta que mi padre estaba levantado temprano. Ten\u00eda listas las cosas, feliz le llev\u00e9 la maleta al coche, me trat\u00e9 de contener, pero lo cierto es que no pod\u00eda evitar estar animado por su partida.<\/p>\n<p>\u00c9l segu\u00eda taciturno, pero no le hice mucho caso. Condujo hasta el aeropuerto y me quit\u00f3 la sonrisa de la cara con una pregunta:<\/p>\n<p>\u2013Mario, cuando me llamaba por mi nombre no era bueno, estoy un poco preocupado\u2026<\/p>\n<p>\u2013Me va bien en clase, bueno podr\u00eda irme mejor pero que apruebo todo seguro. Le cort\u00e9 convencido de que los tiros iban por ah\u00ed, mi padre me exig\u00eda bastante en los estudios.<\/p>\n<p>\u2013No es eso. Es tu madre. Me acojon\u00f3.<\/p>\n<p>\u2013No s\u00e9 c\u00f3mo decir esto, no pod\u00eda saber nada<\/p>\n<p>\u2013El otro d\u00eda cuando fuimos donde la abuela, ella y t\u00fa pasasteis bastante tiempo juntos y\u2026 mierda.<\/p>\n<p>\u2013Nos pill\u00f3 un atasco ma\u00f1anero, me mir\u00f3 a los ojos, me dio miedo.<\/p>\n<p>\u2013\u00bfNotaste algo raro en ella, miraba mucho el m\u00f3vil o habl\u00f3 con alguien? Negu\u00e9.<\/p>\n<p>\u2013Veras me preocupa que ella pueda estar con alguien, \u00bfSabes algo? Lo qu\u00e9 sea.<\/p>\n<p>Me qued\u00e9 unos largos segundos en silencio, relaj\u00e1ndome del susto inicial, y pensando una respuesta. Por supuesto iba a mentirle, pero quer\u00eda hacerlo de la mejor manera posible.<\/p>\n<p>\u2013No te preocupes pap\u00e1, mam\u00e1 te quiere. Mir\u00e9 a la fila de coches que empezaba a moverse.<\/p>\n<p>\u2013Ella no est\u00e1 por ah\u00ed con cualquiera. Eso no era mentira del todo.<\/p>\n<p>\u2013Espero que tengas raz\u00f3n. Nos mov\u00edamos otra vez.<\/p>\n<p>\u2013Aun as\u00ed quiero que est\u00e9s atento estos d\u00edas, que ser\u00e1n paranoillas m\u00edas pero te lo agradecer\u00eda. Adem\u00e1s as\u00ed me quedo m\u00e1s tranquilo, cuida de tu madre y bueno, ya sabes.<\/p>\n<p>Asent\u00ed, y con una palmada en el hombro, tranquilizadora, apu\u00f1al\u00e9 a mi padre, me convert\u00ed en Edipo del todo.<\/p>\n<p>Le desped\u00ed en la terminal y conduciendo fui hasta la universidad. Era el \u00fanico de mis colegas sin coche, m\u00e1s que nada porque mis padres consideraban que era una responsabilidad que deb\u00eda ganarme.<\/p>\n<p>Al verme llegar, en la berlina de lujo de mi padre, un amigo aplaudi\u00f3 sarc\u00e1sticamente.<\/p>\n<p>\u2013Como te lo montas, dejas dos y te regalan un cochazo.<\/p>\n<p>Me re\u00ed de la broma de Adri\u00e1n.<\/p>\n<p>\u2013Ya ves, que menos. Sal\u00ed chuleando.<\/p>\n<p>\u2013Es el coche de mi padre. Reconoc\u00ed.<\/p>\n<p>\u2013Imagino. Vamos para adentro.<\/p>\n<p>Le segu\u00ed a un sopor\u00edfero d\u00eda de clase. Se me hizo eterno, a base de mirar el reloj, me mor\u00eda de ganas de volver a casa. Por fin lleg\u00f3 la hora de salir, mis amigos me invitaron a tomar unas ca\u00f1as, rechac\u00e9 la invitaci\u00f3n.<\/p>\n<p>Conduje directo a casa, mi padre me hab\u00eda escrito un par de horas antes para decir que ya hab\u00eda llegado. Me encontr\u00e9 solo en casa, solo y caliente me hice una paja con la tanga de mi madre, esa noche hab\u00edan dormido debajo de mi almohada, aun segu\u00edan ah\u00ed.<\/p>\n<p>Mi madre tard\u00f3 algo m\u00e1s de una hora en llegar, en cuanto entr\u00f3 en casa ca\u00ed sobre ella. Acababa de o\u00edr la puerta, me apresur\u00e9 al piso de abajo, salt\u00e9 las tres \u00faltimas escaleras, podr\u00eda haberlas saltado todas.<\/p>\n<p>La cog\u00ed de la cintura y pr\u00e1cticamente la levant\u00e9. Busqu\u00e9 sus labios, y los encontr\u00e9, junto con su lengua. La dej\u00e9 en el suelo, ella se colg\u00f3 de mi cuello. Nos tiramos un par de minutos comi\u00e9ndonos las bocas como adolescentes. Empec\u00e9 a meter mis manos bajo su ropa, a palpar su cuerpo prieto.<\/p>\n<p>\u2013Deja un poco para luego. Se separ\u00f3 de m\u00ed un segundo.<\/p>\n<p>\u2013Vamos a tom\u00e1rnoslo con calma, que tenemos dos d\u00edas.<\/p>\n<p>\u2013Yo tengo muchas ganas mam\u00e1. Avanc\u00e9 hacia ella.<\/p>\n<p>\u2013Vale, dame un segundo al menos, que necesito respirar. Dej\u00f3 la chaqueta en el perchero.<\/p>\n<p>\u2013Acabo de llegar del trabajo, necesito tomar un peque\u00f1o descanso, me voy a dar un ba\u00f1o y seguimos.<\/p>\n<p>Me dio un pico y subi\u00f3 escaleras arriba. Me lanz\u00f3 una mirada que era pr\u00e1cticamente una invitaci\u00f3n a que la siguiese.<\/p>\n<p>Ascend\u00ed las escaleras detr\u00e1s de ella, entramos al ba\u00f1o principal, all\u00ed estaba la \u00fanica ba\u00f1era de la casa, adem\u00e1s de una ducha de hidromasaje.<\/p>\n<p>Me pidi\u00f3 que la ayudase a desnudarse. Lo primero que hizo fue bajarse de los tacones, nuestras alturas se igualaron, ahora yo quedaba algo por encima. Se empez\u00f3 a desabrochar la blusa, yo solo miraba hasta ese momento.<\/p>\n<p>\u2013Ay\u00fadame con los pantalones.<\/p>\n<p>Me agach\u00e9, y abr\u00ed sus pantalones. Le quedaban apretaditos, como ya dije mi madre era una mujer de pocas curvas, delgada y con aspecto de modelo, pero la ropa que usaba le quedaba siempre entallada, y as\u00ed con un ligero esfuerzo fui dejando sus largas piernas al aire.<\/p>\n<p>Cuando le quedaron arrugados en los tobillos se limit\u00f3 a dar un paso a un lado, ya ten\u00eda la blusa completamente desabrochada, pero aun la llevaba puesta.<\/p>\n<p>\u2013Sigue. Me dijo con voz melosa.<\/p>\n<p>Mis manos subieron acariciando su piel, hasta estar de nuevo a la altura de sus caderas. Llevaba un tanga, negro de hilo, algo me dec\u00eda que lo hab\u00eda escogido para m\u00ed.<\/p>\n<p>Como pude agarr\u00e9 y tir\u00e9, saliv\u00e9 ante la imagen de su concha, esos labios grandes que me encantaban. No me resist\u00ed a darle un beso, muy h\u00famedo.<\/p>\n<p>\u2013No empieces, que solo quiero darme un ba\u00f1o. Ment\u00eda y jugaba conmigo.<\/p>\n<p>\u2013Deja que te limpie yo a lametones.<\/p>\n<p>\u2013No, quiero darme un relajante ba\u00f1o, luego jugamos.<\/p>\n<p>Le encantaba negarme, mantener el control. No importaba mucho lo que dijera, todo aquello era un juego sin fin. Me dio la espalda, la quit\u00e9 la blusa y la bes\u00e9 el cuello.<\/p>\n<p>Solt\u00e9 el sujetador, ella abri\u00f3 el grifo, el agua empez\u00f3 a llenar la ba\u00f1era. Agarr\u00e9 sus pechos, pellizqu\u00e9 sus pezones desde atr\u00e1s.<\/p>\n<p>El agua cog\u00eda nivel, se libr\u00f3 de m\u00ed y meti\u00f3 el pie derecho, con cuidado, probando la temperatura. Deb\u00eda de estar a su gusto, pues al poco entr\u00f3 completamente, en un gr\u00e1cil movimiento, algo exagerado tal vez, se hundi\u00f3.<\/p>\n<p>\u2013\u00bfVas a quedarte ah\u00ed mirando? Me pregunt\u00f3.<\/p>\n<p>\u2013Si puedo. Le respond\u00ed, ten\u00eda una marcada erecci\u00f3n.<\/p>\n<p>\u2013Haz algo mejor, fr\u00f3tame la espalda.<\/p>\n<p>Me tendi\u00f3 la esponja. As\u00ed hice, remang\u00e1ndome, comenc\u00e9 a acariciar su espalda. Trat\u00e9 con cuidado su cuello, haciendo a un lado el pelo que ya se hab\u00eda mojado, tras sumergir la cabeza en el agua. Pas\u00e9 a los hombros que masaje\u00e9 con tanta ma\u00f1a como pude, ella gem\u00eda de gusto levemente.<\/p>\n<p>Baj\u00e9 aun m\u00e1s, y m\u00e1s hasta olvidarme de la esponja y empezar a sentir sus nalgas en mi mano, totalmente sumergida. Mis dedos llegaron a una zona sensible, el agua me llegaba casi al hombro, mi madre estaba levant\u00e1ndose, apoyada en la ba\u00f1era, un tanto para darme acceso all\u00ed.<\/p>\n<p>Confund\u00ed el agujero que buscaba, ella se revolvi\u00f3 un segundo. Me moj\u00f3 la camiseta que llevaba.<\/p>\n<p>\u2013Lo siento cari\u00f1o, pero por ah\u00ed no es.<\/p>\n<p>Me re\u00ed. Empec\u00e9 a desnudarme, en un momento estuve sin ropa.<\/p>\n<p>Ella me miraba con una cara que sab\u00eda me volv\u00eda loco, segu\u00eda siendo mi madre pero el gesto era el de una ni\u00f1a inocente, en su magn\u00edficamente conservado rostro de cuarenta.<\/p>\n<p>Di una patada a las prendas y me agach\u00e9 junto a la ba\u00f1era.<\/p>\n<p>\u2013No se te ocurra meterte, no cabemos.<\/p>\n<p>Hab\u00eda adivinado mis intenciones. Si bien probablemente cab\u00edamos, uno encima del otro, no me met\u00ed. En lugar de eso busqu\u00e9, un peque\u00f1o taburete que sab\u00eda ten\u00eda mi madre para la ducha de hidromasaje.<\/p>\n<p>Lo encontr\u00e9 y lo acerqu\u00e9 a la ba\u00f1era, la postura era perfecta.<\/p>\n<p>Mi madre hab\u00eda cerrado los ojos y se hab\u00eda estirado, ahora si daba la sensaci\u00f3n de disfrutar del ba\u00f1o sin m\u00e1s. De no ser, porque, con disimulo, entreabr\u00eda los ojos para mirarme, la hubiese dejado tranquila.<\/p>\n<p>Pero sab\u00eda que ella quer\u00eda que siguiese, as\u00ed que mi mano volvi\u00f3 a mojarse, esta vez baj\u00e9 por delante, acariciando sus pechos, hasta encontrar su concha.<\/p>\n<p>La calent\u00e9, aun sin meterle los dedos, con golpecitos y caricias, ella ronroneaba sin mirar. Mi anular fue el primer expedicionario en su interior, que estaba tan h\u00famedo como el exterior, el ronroneo subi\u00f3 de volumen.<\/p>\n<p>No empez\u00f3 a gemir hasta que a\u00f1ad\u00ed otro dedo a la penetraci\u00f3n. Entonces imprimi\u00f3 un cadencioso movimiento a sus caderas, acomod\u00e1ndose al juguete\u00f3 de mis dedos.<\/p>\n<p>Mi pulgar acariciaba sus cl\u00edtoris y ella gem\u00eda con m\u00e1s ganas, era la vez que m\u00e1s la hab\u00eda o\u00eddo gozar.<\/p>\n<p>Atrap\u00f3 mi mano por la mu\u00f1eca, dentro del agua, para que no dejase de masturbarla. Tuvo un orgasmo, uno sonoro, el primero, adem\u00e1s durante el cl\u00edmax, para volverme loco, grit\u00f3 mi nombre.<\/p>\n<p>Volvi\u00f3 a abrir los ojos, para mirarme, se fij\u00f3 en mi tremenda erecci\u00f3n.<\/p>\n<p>Sac\u00f3 su mano y me hizo una paja, me corr\u00ed sobre el agua, y en parte sobre su pecho.<\/p>\n<p>\u2013Vete, d\u00e9jame terminar el ba\u00f1o. \u2013Se limpi\u00f3 mi semen con la mano. Con la otra mano me hizo un gesto para que saliese.<\/p>\n<p>Me fui del ba\u00f1o, recogiendo mi ropa antes de salir. La esper\u00e9 en el sal\u00f3n viendo la tele, m\u00e1s bien mir\u00e1ndola sin m\u00e1s. Mi madre apareci\u00f3 por el sal\u00f3n, llevaba el t\u00edpico modelito de andar por casa, una camiseta y unas mallas, me baj\u00f3 un poco el l\u00edvido. Se sent\u00f3 a mi lado, sin decirme nada, estuvo pendiente del concurso previo al telediario.<\/p>\n<p>\u2013En seguida cenamos.<\/p>\n<p>Dijo ella sin apartar los ojos de las noticias que empezaban.<\/p>\n<p>\u2013\u00bfY luego? Pregunt\u00e9 sonriendo como un tonto.<\/p>\n<p>\u2013Luego a dormir. Me contest\u00f3 bromista.<\/p>\n<p>\u2013Vamos a hacerlo, en la vuestra cama, \u00bfVerdad?<\/p>\n<p>\u2013S\u00ed, pero estate un poco tranquilo, que esto es algo especial porque tu padre est\u00e1 fuera, cuando \u00e9l est\u00e9 en casa te vas a tener que aguantar.<\/p>\n<p>\u2013Ya me hab\u00eda aguantado tres d\u00edas y no pod\u00eda m\u00e1s.<\/p>\n<p>\u2013Por cierto. Record\u00e9<\/p>\n<p>\u2013pap\u00e1 me ha dicho que te vigile. Solt\u00e9 como si tal cosa.<\/p>\n<p>\u2013\u00a1\u00bfC\u00f3mo es eso? ! Exclam\u00f3 enfada, no entend\u00ed su reacci\u00f3n la verdad.<\/p>\n<p>\u2013Pues que cree que tienes un lio, esta ma\u00f1ana en el coche me lo ha dejado caer.<\/p>\n<p>\u2013Ser\u00e1 cabr\u00f3n, as\u00ed que me tienes que vigilar. Segu\u00eda furibunda.<\/p>\n<p>\u2013Este hombre es idiota, soy yo a la que le sobran los motivos y va \u00e9l\u2026<\/p>\n<p>Me re\u00ed, mi madre exageraba su reacci\u00f3n, m\u00e1s aun cuando mi padre estaba en lo cierto.<\/p>\n<p>\u2013\u00bfQu\u00e9 te hace tanta gracia? Me pregunt\u00f3.<\/p>\n<p>\u2013Joder mam\u00e1, que t\u00fa y yo nos lo hemos montado, as\u00ed que, pues eso.<\/p>\n<p>\u2013\u00bfY qu\u00e9? El enfado se volvi\u00f3 en un segundo hacia m\u00ed.<\/p>\n<p>\u2013Yo no soy ninguna guarra que se vaya tirando a todo bicho viviente.<\/p>\n<p>\u2013Bueno pues en el coche me soltaste toda la historia de que andabas necesitada. Le repliqu\u00e9.<\/p>\n<p>\u2013Imagino que la cosa le viene de lejos, siendo t\u00fa una mujer tan atractiva y dem\u00e1s, yo le entiendo.<\/p>\n<p>\u2013Mario, nunca le he sido infiel a tu padre con un cualquiera. Me dijo muy seria.<\/p>\n<p>\u2013Lo que hemos hecho t\u00fa y yo es algo \u00fanico. Y me parece que como sigas as\u00ed de idiota se va a acabar muy pronto. Se levant\u00f3 y fue en direcci\u00f3n a la cocina.<\/p>\n<p>\u2013Mam\u00e1, no te enfades. Me hab\u00eda hecho la peor amenaza posible.<\/p>\n<p>\u2013Si lo s\u00e9 no te digo nada.<\/p>\n<p>\u2013No es culpa tuya. Se detuvo a mitad de camino y se volvi\u00f3 a mirarme.<\/p>\n<p>\u2013Pero no te deber\u00eda hacer gracia, si tu padre sospecha algo, si llega a enterarse de algo. Asent\u00ed.<\/p>\n<p>\u2013Me voy a poner la cena.<\/p>\n<p>Se encerr\u00f3 en la cocina, prefer\u00ed dejarla en paz un rato, hab\u00eda metido la pata. Siempre me pasaba al abrir la boca, con mi t\u00eda en el pueblo, ahora con mi madre, ten\u00eda que aprender cuando callarme.<\/p>\n<p>Mi madre me avis\u00f3 cuando la cena estuvo lista, esta vez no hubo pie bajo la mesa, ni animaci\u00f3n ninguna, ni siquiera conversaci\u00f3n. Mantuve le silencio hasta que terminamos, mi madre aun parec\u00eda molesta, se excus\u00f3 a su habitaci\u00f3n.<\/p>\n<p>Me aparqu\u00e9, deca\u00eddo, delante de la tele, por haberla cagado me iba a quedar sin foll\u00e1rmela.<\/p>\n<p>Para eso de las once, como no hab\u00eda nada que valiese la pena ver, me march\u00e9 escaleras arriba.<\/p>\n<p>Pas\u00e9 por delante de la puerta cerrada de la habitaci\u00f3n de matrimonio, segu\u00ed para mi cuarto. Me detuve antes de llegar y regres\u00e9, golpe\u00e9 la puerta un par de veces.<\/p>\n<p>No hubo respuesta, era pronto, o al menos no lo suficientemente tarde para que estuviera dormida, entr\u00e9 con cuidado.<\/p>\n<p>\u2013Lo siento. \u2013Dije al mismo tiempo que abr\u00eda la puerta.<\/p>\n<p>Mi madre estaba sobre la cama, leyendo, con sus gafas puestas, en un sugerente conjunto de lencer\u00eda roja. Me qued\u00e9 atontado mir\u00e1ndola, recorriendo su cuerpo con los ojos. El sujetador y las braguitas eran de encaje, llevaba adem\u00e1s un liguero a juego con el resto, y medias ataditas al mismo.<\/p>\n<p>\u2013S\u00ed que has tardado. Me coment\u00f3.<\/p>\n<p>\u2013Ya cre\u00ed que no ven\u00edas.<\/p>\n<p>\u2013\u00bfNo est\u00e1s enfadada? Pregunt\u00e9 con cuidado.<\/p>\n<p>\u2013Un poco, pero prefiero no pensar en eso ahora. Se quit\u00f3 las gafas.<\/p>\n<p>\u2013\u00bfTe gusta? Me pregunt\u00f3 por el atuendo, asent\u00ed.<\/p>\n<p>\u2013A tu padre no le va el rojo, prefiere el negro.<\/p>\n<p>\u2013Peor para \u00e9l. Me mord\u00eda el labio inferior y frotaba el paquete.<\/p>\n<p>\u2013\u00bfPuedes volver a ponerte las gafas? Lo hizo, me mir\u00f3 por encima de estas.<\/p>\n<p>\u2013As\u00ed das un morbazo mam\u00e1, rollo profesora caliente. Se r\u00edo.<\/p>\n<p>\u2013Poco te duran las preocupaciones mi ni\u00f1o.<\/p>\n<p>La verdad es que ya no me importaba nada m\u00e1s que ella.<\/p>\n<p>\u2013Ven para ac\u00e1, que te voy a poner unos deberes. Me acerqu\u00e9.<\/p>\n<p>\u2013Me vas a hacer un cunnilingus, ya sabes, como el otro d\u00eda, pero esta vez hasta el final.<\/p>\n<p>\u2013Hasta ma\u00f1ana si quieres. Le dije y me lanc\u00e9 a la cama.<\/p>\n<p>\u2013Desn\u00fadate tonto, que vamos a hacer m\u00e1s cosas y no quiero perder un momento cuando empecemos.<\/p>\n<p>Obedec\u00ed a mi madre, en todo. Me qued\u00e9 en pelotas, la polla la ten\u00eda morcillona, pero eso no importaba entonces.<\/p>\n<p>Importaba quitarle a mi madre sus preciosas bragas de encaje rojas, desatando el liguero de las medias negras, para una vez hubieron pasado, volver a atarlo.<\/p>\n<p>Mi madre me pregunt\u00f3 por qu\u00e9 volv\u00eda a coloc\u00e1rselo, le dije que me daba m\u00e1s morbo de aquella forma.<\/p>\n<p>Ten\u00eda la concha perfectamente rasurado, sin un solo pelito. Empec\u00e9 bes\u00e1ndola el interior de los muslos, subiendo con mucha calma.<\/p>\n<p>Llegu\u00e9 a sus co\u00f1o, lo acarici\u00e9 por fuera con mi lengua, saboreando cada cent\u00edmetro. Termin\u00e9 de hundir mi cara entre sus piernas y me dediqu\u00e9 los siguientes diez minutos a darle todo el placer que ella me pidi\u00f3, y algo m\u00e1s. Mi madre lleg\u00f3 al orgasmo, pero aun as\u00ed continu\u00f3 apretando mi cabeza contra s\u00ed\u2026<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_65053\" class=\"pvc_stats total_only  \" data-element-id=\"65053\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" =0 title=\"\"><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">T. Lectura:<\/span> <span class=\"rt-time\"> 12<\/span> <span class=\"rt-label rt-postfix\">min.<\/span><\/span>La calent\u00e9, aun sin meterle los dedos, con golpecitos y caricias, ella ronroneaba sin mirar. Mi anular fue el primer expedicionario en su interior, que estaba tan h\u00famedo como el exterior, el ronroneo subi\u00f3 de volumen. No empez\u00f3 a gemir hasta que a\u00f1ad\u00ed otro dedo a la penetraci\u00f3n. Entonces imprimi\u00f3 un cadencioso movimiento a sus caderas, acomod\u00e1ndose al jugueteo de<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_65053\" class=\"pvc_stats total_only  \" data-element-id=\"65053\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.cuentorelatos.com\/archivos\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":32737,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-65053","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-amor-filial"},"a3_pvc":{"activated":true,"total_views":9681,"today_views":7},"_links":{"self":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/65053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/users\/32737"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/comments?post=65053"}],"version-history":[{"count":2,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/65053\/revisions"}],"predecessor-version":[{"id":65055,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/posts\/65053\/revisions\/65055"}],"wp:attachment":[{"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/media?parent=65053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/categories?post=65053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuentorelatos.com\/archivos\/wp-json\/wp\/v2\/tags?post=65053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}